{"id":760,"date":"2016-02-15T11:09:47","date_gmt":"2016-02-15T11:09:47","guid":{"rendered":"http:\/\/naimahassert.com\/?p=760"},"modified":"2020-08-03T23:00:13","modified_gmt":"2020-08-03T23:00:13","slug":"la-puissance-de-la-joie","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/la-puissance-de-la-joie\/","title":{"rendered":"La puissance de la joie"},"content":{"rendered":"<p><strong>En France, mais aussi au Qu\u00e9bec, <em>La puissance de la joie<\/em> fait un tabac. <a href=\"http:\/\/www.lepoint.fr\/societe\/frederic-lenoir-la-joie-est-un-acte-de-resistance-individuel-et-collectif-27-11-2015-1985341_23.php\">On pr\u00e9tend<\/a> que ce succ\u00e8s est en partie caus\u00e9 par les attentats de Paris, qui pousseraient les gens \u00e0 chercher des raisons d&#8217;\u00eatre heureux ou des pistes pour le devenir. Et c&#8217;est ce que Fr\u00e9d\u00e9ric Lenoir propose, magnifiquement, sans se placer en gourou. Il partage tout simplement\u00a0sa sagesse de philosophe.<\/strong><\/p>\n<p>Il ne faut pas s&#8217;attendre ici \u00e0 un guide de croissance personnelle. On ne trouvera pas dans <em>La puissance de la joie<\/em> d&#8217;id\u00e9e toute faite, ou de th\u00e9orie universelle, pour devenir joyeux, mais plut\u00f4t un ouvrage de vulgarisation philosophique. Un cadeau rare qu&#8217;il ne faudrait pas laisser passer. Fr\u00e9d\u00e9ric Lenoir a pass\u00e9 des ann\u00e9es le nez plong\u00e9 dans les livres des plus grands philosophes. Dans ce court ouvrage de 200 pages, il nous fait le r\u00e9sum\u00e9 de ce qu&#8217;il a appris en ce concentrant sur la &#8220;joie&#8221;, ce sentiment plus facile \u00e0 atteindre, dit-il, et plus concret que le bonheur.<\/p>\n<p>Il nous apprend que Spinoza, Nietzsche ou Tchouang-Tseu ne s&#8217;entendaient certes pas sur tout, mais que quant \u00e0 la joie, ils sont unanimes sur certains \u00e9l\u00e9ments. Par exemple, ils s&#8217;entendent pour dire que la joie passe par le consentement \u00e0 la vie, peu importe ce qu&#8217;elle nous apporte. Que donner nous apporte plus de joie que de recevoir. Et que pour appr\u00e9cier la vie, il faut apprendre \u00e0 ralentir, \u00e0 savourer, mais aussi \u00e0 se conna\u00eetre soi-m\u00eame et \u00e0 s&#8217;ouvrir aux autres.<\/p>\n<p>Pour appuyer ses propos, Fr\u00e9d\u00e9ric Lenoir\u00a0nous parle aussi de ses exp\u00e9riences. Comment il est devenu plus joyeux en vendant sa grande maison pour \u00eatre moins endett\u00e9 et retrouver le temps qu&#8217;il lui manquait pour respirer. Comment il a\u00a0r\u00e9ussi \u00e0 transformer en quelques minutes sa\u00a0frustration contre sa voiture en \u00e9clat de rire, par joie.<\/p>\n<p>Ce livre est une succession de passages l\u00e9gers, inspirants, qui font souvent sourire et r\u00e9fl\u00e9chir. Aux lecteurs de d\u00e9terminer quelle sera leur chemin pour acc\u00e9der \u00e0 la joie. Mais au moins, avec ce livre, on est convaincus que c&#8217;est ce qu&#8217;il nous faut.<\/p>\n<p>&#8212;<\/p>\n<p><strong><a href=\"http:\/\/www.amazon.ca\/PUISSANCE-JOIE-LENOIR-FR%C3%89D%C3%89RIC\/dp\/2213661359\/?_encoding=UTF8&amp;camp=15121&amp;creative=330641&amp;keywords=la%20puissance%20de%20la%20joie&amp;linkCode=ur2&amp;qid=1455533258&amp;sr=8-1&amp;tag=naimahassertc-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">La puissance de la joie<\/a><img decoding=\"async\" style=\"border: none !important; margin: 0!important;\" src=\"http:\/\/ir-ca.amazon-adsystem.com\/e\/ir?t=naimahassertc-20&amp;l=ur2&amp;o=15\" alt=\"\" width=\"1\" height=\"1\" border=\"0\" \/><\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.fredericlenoir.com\/\">Fr\u00e9d\u00e9ric Lenoir<\/a><\/strong><\/p>\n<p><strong>Fayard<\/strong><\/p>\n<p><strong>24,26 $<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En France, mais aussi au Qu\u00e9bec, La puissance de la joie fait un tabac. On pr\u00e9tend que ce succ\u00e8s est en partie caus\u00e9 par les attentats de Paris, qui pousseraient les gens \u00e0 chercher des raisons d&#8217;\u00eatre heureux ou des pistes pour le devenir. Et c&#8217;est ce que Fr\u00e9d\u00e9ric Lenoir propose, magnifiquement, sans se placer en gourou. Il partage tout simplement\u00a0sa sagesse de philosophe. Il ne faut pas s&#8217;attendre ici \u00e0 un guide de croissance personnelle. On ne trouvera pas dans La puissance de la joie d&#8217;id\u00e9e toute faite, ou de th\u00e9orie universelle, pour devenir joyeux, mais plut\u00f4t un ouvrage de vulgarisation philosophique. Un cadeau rare qu&#8217;il ne faudrait pas laisser passer. Fr\u00e9d\u00e9ric Lenoir a pass\u00e9 des ann\u00e9es le nez plong\u00e9 dans les livres des plus grands philosophes. Dans ce court ouvrage de 200 pages, il nous fait le r\u00e9sum\u00e9 de ce qu&#8217;il a appris en ce concentrant sur la &#8220;joie&#8221;, ce sentiment plus facile \u00e0 atteindre, dit-il, et plus concret que le bonheur. Il nous apprend que Spinoza, Nietzsche ou Tchouang-Tseu ne s&#8217;entendaient certes pas sur tout, mais que quant \u00e0 la joie, ils sont unanimes sur certains \u00e9l\u00e9ments. Par exemple, ils s&#8217;entendent pour dire que la joie passe par le consentement \u00e0 la vie, peu importe ce qu&#8217;elle nous apporte. Que donner nous apporte plus de joie que de recevoir. Et que pour appr\u00e9cier la vie, il faut apprendre \u00e0 ralentir, \u00e0 savourer, mais aussi \u00e0 se conna\u00eetre soi-m\u00eame et \u00e0 s&#8217;ouvrir aux autres. Pour appuyer ses propos, Fr\u00e9d\u00e9ric Lenoir\u00a0nous parle aussi de ses exp\u00e9riences. Comment il est devenu plus joyeux en vendant sa grande maison pour \u00eatre moins endett\u00e9 et retrouver le temps qu&#8217;il lui manquait pour respirer. Comment il a\u00a0r\u00e9ussi \u00e0 transformer en quelques minutes sa\u00a0frustration contre sa voiture en \u00e9clat de rire, par joie. Ce livre est une succession de passages l\u00e9gers, inspirants, qui font souvent sourire et r\u00e9fl\u00e9chir. Aux lecteurs de d\u00e9terminer quelle sera leur chemin pour acc\u00e9der \u00e0 la joie. Mais au moins, avec ce livre, on est convaincus que c&#8217;est ce qu&#8217;il nous faut. &#8212; La puissance de la joie Fr\u00e9d\u00e9ric Lenoir Fayard 24,26 $<\/p>\n","protected":false},"author":1,"featured_media":3454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[254,251,249],"tags":[],"class_list":["post-760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-developpement-personnel","category-philosophie","category-se-renseigner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La puissance de la joie - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/la-puissance-de-la-joie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La puissance de la joie - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"En France, mais aussi au Qu\u00e9bec, La puissance de la joie fait un tabac. On pr\u00e9tend que ce succ\u00e8s est en partie caus\u00e9 par les attentats de Paris, qui pousseraient les gens \u00e0 chercher des raisons d&#8217;\u00eatre heureux ou des pistes pour le devenir. Et c&#8217;est ce que Fr\u00e9d\u00e9ric Lenoir propose, magnifiquement, sans se placer en gourou. Il partage tout simplement\u00a0sa sagesse de philosophe. Il ne faut pas s&#8217;attendre ici \u00e0 un guide de croissance personnelle. On ne trouvera pas dans La puissance de la joie d&#8217;id\u00e9e toute faite, ou de th\u00e9orie universelle, pour devenir joyeux, mais plut\u00f4t un ouvrage de vulgarisation philosophique. Un cadeau rare qu&#8217;il ne faudrait pas laisser passer. Fr\u00e9d\u00e9ric Lenoir a pass\u00e9 des ann\u00e9es le nez plong\u00e9 dans les livres des plus grands philosophes. Dans ce court ouvrage de 200 pages, il nous fait le r\u00e9sum\u00e9 de ce qu&#8217;il a appris en ce concentrant sur la &#8220;joie&#8221;, ce sentiment plus facile \u00e0 atteindre, dit-il, et plus concret que le bonheur. Il nous apprend que Spinoza, Nietzsche ou Tchouang-Tseu ne s&#8217;entendaient certes pas sur tout, mais que quant \u00e0 la joie, ils sont unanimes sur certains \u00e9l\u00e9ments. Par exemple, ils s&#8217;entendent pour dire que la joie passe par le consentement \u00e0 la vie, peu importe ce qu&#8217;elle nous apporte. Que donner nous apporte plus de joie que de recevoir. Et que pour appr\u00e9cier la vie, il faut apprendre \u00e0 ralentir, \u00e0 savourer, mais aussi \u00e0 se conna\u00eetre soi-m\u00eame et \u00e0 s&#8217;ouvrir aux autres. Pour appuyer ses propos, Fr\u00e9d\u00e9ric Lenoir\u00a0nous parle aussi de ses exp\u00e9riences. Comment il est devenu plus joyeux en vendant sa grande maison pour \u00eatre moins endett\u00e9 et retrouver le temps qu&#8217;il lui manquait pour respirer. Comment il a\u00a0r\u00e9ussi \u00e0 transformer en quelques minutes sa\u00a0frustration contre sa voiture en \u00e9clat de rire, par joie. Ce livre est une succession de passages l\u00e9gers, inspirants, qui font souvent sourire et r\u00e9fl\u00e9chir. Aux lecteurs de d\u00e9terminer quelle sera leur chemin pour acc\u00e9der \u00e0 la joie. Mais au moins, avec ce livre, on est convaincus que c&#8217;est ce qu&#8217;il nous faut. &#8212; La puissance de la joie Fr\u00e9d\u00e9ric Lenoir Fayard 24,26 $\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/la-puissance-de-la-joie\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-15T11:09:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-03T23:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/02\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"559\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"La puissance de la joie\",\"datePublished\":\"2016-02-15T11:09:47+00:00\",\"dateModified\":\"2020-08-03T23:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/\"},\"wordCount\":388,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1\",\"articleSection\":[\"D\u00e9veloppement personnel\",\"Philosophie\",\"Se renseigner\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/\",\"name\":\"La puissance de la joie - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1\",\"datePublished\":\"2016-02-15T11:09:47+00:00\",\"dateModified\":\"2020-08-03T23:00:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1\",\"width\":840,\"height\":559},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-puissance-de-la-joie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La puissance de la joie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La puissance de la joie - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/la-puissance-de-la-joie\/","og_locale":"fr_CA","og_type":"article","og_title":"La puissance de la joie - Prochaine lecture","og_description":"En France, mais aussi au Qu\u00e9bec, La puissance de la joie fait un tabac. On pr\u00e9tend que ce succ\u00e8s est en partie caus\u00e9 par les attentats de Paris, qui pousseraient les gens \u00e0 chercher des raisons d&#8217;\u00eatre heureux ou des pistes pour le devenir. Et c&#8217;est ce que Fr\u00e9d\u00e9ric Lenoir propose, magnifiquement, sans se placer en gourou. Il partage tout simplement\u00a0sa sagesse de philosophe. Il ne faut pas s&#8217;attendre ici \u00e0 un guide de croissance personnelle. On ne trouvera pas dans La puissance de la joie d&#8217;id\u00e9e toute faite, ou de th\u00e9orie universelle, pour devenir joyeux, mais plut\u00f4t un ouvrage de vulgarisation philosophique. Un cadeau rare qu&#8217;il ne faudrait pas laisser passer. Fr\u00e9d\u00e9ric Lenoir a pass\u00e9 des ann\u00e9es le nez plong\u00e9 dans les livres des plus grands philosophes. Dans ce court ouvrage de 200 pages, il nous fait le r\u00e9sum\u00e9 de ce qu&#8217;il a appris en ce concentrant sur la &#8220;joie&#8221;, ce sentiment plus facile \u00e0 atteindre, dit-il, et plus concret que le bonheur. Il nous apprend que Spinoza, Nietzsche ou Tchouang-Tseu ne s&#8217;entendaient certes pas sur tout, mais que quant \u00e0 la joie, ils sont unanimes sur certains \u00e9l\u00e9ments. Par exemple, ils s&#8217;entendent pour dire que la joie passe par le consentement \u00e0 la vie, peu importe ce qu&#8217;elle nous apporte. Que donner nous apporte plus de joie que de recevoir. Et que pour appr\u00e9cier la vie, il faut apprendre \u00e0 ralentir, \u00e0 savourer, mais aussi \u00e0 se conna\u00eetre soi-m\u00eame et \u00e0 s&#8217;ouvrir aux autres. Pour appuyer ses propos, Fr\u00e9d\u00e9ric Lenoir\u00a0nous parle aussi de ses exp\u00e9riences. Comment il est devenu plus joyeux en vendant sa grande maison pour \u00eatre moins endett\u00e9 et retrouver le temps qu&#8217;il lui manquait pour respirer. Comment il a\u00a0r\u00e9ussi \u00e0 transformer en quelques minutes sa\u00a0frustration contre sa voiture en \u00e9clat de rire, par joie. Ce livre est une succession de passages l\u00e9gers, inspirants, qui font souvent sourire et r\u00e9fl\u00e9chir. Aux lecteurs de d\u00e9terminer quelle sera leur chemin pour acc\u00e9der \u00e0 la joie. Mais au moins, avec ce livre, on est convaincus que c&#8217;est ce qu&#8217;il nous faut. &#8212; La puissance de la joie Fr\u00e9d\u00e9ric Lenoir Fayard 24,26 $","og_url":"https:\/\/prochainelecture.com\/fr\/la-puissance-de-la-joie\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2016-02-15T11:09:47+00:00","article_modified_time":"2020-08-03T23:00:13+00:00","og_image":[{"width":840,"height":559,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/02\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1","type":"image\/png"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"La puissance de la joie","datePublished":"2016-02-15T11:09:47+00:00","dateModified":"2020-08-03T23:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/"},"wordCount":388,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/02\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1","articleSection":["D\u00e9veloppement personnel","Philosophie","Se renseigner"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/","url":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/","name":"La puissance de la joie - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/02\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1","datePublished":"2016-02-15T11:09:47+00:00","dateModified":"2020-08-03T23:00:13+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/02\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/02\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1","width":840,"height":559},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/la-puissance-de-la-joie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"La puissance de la joie"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/02\/la_puissance_de_la_joie_0.png?fit=840%2C559&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-cg","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":2,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"predecessor-version":[{"id":3455,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/760\/revisions\/3455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3454"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}