{"id":4959,"date":"2025-03-30T20:21:05","date_gmt":"2025-03-31T00:21:05","guid":{"rendered":"https:\/\/prochainelecture.com\/fr\/?p=4959"},"modified":"2025-03-30T20:29:00","modified_gmt":"2025-03-31T00:29:00","slug":"ma-sombre-vanessa-de-kate-elizabeth-russell","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/","title":{"rendered":"Ma sombre Vanessa, de Kate Elizabeth Russell"},"content":{"rendered":"\n<p>Ce livre \u00e9tait dans ma liste depuis longtemps, probablement depuis sa sortie en 2020. J&#8217;ai d\u00fb l&#8217;y ajouter parce qu&#8217;il a eu de tr\u00e8s bonnes critiques, mais \u00e7a ne me tentait vraiment pas de le lire. Selon le peu que je savais, c&#8217;\u00e9tait un histoire d&#8217;abus de pouvoir. \u00c7a n&#8217;allait certainement pas \u00eatre l\u00e9ger.<\/p>\n\n\n\n<p>Et \u00e7a ne l&#8217;\u00e9tait pas du tout. Mais c&#8217;est, je pense, le seul aspect de ce livre qui ne m&#8217;a pas \u00e9tonn\u00e9e.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9 <\/h2>\n\n\n\n<p>Vanessa raconte sa relation abusive avec son professeur d&#8217;anglais, qui a commenc\u00e9 alors qu&#8217;elle avait 15 ans et lui 42. Elle nous raconte ce qui s&#8217;est pass\u00e9 \u00e0 l&#8217;\u00e9poque, puis 17 ans plus tard, alors que le mouvement #MeToo bouleverse le monde et que d&#8217;autres filles que le professeur a abus\u00e9es le d\u00e9nonce dans les m\u00e9dias.<\/p>\n\n\n\n<p>Vanessa refuse toutefois de t\u00e9moigner. Elle insiste pour dire qu&#8217;il ne l&#8217;a pas abus\u00e9e, qu&#8217;il l&#8217;aimait, et qu&#8217;elle \u00e9tait consentante. <\/p>\n\n\n\n<p>Ce qui n&#8217;est pas totalement faux. Mais certainement pas vrai non plus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions <\/h2>\n\n\n\n<p>Je l&#8217;ai mentionn\u00e9, je m&#8217;attendais \u00e0 ce que ce livre soit lourd. Mais je ne m&#8217;attendais pas du tout \u00e0 ce qu&#8217;il se lise comme un suspense, ni qu&#8217;il soit aussi juste, touchant et nuanc\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Suspense<\/h3>\n\n\n\n<p>Vanessa, la jeune \u00e9l\u00e8ve qui a une relation sexuelle avec son professeur d&#8217;anglais, est la narratrice. On a donc droit \u00e0 tout, du d\u00e9but \u00e0 la fin : tous les faits et gestes ext\u00e9rieurs qui m\u00e8nent \u00e0 cette relation et toutes les pens\u00e9es intimes de la jeune fille. On voit bien qu&#8217;elle est attir\u00e9e par le professeur, qu&#8217;elle lui tourne autour, qu&#8217;elle est incroyablement touch\u00e9e par les compliments qu&#8217;il lui fait, qu&#8217;elle se sent adulte, diff\u00e9rente des autres, et fi\u00e8re d&#8217;avoir une relation avec un homme qui semble \u00eatre en p\u00e2moison devant elle. On voit aussi tout ce que le professeur dit pour la manipuler, et de notre regard externe, on voit tr\u00e8s bien qu&#8217;il ne s&#8217;agit pas d&#8217;une histoire d&#8217;amour, mais d&#8217;une histoire d&#8217;abus.<\/p>\n\n\n\n<p>C&#8217;est incroyablement frustrant, et on ne peut pas s&#8217;emp\u00eacher de continuer \u00e0 lire pour savoir ce qui va arriver. On a envie de secouer Vanessa par les \u00e9paules quand on la voit r\u00e9p\u00e9ter \u00e0 tout le monde que ce qu&#8217;elle a v\u00e9cu avec son professeur \u00e9tait une histoire d&#8217;amour, quand elle l&#8217;appelle encore 17 ans plus tard pour revivre des souvenirs avec lui, quand, \u00e0 15 ans, elle prend le bl\u00e2me et accepte toutes les cons\u00e9quences pour le prot\u00e9ger quand les rumeurs de leur relation sont trop fortes. On aimerait tellement qu&#8217;il se fasse emprisonner. On tourne f\u00e9rocement les pages en esp\u00e9rant ce d\u00e9nouement.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Juste<\/h3>\n\n\n\n<p>Je ne m&#8217;attendais pas non plus \u00e0 un r\u00e9cit aussi juste et aussi touchant, parce qu&#8217;on voit l&#8217;ambivalence de Vanessa. On voit qu&#8217;elle n&#8217;est pas compl\u00e8tement \u00e0 l&#8217;aise avec lui, qu&#8217;elle se rend compte qu&#8217;elle ne conna\u00eet rien de lui, qu&#8217;elle fait l&#8217;amour alors qu&#8217;elle n&#8217;en a pas vraiment envie, qu&#8217;elle se demande parfois si elle se fait violer. On a acc\u00e8s \u00e0 sa col\u00e8re envers lui, \u00e0 son ins\u00e9curit\u00e9 et \u00e0 sa solitude. On finit par comprendre, en m\u00eame temps qu&#8217;elle, que son insistance \u00e0 dire que son histoire en \u00e9tait une belle est une tentative de se convaincre elle-m\u00eame. Elle \u00e9tait tellement jeune quand c&#8217;est arriv\u00e9 qu&#8217;elle en est rest\u00e9e marqu\u00e9e \u00e0 vie. De plus, elle n&#8217;a presque rien connu d&#8217;autre, l&#8217;emprise du professeur sur elle \u00e9tait trop forte. Alors si, presque vingt ans plus tard, elle change d&#8217;opinion sur un \u00e9v\u00e8nement aussi formateur, qui est-elle?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Nuanc\u00e9<\/h3>\n\n\n\n<p>Je n&#8217;ai jamais lu un texte aussi nuanc\u00e9 sur la question. Pas nuanc\u00e9 par rapport \u00e0 la moralit\u00e9 du gars (il n&#8217;en a pas, c&#8217;est un homme d\u00e9gueu, merci bonsoir. \u00c7a va faire, l&#8217;empathie pour les pauvres hommes qui ne sont pas capables de contr\u00f4ler leur p\u00e9nis.) Mais nuanc\u00e9 par rapport \u00e0 l&#8217;exp\u00e9rience de la fille. <\/p>\n\n\n\n<p>C&#8217;est vrai qu&#8217;elle \u00e9tait partiellement consentante. C&#8217;est vrai qu&#8217;elle avait des sentiments tr\u00e8s forts pour cet homme. On peut comprendre qu&#8217;elle ne soit pas d&#8217;accord quand on lui dit tout bonnement qu&#8217;elle est une victime d&#8217;abus. Mais c&#8217;est vrai aussi que ce n&#8217;est pas elle qui a instigu\u00e9 cette relation, malgr\u00e9 ce que son professeur essaie de lui faire croire par la suite. C&#8217;est vrai qu&#8217;elle \u00e9tait trop jeune pour comprendre les implications de ce qui \u00e9tait en train de se passer. Et c&#8217;est vrai que ce qu&#8217;elle voulait, en fait, c&#8217;\u00e9tait de la reconnaissance et de l&#8217;amour. Pas du sexe.<\/p>\n\n\n\n<p>J&#8217;en ai d\u00e9j\u00e0 parl\u00e9, les histoires &#8220;d&#8217;amour&#8221; entre des adolescentes et des hommes beaucoup plus vieux me font dresser les cheveux sur la t\u00eate. Je pense \u00e0 <a href=\"https:\/\/prochainelecture.com\/fr\/lamant\/\"><em>L&#8217;<\/em><\/a><a href=\"https:\/\/prochainelecture.com\/fr\/lamant\/\">A<\/a><a href=\"https:\/\/prochainelecture.com\/fr\/lamant\/\"><em>mant<\/em><\/a><em> <\/em>de Marguerite Duras e<a href=\"https:\/\/prochainelecture.com\/fr\/la-verite-sur-laffaire-harry-quebert-de-joel-dicker\/\">t <\/a><a href=\"https:\/\/prochainelecture.com\/fr\/la-verite-sur-laffaire-harry-quebert-de-joel-dicker\/\"><em>La V\u00e9rit\u00e9 sur l&#8217;affaire Harry Quebert<\/em><\/a><em> <\/em>de Jo\u00ebl Dicker. Ces deux livres ont connu un bon succ\u00e8s malgr\u00e9 le fait qu&#8217;ils font passer l&#8217;attirance sexuelle d&#8217;hommes pour des jeunes filles impressionnables pour de la romance. \u00c7a me d\u00e9passe, parce qu&#8217;\u00e0 mes yeux, n&#8217;importe qui ayant v\u00e9cu ce genre de choses sait tout de suite que c&#8217;est n&#8217;importe quoi. N\u00e9anmoins, ces auteurs, par ignorance ou par calcul, utilisent leur r\u00e9putation pour propager l&#8217;id\u00e9e fausse et d\u00e9vastatrice que &#8220;l&#8217;amour n&#8217;a pas d&#8217;\u00e2ge&#8221;.<\/p>\n\n\n\n<p>Et puis je lis un livre comme <em>Ma sombre Vanessa<\/em>, et je me rappelle qu&#8217;on va quand m\u00eame dans la bonne direction. Des femmes \u00e9loquentes qui ont v\u00e9cu ce genre de relations peuvent en parler avec toute la finesse n\u00e9cessaire pour \u00e0 la fois d\u00e9faire les mythes persistants, d\u00e9noncer les agresseurs et saisir la complexit\u00e9 des exp\u00e9riences des jeunes filles.<\/p>\n\n\n\n<p>Ce n&#8217;est pas une lecture facile. J&#8217;ai \u00e9t\u00e9 d\u00e9go\u00fbt\u00e9e la majorit\u00e9 du temps (ce n&#8217;est pas agr\u00e9able de lire des sc\u00e8nes de sexe entre une enfant et un homme adulte), et il m&#8217;a un peu d\u00e9prim\u00e9e. Mais je crois que c&#8217;est un excellent livre, et qu&#8217;il est n\u00e9cessaire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce livre \u00e9tait dans ma liste depuis longtemps, probablement depuis sa sortie en 2020. J&#8217;ai d\u00fb l&#8217;y ajouter parce qu&#8217;il a eu de tr\u00e8s bonnes critiques, mais \u00e7a ne me tentait vraiment pas de le lire. Selon le peu que je savais, c&#8217;\u00e9tait un histoire d&#8217;abus de pouvoir. \u00c7a n&#8217;allait certainement pas \u00eatre l\u00e9ger. Et \u00e7a ne l&#8217;\u00e9tait pas du tout. Mais c&#8217;est, je pense, le seul aspect de ce livre qui ne m&#8217;a pas \u00e9tonn\u00e9e. R\u00e9sum\u00e9 Vanessa raconte sa relation abusive avec son professeur d&#8217;anglais, qui a commenc\u00e9 alors qu&#8217;elle avait 15 ans et lui 42. Elle nous raconte ce qui s&#8217;est pass\u00e9 \u00e0 l&#8217;\u00e9poque, puis 17 ans plus tard, alors que le mouvement #MeToo bouleverse le monde et que d&#8217;autres filles que le professeur a abus\u00e9es le d\u00e9nonce dans les m\u00e9dias. Vanessa refuse toutefois de t\u00e9moigner. Elle insiste pour dire qu&#8217;il ne l&#8217;a pas abus\u00e9e, qu&#8217;il l&#8217;aimait, et qu&#8217;elle \u00e9tait consentante. Ce qui n&#8217;est pas totalement faux. Mais certainement pas vrai non plus. Impressions Je l&#8217;ai mentionn\u00e9, je m&#8217;attendais \u00e0 ce que ce livre soit lourd. Mais je ne m&#8217;attendais pas du tout \u00e0 ce qu&#8217;il se lise comme un suspense, ni qu&#8217;il soit aussi juste, touchant et nuanc\u00e9. Suspense Vanessa, la jeune \u00e9l\u00e8ve qui a une relation sexuelle avec son professeur d&#8217;anglais, est la narratrice. On a donc droit \u00e0 tout, du d\u00e9but \u00e0 la fin : tous les faits et gestes ext\u00e9rieurs qui m\u00e8nent \u00e0 cette relation et toutes les pens\u00e9es intimes de la jeune fille. On voit bien qu&#8217;elle est attir\u00e9e par le professeur, qu&#8217;elle lui tourne autour, qu&#8217;elle est incroyablement touch\u00e9e par les compliments qu&#8217;il lui fait, qu&#8217;elle se sent adulte, diff\u00e9rente des autres, et fi\u00e8re d&#8217;avoir une relation avec un homme qui semble \u00eatre en p\u00e2moison devant elle. On voit aussi tout ce que le professeur dit pour la manipuler, et de notre regard externe, on voit tr\u00e8s bien qu&#8217;il ne s&#8217;agit pas d&#8217;une histoire d&#8217;amour, mais d&#8217;une histoire d&#8217;abus. C&#8217;est incroyablement frustrant, et on ne peut pas s&#8217;emp\u00eacher de continuer \u00e0 lire pour savoir ce qui va arriver. On a envie de secouer Vanessa par les \u00e9paules quand on la voit r\u00e9p\u00e9ter \u00e0 tout le monde que ce qu&#8217;elle a v\u00e9cu avec son professeur \u00e9tait une histoire d&#8217;amour, quand elle l&#8217;appelle encore 17 ans plus tard pour revivre des souvenirs avec lui, quand, \u00e0 15 ans, elle prend le bl\u00e2me et accepte toutes les cons\u00e9quences pour le prot\u00e9ger quand les rumeurs de leur relation sont trop fortes. On aimerait tellement qu&#8217;il se fasse emprisonner. On tourne f\u00e9rocement les pages en esp\u00e9rant ce d\u00e9nouement. Juste Je ne m&#8217;attendais pas non plus \u00e0 un r\u00e9cit aussi juste et aussi touchant, parce qu&#8217;on voit l&#8217;ambivalence de Vanessa. On voit qu&#8217;elle n&#8217;est pas compl\u00e8tement \u00e0 l&#8217;aise avec lui, qu&#8217;elle se rend compte qu&#8217;elle ne conna\u00eet rien de lui, qu&#8217;elle fait l&#8217;amour alors qu&#8217;elle n&#8217;en a pas vraiment envie, qu&#8217;elle se demande parfois si elle se fait violer. On a acc\u00e8s \u00e0 sa col\u00e8re envers lui, \u00e0 son ins\u00e9curit\u00e9 et \u00e0 sa solitude. On finit par comprendre, en m\u00eame temps qu&#8217;elle, que son insistance \u00e0 dire que son histoire en \u00e9tait une belle est une tentative de se convaincre elle-m\u00eame. Elle \u00e9tait tellement jeune quand c&#8217;est arriv\u00e9 qu&#8217;elle en est rest\u00e9e marqu\u00e9e \u00e0 vie. De plus, elle n&#8217;a presque rien connu d&#8217;autre, l&#8217;emprise du professeur sur elle \u00e9tait trop forte. Alors si, presque vingt ans plus tard, elle change d&#8217;opinion sur un \u00e9v\u00e8nement aussi formateur, qui est-elle? Nuanc\u00e9 Je n&#8217;ai jamais lu un texte aussi nuanc\u00e9 sur la question. Pas nuanc\u00e9 par rapport \u00e0 la moralit\u00e9 du gars (il n&#8217;en a pas, c&#8217;est un homme d\u00e9gueu, merci bonsoir. \u00c7a va faire, l&#8217;empathie pour les pauvres hommes qui ne sont pas capables de contr\u00f4ler leur p\u00e9nis.) Mais nuanc\u00e9 par rapport \u00e0 l&#8217;exp\u00e9rience de la fille. C&#8217;est vrai qu&#8217;elle \u00e9tait partiellement consentante. C&#8217;est vrai qu&#8217;elle avait des sentiments tr\u00e8s forts pour cet homme. On peut comprendre qu&#8217;elle ne soit pas d&#8217;accord quand on lui dit tout bonnement qu&#8217;elle est une victime d&#8217;abus. Mais c&#8217;est vrai aussi que ce n&#8217;est pas elle qui a instigu\u00e9 cette relation, malgr\u00e9 ce que son professeur essaie de lui faire croire par la suite. C&#8217;est vrai qu&#8217;elle \u00e9tait trop jeune pour comprendre les implications de ce qui \u00e9tait en train de se passer. Et c&#8217;est vrai que ce qu&#8217;elle voulait, en fait, c&#8217;\u00e9tait de la reconnaissance et de l&#8217;amour. Pas du sexe. J&#8217;en ai d\u00e9j\u00e0 parl\u00e9, les histoires &#8220;d&#8217;amour&#8221; entre des adolescentes et des hommes beaucoup plus vieux me font dresser les cheveux sur la t\u00eate. Je pense \u00e0 L&#8217;Amant de Marguerite Duras et La V\u00e9rit\u00e9 sur l&#8217;affaire Harry Quebert de Jo\u00ebl Dicker. Ces deux livres ont connu un bon succ\u00e8s malgr\u00e9 le fait qu&#8217;ils font passer l&#8217;attirance sexuelle d&#8217;hommes pour des jeunes filles impressionnables pour de la romance. \u00c7a me d\u00e9passe, parce qu&#8217;\u00e0 mes yeux, n&#8217;importe qui ayant v\u00e9cu ce genre de choses sait tout de suite que c&#8217;est n&#8217;importe quoi. N\u00e9anmoins, ces auteurs, par ignorance ou par calcul, utilisent leur r\u00e9putation pour propager l&#8217;id\u00e9e fausse et d\u00e9vastatrice que &#8220;l&#8217;amour n&#8217;a pas d&#8217;\u00e2ge&#8221;. Et puis je lis un livre comme Ma sombre Vanessa, et je me rappelle qu&#8217;on va quand m\u00eame dans la bonne direction. Des femmes \u00e9loquentes qui ont v\u00e9cu ce genre de relations peuvent en parler avec toute la finesse n\u00e9cessaire pour \u00e0 la fois d\u00e9faire les mythes persistants, d\u00e9noncer les agresseurs et saisir la complexit\u00e9 des exp\u00e9riences des jeunes filles. Ce n&#8217;est pas une lecture facile. J&#8217;ai \u00e9t\u00e9 d\u00e9go\u00fbt\u00e9e la majorit\u00e9 du temps (ce n&#8217;est pas agr\u00e9able de lire des sc\u00e8nes de sexe entre une enfant et un homme adulte), et il m&#8217;a un peu d\u00e9prim\u00e9e. Mais je crois que c&#8217;est un excellent livre, et qu&#8217;il est n\u00e9cessaire.<\/p>\n","protected":false},"author":1,"featured_media":4960,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[249,253],"tags":[],"class_list":["post-4959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-se-renseigner","category-societe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ma sombre Vanessa, de Kate Elizabeth Russell - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ma sombre Vanessa, de Kate Elizabeth Russell - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Ce livre \u00e9tait dans ma liste depuis longtemps, probablement depuis sa sortie en 2020. J&#8217;ai d\u00fb l&#8217;y ajouter parce qu&#8217;il a eu de tr\u00e8s bonnes critiques, mais \u00e7a ne me tentait vraiment pas de le lire. Selon le peu que je savais, c&#8217;\u00e9tait un histoire d&#8217;abus de pouvoir. \u00c7a n&#8217;allait certainement pas \u00eatre l\u00e9ger. Et \u00e7a ne l&#8217;\u00e9tait pas du tout. Mais c&#8217;est, je pense, le seul aspect de ce livre qui ne m&#8217;a pas \u00e9tonn\u00e9e. R\u00e9sum\u00e9 Vanessa raconte sa relation abusive avec son professeur d&#8217;anglais, qui a commenc\u00e9 alors qu&#8217;elle avait 15 ans et lui 42. Elle nous raconte ce qui s&#8217;est pass\u00e9 \u00e0 l&#8217;\u00e9poque, puis 17 ans plus tard, alors que le mouvement #MeToo bouleverse le monde et que d&#8217;autres filles que le professeur a abus\u00e9es le d\u00e9nonce dans les m\u00e9dias. Vanessa refuse toutefois de t\u00e9moigner. Elle insiste pour dire qu&#8217;il ne l&#8217;a pas abus\u00e9e, qu&#8217;il l&#8217;aimait, et qu&#8217;elle \u00e9tait consentante. Ce qui n&#8217;est pas totalement faux. Mais certainement pas vrai non plus. Impressions Je l&#8217;ai mentionn\u00e9, je m&#8217;attendais \u00e0 ce que ce livre soit lourd. Mais je ne m&#8217;attendais pas du tout \u00e0 ce qu&#8217;il se lise comme un suspense, ni qu&#8217;il soit aussi juste, touchant et nuanc\u00e9. Suspense Vanessa, la jeune \u00e9l\u00e8ve qui a une relation sexuelle avec son professeur d&#8217;anglais, est la narratrice. On a donc droit \u00e0 tout, du d\u00e9but \u00e0 la fin : tous les faits et gestes ext\u00e9rieurs qui m\u00e8nent \u00e0 cette relation et toutes les pens\u00e9es intimes de la jeune fille. On voit bien qu&#8217;elle est attir\u00e9e par le professeur, qu&#8217;elle lui tourne autour, qu&#8217;elle est incroyablement touch\u00e9e par les compliments qu&#8217;il lui fait, qu&#8217;elle se sent adulte, diff\u00e9rente des autres, et fi\u00e8re d&#8217;avoir une relation avec un homme qui semble \u00eatre en p\u00e2moison devant elle. On voit aussi tout ce que le professeur dit pour la manipuler, et de notre regard externe, on voit tr\u00e8s bien qu&#8217;il ne s&#8217;agit pas d&#8217;une histoire d&#8217;amour, mais d&#8217;une histoire d&#8217;abus. C&#8217;est incroyablement frustrant, et on ne peut pas s&#8217;emp\u00eacher de continuer \u00e0 lire pour savoir ce qui va arriver. On a envie de secouer Vanessa par les \u00e9paules quand on la voit r\u00e9p\u00e9ter \u00e0 tout le monde que ce qu&#8217;elle a v\u00e9cu avec son professeur \u00e9tait une histoire d&#8217;amour, quand elle l&#8217;appelle encore 17 ans plus tard pour revivre des souvenirs avec lui, quand, \u00e0 15 ans, elle prend le bl\u00e2me et accepte toutes les cons\u00e9quences pour le prot\u00e9ger quand les rumeurs de leur relation sont trop fortes. On aimerait tellement qu&#8217;il se fasse emprisonner. On tourne f\u00e9rocement les pages en esp\u00e9rant ce d\u00e9nouement. Juste Je ne m&#8217;attendais pas non plus \u00e0 un r\u00e9cit aussi juste et aussi touchant, parce qu&#8217;on voit l&#8217;ambivalence de Vanessa. On voit qu&#8217;elle n&#8217;est pas compl\u00e8tement \u00e0 l&#8217;aise avec lui, qu&#8217;elle se rend compte qu&#8217;elle ne conna\u00eet rien de lui, qu&#8217;elle fait l&#8217;amour alors qu&#8217;elle n&#8217;en a pas vraiment envie, qu&#8217;elle se demande parfois si elle se fait violer. On a acc\u00e8s \u00e0 sa col\u00e8re envers lui, \u00e0 son ins\u00e9curit\u00e9 et \u00e0 sa solitude. On finit par comprendre, en m\u00eame temps qu&#8217;elle, que son insistance \u00e0 dire que son histoire en \u00e9tait une belle est une tentative de se convaincre elle-m\u00eame. Elle \u00e9tait tellement jeune quand c&#8217;est arriv\u00e9 qu&#8217;elle en est rest\u00e9e marqu\u00e9e \u00e0 vie. De plus, elle n&#8217;a presque rien connu d&#8217;autre, l&#8217;emprise du professeur sur elle \u00e9tait trop forte. Alors si, presque vingt ans plus tard, elle change d&#8217;opinion sur un \u00e9v\u00e8nement aussi formateur, qui est-elle? Nuanc\u00e9 Je n&#8217;ai jamais lu un texte aussi nuanc\u00e9 sur la question. Pas nuanc\u00e9 par rapport \u00e0 la moralit\u00e9 du gars (il n&#8217;en a pas, c&#8217;est un homme d\u00e9gueu, merci bonsoir. \u00c7a va faire, l&#8217;empathie pour les pauvres hommes qui ne sont pas capables de contr\u00f4ler leur p\u00e9nis.) Mais nuanc\u00e9 par rapport \u00e0 l&#8217;exp\u00e9rience de la fille. C&#8217;est vrai qu&#8217;elle \u00e9tait partiellement consentante. C&#8217;est vrai qu&#8217;elle avait des sentiments tr\u00e8s forts pour cet homme. On peut comprendre qu&#8217;elle ne soit pas d&#8217;accord quand on lui dit tout bonnement qu&#8217;elle est une victime d&#8217;abus. Mais c&#8217;est vrai aussi que ce n&#8217;est pas elle qui a instigu\u00e9 cette relation, malgr\u00e9 ce que son professeur essaie de lui faire croire par la suite. C&#8217;est vrai qu&#8217;elle \u00e9tait trop jeune pour comprendre les implications de ce qui \u00e9tait en train de se passer. Et c&#8217;est vrai que ce qu&#8217;elle voulait, en fait, c&#8217;\u00e9tait de la reconnaissance et de l&#8217;amour. Pas du sexe. J&#8217;en ai d\u00e9j\u00e0 parl\u00e9, les histoires &#8220;d&#8217;amour&#8221; entre des adolescentes et des hommes beaucoup plus vieux me font dresser les cheveux sur la t\u00eate. Je pense \u00e0 L&#8217;Amant de Marguerite Duras et La V\u00e9rit\u00e9 sur l&#8217;affaire Harry Quebert de Jo\u00ebl Dicker. Ces deux livres ont connu un bon succ\u00e8s malgr\u00e9 le fait qu&#8217;ils font passer l&#8217;attirance sexuelle d&#8217;hommes pour des jeunes filles impressionnables pour de la romance. \u00c7a me d\u00e9passe, parce qu&#8217;\u00e0 mes yeux, n&#8217;importe qui ayant v\u00e9cu ce genre de choses sait tout de suite que c&#8217;est n&#8217;importe quoi. N\u00e9anmoins, ces auteurs, par ignorance ou par calcul, utilisent leur r\u00e9putation pour propager l&#8217;id\u00e9e fausse et d\u00e9vastatrice que &#8220;l&#8217;amour n&#8217;a pas d&#8217;\u00e2ge&#8221;. Et puis je lis un livre comme Ma sombre Vanessa, et je me rappelle qu&#8217;on va quand m\u00eame dans la bonne direction. Des femmes \u00e9loquentes qui ont v\u00e9cu ce genre de relations peuvent en parler avec toute la finesse n\u00e9cessaire pour \u00e0 la fois d\u00e9faire les mythes persistants, d\u00e9noncer les agresseurs et saisir la complexit\u00e9 des exp\u00e9riences des jeunes filles. Ce n&#8217;est pas une lecture facile. J&#8217;ai \u00e9t\u00e9 d\u00e9go\u00fbt\u00e9e la majorit\u00e9 du temps (ce n&#8217;est pas agr\u00e9able de lire des sc\u00e8nes de sexe entre une enfant et un homme adulte), et il m&#8217;a un peu d\u00e9prim\u00e9e. Mais je crois que c&#8217;est un excellent livre, et qu&#8217;il est n\u00e9cessaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-31T00:21:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-31T00:29:00+00:00\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Ma sombre Vanessa, de Kate Elizabeth Russell\",\"datePublished\":\"2025-03-31T00:21:05+00:00\",\"dateModified\":\"2025-03-31T00:29:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/\"},\"wordCount\":1116,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1\",\"articleSection\":[\"Se renseigner\",\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/\",\"name\":\"Ma sombre Vanessa, de Kate Elizabeth Russell - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1\",\"datePublished\":\"2025-03-31T00:21:05+00:00\",\"dateModified\":\"2025-03-31T00:29:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1\",\"width\":1041,\"height\":1387},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/ma-sombre-vanessa-de-kate-elizabeth-russell\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ma sombre Vanessa, de Kate Elizabeth Russell\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ma sombre Vanessa, de Kate Elizabeth Russell - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/","og_locale":"fr_CA","og_type":"article","og_title":"Ma sombre Vanessa, de Kate Elizabeth Russell - Prochaine lecture","og_description":"Ce livre \u00e9tait dans ma liste depuis longtemps, probablement depuis sa sortie en 2020. J&#8217;ai d\u00fb l&#8217;y ajouter parce qu&#8217;il a eu de tr\u00e8s bonnes critiques, mais \u00e7a ne me tentait vraiment pas de le lire. Selon le peu que je savais, c&#8217;\u00e9tait un histoire d&#8217;abus de pouvoir. \u00c7a n&#8217;allait certainement pas \u00eatre l\u00e9ger. Et \u00e7a ne l&#8217;\u00e9tait pas du tout. Mais c&#8217;est, je pense, le seul aspect de ce livre qui ne m&#8217;a pas \u00e9tonn\u00e9e. R\u00e9sum\u00e9 Vanessa raconte sa relation abusive avec son professeur d&#8217;anglais, qui a commenc\u00e9 alors qu&#8217;elle avait 15 ans et lui 42. Elle nous raconte ce qui s&#8217;est pass\u00e9 \u00e0 l&#8217;\u00e9poque, puis 17 ans plus tard, alors que le mouvement #MeToo bouleverse le monde et que d&#8217;autres filles que le professeur a abus\u00e9es le d\u00e9nonce dans les m\u00e9dias. Vanessa refuse toutefois de t\u00e9moigner. Elle insiste pour dire qu&#8217;il ne l&#8217;a pas abus\u00e9e, qu&#8217;il l&#8217;aimait, et qu&#8217;elle \u00e9tait consentante. Ce qui n&#8217;est pas totalement faux. Mais certainement pas vrai non plus. Impressions Je l&#8217;ai mentionn\u00e9, je m&#8217;attendais \u00e0 ce que ce livre soit lourd. Mais je ne m&#8217;attendais pas du tout \u00e0 ce qu&#8217;il se lise comme un suspense, ni qu&#8217;il soit aussi juste, touchant et nuanc\u00e9. Suspense Vanessa, la jeune \u00e9l\u00e8ve qui a une relation sexuelle avec son professeur d&#8217;anglais, est la narratrice. On a donc droit \u00e0 tout, du d\u00e9but \u00e0 la fin : tous les faits et gestes ext\u00e9rieurs qui m\u00e8nent \u00e0 cette relation et toutes les pens\u00e9es intimes de la jeune fille. On voit bien qu&#8217;elle est attir\u00e9e par le professeur, qu&#8217;elle lui tourne autour, qu&#8217;elle est incroyablement touch\u00e9e par les compliments qu&#8217;il lui fait, qu&#8217;elle se sent adulte, diff\u00e9rente des autres, et fi\u00e8re d&#8217;avoir une relation avec un homme qui semble \u00eatre en p\u00e2moison devant elle. On voit aussi tout ce que le professeur dit pour la manipuler, et de notre regard externe, on voit tr\u00e8s bien qu&#8217;il ne s&#8217;agit pas d&#8217;une histoire d&#8217;amour, mais d&#8217;une histoire d&#8217;abus. C&#8217;est incroyablement frustrant, et on ne peut pas s&#8217;emp\u00eacher de continuer \u00e0 lire pour savoir ce qui va arriver. On a envie de secouer Vanessa par les \u00e9paules quand on la voit r\u00e9p\u00e9ter \u00e0 tout le monde que ce qu&#8217;elle a v\u00e9cu avec son professeur \u00e9tait une histoire d&#8217;amour, quand elle l&#8217;appelle encore 17 ans plus tard pour revivre des souvenirs avec lui, quand, \u00e0 15 ans, elle prend le bl\u00e2me et accepte toutes les cons\u00e9quences pour le prot\u00e9ger quand les rumeurs de leur relation sont trop fortes. On aimerait tellement qu&#8217;il se fasse emprisonner. On tourne f\u00e9rocement les pages en esp\u00e9rant ce d\u00e9nouement. Juste Je ne m&#8217;attendais pas non plus \u00e0 un r\u00e9cit aussi juste et aussi touchant, parce qu&#8217;on voit l&#8217;ambivalence de Vanessa. On voit qu&#8217;elle n&#8217;est pas compl\u00e8tement \u00e0 l&#8217;aise avec lui, qu&#8217;elle se rend compte qu&#8217;elle ne conna\u00eet rien de lui, qu&#8217;elle fait l&#8217;amour alors qu&#8217;elle n&#8217;en a pas vraiment envie, qu&#8217;elle se demande parfois si elle se fait violer. On a acc\u00e8s \u00e0 sa col\u00e8re envers lui, \u00e0 son ins\u00e9curit\u00e9 et \u00e0 sa solitude. On finit par comprendre, en m\u00eame temps qu&#8217;elle, que son insistance \u00e0 dire que son histoire en \u00e9tait une belle est une tentative de se convaincre elle-m\u00eame. Elle \u00e9tait tellement jeune quand c&#8217;est arriv\u00e9 qu&#8217;elle en est rest\u00e9e marqu\u00e9e \u00e0 vie. De plus, elle n&#8217;a presque rien connu d&#8217;autre, l&#8217;emprise du professeur sur elle \u00e9tait trop forte. Alors si, presque vingt ans plus tard, elle change d&#8217;opinion sur un \u00e9v\u00e8nement aussi formateur, qui est-elle? Nuanc\u00e9 Je n&#8217;ai jamais lu un texte aussi nuanc\u00e9 sur la question. Pas nuanc\u00e9 par rapport \u00e0 la moralit\u00e9 du gars (il n&#8217;en a pas, c&#8217;est un homme d\u00e9gueu, merci bonsoir. \u00c7a va faire, l&#8217;empathie pour les pauvres hommes qui ne sont pas capables de contr\u00f4ler leur p\u00e9nis.) Mais nuanc\u00e9 par rapport \u00e0 l&#8217;exp\u00e9rience de la fille. C&#8217;est vrai qu&#8217;elle \u00e9tait partiellement consentante. C&#8217;est vrai qu&#8217;elle avait des sentiments tr\u00e8s forts pour cet homme. On peut comprendre qu&#8217;elle ne soit pas d&#8217;accord quand on lui dit tout bonnement qu&#8217;elle est une victime d&#8217;abus. Mais c&#8217;est vrai aussi que ce n&#8217;est pas elle qui a instigu\u00e9 cette relation, malgr\u00e9 ce que son professeur essaie de lui faire croire par la suite. C&#8217;est vrai qu&#8217;elle \u00e9tait trop jeune pour comprendre les implications de ce qui \u00e9tait en train de se passer. Et c&#8217;est vrai que ce qu&#8217;elle voulait, en fait, c&#8217;\u00e9tait de la reconnaissance et de l&#8217;amour. Pas du sexe. J&#8217;en ai d\u00e9j\u00e0 parl\u00e9, les histoires &#8220;d&#8217;amour&#8221; entre des adolescentes et des hommes beaucoup plus vieux me font dresser les cheveux sur la t\u00eate. Je pense \u00e0 L&#8217;Amant de Marguerite Duras et La V\u00e9rit\u00e9 sur l&#8217;affaire Harry Quebert de Jo\u00ebl Dicker. Ces deux livres ont connu un bon succ\u00e8s malgr\u00e9 le fait qu&#8217;ils font passer l&#8217;attirance sexuelle d&#8217;hommes pour des jeunes filles impressionnables pour de la romance. \u00c7a me d\u00e9passe, parce qu&#8217;\u00e0 mes yeux, n&#8217;importe qui ayant v\u00e9cu ce genre de choses sait tout de suite que c&#8217;est n&#8217;importe quoi. N\u00e9anmoins, ces auteurs, par ignorance ou par calcul, utilisent leur r\u00e9putation pour propager l&#8217;id\u00e9e fausse et d\u00e9vastatrice que &#8220;l&#8217;amour n&#8217;a pas d&#8217;\u00e2ge&#8221;. Et puis je lis un livre comme Ma sombre Vanessa, et je me rappelle qu&#8217;on va quand m\u00eame dans la bonne direction. Des femmes \u00e9loquentes qui ont v\u00e9cu ce genre de relations peuvent en parler avec toute la finesse n\u00e9cessaire pour \u00e0 la fois d\u00e9faire les mythes persistants, d\u00e9noncer les agresseurs et saisir la complexit\u00e9 des exp\u00e9riences des jeunes filles. Ce n&#8217;est pas une lecture facile. J&#8217;ai \u00e9t\u00e9 d\u00e9go\u00fbt\u00e9e la majorit\u00e9 du temps (ce n&#8217;est pas agr\u00e9able de lire des sc\u00e8nes de sexe entre une enfant et un homme adulte), et il m&#8217;a un peu d\u00e9prim\u00e9e. Mais je crois que c&#8217;est un excellent livre, et qu&#8217;il est n\u00e9cessaire.","og_url":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2025-03-31T00:21:05+00:00","article_modified_time":"2025-03-31T00:29:00+00:00","author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Ma sombre Vanessa, de Kate Elizabeth Russell","datePublished":"2025-03-31T00:21:05+00:00","dateModified":"2025-03-31T00:29:00+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/"},"wordCount":1116,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2025\/03\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1","articleSection":["Se renseigner","Soci\u00e9t\u00e9"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/","url":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/","name":"Ma sombre Vanessa, de Kate Elizabeth Russell - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2025\/03\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1","datePublished":"2025-03-31T00:21:05+00:00","dateModified":"2025-03-31T00:29:00+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2025\/03\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2025\/03\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1","width":1041,"height":1387},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/fr\/ma-sombre-vanessa-de-kate-elizabeth-russell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Ma sombre Vanessa, de Kate Elizabeth Russell"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2025\/03\/image_editor_output_image-1622660298-1743380852428.jpg?fit=1041%2C1387&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-1hZ","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=4959"}],"version-history":[{"count":1,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4959\/revisions"}],"predecessor-version":[{"id":4961,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4959\/revisions\/4961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/4960"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=4959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=4959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=4959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}