{"id":4403,"date":"2022-09-03T15:36:23","date_gmt":"2022-09-03T19:36:23","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4403"},"modified":"2022-09-03T15:36:27","modified_gmt":"2022-09-03T19:36:27","slug":"bonjour-tristesse","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/bonjour-tristesse\/","title":{"rendered":"Bonjour tristesse"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/francoise-sagan-172194-330-540.jpg?resize=238%2C307&#038;ssl=1\" alt=\"\" class=\"wp-image-4408\" width=\"238\" height=\"307\" srcset=\"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/francoise-sagan-172194-330-540.jpg?w=330&amp;ssl=1 330w, https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/francoise-sagan-172194-330-540.jpg?resize=232%2C300&amp;ssl=1 232w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/><figcaption>https:\/\/booknode.com\/auteur\/francoise-sagan\/photos<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Premier contact avec Fran\u00e7oise Sagan, cette auteure au si beau nom (de plume) et au visage si sympathique (voir la photo). J&#8217;avais entendu souvent parler de <em>Bonjour tristesse<\/em>, sans vraiment savoir ce que c&#8217;\u00e9tait. Et comme d&#8217;habitude quand je ne sais pas \u00e0 quoi m&#8217;attendre, j&#8217;ai \u00e9t\u00e9 assez surprise :  il \u00e9tait court, facile \u00e0 lire, et, d&#8217;un point de vue de 2022, pas particuli\u00e8rement original. Mais ce que j&#8217;avais oubli\u00e9, c&#8217;est que ce livre n&#8217;a pas \u00e9t\u00e9 \u00e9crit cette ann\u00e9e, mais il y a 70 ans. Un temps o\u00f9 les femmes et leur sexualit\u00e9 n&#8217;\u00e9taient pas particuli\u00e8rement valoris\u00e9es, disons \u00e7a comme \u00e7a.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p>C\u00e9cile a 17 ans. Elle vient d&#8217;\u00e9chouer son baccalaur\u00e9at, et passe un \u00e9t\u00e9 \u00e0 la plage avec son p\u00e8re et la ma\u00eetresse de celui-ci (la m\u00e8re de C\u00e9cile est morte il y a d\u00e9j\u00e0 bien longtemps). La fille et le p\u00e8re se ressemblent dans leur temp\u00e9rament : les deux mettent le plaisir en priorit\u00e9. C\u00e9cile s&#8217;entend bien avec la ma\u00eetresse de son p\u00e8re, jeune aussi, et passe un \u00e9t\u00e9 tout ce qu&#8217;il y a de plus clich\u00e9 : siestes sur la plage, baignades plusieurs fois par jour, et un amour d&#8217;\u00e9t\u00e9, un jeune homme de 26 ans qui \u00e9tudie en droit, avec qui elle perd sa virginit\u00e9.<\/p>\n\n\n\n<p>Un jour, le p\u00e8re de C\u00e9cile annonce qu&#8217;Anne, une amie de sa d\u00e9funte femme, viendra leur rendre visite. Anne jure avec les vacanciers : elle est s\u00e9rieuse, intelligente, et essaie de remettre C\u00e9cile sur le droit chemin, notamment en l&#8217;obligeant \u00e0 \u00e9tudier pour son baccalaur\u00e9at et en lui interdisant de fr\u00e9quenter le jeune homme de 26 ans. Quand Anne et son p\u00e8re annoncent qu&#8217;ils ont d\u00e9cid\u00e9 de se marier, C\u00e9cile met un plan en oeuvre pour les s\u00e9parer. Plan qui r\u00e9ussit un peu trop bien&#8230;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>Je m&#8217;attendais un peu \u00e0 \u00eatre souffl\u00e9e, ce que je n&#8217;ai pas \u00e9t\u00e9. Mais franchement, c&#8217;est pas la faute \u00e0 Fran\u00e7oise (vous voyez, j&#8217;ai d\u00e9j\u00e0 de l&#8217;attachement pour elle) : premi\u00e8rement, je m&#8217;attendais \u00e0 quelque chose de philosophique, allez savoir pourquoi (\u00e0 cause de son lien avec Sartre, peut-\u00eatre?), alors que c&#8217;est une bonne vieille fiction. Et puis, elle avait 18 ans quand elle a \u00e9crit ce livre. Ce qui fait peut-\u00eatre en sorte que je n&#8217;avais pas envie de crier au g\u00e9nie, mais ce qui explique aussi pourquoi je trouvais que la narratrice de 17 ans \u00e9tait tellement cr\u00e9dible. Je ne suis pas vieille, et je ne pense pas que je me souviens aussi bien de ce qu&#8217;avaient l&#8217;air mes 17 ans (soupir). <\/p>\n\n\n\n<p>Comme je l&#8217;ai mentionn\u00e9, ce livre est tr\u00e8s court, et je l&#8217;ai lu en deux petites soir\u00e9es. Je ne me suis pas ennuy\u00e9e. Je trouvais C\u00e9cile un peu \u00e9nervante, mais qui ne l&#8217;est pas \u00e0 17 ans? Et la fin ouverte fait bien son travail : j&#8217;y pense de temps en temps, en me demandant ce qui est vraiment arriv\u00e9.<\/p>\n\n\n\n<p>Contente d&#8217;avoir fait ta connaissance, Fran\u00e7oise.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/bonjour-tristesse-francoise-sagan-9782234075979.html\/?type=livre&#038;configuration=126&#038;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Premier contact avec Fran\u00e7oise Sagan, cette auteure au si beau nom (de plume) et au visage si sympathique (voir la photo). J&#8217;avais entendu souvent parler de Bonjour tristesse, sans vraiment savoir ce que c&#8217;\u00e9tait. Et comme d&#8217;habitude quand je ne sais pas \u00e0 quoi m&#8217;attendre, j&#8217;ai \u00e9t\u00e9 assez surprise : il \u00e9tait court, facile \u00e0 lire, et, d&#8217;un point de vue de 2022, pas particuli\u00e8rement original. Mais ce que j&#8217;avais oubli\u00e9, c&#8217;est que ce livre n&#8217;a pas \u00e9t\u00e9 \u00e9crit cette ann\u00e9e, mais il y a 70 ans. Un temps o\u00f9 les femmes et leur sexualit\u00e9 n&#8217;\u00e9taient pas particuli\u00e8rement valoris\u00e9es, disons \u00e7a comme \u00e7a. R\u00e9sum\u00e9 C\u00e9cile a 17 ans. Elle vient d&#8217;\u00e9chouer son baccalaur\u00e9at, et passe un \u00e9t\u00e9 \u00e0 la plage avec son p\u00e8re et la ma\u00eetresse de celui-ci (la m\u00e8re de C\u00e9cile est morte il y a d\u00e9j\u00e0 bien longtemps). La fille et le p\u00e8re se ressemblent dans leur temp\u00e9rament : les deux mettent le plaisir en priorit\u00e9. C\u00e9cile s&#8217;entend bien avec la ma\u00eetresse de son p\u00e8re, jeune aussi, et passe un \u00e9t\u00e9 tout ce qu&#8217;il y a de plus clich\u00e9 : siestes sur la plage, baignades plusieurs fois par jour, et un amour d&#8217;\u00e9t\u00e9, un jeune homme de 26 ans qui \u00e9tudie en droit, avec qui elle perd sa virginit\u00e9. Un jour, le p\u00e8re de C\u00e9cile annonce qu&#8217;Anne, une amie de sa d\u00e9funte femme, viendra leur rendre visite. Anne jure avec les vacanciers : elle est s\u00e9rieuse, intelligente, et essaie de remettre C\u00e9cile sur le droit chemin, notamment en l&#8217;obligeant \u00e0 \u00e9tudier pour son baccalaur\u00e9at et en lui interdisant de fr\u00e9quenter le jeune homme de 26 ans. Quand Anne et son p\u00e8re annoncent qu&#8217;ils ont d\u00e9cid\u00e9 de se marier, C\u00e9cile met un plan en oeuvre pour les s\u00e9parer. Plan qui r\u00e9ussit un peu trop bien&#8230; Impressions Je m&#8217;attendais un peu \u00e0 \u00eatre souffl\u00e9e, ce que je n&#8217;ai pas \u00e9t\u00e9. Mais franchement, c&#8217;est pas la faute \u00e0 Fran\u00e7oise (vous voyez, j&#8217;ai d\u00e9j\u00e0 de l&#8217;attachement pour elle) : premi\u00e8rement, je m&#8217;attendais \u00e0 quelque chose de philosophique, allez savoir pourquoi (\u00e0 cause de son lien avec Sartre, peut-\u00eatre?), alors que c&#8217;est une bonne vieille fiction. Et puis, elle avait 18 ans quand elle a \u00e9crit ce livre. Ce qui fait peut-\u00eatre en sorte que je n&#8217;avais pas envie de crier au g\u00e9nie, mais ce qui explique aussi pourquoi je trouvais que la narratrice de 17 ans \u00e9tait tellement cr\u00e9dible. Je ne suis pas vieille, et je ne pense pas que je me souviens aussi bien de ce qu&#8217;avaient l&#8217;air mes 17 ans (soupir). Comme je l&#8217;ai mentionn\u00e9, ce livre est tr\u00e8s court, et je l&#8217;ai lu en deux petites soir\u00e9es. Je ne me suis pas ennuy\u00e9e. Je trouvais C\u00e9cile un peu \u00e9nervante, mais qui ne l&#8217;est pas \u00e0 17 ans? Et la fin ouverte fait bien son travail : j&#8217;y pense de temps en temps, en me demandant ce qui est vraiment arriv\u00e9. Contente d&#8217;avoir fait ta connaissance, Fran\u00e7oise.<\/p>\n","protected":false},"author":1,"featured_media":4409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[243,242],"tags":[],"class_list":["post-4403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-classiques","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bonjour tristesse - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/bonjour-tristesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bonjour tristesse - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Premier contact avec Fran\u00e7oise Sagan, cette auteure au si beau nom (de plume) et au visage si sympathique (voir la photo). J&#8217;avais entendu souvent parler de Bonjour tristesse, sans vraiment savoir ce que c&#8217;\u00e9tait. Et comme d&#8217;habitude quand je ne sais pas \u00e0 quoi m&#8217;attendre, j&#8217;ai \u00e9t\u00e9 assez surprise : il \u00e9tait court, facile \u00e0 lire, et, d&#8217;un point de vue de 2022, pas particuli\u00e8rement original. Mais ce que j&#8217;avais oubli\u00e9, c&#8217;est que ce livre n&#8217;a pas \u00e9t\u00e9 \u00e9crit cette ann\u00e9e, mais il y a 70 ans. Un temps o\u00f9 les femmes et leur sexualit\u00e9 n&#8217;\u00e9taient pas particuli\u00e8rement valoris\u00e9es, disons \u00e7a comme \u00e7a. R\u00e9sum\u00e9 C\u00e9cile a 17 ans. Elle vient d&#8217;\u00e9chouer son baccalaur\u00e9at, et passe un \u00e9t\u00e9 \u00e0 la plage avec son p\u00e8re et la ma\u00eetresse de celui-ci (la m\u00e8re de C\u00e9cile est morte il y a d\u00e9j\u00e0 bien longtemps). La fille et le p\u00e8re se ressemblent dans leur temp\u00e9rament : les deux mettent le plaisir en priorit\u00e9. C\u00e9cile s&#8217;entend bien avec la ma\u00eetresse de son p\u00e8re, jeune aussi, et passe un \u00e9t\u00e9 tout ce qu&#8217;il y a de plus clich\u00e9 : siestes sur la plage, baignades plusieurs fois par jour, et un amour d&#8217;\u00e9t\u00e9, un jeune homme de 26 ans qui \u00e9tudie en droit, avec qui elle perd sa virginit\u00e9. Un jour, le p\u00e8re de C\u00e9cile annonce qu&#8217;Anne, une amie de sa d\u00e9funte femme, viendra leur rendre visite. Anne jure avec les vacanciers : elle est s\u00e9rieuse, intelligente, et essaie de remettre C\u00e9cile sur le droit chemin, notamment en l&#8217;obligeant \u00e0 \u00e9tudier pour son baccalaur\u00e9at et en lui interdisant de fr\u00e9quenter le jeune homme de 26 ans. Quand Anne et son p\u00e8re annoncent qu&#8217;ils ont d\u00e9cid\u00e9 de se marier, C\u00e9cile met un plan en oeuvre pour les s\u00e9parer. Plan qui r\u00e9ussit un peu trop bien&#8230; Impressions Je m&#8217;attendais un peu \u00e0 \u00eatre souffl\u00e9e, ce que je n&#8217;ai pas \u00e9t\u00e9. Mais franchement, c&#8217;est pas la faute \u00e0 Fran\u00e7oise (vous voyez, j&#8217;ai d\u00e9j\u00e0 de l&#8217;attachement pour elle) : premi\u00e8rement, je m&#8217;attendais \u00e0 quelque chose de philosophique, allez savoir pourquoi (\u00e0 cause de son lien avec Sartre, peut-\u00eatre?), alors que c&#8217;est une bonne vieille fiction. Et puis, elle avait 18 ans quand elle a \u00e9crit ce livre. Ce qui fait peut-\u00eatre en sorte que je n&#8217;avais pas envie de crier au g\u00e9nie, mais ce qui explique aussi pourquoi je trouvais que la narratrice de 17 ans \u00e9tait tellement cr\u00e9dible. Je ne suis pas vieille, et je ne pense pas que je me souviens aussi bien de ce qu&#8217;avaient l&#8217;air mes 17 ans (soupir). Comme je l&#8217;ai mentionn\u00e9, ce livre est tr\u00e8s court, et je l&#8217;ai lu en deux petites soir\u00e9es. Je ne me suis pas ennuy\u00e9e. Je trouvais C\u00e9cile un peu \u00e9nervante, mais qui ne l&#8217;est pas \u00e0 17 ans? Et la fin ouverte fait bien son travail : j&#8217;y pense de temps en temps, en me demandant ce qui est vraiment arriv\u00e9. Contente d&#8217;avoir fait ta connaissance, Fran\u00e7oise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/bonjour-tristesse\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-03T19:36:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-03T19:36:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/20220903_165702_HDR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Bonjour tristesse\",\"datePublished\":\"2022-09-03T19:36:23+00:00\",\"dateModified\":\"2022-09-03T19:36:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/\"},\"wordCount\":546,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Classiques\",\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/\",\"name\":\"Bonjour tristesse - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2022-09-03T19:36:23+00:00\",\"dateModified\":\"2022-09-03T19:36:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/bonjour-tristesse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bonjour tristesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bonjour tristesse - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/bonjour-tristesse\/","og_locale":"fr_CA","og_type":"article","og_title":"Bonjour tristesse - Prochaine lecture","og_description":"Premier contact avec Fran\u00e7oise Sagan, cette auteure au si beau nom (de plume) et au visage si sympathique (voir la photo). J&#8217;avais entendu souvent parler de Bonjour tristesse, sans vraiment savoir ce que c&#8217;\u00e9tait. Et comme d&#8217;habitude quand je ne sais pas \u00e0 quoi m&#8217;attendre, j&#8217;ai \u00e9t\u00e9 assez surprise : il \u00e9tait court, facile \u00e0 lire, et, d&#8217;un point de vue de 2022, pas particuli\u00e8rement original. Mais ce que j&#8217;avais oubli\u00e9, c&#8217;est que ce livre n&#8217;a pas \u00e9t\u00e9 \u00e9crit cette ann\u00e9e, mais il y a 70 ans. Un temps o\u00f9 les femmes et leur sexualit\u00e9 n&#8217;\u00e9taient pas particuli\u00e8rement valoris\u00e9es, disons \u00e7a comme \u00e7a. R\u00e9sum\u00e9 C\u00e9cile a 17 ans. Elle vient d&#8217;\u00e9chouer son baccalaur\u00e9at, et passe un \u00e9t\u00e9 \u00e0 la plage avec son p\u00e8re et la ma\u00eetresse de celui-ci (la m\u00e8re de C\u00e9cile est morte il y a d\u00e9j\u00e0 bien longtemps). La fille et le p\u00e8re se ressemblent dans leur temp\u00e9rament : les deux mettent le plaisir en priorit\u00e9. C\u00e9cile s&#8217;entend bien avec la ma\u00eetresse de son p\u00e8re, jeune aussi, et passe un \u00e9t\u00e9 tout ce qu&#8217;il y a de plus clich\u00e9 : siestes sur la plage, baignades plusieurs fois par jour, et un amour d&#8217;\u00e9t\u00e9, un jeune homme de 26 ans qui \u00e9tudie en droit, avec qui elle perd sa virginit\u00e9. Un jour, le p\u00e8re de C\u00e9cile annonce qu&#8217;Anne, une amie de sa d\u00e9funte femme, viendra leur rendre visite. Anne jure avec les vacanciers : elle est s\u00e9rieuse, intelligente, et essaie de remettre C\u00e9cile sur le droit chemin, notamment en l&#8217;obligeant \u00e0 \u00e9tudier pour son baccalaur\u00e9at et en lui interdisant de fr\u00e9quenter le jeune homme de 26 ans. Quand Anne et son p\u00e8re annoncent qu&#8217;ils ont d\u00e9cid\u00e9 de se marier, C\u00e9cile met un plan en oeuvre pour les s\u00e9parer. Plan qui r\u00e9ussit un peu trop bien&#8230; Impressions Je m&#8217;attendais un peu \u00e0 \u00eatre souffl\u00e9e, ce que je n&#8217;ai pas \u00e9t\u00e9. Mais franchement, c&#8217;est pas la faute \u00e0 Fran\u00e7oise (vous voyez, j&#8217;ai d\u00e9j\u00e0 de l&#8217;attachement pour elle) : premi\u00e8rement, je m&#8217;attendais \u00e0 quelque chose de philosophique, allez savoir pourquoi (\u00e0 cause de son lien avec Sartre, peut-\u00eatre?), alors que c&#8217;est une bonne vieille fiction. Et puis, elle avait 18 ans quand elle a \u00e9crit ce livre. Ce qui fait peut-\u00eatre en sorte que je n&#8217;avais pas envie de crier au g\u00e9nie, mais ce qui explique aussi pourquoi je trouvais que la narratrice de 17 ans \u00e9tait tellement cr\u00e9dible. Je ne suis pas vieille, et je ne pense pas que je me souviens aussi bien de ce qu&#8217;avaient l&#8217;air mes 17 ans (soupir). Comme je l&#8217;ai mentionn\u00e9, ce livre est tr\u00e8s court, et je l&#8217;ai lu en deux petites soir\u00e9es. Je ne me suis pas ennuy\u00e9e. Je trouvais C\u00e9cile un peu \u00e9nervante, mais qui ne l&#8217;est pas \u00e0 17 ans? Et la fin ouverte fait bien son travail : j&#8217;y pense de temps en temps, en me demandant ce qui est vraiment arriv\u00e9. Contente d&#8217;avoir fait ta connaissance, Fran\u00e7oise.","og_url":"https:\/\/prochainelecture.com\/fr\/bonjour-tristesse\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2022-09-03T19:36:23+00:00","article_modified_time":"2022-09-03T19:36:27+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/20220903_165702_HDR.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Bonjour tristesse","datePublished":"2022-09-03T19:36:23+00:00","dateModified":"2022-09-03T19:36:27+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/"},"wordCount":546,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1","articleSection":["Classiques","Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/bonjour-tristesse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/","url":"https:\/\/prochainelecture.com\/bonjour-tristesse\/","name":"Bonjour tristesse - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1","datePublished":"2022-09-03T19:36:23+00:00","dateModified":"2022-09-03T19:36:27+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/bonjour-tristesse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/bonjour-tristesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Bonjour tristesse"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/09\/20220903_165702_HDR.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-191","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=4403"}],"version-history":[{"count":1,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4403\/revisions"}],"predecessor-version":[{"id":4410,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4403\/revisions\/4410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/4409"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=4403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=4403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=4403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}