{"id":4318,"date":"2022-03-13T11:54:09","date_gmt":"2022-03-13T15:54:09","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4318"},"modified":"2022-03-13T11:54:13","modified_gmt":"2022-03-13T15:54:13","slug":"molly-melo","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/molly-melo\/","title":{"rendered":"Molly m\u00e9lo"},"content":{"rendered":"\n<p>J&#8217;avoue que je vous induis un peu en erreur en mettant le titre fran\u00e7ais. \u00c0 moins que vous soyez pr\u00eates \u00e0 d\u00e9penser 130$ sur Amazon, vous aurez tr\u00e8s peu de chance de mettre la main sur <a href=\"https:\/\/www.amazon.ca\/-\/fr\/Brown-Rita-Mae\/dp\/2226006540\/ref=sr_1_8?qid=1647182031&amp;refinements=p_27%3ARITA+MAE+BROWN%2Cp_n_feature_nine_browse-bin%3A5499125011&amp;rnid=5499102011&amp;s=books&amp;sr=1-8&amp;text=RITA+MAE+BROWN\">la traduction fran\u00e7aise de <em>Rubyfruit Jungle<\/em><\/a>, de Rita Mae Brown. Un peu \u00e9trange quand m\u00eame, consid\u00e9rant que c&#8217;est l&#8217;un des livres consid\u00e9r\u00e9s les plus importants pour le mouvement queer, \u00e0 l&#8217;\u00e9poque et encore aujourd&#8217;hui.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p>Molly vit pauvrement dans le sud des \u00c9tats-Unis avec ses parents adoptifs. Elle d\u00e9teste porter des robes, se tient surtout avec des gar\u00e7ons et dit \u00e0 tout le monde quoi faire. Elle a en horreur l&#8217;id\u00e9e de se marier et d&#8217;\u00eatre femme au foyer. Mais quand elle se perd dans les yeux de son amie Leota, elle est tout \u00e0 coup pr\u00eate \u00e0 faire des concessions. C&#8217;est avec elle, \u00e0 11 ans, qu&#8217;elle perd sa virginit\u00e9 pour la premi\u00e8re fois.<\/p>\n\n\n\n<p>Brillante et fonceuse, Molly assume pleinement son attirance pour les femmes. Dans les \u00c9tats-Unis des ann\u00e9es 70, la soci\u00e9t\u00e9 n&#8217;est pas de son bord, mais Molly n&#8217;en a que faire. Malgr\u00e9 tous les obstacles, elle va \u00e9tudier en cin\u00e9ma, coucher avec le plus de femmes possibles, et cr\u00e9er son propre bonheur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>Je peux comprendre pourquoi \u00e7a a fait sensation \u00e0 l&#8217;\u00e9poque. Clairement, c&#8217;\u00e9tait original. Voir une femme qui s&#8217;assume autant et qui a une sexualit\u00e9 aussi d\u00e9brid\u00e9e, \u00e7a devait en inspirer plusieurs, m\u00eame si on ne comprend pas du tout d&#8217;o\u00f9 est-ce que cette confiance peut bien venir \u00e9tant donn\u00e9 le contexte.<\/p>\n\n\n\n<p>Mais 50 ans plus tard, j&#8217;avoue que je trouve \u00e7a plut\u00f4t grossier. Pour passer le message que le lesbianisme est plus commun qu&#8217;on pense, l&#8217;auteure cr\u00e9e un personnage qui convertit toutes les femmes sur son passage, comme si toutes les femmes avaient \u00e7a quelque part en elles. Molly aime le sexe, et le fait avec tout le monde, gars ou fille, m\u00eame si les filles, c&#8217;est pour elle infiniment mieux. Elle n&#8217;a pas une once de jalousie en elle. Jamais elle ne se remet en question. Il y a quelque chose d&#8217;int\u00e9ressant l\u00e0-dedans. Mais quand elle se met \u00e0 dire que l&#8217;inceste, c&#8217;est pas grave, qu&#8217;elle couche avec la m\u00e8re et sa fille, ou quand elle viole une femme (qui le voulait dans le fond, bien s\u00fbr), on trouve \u00e7a moins dr\u00f4le.<\/p>\n\n\n\n<p>Je sais que ce livre a suscit\u00e9 beaucoup d&#8217;\u00e9motions chez les gens. Il en a inspir\u00e9 beaucoup et en a choqu\u00e9 beaucoup d&#8217;autres. Mais moi, je suis rest\u00e9e ti\u00e8de. Le livre a des qualit\u00e9s, des d\u00e9fauts aussi. Pas mauvais, pas super. Un beau trois \u00e9toiles.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/rubyfruit-jungle-rita-mae-brown-9781101965122.html\/?type=livre&#038;configuration=126&#038;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>J&#8217;avoue que je vous induis un peu en erreur en mettant le titre fran\u00e7ais. \u00c0 moins que vous soyez pr\u00eates \u00e0 d\u00e9penser 130$ sur Amazon, vous aurez tr\u00e8s peu de chance de mettre la main sur la traduction fran\u00e7aise de Rubyfruit Jungle, de Rita Mae Brown. Un peu \u00e9trange quand m\u00eame, consid\u00e9rant que c&#8217;est l&#8217;un des livres consid\u00e9r\u00e9s les plus importants pour le mouvement queer, \u00e0 l&#8217;\u00e9poque et encore aujourd&#8217;hui. R\u00e9sum\u00e9 Molly vit pauvrement dans le sud des \u00c9tats-Unis avec ses parents adoptifs. Elle d\u00e9teste porter des robes, se tient surtout avec des gar\u00e7ons et dit \u00e0 tout le monde quoi faire. Elle a en horreur l&#8217;id\u00e9e de se marier et d&#8217;\u00eatre femme au foyer. Mais quand elle se perd dans les yeux de son amie Leota, elle est tout \u00e0 coup pr\u00eate \u00e0 faire des concessions. C&#8217;est avec elle, \u00e0 11 ans, qu&#8217;elle perd sa virginit\u00e9 pour la premi\u00e8re fois. Brillante et fonceuse, Molly assume pleinement son attirance pour les femmes. Dans les \u00c9tats-Unis des ann\u00e9es 70, la soci\u00e9t\u00e9 n&#8217;est pas de son bord, mais Molly n&#8217;en a que faire. Malgr\u00e9 tous les obstacles, elle va \u00e9tudier en cin\u00e9ma, coucher avec le plus de femmes possibles, et cr\u00e9er son propre bonheur. Impressions Je peux comprendre pourquoi \u00e7a a fait sensation \u00e0 l&#8217;\u00e9poque. Clairement, c&#8217;\u00e9tait original. Voir une femme qui s&#8217;assume autant et qui a une sexualit\u00e9 aussi d\u00e9brid\u00e9e, \u00e7a devait en inspirer plusieurs, m\u00eame si on ne comprend pas du tout d&#8217;o\u00f9 est-ce que cette confiance peut bien venir \u00e9tant donn\u00e9 le contexte. Mais 50 ans plus tard, j&#8217;avoue que je trouve \u00e7a plut\u00f4t grossier. Pour passer le message que le lesbianisme est plus commun qu&#8217;on pense, l&#8217;auteure cr\u00e9e un personnage qui convertit toutes les femmes sur son passage, comme si toutes les femmes avaient \u00e7a quelque part en elles. Molly aime le sexe, et le fait avec tout le monde, gars ou fille, m\u00eame si les filles, c&#8217;est pour elle infiniment mieux. Elle n&#8217;a pas une once de jalousie en elle. Jamais elle ne se remet en question. Il y a quelque chose d&#8217;int\u00e9ressant l\u00e0-dedans. Mais quand elle se met \u00e0 dire que l&#8217;inceste, c&#8217;est pas grave, qu&#8217;elle couche avec la m\u00e8re et sa fille, ou quand elle viole une femme (qui le voulait dans le fond, bien s\u00fbr), on trouve \u00e7a moins dr\u00f4le. Je sais que ce livre a suscit\u00e9 beaucoup d&#8217;\u00e9motions chez les gens. Il en a inspir\u00e9 beaucoup et en a choqu\u00e9 beaucoup d&#8217;autres. Mais moi, je suis rest\u00e9e ti\u00e8de. Le livre a des qualit\u00e9s, des d\u00e9fauts aussi. Pas mauvais, pas super. Un beau trois \u00e9toiles.<\/p>\n","protected":false},"author":1,"featured_media":4319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"\ud83c\udf51 Molly m\u00e9lo, de Rita Mae Brown\n---\nJ'ai lu un des livres consid\u00e9r\u00e9s les plus importants pour le mouvement queer des ann\u00e9es 70. Lisez ce que j'en ai pens\u00e9 dans ma critique d'aujourd'hui.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[242],"tags":[],"class_list":["post-4318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Molly m\u00e9lo - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/molly-melo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Molly m\u00e9lo - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"J&#8217;avoue que je vous induis un peu en erreur en mettant le titre fran\u00e7ais. \u00c0 moins que vous soyez pr\u00eates \u00e0 d\u00e9penser 130$ sur Amazon, vous aurez tr\u00e8s peu de chance de mettre la main sur la traduction fran\u00e7aise de Rubyfruit Jungle, de Rita Mae Brown. Un peu \u00e9trange quand m\u00eame, consid\u00e9rant que c&#8217;est l&#8217;un des livres consid\u00e9r\u00e9s les plus importants pour le mouvement queer, \u00e0 l&#8217;\u00e9poque et encore aujourd&#8217;hui. R\u00e9sum\u00e9 Molly vit pauvrement dans le sud des \u00c9tats-Unis avec ses parents adoptifs. Elle d\u00e9teste porter des robes, se tient surtout avec des gar\u00e7ons et dit \u00e0 tout le monde quoi faire. Elle a en horreur l&#8217;id\u00e9e de se marier et d&#8217;\u00eatre femme au foyer. Mais quand elle se perd dans les yeux de son amie Leota, elle est tout \u00e0 coup pr\u00eate \u00e0 faire des concessions. C&#8217;est avec elle, \u00e0 11 ans, qu&#8217;elle perd sa virginit\u00e9 pour la premi\u00e8re fois. Brillante et fonceuse, Molly assume pleinement son attirance pour les femmes. Dans les \u00c9tats-Unis des ann\u00e9es 70, la soci\u00e9t\u00e9 n&#8217;est pas de son bord, mais Molly n&#8217;en a que faire. Malgr\u00e9 tous les obstacles, elle va \u00e9tudier en cin\u00e9ma, coucher avec le plus de femmes possibles, et cr\u00e9er son propre bonheur. Impressions Je peux comprendre pourquoi \u00e7a a fait sensation \u00e0 l&#8217;\u00e9poque. Clairement, c&#8217;\u00e9tait original. Voir une femme qui s&#8217;assume autant et qui a une sexualit\u00e9 aussi d\u00e9brid\u00e9e, \u00e7a devait en inspirer plusieurs, m\u00eame si on ne comprend pas du tout d&#8217;o\u00f9 est-ce que cette confiance peut bien venir \u00e9tant donn\u00e9 le contexte. Mais 50 ans plus tard, j&#8217;avoue que je trouve \u00e7a plut\u00f4t grossier. Pour passer le message que le lesbianisme est plus commun qu&#8217;on pense, l&#8217;auteure cr\u00e9e un personnage qui convertit toutes les femmes sur son passage, comme si toutes les femmes avaient \u00e7a quelque part en elles. Molly aime le sexe, et le fait avec tout le monde, gars ou fille, m\u00eame si les filles, c&#8217;est pour elle infiniment mieux. Elle n&#8217;a pas une once de jalousie en elle. Jamais elle ne se remet en question. Il y a quelque chose d&#8217;int\u00e9ressant l\u00e0-dedans. Mais quand elle se met \u00e0 dire que l&#8217;inceste, c&#8217;est pas grave, qu&#8217;elle couche avec la m\u00e8re et sa fille, ou quand elle viole une femme (qui le voulait dans le fond, bien s\u00fbr), on trouve \u00e7a moins dr\u00f4le. Je sais que ce livre a suscit\u00e9 beaucoup d&#8217;\u00e9motions chez les gens. Il en a inspir\u00e9 beaucoup et en a choqu\u00e9 beaucoup d&#8217;autres. Mais moi, je suis rest\u00e9e ti\u00e8de. Le livre a des qualit\u00e9s, des d\u00e9fauts aussi. Pas mauvais, pas super. Un beau trois \u00e9toiles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/molly-melo\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-13T15:54:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-13T15:54:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/03\/20220313_101215.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Molly m\u00e9lo\",\"datePublished\":\"2022-03-13T15:54:09+00:00\",\"dateModified\":\"2022-03-13T15:54:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/\"},\"wordCount\":481,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220313_101215.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/\",\"name\":\"Molly m\u00e9lo - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220313_101215.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2022-03-13T15:54:09+00:00\",\"dateModified\":\"2022-03-13T15:54:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220313_101215.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/20220313_101215.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/molly-melo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Molly m\u00e9lo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Molly m\u00e9lo - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/molly-melo\/","og_locale":"fr_CA","og_type":"article","og_title":"Molly m\u00e9lo - Prochaine lecture","og_description":"J&#8217;avoue que je vous induis un peu en erreur en mettant le titre fran\u00e7ais. \u00c0 moins que vous soyez pr\u00eates \u00e0 d\u00e9penser 130$ sur Amazon, vous aurez tr\u00e8s peu de chance de mettre la main sur la traduction fran\u00e7aise de Rubyfruit Jungle, de Rita Mae Brown. Un peu \u00e9trange quand m\u00eame, consid\u00e9rant que c&#8217;est l&#8217;un des livres consid\u00e9r\u00e9s les plus importants pour le mouvement queer, \u00e0 l&#8217;\u00e9poque et encore aujourd&#8217;hui. R\u00e9sum\u00e9 Molly vit pauvrement dans le sud des \u00c9tats-Unis avec ses parents adoptifs. Elle d\u00e9teste porter des robes, se tient surtout avec des gar\u00e7ons et dit \u00e0 tout le monde quoi faire. Elle a en horreur l&#8217;id\u00e9e de se marier et d&#8217;\u00eatre femme au foyer. Mais quand elle se perd dans les yeux de son amie Leota, elle est tout \u00e0 coup pr\u00eate \u00e0 faire des concessions. C&#8217;est avec elle, \u00e0 11 ans, qu&#8217;elle perd sa virginit\u00e9 pour la premi\u00e8re fois. Brillante et fonceuse, Molly assume pleinement son attirance pour les femmes. Dans les \u00c9tats-Unis des ann\u00e9es 70, la soci\u00e9t\u00e9 n&#8217;est pas de son bord, mais Molly n&#8217;en a que faire. Malgr\u00e9 tous les obstacles, elle va \u00e9tudier en cin\u00e9ma, coucher avec le plus de femmes possibles, et cr\u00e9er son propre bonheur. Impressions Je peux comprendre pourquoi \u00e7a a fait sensation \u00e0 l&#8217;\u00e9poque. Clairement, c&#8217;\u00e9tait original. Voir une femme qui s&#8217;assume autant et qui a une sexualit\u00e9 aussi d\u00e9brid\u00e9e, \u00e7a devait en inspirer plusieurs, m\u00eame si on ne comprend pas du tout d&#8217;o\u00f9 est-ce que cette confiance peut bien venir \u00e9tant donn\u00e9 le contexte. Mais 50 ans plus tard, j&#8217;avoue que je trouve \u00e7a plut\u00f4t grossier. Pour passer le message que le lesbianisme est plus commun qu&#8217;on pense, l&#8217;auteure cr\u00e9e un personnage qui convertit toutes les femmes sur son passage, comme si toutes les femmes avaient \u00e7a quelque part en elles. Molly aime le sexe, et le fait avec tout le monde, gars ou fille, m\u00eame si les filles, c&#8217;est pour elle infiniment mieux. Elle n&#8217;a pas une once de jalousie en elle. Jamais elle ne se remet en question. Il y a quelque chose d&#8217;int\u00e9ressant l\u00e0-dedans. Mais quand elle se met \u00e0 dire que l&#8217;inceste, c&#8217;est pas grave, qu&#8217;elle couche avec la m\u00e8re et sa fille, ou quand elle viole une femme (qui le voulait dans le fond, bien s\u00fbr), on trouve \u00e7a moins dr\u00f4le. Je sais que ce livre a suscit\u00e9 beaucoup d&#8217;\u00e9motions chez les gens. Il en a inspir\u00e9 beaucoup et en a choqu\u00e9 beaucoup d&#8217;autres. Mais moi, je suis rest\u00e9e ti\u00e8de. Le livre a des qualit\u00e9s, des d\u00e9fauts aussi. Pas mauvais, pas super. Un beau trois \u00e9toiles.","og_url":"https:\/\/prochainelecture.com\/fr\/molly-melo\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2022-03-13T15:54:09+00:00","article_modified_time":"2022-03-13T15:54:13+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/03\/20220313_101215.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/molly-melo\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/molly-melo\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Molly m\u00e9lo","datePublished":"2022-03-13T15:54:09+00:00","dateModified":"2022-03-13T15:54:13+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/molly-melo\/"},"wordCount":481,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/molly-melo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/03\/20220313_101215.jpg?fit=1200%2C800&ssl=1","articleSection":["Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/molly-melo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/molly-melo\/","url":"https:\/\/prochainelecture.com\/molly-melo\/","name":"Molly m\u00e9lo - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/molly-melo\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/molly-melo\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/03\/20220313_101215.jpg?fit=1200%2C800&ssl=1","datePublished":"2022-03-13T15:54:09+00:00","dateModified":"2022-03-13T15:54:13+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/molly-melo\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/molly-melo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/molly-melo\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/03\/20220313_101215.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/03\/20220313_101215.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/molly-melo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Molly m\u00e9lo"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/03\/20220313_101215.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-17E","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=4318"}],"version-history":[{"count":1,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4318\/revisions"}],"predecessor-version":[{"id":4320,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4318\/revisions\/4320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/4319"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=4318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=4318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=4318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}