{"id":4310,"date":"2022-02-28T23:17:30","date_gmt":"2022-03-01T03:17:30","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4310"},"modified":"2022-02-28T23:17:47","modified_gmt":"2022-03-01T03:17:47","slug":"a-childrens-bible","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/a-childrens-bible\/","title":{"rendered":"A Children&#8217;s Bible"},"content":{"rendered":"\n<p>C&#8217;\u00e9tait risqu\u00e9 de la part de l&#8217;auteure de donner ce titre \u00e0 son livre. Tapez &#8220;Children&#8217;s Bible&#8221; sur Google pour voir. Pauvres cookies, ils doivent \u00eatre tout m\u00e9lang\u00e9s en ce moment. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p>Une douzaine d&#8217;enfants dont les parents sont des vieux amis se retrouvent dans un grand chalet pour passer l&#8217;\u00e9t\u00e9. Les enfants m\u00e9prisent leurs parents, des gens de la classe moyenne ais\u00e9e qui se so\u00fblent aux cocktails pour passer le temps, les \u00e9vitent et trouvent toutes sortes de mani\u00e8res de les \u00e9nerver. Avec plus ou moins de succ\u00e8s, on dirait. Les parents sont dans une sorte de torpeur constante et se fichent pas mal de ce que les enfants font. Ceux-ci vont alors passer quelques jours dans une \u00eele, loin de toute autorit\u00e9. Quelques jours avant l&#8217;apocalypse.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>J&#8217;avais pris en note ce livre il y a au moins un an. L&#8217;auteure de la critique que j&#8217;avais lue, je ne me souviens plus o\u00f9, disait que la fin \u00e9tait tellement g\u00e9niale qu&#8217;elle aurait aim\u00e9 que ce soit elle qui l&#8217;ait \u00e9crite. Alors j&#8217;ai pas mal lu ce livre pour la fin. J&#8217;avais h\u00e2te que \u00e7a finisse, mais pour les bonnes raisons.<\/p>\n\n\n\n<p>Il s&#8217;av\u00e8re que la fin \u00e9tait plut\u00f4t bof selon moi (le genre qui demanderait une bonne heure de r\u00e9flexion et d&#8217;analyse, que je n&#8217;ai pas envie de faire), mais que ce qui y menait \u00e9tait hautement divertissant. Je ne voyais plus le temps passer quand je me plongeais dans ce livre. Tout est bizarre : les parents sont des grosses larves, les enfants sont un peu cruels et \u00e9trangement matures pour leur \u00e2ge, et une fois que l&#8217;apocalypse arrive, les \u00e9v\u00e9nements sont tellement impr\u00e9visibles que j&#8217;\u00e9tais dans un \u00e9tat de surprise permanent. Je ne suis pas la meilleure pour pr\u00e9dire la suite d&#8217;une histoire. Mais quand m\u00eame.<\/p>\n\n\n\n<p>Il y a clairement un tas de r\u00e9f\u00e9rences avec la Bible, dont certaines sont suffisamment \u00e9videntes pour que je m&#8217;en rende compte (la narratrice s&#8217;appelle Eve, son petit fr\u00e8re sauve toutes sortes d&#8217;animaux d&#8217;une grande inondation, il lit la Bible, il y a trois &#8220;anges&#8221;, etc.), et s\u00fbrement plein d&#8217;autres qu&#8217;on pourrait s&#8217;amuser \u00e0 d\u00e9crypter. Mais honn\u00eatement, j&#8217;aurais pu m&#8217;en passer, ce n&#8217;\u00e9tait pas \u00e7a l&#8217;important.<\/p>\n\n\n\n<p>Je me suis beaucoup amus\u00e9e. C&#8217;\u00e9tait facile \u00e0 lire, c&#8217;\u00e9tait tr\u00e8s \u00e9trange et un peu effrayant, mais aussi assez dr\u00f4le. Je crois que j&#8217;ai ri? Je ne suis pas s\u00fbre. Je ne sais pas de quoi j&#8217;aurais ri. Mais quand je pense \u00e0 ce livre, je souris.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/a-children-s-bible-9781324005032.html\/?type=livre&#038;configuration=126&#038;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>C&#8217;\u00e9tait risqu\u00e9 de la part de l&#8217;auteure de donner ce titre \u00e0 son livre. Tapez &#8220;Children&#8217;s Bible&#8221; sur Google pour voir. Pauvres cookies, ils doivent \u00eatre tout m\u00e9lang\u00e9s en ce moment. R\u00e9sum\u00e9 Une douzaine d&#8217;enfants dont les parents sont des vieux amis se retrouvent dans un grand chalet pour passer l&#8217;\u00e9t\u00e9. Les enfants m\u00e9prisent leurs parents, des gens de la classe moyenne ais\u00e9e qui se so\u00fblent aux cocktails pour passer le temps, les \u00e9vitent et trouvent toutes sortes de mani\u00e8res de les \u00e9nerver. Avec plus ou moins de succ\u00e8s, on dirait. Les parents sont dans une sorte de torpeur constante et se fichent pas mal de ce que les enfants font. Ceux-ci vont alors passer quelques jours dans une \u00eele, loin de toute autorit\u00e9. Quelques jours avant l&#8217;apocalypse. Impressions J&#8217;avais pris en note ce livre il y a au moins un an. L&#8217;auteure de la critique que j&#8217;avais lue, je ne me souviens plus o\u00f9, disait que la fin \u00e9tait tellement g\u00e9niale qu&#8217;elle aurait aim\u00e9 que ce soit elle qui l&#8217;ait \u00e9crite. Alors j&#8217;ai pas mal lu ce livre pour la fin. J&#8217;avais h\u00e2te que \u00e7a finisse, mais pour les bonnes raisons. Il s&#8217;av\u00e8re que la fin \u00e9tait plut\u00f4t bof selon moi (le genre qui demanderait une bonne heure de r\u00e9flexion et d&#8217;analyse, que je n&#8217;ai pas envie de faire), mais que ce qui y menait \u00e9tait hautement divertissant. Je ne voyais plus le temps passer quand je me plongeais dans ce livre. Tout est bizarre : les parents sont des grosses larves, les enfants sont un peu cruels et \u00e9trangement matures pour leur \u00e2ge, et une fois que l&#8217;apocalypse arrive, les \u00e9v\u00e9nements sont tellement impr\u00e9visibles que j&#8217;\u00e9tais dans un \u00e9tat de surprise permanent. Je ne suis pas la meilleure pour pr\u00e9dire la suite d&#8217;une histoire. Mais quand m\u00eame. Il y a clairement un tas de r\u00e9f\u00e9rences avec la Bible, dont certaines sont suffisamment \u00e9videntes pour que je m&#8217;en rende compte (la narratrice s&#8217;appelle Eve, son petit fr\u00e8re sauve toutes sortes d&#8217;animaux d&#8217;une grande inondation, il lit la Bible, il y a trois &#8220;anges&#8221;, etc.), et s\u00fbrement plein d&#8217;autres qu&#8217;on pourrait s&#8217;amuser \u00e0 d\u00e9crypter. Mais honn\u00eatement, j&#8217;aurais pu m&#8217;en passer, ce n&#8217;\u00e9tait pas \u00e7a l&#8217;important. Je me suis beaucoup amus\u00e9e. C&#8217;\u00e9tait facile \u00e0 lire, c&#8217;\u00e9tait tr\u00e8s \u00e9trange et un peu effrayant, mais aussi assez dr\u00f4le. Je crois que j&#8217;ai ri? Je ne suis pas s\u00fbre. Je ne sais pas de quoi j&#8217;aurais ri. Mais quand je pense \u00e0 ce livre, je souris.<\/p>\n","protected":false},"author":1,"featured_media":4311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"C'\u00e9tait risqu\u00e9 de la part de l'auteure de donner ce titre \u00e0 son livre. Tapez \"Children's Bible\" sur Google pour voir. Pauvres cookies, ils doivent \u00eatre tout m\u00e9lang\u00e9s en ce moment. ","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[242],"tags":[],"class_list":["post-4310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Children&#039;s Bible - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/a-childrens-bible\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Children&#039;s Bible - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"C&#8217;\u00e9tait risqu\u00e9 de la part de l&#8217;auteure de donner ce titre \u00e0 son livre. Tapez &#8220;Children&#8217;s Bible&#8221; sur Google pour voir. Pauvres cookies, ils doivent \u00eatre tout m\u00e9lang\u00e9s en ce moment. R\u00e9sum\u00e9 Une douzaine d&#8217;enfants dont les parents sont des vieux amis se retrouvent dans un grand chalet pour passer l&#8217;\u00e9t\u00e9. Les enfants m\u00e9prisent leurs parents, des gens de la classe moyenne ais\u00e9e qui se so\u00fblent aux cocktails pour passer le temps, les \u00e9vitent et trouvent toutes sortes de mani\u00e8res de les \u00e9nerver. Avec plus ou moins de succ\u00e8s, on dirait. Les parents sont dans une sorte de torpeur constante et se fichent pas mal de ce que les enfants font. Ceux-ci vont alors passer quelques jours dans une \u00eele, loin de toute autorit\u00e9. Quelques jours avant l&#8217;apocalypse. Impressions J&#8217;avais pris en note ce livre il y a au moins un an. L&#8217;auteure de la critique que j&#8217;avais lue, je ne me souviens plus o\u00f9, disait que la fin \u00e9tait tellement g\u00e9niale qu&#8217;elle aurait aim\u00e9 que ce soit elle qui l&#8217;ait \u00e9crite. Alors j&#8217;ai pas mal lu ce livre pour la fin. J&#8217;avais h\u00e2te que \u00e7a finisse, mais pour les bonnes raisons. Il s&#8217;av\u00e8re que la fin \u00e9tait plut\u00f4t bof selon moi (le genre qui demanderait une bonne heure de r\u00e9flexion et d&#8217;analyse, que je n&#8217;ai pas envie de faire), mais que ce qui y menait \u00e9tait hautement divertissant. Je ne voyais plus le temps passer quand je me plongeais dans ce livre. Tout est bizarre : les parents sont des grosses larves, les enfants sont un peu cruels et \u00e9trangement matures pour leur \u00e2ge, et une fois que l&#8217;apocalypse arrive, les \u00e9v\u00e9nements sont tellement impr\u00e9visibles que j&#8217;\u00e9tais dans un \u00e9tat de surprise permanent. Je ne suis pas la meilleure pour pr\u00e9dire la suite d&#8217;une histoire. Mais quand m\u00eame. Il y a clairement un tas de r\u00e9f\u00e9rences avec la Bible, dont certaines sont suffisamment \u00e9videntes pour que je m&#8217;en rende compte (la narratrice s&#8217;appelle Eve, son petit fr\u00e8re sauve toutes sortes d&#8217;animaux d&#8217;une grande inondation, il lit la Bible, il y a trois &#8220;anges&#8221;, etc.), et s\u00fbrement plein d&#8217;autres qu&#8217;on pourrait s&#8217;amuser \u00e0 d\u00e9crypter. Mais honn\u00eatement, j&#8217;aurais pu m&#8217;en passer, ce n&#8217;\u00e9tait pas \u00e7a l&#8217;important. Je me suis beaucoup amus\u00e9e. C&#8217;\u00e9tait facile \u00e0 lire, c&#8217;\u00e9tait tr\u00e8s \u00e9trange et un peu effrayant, mais aussi assez dr\u00f4le. Je crois que j&#8217;ai ri? Je ne suis pas s\u00fbre. Je ne sais pas de quoi j&#8217;aurais ri. Mais quand je pense \u00e0 ce livre, je souris.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/a-childrens-bible\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-01T03:17:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-01T03:17:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/02\/20220228_212711.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"A Children&#8217;s Bible\",\"datePublished\":\"2022-03-01T03:17:30+00:00\",\"dateModified\":\"2022-03-01T03:17:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/\"},\"wordCount\":472,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/20220228_212711.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/\",\"name\":\"A Children's Bible - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/20220228_212711.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2022-03-01T03:17:30+00:00\",\"dateModified\":\"2022-03-01T03:17:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/20220228_212711.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/20220228_212711.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/a-childrens-bible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Children&rsquo;s Bible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Children's Bible - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/a-childrens-bible\/","og_locale":"fr_CA","og_type":"article","og_title":"A Children's Bible - Prochaine lecture","og_description":"C&#8217;\u00e9tait risqu\u00e9 de la part de l&#8217;auteure de donner ce titre \u00e0 son livre. Tapez &#8220;Children&#8217;s Bible&#8221; sur Google pour voir. Pauvres cookies, ils doivent \u00eatre tout m\u00e9lang\u00e9s en ce moment. R\u00e9sum\u00e9 Une douzaine d&#8217;enfants dont les parents sont des vieux amis se retrouvent dans un grand chalet pour passer l&#8217;\u00e9t\u00e9. Les enfants m\u00e9prisent leurs parents, des gens de la classe moyenne ais\u00e9e qui se so\u00fblent aux cocktails pour passer le temps, les \u00e9vitent et trouvent toutes sortes de mani\u00e8res de les \u00e9nerver. Avec plus ou moins de succ\u00e8s, on dirait. Les parents sont dans une sorte de torpeur constante et se fichent pas mal de ce que les enfants font. Ceux-ci vont alors passer quelques jours dans une \u00eele, loin de toute autorit\u00e9. Quelques jours avant l&#8217;apocalypse. Impressions J&#8217;avais pris en note ce livre il y a au moins un an. L&#8217;auteure de la critique que j&#8217;avais lue, je ne me souviens plus o\u00f9, disait que la fin \u00e9tait tellement g\u00e9niale qu&#8217;elle aurait aim\u00e9 que ce soit elle qui l&#8217;ait \u00e9crite. Alors j&#8217;ai pas mal lu ce livre pour la fin. J&#8217;avais h\u00e2te que \u00e7a finisse, mais pour les bonnes raisons. Il s&#8217;av\u00e8re que la fin \u00e9tait plut\u00f4t bof selon moi (le genre qui demanderait une bonne heure de r\u00e9flexion et d&#8217;analyse, que je n&#8217;ai pas envie de faire), mais que ce qui y menait \u00e9tait hautement divertissant. Je ne voyais plus le temps passer quand je me plongeais dans ce livre. Tout est bizarre : les parents sont des grosses larves, les enfants sont un peu cruels et \u00e9trangement matures pour leur \u00e2ge, et une fois que l&#8217;apocalypse arrive, les \u00e9v\u00e9nements sont tellement impr\u00e9visibles que j&#8217;\u00e9tais dans un \u00e9tat de surprise permanent. Je ne suis pas la meilleure pour pr\u00e9dire la suite d&#8217;une histoire. Mais quand m\u00eame. Il y a clairement un tas de r\u00e9f\u00e9rences avec la Bible, dont certaines sont suffisamment \u00e9videntes pour que je m&#8217;en rende compte (la narratrice s&#8217;appelle Eve, son petit fr\u00e8re sauve toutes sortes d&#8217;animaux d&#8217;une grande inondation, il lit la Bible, il y a trois &#8220;anges&#8221;, etc.), et s\u00fbrement plein d&#8217;autres qu&#8217;on pourrait s&#8217;amuser \u00e0 d\u00e9crypter. Mais honn\u00eatement, j&#8217;aurais pu m&#8217;en passer, ce n&#8217;\u00e9tait pas \u00e7a l&#8217;important. Je me suis beaucoup amus\u00e9e. C&#8217;\u00e9tait facile \u00e0 lire, c&#8217;\u00e9tait tr\u00e8s \u00e9trange et un peu effrayant, mais aussi assez dr\u00f4le. Je crois que j&#8217;ai ri? Je ne suis pas s\u00fbre. Je ne sais pas de quoi j&#8217;aurais ri. Mais quand je pense \u00e0 ce livre, je souris.","og_url":"https:\/\/prochainelecture.com\/fr\/a-childrens-bible\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2022-03-01T03:17:30+00:00","article_modified_time":"2022-03-01T03:17:47+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/02\/20220228_212711.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"A Children&#8217;s Bible","datePublished":"2022-03-01T03:17:30+00:00","dateModified":"2022-03-01T03:17:47+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/"},"wordCount":472,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/02\/20220228_212711.jpg?fit=1200%2C800&ssl=1","articleSection":["Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/a-childrens-bible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/","url":"https:\/\/prochainelecture.com\/a-childrens-bible\/","name":"A Children's Bible - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/02\/20220228_212711.jpg?fit=1200%2C800&ssl=1","datePublished":"2022-03-01T03:17:30+00:00","dateModified":"2022-03-01T03:17:47+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/a-childrens-bible\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/02\/20220228_212711.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/02\/20220228_212711.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/a-childrens-bible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"A Children&rsquo;s Bible"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/02\/20220228_212711.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-17w","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=4310"}],"version-history":[{"count":1,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4310\/revisions"}],"predecessor-version":[{"id":4312,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4310\/revisions\/4312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/4311"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=4310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=4310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=4310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}