{"id":4285,"date":"2022-01-23T21:21:33","date_gmt":"2022-01-24T01:21:33","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4285"},"modified":"2022-11-20T16:02:29","modified_gmt":"2022-11-20T20:02:29","slug":"the-road","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/the-road\/","title":{"rendered":"La Route, de Cormac McCarthy"},"content":{"rendered":"\n<p>Je vais vous dire quelque chose : je suis un peu tann\u00e9e d&#8217;\u00eatre confront\u00e9e \u00e0 des livres qui me donnent l&#8217;impression de rien comprendre. Pas que le livre est difficile \u00e0 comprendre : au contraire, l&#8217;histoire est on ne peut plus simple, et il n&#8217;y a rien de complexe dans la prose de Cormac McCarthy (\u00e0 part certains passages lyriques qui ne veulent absolument rien dire). Ce que je ne comprends pas, c&#8217;est comment \u00e7a se fait qu&#8217;un tel livre ait pu obtenir le prix Pulitzer, et comment \u00e7a se fait qu&#8217;autant de lecteurs lui aient donn\u00e9 une note parfaite. <\/p>\n\n\n\n<p>Allez voir les opinions de ce livre sur <a href=\"https:\/\/www.goodreads.com\/book\/show\/6288.The_Road\">GoodReads<\/a>. Une grande majorit\u00e9 des lecteurs (74%) lui ont donn\u00e9 une note parfaite ou presque parfaite, tandis que seulement 3% lui ont donn\u00e9 la pire note. Mais la critique qui a \u00e9t\u00e9 le plus aim\u00e9e en est une qui lui donnait une \u00e9toile, et la deuxi\u00e8me plus aim\u00e9e lui donnait 5 \u00e9toiles. Les deux sont absolument cat\u00e9goriques dans leur opinion. Je suis en accord \u00e0 peu pr\u00e8s complet avec la critique \u00e0 une \u00e9toile (tr\u00e8s compl\u00e8te d&#8217;ailleurs), tandis que je ne comprends aucun des arguments de ceux qui lui donnent une note parfaite. Une telle divergence d&#8217;opinion est quand m\u00eame surprenante. Je suis dans le clan \u00e0 une \u00e9toile. Et vous?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p>Un incident inconnu a compl\u00e8tement ravag\u00e9 la plan\u00e8te. Le ciel est constamment obscurci par une poussi\u00e8re ou une fum\u00e9e grise; tout a \u00e9t\u00e9 br\u00fbl\u00e9; plus rien ne pousse dans la terre; les plantes et les animaux sont morts; il fait constamment froid. Un homme et son fils (dont on ne saura jamais les noms) marchent vers le sud en esp\u00e9rant que ce soit mieux l\u00e0-bas et tentent de survivre. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>Prenons un extrait au hasard.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>While the boy slept he began to go methodically through the stores. Clothes, sweaters, socks. A stainless steel basin and sponges and bars of soap. Toothpaste and toothbrushes. In the bottom of a big plastic jar of bolts and screws and miscellaneous hardware he found a double handful of gold krugerrands in a cloth sack. He dumped them out and kneaded them in his hand and looked at them and then scooped them back into the jar along with the hardware and put the jar back on the shelf.<\/p>\n<cite><em>&#8211; The Road<\/em>, p. 142<\/cite><\/blockquote>\n\n\n\n<p>Ceci \u00e9tait un paragraphe. On a une ligne blanche, puis un autre paragraphe. Vous avez maintenant une tr\u00e8s bonne id\u00e9e de ce \u00e0 quoi ce livre ressemble. Beaucoup de &#8220;and&#8221; qui sont suppos\u00e9s donner un style, beaucoup d&#8217;\u00e9num\u00e9rations. Beaucoup de sc\u00e8nes qui ne servent pas \u00e0 grand-chose.<\/p>\n\n\n\n<p>Je suis un peu dure en ce moment. Mais honn\u00eatement, j&#8217;ai essay\u00e9, pendant tout le livre, de comprendre ce qui avait excit\u00e9 tant les critiques et, apparemment, le lectorat. Et ce que j&#8217;ai vu, c&#8217;est un style qui devient fatigant tr\u00e8s rapidement, des sc\u00e8nes monotones, une histoire qui n&#8217;allait nulle part, une relation p\u00e8re-fils qui n&#8217;\u00e9volue pas, et des dialogues path\u00e9tiques. J&#8217;avais l&#8217;impression de me faire flasher un style d&#8217;Auteur avec un grand A devant mes yeux et qu&#8217;il fallait que je creuse tr\u00e8s loin pour trouver une profondeur l\u00e0-dedans. <\/p>\n\n\n\n<p>Les gens ont encens\u00e9 la relation p\u00e8re-fils. Ils ont trouv\u00e9 que c&#8217;est une histoire touchante, qui montre que l&#8217;amour triomphe sur tout. Je ne sais pas trop o\u00f9 ils ont vu \u00e7a. Premi\u00e8rement, on ne les conna\u00eet pas. On ne sait rien sur eux, ils n&#8217;\u00e9voluent pas, ils parlent \u00e0 peine, ils n&#8217;ont m\u00eame pas de nom, et on ne s&#8217;attache pas \u00e0 eux. \u00c0 part le fait qu&#8217;ils soient physiquement ensemble, rien dans les dialogues ou dans les \u00e9v\u00e9nements ne m&#8217;a fait comprendre que leur amour \u00e9tait particuli\u00e8rement beau et puissant. L&#8217;enfant avait toujours peur, le p\u00e8re \u00e9tait toujours aust\u00e8re et protecteur comme un vrai homme viril. Rien de particuli\u00e8rement poignant l\u00e0-dedans.<\/p>\n\n\n\n<p>Les gens ont trouv\u00e9 de la beaut\u00e9 l\u00e0-dedans, mais je trouve qu&#8217;il faut pour \u00e7a une imagination assez d\u00e9bordante. Les personnages ont faim et froid tout le temps, tout le paysage est dans des nuances de gris, rien ne pousse et tout le monde est mis\u00e9rable, et, <em>spoiler alert<\/em>, le p\u00e8re meurt et on ne sait pas ce qui va se passer avec l&#8217;enfant. Une fin qui laisse pas mal \u00e0 d\u00e9sirer et qui ne conclut absolument rien.<\/p>\n\n\n\n<p>Les gens ont trouv\u00e9 que c&#8217;\u00e9tait un livre &#8220;\u00e9peurant&#8221;. \u00c0 part les deux-trois sc\u00e8nes de cannibalisme qui nous sont jet\u00e9es dans la figure, je ne vois rien qui peut vraiment faire peur dans ce livre. L&#8217;\u00e9motion principale que j&#8217;ai ressentie \u00e9tait l&#8217;ennui; dans ces sc\u00e8nes-l\u00e0, je n&#8217;ai ressenti que du vague d\u00e9go\u00fbt.<\/p>\n\n\n\n<p>Les gens ont trouv\u00e9 que le style de McCarthy \u00e9tait magnifique, minimaliste et direct. \u00c0 consid\u00e9rer le nombre de conjonctions de coordination inutiles, les d\u00e9tails insignifiants sur les objets qu&#8217;ils trouvent et les envol\u00e9es lyriques absolument incompr\u00e9hensibles, je ne trouve \u00e7a ni magnifique, ni minimaliste, ni direct. C&#8217;est p\u00e9dant.<\/p>\n\n\n\n<p>Pourquoi, alors, ce livre a eu autant de succ\u00e8s? Selon moi, c&#8217;est parce que, comme bien des livres p\u00e9nibles \u00e0 lire \u00e9crits par des auteurs pr\u00e9tentieux, personne n&#8217;ose dire qu&#8217;il n&#8217;a pas compris, qu&#8217;il a trouv\u00e9 \u00e7a plate, qu&#8217;il n&#8217;a pas vu le point. Ces auteurs font du flafla qui r\u00e9ussit \u00e9tonnamment \u00e0 impressionner &#8220;l&#8217;\u00e9lite&#8221; litt\u00e9raire. \u00c7a lui fait une r\u00e9putation, les lecteurs sont vendus d&#8217;avance et travaillent tr\u00e8s fort pour trouver quelque chose \u00e0 aimer et ne pas avoir l&#8217;air tata. <\/p>\n\n\n\n<p>Avant, \u00e7a me donnait l&#8217;impression que j&#8217;\u00e9tais simplement un peu b\u00eate. Mais apr\u00e8s environ 22 ans \u00e0 lire compulsivement et avoir \u00e9tudi\u00e9 la litt\u00e9rature pendant un an et demi \u00e0 temps plein \u00e0 l&#8217;universit\u00e9 (avec d&#8217;excellentes notes en passant), je commence \u00e0 assumer que je sais lire, et que mon opinion est parfaitement valable.<\/p>\n\n\n\n<p>Si vous pensez comme moi, je vous conseille cet article dans <em><a href=\"https:\/\/www.theatlantic.com\/magazine\/archive\/2001\/07\/a-readers-manifesto\/302270\/#\">The Atlantic<\/a><\/em>, qui risque fort de vous faire rire et de vous flatter dans le sens du poil. <\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/the-road-cormac-mccarthy-9780307387899.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Je vais vous dire quelque chose : je suis un peu tann\u00e9e d&#8217;\u00eatre confront\u00e9e \u00e0 des livres qui me donnent l&#8217;impression de rien comprendre. Pas que le livre est difficile \u00e0 comprendre : au contraire, l&#8217;histoire est on ne peut plus simple, et il n&#8217;y a rien de complexe dans la prose de Cormac McCarthy (\u00e0 part certains passages lyriques qui ne veulent absolument rien dire). Ce que je ne comprends pas, c&#8217;est comment \u00e7a se fait qu&#8217;un tel livre ait pu obtenir le prix Pulitzer, et comment \u00e7a se fait qu&#8217;autant de lecteurs lui aient donn\u00e9 une note parfaite. Allez voir les opinions de ce livre sur GoodReads. Une grande majorit\u00e9 des lecteurs (74%) lui ont donn\u00e9 une note parfaite ou presque parfaite, tandis que seulement 3% lui ont donn\u00e9 la pire note. Mais la critique qui a \u00e9t\u00e9 le plus aim\u00e9e en est une qui lui donnait une \u00e9toile, et la deuxi\u00e8me plus aim\u00e9e lui donnait 5 \u00e9toiles. Les deux sont absolument cat\u00e9goriques dans leur opinion. Je suis en accord \u00e0 peu pr\u00e8s complet avec la critique \u00e0 une \u00e9toile (tr\u00e8s compl\u00e8te d&#8217;ailleurs), tandis que je ne comprends aucun des arguments de ceux qui lui donnent une note parfaite. Une telle divergence d&#8217;opinion est quand m\u00eame surprenante. Je suis dans le clan \u00e0 une \u00e9toile. Et vous? R\u00e9sum\u00e9 Un incident inconnu a compl\u00e8tement ravag\u00e9 la plan\u00e8te. Le ciel est constamment obscurci par une poussi\u00e8re ou une fum\u00e9e grise; tout a \u00e9t\u00e9 br\u00fbl\u00e9; plus rien ne pousse dans la terre; les plantes et les animaux sont morts; il fait constamment froid. Un homme et son fils (dont on ne saura jamais les noms) marchent vers le sud en esp\u00e9rant que ce soit mieux l\u00e0-bas et tentent de survivre. Impressions Prenons un extrait au hasard. While the boy slept he began to go methodically through the stores. Clothes, sweaters, socks. A stainless steel basin and sponges and bars of soap. Toothpaste and toothbrushes. In the bottom of a big plastic jar of bolts and screws and miscellaneous hardware he found a double handful of gold krugerrands in a cloth sack. He dumped them out and kneaded them in his hand and looked at them and then scooped them back into the jar along with the hardware and put the jar back on the shelf. &#8211; The Road, p. 142 Ceci \u00e9tait un paragraphe. On a une ligne blanche, puis un autre paragraphe. Vous avez maintenant une tr\u00e8s bonne id\u00e9e de ce \u00e0 quoi ce livre ressemble. Beaucoup de &#8220;and&#8221; qui sont suppos\u00e9s donner un style, beaucoup d&#8217;\u00e9num\u00e9rations. Beaucoup de sc\u00e8nes qui ne servent pas \u00e0 grand-chose. Je suis un peu dure en ce moment. Mais honn\u00eatement, j&#8217;ai essay\u00e9, pendant tout le livre, de comprendre ce qui avait excit\u00e9 tant les critiques et, apparemment, le lectorat. Et ce que j&#8217;ai vu, c&#8217;est un style qui devient fatigant tr\u00e8s rapidement, des sc\u00e8nes monotones, une histoire qui n&#8217;allait nulle part, une relation p\u00e8re-fils qui n&#8217;\u00e9volue pas, et des dialogues path\u00e9tiques. J&#8217;avais l&#8217;impression de me faire flasher un style d&#8217;Auteur avec un grand A devant mes yeux et qu&#8217;il fallait que je creuse tr\u00e8s loin pour trouver une profondeur l\u00e0-dedans. Les gens ont encens\u00e9 la relation p\u00e8re-fils. Ils ont trouv\u00e9 que c&#8217;est une histoire touchante, qui montre que l&#8217;amour triomphe sur tout. Je ne sais pas trop o\u00f9 ils ont vu \u00e7a. Premi\u00e8rement, on ne les conna\u00eet pas. On ne sait rien sur eux, ils n&#8217;\u00e9voluent pas, ils parlent \u00e0 peine, ils n&#8217;ont m\u00eame pas de nom, et on ne s&#8217;attache pas \u00e0 eux. \u00c0 part le fait qu&#8217;ils soient physiquement ensemble, rien dans les dialogues ou dans les \u00e9v\u00e9nements ne m&#8217;a fait comprendre que leur amour \u00e9tait particuli\u00e8rement beau et puissant. L&#8217;enfant avait toujours peur, le p\u00e8re \u00e9tait toujours aust\u00e8re et protecteur comme un vrai homme viril. Rien de particuli\u00e8rement poignant l\u00e0-dedans. Les gens ont trouv\u00e9 de la beaut\u00e9 l\u00e0-dedans, mais je trouve qu&#8217;il faut pour \u00e7a une imagination assez d\u00e9bordante. Les personnages ont faim et froid tout le temps, tout le paysage est dans des nuances de gris, rien ne pousse et tout le monde est mis\u00e9rable, et, spoiler alert, le p\u00e8re meurt et on ne sait pas ce qui va se passer avec l&#8217;enfant. Une fin qui laisse pas mal \u00e0 d\u00e9sirer et qui ne conclut absolument rien. Les gens ont trouv\u00e9 que c&#8217;\u00e9tait un livre &#8220;\u00e9peurant&#8221;. \u00c0 part les deux-trois sc\u00e8nes de cannibalisme qui nous sont jet\u00e9es dans la figure, je ne vois rien qui peut vraiment faire peur dans ce livre. L&#8217;\u00e9motion principale que j&#8217;ai ressentie \u00e9tait l&#8217;ennui; dans ces sc\u00e8nes-l\u00e0, je n&#8217;ai ressenti que du vague d\u00e9go\u00fbt. Les gens ont trouv\u00e9 que le style de McCarthy \u00e9tait magnifique, minimaliste et direct. \u00c0 consid\u00e9rer le nombre de conjonctions de coordination inutiles, les d\u00e9tails insignifiants sur les objets qu&#8217;ils trouvent et les envol\u00e9es lyriques absolument incompr\u00e9hensibles, je ne trouve \u00e7a ni magnifique, ni minimaliste, ni direct. C&#8217;est p\u00e9dant. Pourquoi, alors, ce livre a eu autant de succ\u00e8s? Selon moi, c&#8217;est parce que, comme bien des livres p\u00e9nibles \u00e0 lire \u00e9crits par des auteurs pr\u00e9tentieux, personne n&#8217;ose dire qu&#8217;il n&#8217;a pas compris, qu&#8217;il a trouv\u00e9 \u00e7a plate, qu&#8217;il n&#8217;a pas vu le point. Ces auteurs font du flafla qui r\u00e9ussit \u00e9tonnamment \u00e0 impressionner &#8220;l&#8217;\u00e9lite&#8221; litt\u00e9raire. \u00c7a lui fait une r\u00e9putation, les lecteurs sont vendus d&#8217;avance et travaillent tr\u00e8s fort pour trouver quelque chose \u00e0 aimer et ne pas avoir l&#8217;air tata. Avant, \u00e7a me donnait l&#8217;impression que j&#8217;\u00e9tais simplement un peu b\u00eate. Mais apr\u00e8s environ 22 ans \u00e0 lire compulsivement et avoir \u00e9tudi\u00e9 la litt\u00e9rature pendant un an et demi \u00e0 temps plein \u00e0 l&#8217;universit\u00e9 (avec d&#8217;excellentes notes en passant), je commence \u00e0 assumer que je sais lire, et que mon opinion est parfaitement valable. Si vous pensez comme moi, je vous conseille cet article dans The Atlantic, qui risque fort de vous faire rire et de vous flatter dans le sens du poil.<\/p>\n","protected":false},"author":1,"featured_media":4287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Je pense que ce livre, soit on l'aime comme apparemment tous les critiques de la terre, soit on le d\u00e9teste. Moi, je le d\u00e9teste \ud83e\udd37\u200d\u2640\ufe0f Et vous?","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[242],"tags":[],"class_list":["post-4285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Route, de Cormac McCarthy - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/the-road\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Route, de Cormac McCarthy - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Je vais vous dire quelque chose : je suis un peu tann\u00e9e d&#8217;\u00eatre confront\u00e9e \u00e0 des livres qui me donnent l&#8217;impression de rien comprendre. Pas que le livre est difficile \u00e0 comprendre : au contraire, l&#8217;histoire est on ne peut plus simple, et il n&#8217;y a rien de complexe dans la prose de Cormac McCarthy (\u00e0 part certains passages lyriques qui ne veulent absolument rien dire). Ce que je ne comprends pas, c&#8217;est comment \u00e7a se fait qu&#8217;un tel livre ait pu obtenir le prix Pulitzer, et comment \u00e7a se fait qu&#8217;autant de lecteurs lui aient donn\u00e9 une note parfaite. Allez voir les opinions de ce livre sur GoodReads. Une grande majorit\u00e9 des lecteurs (74%) lui ont donn\u00e9 une note parfaite ou presque parfaite, tandis que seulement 3% lui ont donn\u00e9 la pire note. Mais la critique qui a \u00e9t\u00e9 le plus aim\u00e9e en est une qui lui donnait une \u00e9toile, et la deuxi\u00e8me plus aim\u00e9e lui donnait 5 \u00e9toiles. Les deux sont absolument cat\u00e9goriques dans leur opinion. Je suis en accord \u00e0 peu pr\u00e8s complet avec la critique \u00e0 une \u00e9toile (tr\u00e8s compl\u00e8te d&#8217;ailleurs), tandis que je ne comprends aucun des arguments de ceux qui lui donnent une note parfaite. Une telle divergence d&#8217;opinion est quand m\u00eame surprenante. Je suis dans le clan \u00e0 une \u00e9toile. Et vous? R\u00e9sum\u00e9 Un incident inconnu a compl\u00e8tement ravag\u00e9 la plan\u00e8te. Le ciel est constamment obscurci par une poussi\u00e8re ou une fum\u00e9e grise; tout a \u00e9t\u00e9 br\u00fbl\u00e9; plus rien ne pousse dans la terre; les plantes et les animaux sont morts; il fait constamment froid. Un homme et son fils (dont on ne saura jamais les noms) marchent vers le sud en esp\u00e9rant que ce soit mieux l\u00e0-bas et tentent de survivre. Impressions Prenons un extrait au hasard. While the boy slept he began to go methodically through the stores. Clothes, sweaters, socks. A stainless steel basin and sponges and bars of soap. Toothpaste and toothbrushes. In the bottom of a big plastic jar of bolts and screws and miscellaneous hardware he found a double handful of gold krugerrands in a cloth sack. He dumped them out and kneaded them in his hand and looked at them and then scooped them back into the jar along with the hardware and put the jar back on the shelf. &#8211; The Road, p. 142 Ceci \u00e9tait un paragraphe. On a une ligne blanche, puis un autre paragraphe. Vous avez maintenant une tr\u00e8s bonne id\u00e9e de ce \u00e0 quoi ce livre ressemble. Beaucoup de &#8220;and&#8221; qui sont suppos\u00e9s donner un style, beaucoup d&#8217;\u00e9num\u00e9rations. Beaucoup de sc\u00e8nes qui ne servent pas \u00e0 grand-chose. Je suis un peu dure en ce moment. Mais honn\u00eatement, j&#8217;ai essay\u00e9, pendant tout le livre, de comprendre ce qui avait excit\u00e9 tant les critiques et, apparemment, le lectorat. Et ce que j&#8217;ai vu, c&#8217;est un style qui devient fatigant tr\u00e8s rapidement, des sc\u00e8nes monotones, une histoire qui n&#8217;allait nulle part, une relation p\u00e8re-fils qui n&#8217;\u00e9volue pas, et des dialogues path\u00e9tiques. J&#8217;avais l&#8217;impression de me faire flasher un style d&#8217;Auteur avec un grand A devant mes yeux et qu&#8217;il fallait que je creuse tr\u00e8s loin pour trouver une profondeur l\u00e0-dedans. Les gens ont encens\u00e9 la relation p\u00e8re-fils. Ils ont trouv\u00e9 que c&#8217;est une histoire touchante, qui montre que l&#8217;amour triomphe sur tout. Je ne sais pas trop o\u00f9 ils ont vu \u00e7a. Premi\u00e8rement, on ne les conna\u00eet pas. On ne sait rien sur eux, ils n&#8217;\u00e9voluent pas, ils parlent \u00e0 peine, ils n&#8217;ont m\u00eame pas de nom, et on ne s&#8217;attache pas \u00e0 eux. \u00c0 part le fait qu&#8217;ils soient physiquement ensemble, rien dans les dialogues ou dans les \u00e9v\u00e9nements ne m&#8217;a fait comprendre que leur amour \u00e9tait particuli\u00e8rement beau et puissant. L&#8217;enfant avait toujours peur, le p\u00e8re \u00e9tait toujours aust\u00e8re et protecteur comme un vrai homme viril. Rien de particuli\u00e8rement poignant l\u00e0-dedans. Les gens ont trouv\u00e9 de la beaut\u00e9 l\u00e0-dedans, mais je trouve qu&#8217;il faut pour \u00e7a une imagination assez d\u00e9bordante. Les personnages ont faim et froid tout le temps, tout le paysage est dans des nuances de gris, rien ne pousse et tout le monde est mis\u00e9rable, et, spoiler alert, le p\u00e8re meurt et on ne sait pas ce qui va se passer avec l&#8217;enfant. Une fin qui laisse pas mal \u00e0 d\u00e9sirer et qui ne conclut absolument rien. Les gens ont trouv\u00e9 que c&#8217;\u00e9tait un livre &#8220;\u00e9peurant&#8221;. \u00c0 part les deux-trois sc\u00e8nes de cannibalisme qui nous sont jet\u00e9es dans la figure, je ne vois rien qui peut vraiment faire peur dans ce livre. L&#8217;\u00e9motion principale que j&#8217;ai ressentie \u00e9tait l&#8217;ennui; dans ces sc\u00e8nes-l\u00e0, je n&#8217;ai ressenti que du vague d\u00e9go\u00fbt. Les gens ont trouv\u00e9 que le style de McCarthy \u00e9tait magnifique, minimaliste et direct. \u00c0 consid\u00e9rer le nombre de conjonctions de coordination inutiles, les d\u00e9tails insignifiants sur les objets qu&#8217;ils trouvent et les envol\u00e9es lyriques absolument incompr\u00e9hensibles, je ne trouve \u00e7a ni magnifique, ni minimaliste, ni direct. C&#8217;est p\u00e9dant. Pourquoi, alors, ce livre a eu autant de succ\u00e8s? Selon moi, c&#8217;est parce que, comme bien des livres p\u00e9nibles \u00e0 lire \u00e9crits par des auteurs pr\u00e9tentieux, personne n&#8217;ose dire qu&#8217;il n&#8217;a pas compris, qu&#8217;il a trouv\u00e9 \u00e7a plate, qu&#8217;il n&#8217;a pas vu le point. Ces auteurs font du flafla qui r\u00e9ussit \u00e9tonnamment \u00e0 impressionner &#8220;l&#8217;\u00e9lite&#8221; litt\u00e9raire. \u00c7a lui fait une r\u00e9putation, les lecteurs sont vendus d&#8217;avance et travaillent tr\u00e8s fort pour trouver quelque chose \u00e0 aimer et ne pas avoir l&#8217;air tata. Avant, \u00e7a me donnait l&#8217;impression que j&#8217;\u00e9tais simplement un peu b\u00eate. Mais apr\u00e8s environ 22 ans \u00e0 lire compulsivement et avoir \u00e9tudi\u00e9 la litt\u00e9rature pendant un an et demi \u00e0 temps plein \u00e0 l&#8217;universit\u00e9 (avec d&#8217;excellentes notes en passant), je commence \u00e0 assumer que je sais lire, et que mon opinion est parfaitement valable. Si vous pensez comme moi, je vous conseille cet article dans The Atlantic, qui risque fort de vous faire rire et de vous flatter dans le sens du poil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/the-road\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-24T01:21:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-20T20:02:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220123_191114.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"La Route, de Cormac McCarthy\",\"datePublished\":\"2022-01-24T01:21:33+00:00\",\"dateModified\":\"2022-11-20T20:02:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/\"},\"wordCount\":1075,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20220123_191114.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/\",\"name\":\"La Route, de Cormac McCarthy - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20220123_191114.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2022-01-24T01:21:33+00:00\",\"dateModified\":\"2022-11-20T20:02:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20220123_191114.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20220123_191114.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/the-road\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Route, de Cormac McCarthy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Route, de Cormac McCarthy - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/the-road\/","og_locale":"fr_CA","og_type":"article","og_title":"La Route, de Cormac McCarthy - Prochaine lecture","og_description":"Je vais vous dire quelque chose : je suis un peu tann\u00e9e d&#8217;\u00eatre confront\u00e9e \u00e0 des livres qui me donnent l&#8217;impression de rien comprendre. Pas que le livre est difficile \u00e0 comprendre : au contraire, l&#8217;histoire est on ne peut plus simple, et il n&#8217;y a rien de complexe dans la prose de Cormac McCarthy (\u00e0 part certains passages lyriques qui ne veulent absolument rien dire). Ce que je ne comprends pas, c&#8217;est comment \u00e7a se fait qu&#8217;un tel livre ait pu obtenir le prix Pulitzer, et comment \u00e7a se fait qu&#8217;autant de lecteurs lui aient donn\u00e9 une note parfaite. Allez voir les opinions de ce livre sur GoodReads. Une grande majorit\u00e9 des lecteurs (74%) lui ont donn\u00e9 une note parfaite ou presque parfaite, tandis que seulement 3% lui ont donn\u00e9 la pire note. Mais la critique qui a \u00e9t\u00e9 le plus aim\u00e9e en est une qui lui donnait une \u00e9toile, et la deuxi\u00e8me plus aim\u00e9e lui donnait 5 \u00e9toiles. Les deux sont absolument cat\u00e9goriques dans leur opinion. Je suis en accord \u00e0 peu pr\u00e8s complet avec la critique \u00e0 une \u00e9toile (tr\u00e8s compl\u00e8te d&#8217;ailleurs), tandis que je ne comprends aucun des arguments de ceux qui lui donnent une note parfaite. Une telle divergence d&#8217;opinion est quand m\u00eame surprenante. Je suis dans le clan \u00e0 une \u00e9toile. Et vous? R\u00e9sum\u00e9 Un incident inconnu a compl\u00e8tement ravag\u00e9 la plan\u00e8te. Le ciel est constamment obscurci par une poussi\u00e8re ou une fum\u00e9e grise; tout a \u00e9t\u00e9 br\u00fbl\u00e9; plus rien ne pousse dans la terre; les plantes et les animaux sont morts; il fait constamment froid. Un homme et son fils (dont on ne saura jamais les noms) marchent vers le sud en esp\u00e9rant que ce soit mieux l\u00e0-bas et tentent de survivre. Impressions Prenons un extrait au hasard. While the boy slept he began to go methodically through the stores. Clothes, sweaters, socks. A stainless steel basin and sponges and bars of soap. Toothpaste and toothbrushes. In the bottom of a big plastic jar of bolts and screws and miscellaneous hardware he found a double handful of gold krugerrands in a cloth sack. He dumped them out and kneaded them in his hand and looked at them and then scooped them back into the jar along with the hardware and put the jar back on the shelf. &#8211; The Road, p. 142 Ceci \u00e9tait un paragraphe. On a une ligne blanche, puis un autre paragraphe. Vous avez maintenant une tr\u00e8s bonne id\u00e9e de ce \u00e0 quoi ce livre ressemble. Beaucoup de &#8220;and&#8221; qui sont suppos\u00e9s donner un style, beaucoup d&#8217;\u00e9num\u00e9rations. Beaucoup de sc\u00e8nes qui ne servent pas \u00e0 grand-chose. Je suis un peu dure en ce moment. Mais honn\u00eatement, j&#8217;ai essay\u00e9, pendant tout le livre, de comprendre ce qui avait excit\u00e9 tant les critiques et, apparemment, le lectorat. Et ce que j&#8217;ai vu, c&#8217;est un style qui devient fatigant tr\u00e8s rapidement, des sc\u00e8nes monotones, une histoire qui n&#8217;allait nulle part, une relation p\u00e8re-fils qui n&#8217;\u00e9volue pas, et des dialogues path\u00e9tiques. J&#8217;avais l&#8217;impression de me faire flasher un style d&#8217;Auteur avec un grand A devant mes yeux et qu&#8217;il fallait que je creuse tr\u00e8s loin pour trouver une profondeur l\u00e0-dedans. Les gens ont encens\u00e9 la relation p\u00e8re-fils. Ils ont trouv\u00e9 que c&#8217;est une histoire touchante, qui montre que l&#8217;amour triomphe sur tout. Je ne sais pas trop o\u00f9 ils ont vu \u00e7a. Premi\u00e8rement, on ne les conna\u00eet pas. On ne sait rien sur eux, ils n&#8217;\u00e9voluent pas, ils parlent \u00e0 peine, ils n&#8217;ont m\u00eame pas de nom, et on ne s&#8217;attache pas \u00e0 eux. \u00c0 part le fait qu&#8217;ils soient physiquement ensemble, rien dans les dialogues ou dans les \u00e9v\u00e9nements ne m&#8217;a fait comprendre que leur amour \u00e9tait particuli\u00e8rement beau et puissant. L&#8217;enfant avait toujours peur, le p\u00e8re \u00e9tait toujours aust\u00e8re et protecteur comme un vrai homme viril. Rien de particuli\u00e8rement poignant l\u00e0-dedans. Les gens ont trouv\u00e9 de la beaut\u00e9 l\u00e0-dedans, mais je trouve qu&#8217;il faut pour \u00e7a une imagination assez d\u00e9bordante. Les personnages ont faim et froid tout le temps, tout le paysage est dans des nuances de gris, rien ne pousse et tout le monde est mis\u00e9rable, et, spoiler alert, le p\u00e8re meurt et on ne sait pas ce qui va se passer avec l&#8217;enfant. Une fin qui laisse pas mal \u00e0 d\u00e9sirer et qui ne conclut absolument rien. Les gens ont trouv\u00e9 que c&#8217;\u00e9tait un livre &#8220;\u00e9peurant&#8221;. \u00c0 part les deux-trois sc\u00e8nes de cannibalisme qui nous sont jet\u00e9es dans la figure, je ne vois rien qui peut vraiment faire peur dans ce livre. L&#8217;\u00e9motion principale que j&#8217;ai ressentie \u00e9tait l&#8217;ennui; dans ces sc\u00e8nes-l\u00e0, je n&#8217;ai ressenti que du vague d\u00e9go\u00fbt. Les gens ont trouv\u00e9 que le style de McCarthy \u00e9tait magnifique, minimaliste et direct. \u00c0 consid\u00e9rer le nombre de conjonctions de coordination inutiles, les d\u00e9tails insignifiants sur les objets qu&#8217;ils trouvent et les envol\u00e9es lyriques absolument incompr\u00e9hensibles, je ne trouve \u00e7a ni magnifique, ni minimaliste, ni direct. C&#8217;est p\u00e9dant. Pourquoi, alors, ce livre a eu autant de succ\u00e8s? Selon moi, c&#8217;est parce que, comme bien des livres p\u00e9nibles \u00e0 lire \u00e9crits par des auteurs pr\u00e9tentieux, personne n&#8217;ose dire qu&#8217;il n&#8217;a pas compris, qu&#8217;il a trouv\u00e9 \u00e7a plate, qu&#8217;il n&#8217;a pas vu le point. Ces auteurs font du flafla qui r\u00e9ussit \u00e9tonnamment \u00e0 impressionner &#8220;l&#8217;\u00e9lite&#8221; litt\u00e9raire. \u00c7a lui fait une r\u00e9putation, les lecteurs sont vendus d&#8217;avance et travaillent tr\u00e8s fort pour trouver quelque chose \u00e0 aimer et ne pas avoir l&#8217;air tata. Avant, \u00e7a me donnait l&#8217;impression que j&#8217;\u00e9tais simplement un peu b\u00eate. Mais apr\u00e8s environ 22 ans \u00e0 lire compulsivement et avoir \u00e9tudi\u00e9 la litt\u00e9rature pendant un an et demi \u00e0 temps plein \u00e0 l&#8217;universit\u00e9 (avec d&#8217;excellentes notes en passant), je commence \u00e0 assumer que je sais lire, et que mon opinion est parfaitement valable. Si vous pensez comme moi, je vous conseille cet article dans The Atlantic, qui risque fort de vous faire rire et de vous flatter dans le sens du poil.","og_url":"https:\/\/prochainelecture.com\/fr\/the-road\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2022-01-24T01:21:33+00:00","article_modified_time":"2022-11-20T20:02:29+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220123_191114.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/the-road\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/the-road\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"La Route, de Cormac McCarthy","datePublished":"2022-01-24T01:21:33+00:00","dateModified":"2022-11-20T20:02:29+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/the-road\/"},"wordCount":1075,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/the-road\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220123_191114.jpg?fit=1200%2C800&ssl=1","articleSection":["Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/the-road\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/the-road\/","url":"https:\/\/prochainelecture.com\/the-road\/","name":"La Route, de Cormac McCarthy - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/the-road\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/the-road\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220123_191114.jpg?fit=1200%2C800&ssl=1","datePublished":"2022-01-24T01:21:33+00:00","dateModified":"2022-11-20T20:02:29+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/the-road\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/the-road\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/the-road\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220123_191114.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220123_191114.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/the-road\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"La Route, de Cormac McCarthy"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220123_191114.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-177","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=4285"}],"version-history":[{"count":5,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4285\/revisions"}],"predecessor-version":[{"id":4507,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4285\/revisions\/4507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/4287"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=4285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=4285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=4285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}