{"id":4253,"date":"2022-01-02T08:16:00","date_gmt":"2022-01-02T12:16:00","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4253"},"modified":"2021-12-29T12:58:50","modified_gmt":"2021-12-29T16:58:50","slug":"elantris","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/elantris\/","title":{"rendered":"Elantris"},"content":{"rendered":"\n<p>J&#8217;ai lu peu de fantastique dans ma vie. Je me rattrape ces temps-ci avec mon amoureux. Apr\u00e8s avoir \u00e9t\u00e9 plut\u00f4t d\u00e9\u00e7us par <a href=\"https:\/\/prochainelecture.com\/ruin-and-rising\/\">la trilogie <em>Shadow and Bone<\/em><\/a>, on a voulu s&#8217;initier \u00e0 une valeur s\u00fbre : Brandon Sanderson. Auteur d&#8217;un nombre impressionnant de romans (il en \u00e9crit tellement que je n&#8217;ai pas r\u00e9ussi \u00e0 obtenir un chiffre), il a apparemment vendu plus de 21 millions de copies au d\u00e9but de 2021. C&#8217;est un pro. Et c&#8217;est un pro qu&#8217;on voulait.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p>Elantris \u00e9tait autrefois une magnifique cit\u00e9. Ses habitants, immortels et dot\u00e9s de pouvoirs magiques, \u00e9taient v\u00e9n\u00e9r\u00e9s comme des dieux par la population. Mais il y a dix ans, un mal myst\u00e9rieux a frapp\u00e9 ses habitants, les r\u00e9duisant \u00e0 l&#8217;\u00e9tat de morts vivants et emp\u00eachant toute forme de magie de se manifester. Les cit\u00e9s alentour, fragilis\u00e9es par la chute d&#8217;Elantris, sont menac\u00e9es d&#8217;invasion par des villes lointaines.<\/p>\n\n\n\n<p>C&#8217;est dans ce contexte que Sarene, princesse du royaume de Teod, arrive \u00e0 Arelon pour marier Raoden, le prince de la ville. Mais \u00e0 son arriv\u00e9e, elle apprend que son futur mari, qu&#8217;elle n&#8217;a jamais rencontr\u00e9, est mort dans des circonstances myst\u00e9rieuses. Le lecteur, lui, sait toutefois que Raoden n&#8217;est pas mort, mais a plut\u00f4t \u00e9t\u00e9 frapp\u00e9 par le Shaod, le mal qui a ravag\u00e9 Elantris et ses habitants, et a \u00e9t\u00e9 confin\u00e9 dans la cit\u00e9. Alors que Raoden tente d&#8217;insuffler de l&#8217;espoir parmi les malheureux habitants et de d\u00e9couvrir la source de cette \u00e9trange maladie, Sarene, officiellement veuve, tente de comprendre les intrigues politiques en place, la situation \u00e0 Elantris, et ce qui se cache derri\u00e8re la mort de l&#8217;homme qu&#8217;elle avait esp\u00e9r\u00e9 aimer.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>Ce livre est un soulagement. Remarquablement bien \u00e9crit, on sent qu&#8217;on a de la qualit\u00e9 entre les mains. Les personnages sont charismatiques et bien d\u00e9velopp\u00e9s, l&#8217;univers est riche, et l&#8217;histoire est prenante. La totale.<\/p>\n\n\n\n<p>Si vous aimez l&#8217;action, vous allez en avoir. Mais je vous avertis, \u00e7a ne vient pas tout de suite. Au d\u00e9but, le rythme est assez lent, et c&#8217;est tr\u00e8s important : c&#8217;est pour qu&#8217;on ait le temps de se familiariser avec l&#8217;univers, d&#8217;apprendre \u00e0 conna\u00eetre les personnages et de les aimer, et c&#8217;est \u00e7a qui fait toute la qualit\u00e9 du roman. Une fois que l&#8217;immersion est compl\u00e8te, le rythme s&#8217;acc\u00e9l\u00e8re drastiquement et \u00e7a devient impossible d&#8217;arr\u00eater. <\/p>\n\n\n\n<p>On a tous les deux beaucoup aim\u00e9 notre lecture. On avait h\u00e2te de lire <em>Elantris<\/em> le soir, et on \u00e9tait tristes quand il s&#8217;est termin\u00e9.  On a achet\u00e9 la trilogie <em>Mistborn<\/em> (53 heures de lecture selon la Kindle!) Je vous en donne assur\u00e9ment des nouvelles.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/elantris-brandon-sanderson-9780765350374.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>J&#8217;ai lu peu de fantastique dans ma vie. Je me rattrape ces temps-ci avec mon amoureux. Apr\u00e8s avoir \u00e9t\u00e9 plut\u00f4t d\u00e9\u00e7us par la trilogie Shadow and Bone, on a voulu s&#8217;initier \u00e0 une valeur s\u00fbre : Brandon Sanderson. Auteur d&#8217;un nombre impressionnant de romans (il en \u00e9crit tellement que je n&#8217;ai pas r\u00e9ussi \u00e0 obtenir un chiffre), il a apparemment vendu plus de 21 millions de copies au d\u00e9but de 2021. C&#8217;est un pro. Et c&#8217;est un pro qu&#8217;on voulait. R\u00e9sum\u00e9 Elantris \u00e9tait autrefois une magnifique cit\u00e9. Ses habitants, immortels et dot\u00e9s de pouvoirs magiques, \u00e9taient v\u00e9n\u00e9r\u00e9s comme des dieux par la population. Mais il y a dix ans, un mal myst\u00e9rieux a frapp\u00e9 ses habitants, les r\u00e9duisant \u00e0 l&#8217;\u00e9tat de morts vivants et emp\u00eachant toute forme de magie de se manifester. Les cit\u00e9s alentour, fragilis\u00e9es par la chute d&#8217;Elantris, sont menac\u00e9es d&#8217;invasion par des villes lointaines. C&#8217;est dans ce contexte que Sarene, princesse du royaume de Teod, arrive \u00e0 Arelon pour marier Raoden, le prince de la ville. Mais \u00e0 son arriv\u00e9e, elle apprend que son futur mari, qu&#8217;elle n&#8217;a jamais rencontr\u00e9, est mort dans des circonstances myst\u00e9rieuses. Le lecteur, lui, sait toutefois que Raoden n&#8217;est pas mort, mais a plut\u00f4t \u00e9t\u00e9 frapp\u00e9 par le Shaod, le mal qui a ravag\u00e9 Elantris et ses habitants, et a \u00e9t\u00e9 confin\u00e9 dans la cit\u00e9. Alors que Raoden tente d&#8217;insuffler de l&#8217;espoir parmi les malheureux habitants et de d\u00e9couvrir la source de cette \u00e9trange maladie, Sarene, officiellement veuve, tente de comprendre les intrigues politiques en place, la situation \u00e0 Elantris, et ce qui se cache derri\u00e8re la mort de l&#8217;homme qu&#8217;elle avait esp\u00e9r\u00e9 aimer. Impressions Ce livre est un soulagement. Remarquablement bien \u00e9crit, on sent qu&#8217;on a de la qualit\u00e9 entre les mains. Les personnages sont charismatiques et bien d\u00e9velopp\u00e9s, l&#8217;univers est riche, et l&#8217;histoire est prenante. La totale. Si vous aimez l&#8217;action, vous allez en avoir. Mais je vous avertis, \u00e7a ne vient pas tout de suite. Au d\u00e9but, le rythme est assez lent, et c&#8217;est tr\u00e8s important : c&#8217;est pour qu&#8217;on ait le temps de se familiariser avec l&#8217;univers, d&#8217;apprendre \u00e0 conna\u00eetre les personnages et de les aimer, et c&#8217;est \u00e7a qui fait toute la qualit\u00e9 du roman. Une fois que l&#8217;immersion est compl\u00e8te, le rythme s&#8217;acc\u00e9l\u00e8re drastiquement et \u00e7a devient impossible d&#8217;arr\u00eater. On a tous les deux beaucoup aim\u00e9 notre lecture. On avait h\u00e2te de lire Elantris le soir, et on \u00e9tait tristes quand il s&#8217;est termin\u00e9. On a achet\u00e9 la trilogie Mistborn (53 heures de lecture selon la Kindle!) Je vous en donne assur\u00e9ment des nouvelles.<\/p>\n","protected":false},"author":1,"featured_media":4258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[246,242],"tags":[],"class_list":["post-4253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fantastique","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elantris - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/elantris\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elantris - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"J&#8217;ai lu peu de fantastique dans ma vie. Je me rattrape ces temps-ci avec mon amoureux. Apr\u00e8s avoir \u00e9t\u00e9 plut\u00f4t d\u00e9\u00e7us par la trilogie Shadow and Bone, on a voulu s&#8217;initier \u00e0 une valeur s\u00fbre : Brandon Sanderson. Auteur d&#8217;un nombre impressionnant de romans (il en \u00e9crit tellement que je n&#8217;ai pas r\u00e9ussi \u00e0 obtenir un chiffre), il a apparemment vendu plus de 21 millions de copies au d\u00e9but de 2021. C&#8217;est un pro. Et c&#8217;est un pro qu&#8217;on voulait. R\u00e9sum\u00e9 Elantris \u00e9tait autrefois une magnifique cit\u00e9. Ses habitants, immortels et dot\u00e9s de pouvoirs magiques, \u00e9taient v\u00e9n\u00e9r\u00e9s comme des dieux par la population. Mais il y a dix ans, un mal myst\u00e9rieux a frapp\u00e9 ses habitants, les r\u00e9duisant \u00e0 l&#8217;\u00e9tat de morts vivants et emp\u00eachant toute forme de magie de se manifester. Les cit\u00e9s alentour, fragilis\u00e9es par la chute d&#8217;Elantris, sont menac\u00e9es d&#8217;invasion par des villes lointaines. C&#8217;est dans ce contexte que Sarene, princesse du royaume de Teod, arrive \u00e0 Arelon pour marier Raoden, le prince de la ville. Mais \u00e0 son arriv\u00e9e, elle apprend que son futur mari, qu&#8217;elle n&#8217;a jamais rencontr\u00e9, est mort dans des circonstances myst\u00e9rieuses. Le lecteur, lui, sait toutefois que Raoden n&#8217;est pas mort, mais a plut\u00f4t \u00e9t\u00e9 frapp\u00e9 par le Shaod, le mal qui a ravag\u00e9 Elantris et ses habitants, et a \u00e9t\u00e9 confin\u00e9 dans la cit\u00e9. Alors que Raoden tente d&#8217;insuffler de l&#8217;espoir parmi les malheureux habitants et de d\u00e9couvrir la source de cette \u00e9trange maladie, Sarene, officiellement veuve, tente de comprendre les intrigues politiques en place, la situation \u00e0 Elantris, et ce qui se cache derri\u00e8re la mort de l&#8217;homme qu&#8217;elle avait esp\u00e9r\u00e9 aimer. Impressions Ce livre est un soulagement. Remarquablement bien \u00e9crit, on sent qu&#8217;on a de la qualit\u00e9 entre les mains. Les personnages sont charismatiques et bien d\u00e9velopp\u00e9s, l&#8217;univers est riche, et l&#8217;histoire est prenante. La totale. Si vous aimez l&#8217;action, vous allez en avoir. Mais je vous avertis, \u00e7a ne vient pas tout de suite. Au d\u00e9but, le rythme est assez lent, et c&#8217;est tr\u00e8s important : c&#8217;est pour qu&#8217;on ait le temps de se familiariser avec l&#8217;univers, d&#8217;apprendre \u00e0 conna\u00eetre les personnages et de les aimer, et c&#8217;est \u00e7a qui fait toute la qualit\u00e9 du roman. Une fois que l&#8217;immersion est compl\u00e8te, le rythme s&#8217;acc\u00e9l\u00e8re drastiquement et \u00e7a devient impossible d&#8217;arr\u00eater. On a tous les deux beaucoup aim\u00e9 notre lecture. On avait h\u00e2te de lire Elantris le soir, et on \u00e9tait tristes quand il s&#8217;est termin\u00e9. On a achet\u00e9 la trilogie Mistborn (53 heures de lecture selon la Kindle!) Je vous en donne assur\u00e9ment des nouvelles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/elantris\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-02T12:16:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20211229_111538.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Elantris\",\"datePublished\":\"2022-01-02T12:16:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/\"},\"wordCount\":483,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20211229_111538.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Fantastique\",\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/\",\"name\":\"Elantris - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20211229_111538.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2022-01-02T12:16:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20211229_111538.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20211229_111538.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/elantris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elantris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elantris - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/elantris\/","og_locale":"fr_CA","og_type":"article","og_title":"Elantris - Prochaine lecture","og_description":"J&#8217;ai lu peu de fantastique dans ma vie. Je me rattrape ces temps-ci avec mon amoureux. Apr\u00e8s avoir \u00e9t\u00e9 plut\u00f4t d\u00e9\u00e7us par la trilogie Shadow and Bone, on a voulu s&#8217;initier \u00e0 une valeur s\u00fbre : Brandon Sanderson. Auteur d&#8217;un nombre impressionnant de romans (il en \u00e9crit tellement que je n&#8217;ai pas r\u00e9ussi \u00e0 obtenir un chiffre), il a apparemment vendu plus de 21 millions de copies au d\u00e9but de 2021. C&#8217;est un pro. Et c&#8217;est un pro qu&#8217;on voulait. R\u00e9sum\u00e9 Elantris \u00e9tait autrefois une magnifique cit\u00e9. Ses habitants, immortels et dot\u00e9s de pouvoirs magiques, \u00e9taient v\u00e9n\u00e9r\u00e9s comme des dieux par la population. Mais il y a dix ans, un mal myst\u00e9rieux a frapp\u00e9 ses habitants, les r\u00e9duisant \u00e0 l&#8217;\u00e9tat de morts vivants et emp\u00eachant toute forme de magie de se manifester. Les cit\u00e9s alentour, fragilis\u00e9es par la chute d&#8217;Elantris, sont menac\u00e9es d&#8217;invasion par des villes lointaines. C&#8217;est dans ce contexte que Sarene, princesse du royaume de Teod, arrive \u00e0 Arelon pour marier Raoden, le prince de la ville. Mais \u00e0 son arriv\u00e9e, elle apprend que son futur mari, qu&#8217;elle n&#8217;a jamais rencontr\u00e9, est mort dans des circonstances myst\u00e9rieuses. Le lecteur, lui, sait toutefois que Raoden n&#8217;est pas mort, mais a plut\u00f4t \u00e9t\u00e9 frapp\u00e9 par le Shaod, le mal qui a ravag\u00e9 Elantris et ses habitants, et a \u00e9t\u00e9 confin\u00e9 dans la cit\u00e9. Alors que Raoden tente d&#8217;insuffler de l&#8217;espoir parmi les malheureux habitants et de d\u00e9couvrir la source de cette \u00e9trange maladie, Sarene, officiellement veuve, tente de comprendre les intrigues politiques en place, la situation \u00e0 Elantris, et ce qui se cache derri\u00e8re la mort de l&#8217;homme qu&#8217;elle avait esp\u00e9r\u00e9 aimer. Impressions Ce livre est un soulagement. Remarquablement bien \u00e9crit, on sent qu&#8217;on a de la qualit\u00e9 entre les mains. Les personnages sont charismatiques et bien d\u00e9velopp\u00e9s, l&#8217;univers est riche, et l&#8217;histoire est prenante. La totale. Si vous aimez l&#8217;action, vous allez en avoir. Mais je vous avertis, \u00e7a ne vient pas tout de suite. Au d\u00e9but, le rythme est assez lent, et c&#8217;est tr\u00e8s important : c&#8217;est pour qu&#8217;on ait le temps de se familiariser avec l&#8217;univers, d&#8217;apprendre \u00e0 conna\u00eetre les personnages et de les aimer, et c&#8217;est \u00e7a qui fait toute la qualit\u00e9 du roman. Une fois que l&#8217;immersion est compl\u00e8te, le rythme s&#8217;acc\u00e9l\u00e8re drastiquement et \u00e7a devient impossible d&#8217;arr\u00eater. On a tous les deux beaucoup aim\u00e9 notre lecture. On avait h\u00e2te de lire Elantris le soir, et on \u00e9tait tristes quand il s&#8217;est termin\u00e9. On a achet\u00e9 la trilogie Mistborn (53 heures de lecture selon la Kindle!) Je vous en donne assur\u00e9ment des nouvelles.","og_url":"https:\/\/prochainelecture.com\/fr\/elantris\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2022-01-02T12:16:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20211229_111538.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/elantris\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/elantris\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Elantris","datePublished":"2022-01-02T12:16:00+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/elantris\/"},"wordCount":483,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/elantris\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20211229_111538.jpg?fit=1200%2C800&ssl=1","articleSection":["Fantastique","Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/elantris\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/elantris\/","url":"https:\/\/prochainelecture.com\/elantris\/","name":"Elantris - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/elantris\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/elantris\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20211229_111538.jpg?fit=1200%2C800&ssl=1","datePublished":"2022-01-02T12:16:00+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/elantris\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/elantris\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/elantris\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20211229_111538.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20211229_111538.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/elantris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Elantris"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20211229_111538.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s7kvK4-elantris","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=4253"}],"version-history":[{"count":4,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4253\/revisions"}],"predecessor-version":[{"id":4260,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4253\/revisions\/4260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/4258"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=4253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=4253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=4253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}