{"id":4086,"date":"2021-05-30T08:58:08","date_gmt":"2021-05-30T12:58:08","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4086"},"modified":"2021-05-30T08:58:12","modified_gmt":"2021-05-30T12:58:12","slug":"grande-forme","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/grande-forme\/","title":{"rendered":"Grande forme"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Une amie m&#8217;a d\u00e9j\u00e0 dit : &#8220;C&#8217;est facile de se laisser abattre par la vie. Si on veut \u00eatre heureux, il faut travailler pour.&#8221; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plus le temps passe, plus je suis d&#8217;accord avec elle. Il y a tellement de choses qui vont mal dans le monde et le cerveau adore se concentrer sur ce qui va mal. Passer par-dessus cette tendance naturelle demande toute une dose de volont\u00e9 et d&#8217;optimisme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#8217;est pour \u00e7a que j&#8217;ai \u00e9t\u00e9 tent\u00e9e par <em>Grande forme<\/em>, dont le narrateur se laisse emporter par la d\u00e9prime et l&#8217;apathie. C&#8217;est \u00e0 \u00e7a que \u00e7a ressemble, un humain qui n&#8217;a plus envie de faire d&#8217;efforts.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si le narrateur a une constante dans sa vie, c&#8217;est bien son humeur : &#8220;Ce n&#8217;est pas la grande forme.&#8221; Sa copine, Jeanne, ne cache plus son agacement devant son attitude de limace. Les parents de Jeanne, qui viennent d&#8217;am\u00e9nager chez eux, non plus. Son cousin, chez qui il se r\u00e9fugie, l&#8217;intimide tellement qu&#8217;il finit par se d\u00e9barrasser d&#8217;\u00e0 peu pr\u00e8s toutes ses possessions. Et la job qu&#8217;il trouve dans un sursaut d&#8217;instinct de survie est si d\u00e9shumanisante que c&#8217;en est absurde. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La seule chose qui lui reste, c&#8217;est une malle remplie de documents : relev\u00e9s d&#8217;imp\u00f4ts, factures, photos, dessins d&#8217;enfance, etc. Et chaque jour, il doit passer une heure en compagnie d&#8217;un genre de psychoth\u00e9rapeute avec qui il num\u00e9rise, un \u00e0 un et apr\u00e8s de longues discussions et analyses, tous les documents qu&#8217;elle contient. Tous ces documents sont transf\u00e9r\u00e9s dans le Nuage et projet\u00e9s sur un immeuble de la ville pour que tout le monde puisse les voir. Une fois ce processus compl\u00e9t\u00e9, il sera enfin un bon citoyen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/prochainelecture.com\/le-meilleur-des-mondes\/\">J&#8217;ai lu <em>Le meilleur des mondes<\/em> r\u00e9cemment<\/a>, et les parall\u00e8les \u00e0 faire sont nombreux. Mais dans <em>Grande forme<\/em>, l&#8217;univers n&#8217;est pas d\u00e9crit \u00e0 proprement parler. Il n&#8217;est pas clair d\u00e8s le d\u00e9but qu&#8217;on n&#8217;est pas dans notre monde moderne : on pense seulement que le narrateur est vraiment d\u00e9prim\u00e9. C&#8217;est \u00e0 coup de petits indices par-ci par-l\u00e0 qu&#8217;on finit par saisir les conditions dans lesquelles il vit, et par se dire que dans les circonstances, on ne pourrait pas faire autrement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais ce n&#8217;est pas un livre d\u00e9primant du tout, au contraire. Il m&#8217;a fait beaucoup rire. L&#8217;apathie du personnage est telle que \u00e7a en devient absurde. Ses conditions de travail sont tellement affreuses (il n&#8217;a que des pauses de 10 minutes et les toilettes sont trop loin, alors il doit pisser dans une bouteille) et son travail lui-m\u00eame est tellement impossible (remplir une commande de m\u00e9dicaments \u00e0 chaque 7 secondes) qu&#8217;on en rit. Son cousin est compl\u00e8tement fou, sa copine se fout royalement de lui, et ses s\u00e9ances obligatoires et quotidiennes de num\u00e9risation le ruinent pour les ann\u00e9es \u00e0 venir. Difficile de faire pire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce livre n&#8217;est pas long, mais il est tr\u00e8s rafra\u00eechissant. Adeptes d&#8217;humour noir et d&#8217;absurde, vous allez l&#8217;aimer.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/grande-forme-renaud-jean-9782764626405.html\/?type=livre&#038;configuration=126&#038;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Une amie m&#8217;a d\u00e9j\u00e0 dit : &#8220;C&#8217;est facile de se laisser abattre par la vie. Si on veut \u00eatre heureux, il faut travailler pour.&#8221; Plus le temps passe, plus je suis d&#8217;accord avec elle. Il y a tellement de choses qui vont mal dans le monde et le cerveau adore se concentrer sur ce qui va mal. Passer par-dessus cette tendance naturelle demande toute une dose de volont\u00e9 et d&#8217;optimisme. C&#8217;est pour \u00e7a que j&#8217;ai \u00e9t\u00e9 tent\u00e9e par Grande forme, dont le narrateur se laisse emporter par la d\u00e9prime et l&#8217;apathie. C&#8217;est \u00e0 \u00e7a que \u00e7a ressemble, un humain qui n&#8217;a plus envie de faire d&#8217;efforts. R\u00e9sum\u00e9 Si le narrateur a une constante dans sa vie, c&#8217;est bien son humeur : &#8220;Ce n&#8217;est pas la grande forme.&#8221; Sa copine, Jeanne, ne cache plus son agacement devant son attitude de limace. Les parents de Jeanne, qui viennent d&#8217;am\u00e9nager chez eux, non plus. Son cousin, chez qui il se r\u00e9fugie, l&#8217;intimide tellement qu&#8217;il finit par se d\u00e9barrasser d&#8217;\u00e0 peu pr\u00e8s toutes ses possessions. Et la job qu&#8217;il trouve dans un sursaut d&#8217;instinct de survie est si d\u00e9shumanisante que c&#8217;en est absurde. La seule chose qui lui reste, c&#8217;est une malle remplie de documents : relev\u00e9s d&#8217;imp\u00f4ts, factures, photos, dessins d&#8217;enfance, etc. Et chaque jour, il doit passer une heure en compagnie d&#8217;un genre de psychoth\u00e9rapeute avec qui il num\u00e9rise, un \u00e0 un et apr\u00e8s de longues discussions et analyses, tous les documents qu&#8217;elle contient. Tous ces documents sont transf\u00e9r\u00e9s dans le Nuage et projet\u00e9s sur un immeuble de la ville pour que tout le monde puisse les voir. Une fois ce processus compl\u00e9t\u00e9, il sera enfin un bon citoyen. Impressions J&#8217;ai lu Le meilleur des mondes r\u00e9cemment, et les parall\u00e8les \u00e0 faire sont nombreux. Mais dans Grande forme, l&#8217;univers n&#8217;est pas d\u00e9crit \u00e0 proprement parler. Il n&#8217;est pas clair d\u00e8s le d\u00e9but qu&#8217;on n&#8217;est pas dans notre monde moderne : on pense seulement que le narrateur est vraiment d\u00e9prim\u00e9. C&#8217;est \u00e0 coup de petits indices par-ci par-l\u00e0 qu&#8217;on finit par saisir les conditions dans lesquelles il vit, et par se dire que dans les circonstances, on ne pourrait pas faire autrement. Mais ce n&#8217;est pas un livre d\u00e9primant du tout, au contraire. Il m&#8217;a fait beaucoup rire. L&#8217;apathie du personnage est telle que \u00e7a en devient absurde. Ses conditions de travail sont tellement affreuses (il n&#8217;a que des pauses de 10 minutes et les toilettes sont trop loin, alors il doit pisser dans une bouteille) et son travail lui-m\u00eame est tellement impossible (remplir une commande de m\u00e9dicaments \u00e0 chaque 7 secondes) qu&#8217;on en rit. Son cousin est compl\u00e8tement fou, sa copine se fout royalement de lui, et ses s\u00e9ances obligatoires et quotidiennes de num\u00e9risation le ruinent pour les ann\u00e9es \u00e0 venir. Difficile de faire pire. Ce livre n&#8217;est pas long, mais il est tr\u00e8s rafra\u00eechissant. Adeptes d&#8217;humour noir et d&#8217;absurde, vous allez l&#8217;aimer.<\/p>\n","protected":false},"author":1,"featured_media":4089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[245,242],"tags":[],"class_list":["post-4086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litterature-quebecoise","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grande forme - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/grande-forme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grande forme - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Une amie m&#8217;a d\u00e9j\u00e0 dit : &#8220;C&#8217;est facile de se laisser abattre par la vie. Si on veut \u00eatre heureux, il faut travailler pour.&#8221; Plus le temps passe, plus je suis d&#8217;accord avec elle. Il y a tellement de choses qui vont mal dans le monde et le cerveau adore se concentrer sur ce qui va mal. Passer par-dessus cette tendance naturelle demande toute une dose de volont\u00e9 et d&#8217;optimisme. C&#8217;est pour \u00e7a que j&#8217;ai \u00e9t\u00e9 tent\u00e9e par Grande forme, dont le narrateur se laisse emporter par la d\u00e9prime et l&#8217;apathie. C&#8217;est \u00e0 \u00e7a que \u00e7a ressemble, un humain qui n&#8217;a plus envie de faire d&#8217;efforts. R\u00e9sum\u00e9 Si le narrateur a une constante dans sa vie, c&#8217;est bien son humeur : &#8220;Ce n&#8217;est pas la grande forme.&#8221; Sa copine, Jeanne, ne cache plus son agacement devant son attitude de limace. Les parents de Jeanne, qui viennent d&#8217;am\u00e9nager chez eux, non plus. Son cousin, chez qui il se r\u00e9fugie, l&#8217;intimide tellement qu&#8217;il finit par se d\u00e9barrasser d&#8217;\u00e0 peu pr\u00e8s toutes ses possessions. Et la job qu&#8217;il trouve dans un sursaut d&#8217;instinct de survie est si d\u00e9shumanisante que c&#8217;en est absurde. La seule chose qui lui reste, c&#8217;est une malle remplie de documents : relev\u00e9s d&#8217;imp\u00f4ts, factures, photos, dessins d&#8217;enfance, etc. Et chaque jour, il doit passer une heure en compagnie d&#8217;un genre de psychoth\u00e9rapeute avec qui il num\u00e9rise, un \u00e0 un et apr\u00e8s de longues discussions et analyses, tous les documents qu&#8217;elle contient. Tous ces documents sont transf\u00e9r\u00e9s dans le Nuage et projet\u00e9s sur un immeuble de la ville pour que tout le monde puisse les voir. Une fois ce processus compl\u00e9t\u00e9, il sera enfin un bon citoyen. Impressions J&#8217;ai lu Le meilleur des mondes r\u00e9cemment, et les parall\u00e8les \u00e0 faire sont nombreux. Mais dans Grande forme, l&#8217;univers n&#8217;est pas d\u00e9crit \u00e0 proprement parler. Il n&#8217;est pas clair d\u00e8s le d\u00e9but qu&#8217;on n&#8217;est pas dans notre monde moderne : on pense seulement que le narrateur est vraiment d\u00e9prim\u00e9. C&#8217;est \u00e0 coup de petits indices par-ci par-l\u00e0 qu&#8217;on finit par saisir les conditions dans lesquelles il vit, et par se dire que dans les circonstances, on ne pourrait pas faire autrement. Mais ce n&#8217;est pas un livre d\u00e9primant du tout, au contraire. Il m&#8217;a fait beaucoup rire. L&#8217;apathie du personnage est telle que \u00e7a en devient absurde. Ses conditions de travail sont tellement affreuses (il n&#8217;a que des pauses de 10 minutes et les toilettes sont trop loin, alors il doit pisser dans une bouteille) et son travail lui-m\u00eame est tellement impossible (remplir une commande de m\u00e9dicaments \u00e0 chaque 7 secondes) qu&#8217;on en rit. Son cousin est compl\u00e8tement fou, sa copine se fout royalement de lui, et ses s\u00e9ances obligatoires et quotidiennes de num\u00e9risation le ruinent pour les ann\u00e9es \u00e0 venir. Difficile de faire pire. Ce livre n&#8217;est pas long, mais il est tr\u00e8s rafra\u00eechissant. Adeptes d&#8217;humour noir et d&#8217;absurde, vous allez l&#8217;aimer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/grande-forme\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-30T12:58:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-30T12:58:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/05\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Grande forme\",\"datePublished\":\"2021-05-30T12:58:08+00:00\",\"dateModified\":\"2021-05-30T12:58:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/\"},\"wordCount\":543,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Litt\u00e9rature qu\u00e9b\u00e9coise\",\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/\",\"name\":\"Grande forme - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2021-05-30T12:58:08+00:00\",\"dateModified\":\"2021-05-30T12:58:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/grande-forme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grande forme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grande forme - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/grande-forme\/","og_locale":"fr_CA","og_type":"article","og_title":"Grande forme - Prochaine lecture","og_description":"Une amie m&#8217;a d\u00e9j\u00e0 dit : &#8220;C&#8217;est facile de se laisser abattre par la vie. Si on veut \u00eatre heureux, il faut travailler pour.&#8221; Plus le temps passe, plus je suis d&#8217;accord avec elle. Il y a tellement de choses qui vont mal dans le monde et le cerveau adore se concentrer sur ce qui va mal. Passer par-dessus cette tendance naturelle demande toute une dose de volont\u00e9 et d&#8217;optimisme. C&#8217;est pour \u00e7a que j&#8217;ai \u00e9t\u00e9 tent\u00e9e par Grande forme, dont le narrateur se laisse emporter par la d\u00e9prime et l&#8217;apathie. C&#8217;est \u00e0 \u00e7a que \u00e7a ressemble, un humain qui n&#8217;a plus envie de faire d&#8217;efforts. R\u00e9sum\u00e9 Si le narrateur a une constante dans sa vie, c&#8217;est bien son humeur : &#8220;Ce n&#8217;est pas la grande forme.&#8221; Sa copine, Jeanne, ne cache plus son agacement devant son attitude de limace. Les parents de Jeanne, qui viennent d&#8217;am\u00e9nager chez eux, non plus. Son cousin, chez qui il se r\u00e9fugie, l&#8217;intimide tellement qu&#8217;il finit par se d\u00e9barrasser d&#8217;\u00e0 peu pr\u00e8s toutes ses possessions. Et la job qu&#8217;il trouve dans un sursaut d&#8217;instinct de survie est si d\u00e9shumanisante que c&#8217;en est absurde. La seule chose qui lui reste, c&#8217;est une malle remplie de documents : relev\u00e9s d&#8217;imp\u00f4ts, factures, photos, dessins d&#8217;enfance, etc. Et chaque jour, il doit passer une heure en compagnie d&#8217;un genre de psychoth\u00e9rapeute avec qui il num\u00e9rise, un \u00e0 un et apr\u00e8s de longues discussions et analyses, tous les documents qu&#8217;elle contient. Tous ces documents sont transf\u00e9r\u00e9s dans le Nuage et projet\u00e9s sur un immeuble de la ville pour que tout le monde puisse les voir. Une fois ce processus compl\u00e9t\u00e9, il sera enfin un bon citoyen. Impressions J&#8217;ai lu Le meilleur des mondes r\u00e9cemment, et les parall\u00e8les \u00e0 faire sont nombreux. Mais dans Grande forme, l&#8217;univers n&#8217;est pas d\u00e9crit \u00e0 proprement parler. Il n&#8217;est pas clair d\u00e8s le d\u00e9but qu&#8217;on n&#8217;est pas dans notre monde moderne : on pense seulement que le narrateur est vraiment d\u00e9prim\u00e9. C&#8217;est \u00e0 coup de petits indices par-ci par-l\u00e0 qu&#8217;on finit par saisir les conditions dans lesquelles il vit, et par se dire que dans les circonstances, on ne pourrait pas faire autrement. Mais ce n&#8217;est pas un livre d\u00e9primant du tout, au contraire. Il m&#8217;a fait beaucoup rire. L&#8217;apathie du personnage est telle que \u00e7a en devient absurde. Ses conditions de travail sont tellement affreuses (il n&#8217;a que des pauses de 10 minutes et les toilettes sont trop loin, alors il doit pisser dans une bouteille) et son travail lui-m\u00eame est tellement impossible (remplir une commande de m\u00e9dicaments \u00e0 chaque 7 secondes) qu&#8217;on en rit. Son cousin est compl\u00e8tement fou, sa copine se fout royalement de lui, et ses s\u00e9ances obligatoires et quotidiennes de num\u00e9risation le ruinent pour les ann\u00e9es \u00e0 venir. Difficile de faire pire. Ce livre n&#8217;est pas long, mais il est tr\u00e8s rafra\u00eechissant. Adeptes d&#8217;humour noir et d&#8217;absurde, vous allez l&#8217;aimer.","og_url":"https:\/\/prochainelecture.com\/fr\/grande-forme\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2021-05-30T12:58:08+00:00","article_modified_time":"2021-05-30T12:58:12+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/05\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/grande-forme\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/grande-forme\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Grande forme","datePublished":"2021-05-30T12:58:08+00:00","dateModified":"2021-05-30T12:58:12+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/grande-forme\/"},"wordCount":543,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/grande-forme\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/05\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1","articleSection":["Litt\u00e9rature qu\u00e9b\u00e9coise","Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/grande-forme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/grande-forme\/","url":"https:\/\/prochainelecture.com\/grande-forme\/","name":"Grande forme - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/grande-forme\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/grande-forme\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/05\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1","datePublished":"2021-05-30T12:58:08+00:00","dateModified":"2021-05-30T12:58:12+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/grande-forme\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/grande-forme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/grande-forme\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/05\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/05\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/grande-forme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Grande forme"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/05\/20210530_084242-1.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-13U","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=4086"}],"version-history":[{"count":4,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4086\/revisions"}],"predecessor-version":[{"id":4092,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/4086\/revisions\/4092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/4089"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=4086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=4086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=4086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}