{"id":3983,"date":"2021-02-14T14:41:37","date_gmt":"2021-02-14T18:41:37","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=3983"},"modified":"2021-02-14T15:09:29","modified_gmt":"2021-02-14T19:09:29","slug":"captifs","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/captifs\/","title":{"rendered":"Captifs"},"content":{"rendered":"\n<p>Si vous aimez souffrir pour rien, faites-vous plaisir. Mais sinon, ne lisez pas \u00e7a. J&#8217;ai un malaise juste \u00e0 en parler.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p>Ce ne sera pas long. Un psychopathe dont on ne conna\u00eet rien enferme 6 inconnus dans un bunker. Il leur donne de la bouffe via un ascenseur, jusqu&#8217;\u00e0 ce qu&#8217;il n&#8217;en donne plus. Impossible de s&#8217;\u00e9chapper. Tout le monde finit par mourir. Ce qu&#8217;on lit, c&#8217;est le journal que garde un des prisonniers. Voil\u00e0.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>J&#8217;avais entendu parler de ce livre <a href=\"https:\/\/www.nypl.org\/voices\/blogs\/blog-channels\/librarian-is-in\">via un podcast<\/a> il y a d\u00e9j\u00e0 un ou deux ans. Les animateurs ont parl\u00e9 de ce livre avec suffisamment d&#8217;enthousiasme pour que je sois s\u00e9rieusement intrigu\u00e9e et que je le garde en t\u00eate tout ce temps. Ils disaient que c&#8217;\u00e9tait un livre marquant, original, et ils ont refus\u00e9 de r\u00e9v\u00e9ler le &#8220;punch&#8221; pour r\u00e9server le &#8220;plaisir&#8221; aux lecteurs. (Oui, beaucoup de guillemets.) Ils n&#8217;\u00e9taient pas les seuls \u00e0 l&#8217;avoir aim\u00e9. En quatri\u00e8me de couverture, j&#8217;ai pu apprendre que le livre a gagn\u00e9 la m\u00e9daille <em>Carnegie<\/em>. Le <em>Times <\/em>a d\u00e9clar\u00e9 qu&#8217;il \u00e9tait &#8220;Monumental&#8221; et que &#8220;Tout le monde devrait lire ce roman.&#8221; On apprend aussi qu&#8217;il a \u00e9t\u00e9 l&#8217;objet d&#8217;une vive pol\u00e9mique en raison de sa violence et de son nihilisme radical. Avouez que \u00e7a donne envie.<\/p>\n\n\n\n<p>J&#8217;aime beaucoup l&#8217;expression &#8220;nihilisme radical&#8221; : c&#8217;est la meilleure description du livre que j&#8217;aurais pu donner. Le &#8220;punch&#8221; m&#8217;a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 simplement en feuilletant le livre, comme n&#8217;importe qui fait \u00e0 l&#8217;occasion. Le format bizarre des derni\u00e8res pages saute aux yeux : les chapitres sont de plus en plus courts, quelques lignes seulement. Pas trop compliqu\u00e9 de comprendre que ce n&#8217;est <em>pas <\/em>parce que le narrateur a r\u00e9ussi \u00e0 s&#8217;\u00e9chapper et qu&#8217;il vit heureux avec sa femme et ses enfants.<\/p>\n\n\n\n<p>Il s&#8217;agit donc d&#8217;une lecture longue et p\u00e9nible o\u00f9 on regarde six personnages plus ou moins attachants, avec plus ou moins de profondeur, perdre peu \u00e0 peu tout le maigre espoir qu&#8217;ils avaient de s&#8217;\u00e9chapper. \u00c0 la moindre tentative d&#8217;\u00e9vasion, ils se font punir s\u00e9v\u00e8rement : plus de lumi\u00e8re, plus de chauffage, plus de nourriture, des bruits assourdissants en plein milieu de la nuit. \u00c0 la fin on a carr\u00e9ment la naus\u00e9e : on dirait que leur ge\u00f4lier les a oubli\u00e9s. Il n&#8217;y a plus de nourriture du tout, plus de chauffage, et \u00e9ventuellement, plus d&#8217;eau. <\/p>\n\n\n\n<p>J&#8217;ai gard\u00e9 espoir jusqu&#8217;\u00e0 la fin. J&#8217;ai essay\u00e9 de rester positive. Je me disais que le fait qu&#8217;il n&#8217;y avait pas vraiment d&#8217;histoire \u00e9tait original en soi. Jusqu&#8217;\u00e0 la derni\u00e8re page, j&#8217;esp\u00e9rais que quelque chose de surprenant arrive, n&#8217;importe quoi. Mais non. \u00c7a finit comme \u00e7a. Tout le monde est mort de soif, de faim et de froid.<\/p>\n\n\n\n<p>C&#8217;est \u00e9pouvantable. \u00c7a donne mal au coeur. C&#8217;est profond\u00e9ment inutile. Tout le monde ne devrait <em>pas <\/em>lire ce livre. Et la traduction \u00e9tait assez mauvaise. J&#8217;admet tout de m\u00eame qu&#8217;il a la qualit\u00e9 de ne pas laisser indiff\u00e9rent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous aimez souffrir pour rien, faites-vous plaisir. Mais sinon, ne lisez pas \u00e7a. J&#8217;ai un malaise juste \u00e0 en parler. R\u00e9sum\u00e9 Ce ne sera pas long. Un psychopathe dont on ne conna\u00eet rien enferme 6 inconnus dans un bunker. Il leur donne de la bouffe via un ascenseur, jusqu&#8217;\u00e0 ce qu&#8217;il n&#8217;en donne plus. Impossible de s&#8217;\u00e9chapper. Tout le monde finit par mourir. Ce qu&#8217;on lit, c&#8217;est le journal que garde un des prisonniers. Voil\u00e0. Impressions J&#8217;avais entendu parler de ce livre via un podcast il y a d\u00e9j\u00e0 un ou deux ans. Les animateurs ont parl\u00e9 de ce livre avec suffisamment d&#8217;enthousiasme pour que je sois s\u00e9rieusement intrigu\u00e9e et que je le garde en t\u00eate tout ce temps. Ils disaient que c&#8217;\u00e9tait un livre marquant, original, et ils ont refus\u00e9 de r\u00e9v\u00e9ler le &#8220;punch&#8221; pour r\u00e9server le &#8220;plaisir&#8221; aux lecteurs. (Oui, beaucoup de guillemets.) Ils n&#8217;\u00e9taient pas les seuls \u00e0 l&#8217;avoir aim\u00e9. En quatri\u00e8me de couverture, j&#8217;ai pu apprendre que le livre a gagn\u00e9 la m\u00e9daille Carnegie. Le Times a d\u00e9clar\u00e9 qu&#8217;il \u00e9tait &#8220;Monumental&#8221; et que &#8220;Tout le monde devrait lire ce roman.&#8221; On apprend aussi qu&#8217;il a \u00e9t\u00e9 l&#8217;objet d&#8217;une vive pol\u00e9mique en raison de sa violence et de son nihilisme radical. Avouez que \u00e7a donne envie. J&#8217;aime beaucoup l&#8217;expression &#8220;nihilisme radical&#8221; : c&#8217;est la meilleure description du livre que j&#8217;aurais pu donner. Le &#8220;punch&#8221; m&#8217;a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 simplement en feuilletant le livre, comme n&#8217;importe qui fait \u00e0 l&#8217;occasion. Le format bizarre des derni\u00e8res pages saute aux yeux : les chapitres sont de plus en plus courts, quelques lignes seulement. Pas trop compliqu\u00e9 de comprendre que ce n&#8217;est pas parce que le narrateur a r\u00e9ussi \u00e0 s&#8217;\u00e9chapper et qu&#8217;il vit heureux avec sa femme et ses enfants. Il s&#8217;agit donc d&#8217;une lecture longue et p\u00e9nible o\u00f9 on regarde six personnages plus ou moins attachants, avec plus ou moins de profondeur, perdre peu \u00e0 peu tout le maigre espoir qu&#8217;ils avaient de s&#8217;\u00e9chapper. \u00c0 la moindre tentative d&#8217;\u00e9vasion, ils se font punir s\u00e9v\u00e8rement : plus de lumi\u00e8re, plus de chauffage, plus de nourriture, des bruits assourdissants en plein milieu de la nuit. \u00c0 la fin on a carr\u00e9ment la naus\u00e9e : on dirait que leur ge\u00f4lier les a oubli\u00e9s. Il n&#8217;y a plus de nourriture du tout, plus de chauffage, et \u00e9ventuellement, plus d&#8217;eau. J&#8217;ai gard\u00e9 espoir jusqu&#8217;\u00e0 la fin. J&#8217;ai essay\u00e9 de rester positive. Je me disais que le fait qu&#8217;il n&#8217;y avait pas vraiment d&#8217;histoire \u00e9tait original en soi. Jusqu&#8217;\u00e0 la derni\u00e8re page, j&#8217;esp\u00e9rais que quelque chose de surprenant arrive, n&#8217;importe quoi. Mais non. \u00c7a finit comme \u00e7a. Tout le monde est mort de soif, de faim et de froid. C&#8217;est \u00e9pouvantable. \u00c7a donne mal au coeur. C&#8217;est profond\u00e9ment inutile. Tout le monde ne devrait pas lire ce livre. Et la traduction \u00e9tait assez mauvaise. J&#8217;admet tout de m\u00eame qu&#8217;il a la qualit\u00e9 de ne pas laisser indiff\u00e9rent.<\/p>\n","protected":false},"author":1,"featured_media":3984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Si vous aimez souffrir pour rien, faites-vous plaisir. Mais sinon, ne lisez pas \u00e7a. J'ai un malaise juste \u00e0 en parler.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[280,273,242],"tags":[],"class_list":["post-3983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anti-coups-de-coeur","category-jeunesse","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Captifs - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/captifs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Captifs - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Si vous aimez souffrir pour rien, faites-vous plaisir. Mais sinon, ne lisez pas \u00e7a. J&#8217;ai un malaise juste \u00e0 en parler. R\u00e9sum\u00e9 Ce ne sera pas long. Un psychopathe dont on ne conna\u00eet rien enferme 6 inconnus dans un bunker. Il leur donne de la bouffe via un ascenseur, jusqu&#8217;\u00e0 ce qu&#8217;il n&#8217;en donne plus. Impossible de s&#8217;\u00e9chapper. Tout le monde finit par mourir. Ce qu&#8217;on lit, c&#8217;est le journal que garde un des prisonniers. Voil\u00e0. Impressions J&#8217;avais entendu parler de ce livre via un podcast il y a d\u00e9j\u00e0 un ou deux ans. Les animateurs ont parl\u00e9 de ce livre avec suffisamment d&#8217;enthousiasme pour que je sois s\u00e9rieusement intrigu\u00e9e et que je le garde en t\u00eate tout ce temps. Ils disaient que c&#8217;\u00e9tait un livre marquant, original, et ils ont refus\u00e9 de r\u00e9v\u00e9ler le &#8220;punch&#8221; pour r\u00e9server le &#8220;plaisir&#8221; aux lecteurs. (Oui, beaucoup de guillemets.) Ils n&#8217;\u00e9taient pas les seuls \u00e0 l&#8217;avoir aim\u00e9. En quatri\u00e8me de couverture, j&#8217;ai pu apprendre que le livre a gagn\u00e9 la m\u00e9daille Carnegie. Le Times a d\u00e9clar\u00e9 qu&#8217;il \u00e9tait &#8220;Monumental&#8221; et que &#8220;Tout le monde devrait lire ce roman.&#8221; On apprend aussi qu&#8217;il a \u00e9t\u00e9 l&#8217;objet d&#8217;une vive pol\u00e9mique en raison de sa violence et de son nihilisme radical. Avouez que \u00e7a donne envie. J&#8217;aime beaucoup l&#8217;expression &#8220;nihilisme radical&#8221; : c&#8217;est la meilleure description du livre que j&#8217;aurais pu donner. Le &#8220;punch&#8221; m&#8217;a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 simplement en feuilletant le livre, comme n&#8217;importe qui fait \u00e0 l&#8217;occasion. Le format bizarre des derni\u00e8res pages saute aux yeux : les chapitres sont de plus en plus courts, quelques lignes seulement. Pas trop compliqu\u00e9 de comprendre que ce n&#8217;est pas parce que le narrateur a r\u00e9ussi \u00e0 s&#8217;\u00e9chapper et qu&#8217;il vit heureux avec sa femme et ses enfants. Il s&#8217;agit donc d&#8217;une lecture longue et p\u00e9nible o\u00f9 on regarde six personnages plus ou moins attachants, avec plus ou moins de profondeur, perdre peu \u00e0 peu tout le maigre espoir qu&#8217;ils avaient de s&#8217;\u00e9chapper. \u00c0 la moindre tentative d&#8217;\u00e9vasion, ils se font punir s\u00e9v\u00e8rement : plus de lumi\u00e8re, plus de chauffage, plus de nourriture, des bruits assourdissants en plein milieu de la nuit. \u00c0 la fin on a carr\u00e9ment la naus\u00e9e : on dirait que leur ge\u00f4lier les a oubli\u00e9s. Il n&#8217;y a plus de nourriture du tout, plus de chauffage, et \u00e9ventuellement, plus d&#8217;eau. J&#8217;ai gard\u00e9 espoir jusqu&#8217;\u00e0 la fin. J&#8217;ai essay\u00e9 de rester positive. Je me disais que le fait qu&#8217;il n&#8217;y avait pas vraiment d&#8217;histoire \u00e9tait original en soi. Jusqu&#8217;\u00e0 la derni\u00e8re page, j&#8217;esp\u00e9rais que quelque chose de surprenant arrive, n&#8217;importe quoi. Mais non. \u00c7a finit comme \u00e7a. Tout le monde est mort de soif, de faim et de froid. C&#8217;est \u00e9pouvantable. \u00c7a donne mal au coeur. C&#8217;est profond\u00e9ment inutile. Tout le monde ne devrait pas lire ce livre. Et la traduction \u00e9tait assez mauvaise. J&#8217;admet tout de m\u00eame qu&#8217;il a la qualit\u00e9 de ne pas laisser indiff\u00e9rent.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/captifs\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-14T18:41:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-14T19:09:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/02\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Captifs\",\"datePublished\":\"2021-02-14T18:41:37+00:00\",\"dateModified\":\"2021-02-14T19:09:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/\"},\"wordCount\":545,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Anti coups de coeur\",\"Jeunesse\",\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/\",\"name\":\"Captifs - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2021-02-14T18:41:37+00:00\",\"dateModified\":\"2021-02-14T19:09:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/captifs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Captifs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Captifs - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/captifs\/","og_locale":"fr_CA","og_type":"article","og_title":"Captifs - Prochaine lecture","og_description":"Si vous aimez souffrir pour rien, faites-vous plaisir. Mais sinon, ne lisez pas \u00e7a. J&#8217;ai un malaise juste \u00e0 en parler. R\u00e9sum\u00e9 Ce ne sera pas long. Un psychopathe dont on ne conna\u00eet rien enferme 6 inconnus dans un bunker. Il leur donne de la bouffe via un ascenseur, jusqu&#8217;\u00e0 ce qu&#8217;il n&#8217;en donne plus. Impossible de s&#8217;\u00e9chapper. Tout le monde finit par mourir. Ce qu&#8217;on lit, c&#8217;est le journal que garde un des prisonniers. Voil\u00e0. Impressions J&#8217;avais entendu parler de ce livre via un podcast il y a d\u00e9j\u00e0 un ou deux ans. Les animateurs ont parl\u00e9 de ce livre avec suffisamment d&#8217;enthousiasme pour que je sois s\u00e9rieusement intrigu\u00e9e et que je le garde en t\u00eate tout ce temps. Ils disaient que c&#8217;\u00e9tait un livre marquant, original, et ils ont refus\u00e9 de r\u00e9v\u00e9ler le &#8220;punch&#8221; pour r\u00e9server le &#8220;plaisir&#8221; aux lecteurs. (Oui, beaucoup de guillemets.) Ils n&#8217;\u00e9taient pas les seuls \u00e0 l&#8217;avoir aim\u00e9. En quatri\u00e8me de couverture, j&#8217;ai pu apprendre que le livre a gagn\u00e9 la m\u00e9daille Carnegie. Le Times a d\u00e9clar\u00e9 qu&#8217;il \u00e9tait &#8220;Monumental&#8221; et que &#8220;Tout le monde devrait lire ce roman.&#8221; On apprend aussi qu&#8217;il a \u00e9t\u00e9 l&#8217;objet d&#8217;une vive pol\u00e9mique en raison de sa violence et de son nihilisme radical. Avouez que \u00e7a donne envie. J&#8217;aime beaucoup l&#8217;expression &#8220;nihilisme radical&#8221; : c&#8217;est la meilleure description du livre que j&#8217;aurais pu donner. Le &#8220;punch&#8221; m&#8217;a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9 simplement en feuilletant le livre, comme n&#8217;importe qui fait \u00e0 l&#8217;occasion. Le format bizarre des derni\u00e8res pages saute aux yeux : les chapitres sont de plus en plus courts, quelques lignes seulement. Pas trop compliqu\u00e9 de comprendre que ce n&#8217;est pas parce que le narrateur a r\u00e9ussi \u00e0 s&#8217;\u00e9chapper et qu&#8217;il vit heureux avec sa femme et ses enfants. Il s&#8217;agit donc d&#8217;une lecture longue et p\u00e9nible o\u00f9 on regarde six personnages plus ou moins attachants, avec plus ou moins de profondeur, perdre peu \u00e0 peu tout le maigre espoir qu&#8217;ils avaient de s&#8217;\u00e9chapper. \u00c0 la moindre tentative d&#8217;\u00e9vasion, ils se font punir s\u00e9v\u00e8rement : plus de lumi\u00e8re, plus de chauffage, plus de nourriture, des bruits assourdissants en plein milieu de la nuit. \u00c0 la fin on a carr\u00e9ment la naus\u00e9e : on dirait que leur ge\u00f4lier les a oubli\u00e9s. Il n&#8217;y a plus de nourriture du tout, plus de chauffage, et \u00e9ventuellement, plus d&#8217;eau. J&#8217;ai gard\u00e9 espoir jusqu&#8217;\u00e0 la fin. J&#8217;ai essay\u00e9 de rester positive. Je me disais que le fait qu&#8217;il n&#8217;y avait pas vraiment d&#8217;histoire \u00e9tait original en soi. Jusqu&#8217;\u00e0 la derni\u00e8re page, j&#8217;esp\u00e9rais que quelque chose de surprenant arrive, n&#8217;importe quoi. Mais non. \u00c7a finit comme \u00e7a. Tout le monde est mort de soif, de faim et de froid. C&#8217;est \u00e9pouvantable. \u00c7a donne mal au coeur. C&#8217;est profond\u00e9ment inutile. Tout le monde ne devrait pas lire ce livre. Et la traduction \u00e9tait assez mauvaise. J&#8217;admet tout de m\u00eame qu&#8217;il a la qualit\u00e9 de ne pas laisser indiff\u00e9rent.","og_url":"https:\/\/prochainelecture.com\/fr\/captifs\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2021-02-14T18:41:37+00:00","article_modified_time":"2021-02-14T19:09:29+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/02\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/captifs\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/captifs\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Captifs","datePublished":"2021-02-14T18:41:37+00:00","dateModified":"2021-02-14T19:09:29+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/captifs\/"},"wordCount":545,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/captifs\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/02\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1","articleSection":["Anti coups de coeur","Jeunesse","Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/captifs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/captifs\/","url":"https:\/\/prochainelecture.com\/captifs\/","name":"Captifs - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/captifs\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/captifs\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/02\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1","datePublished":"2021-02-14T18:41:37+00:00","dateModified":"2021-02-14T19:09:29+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/captifs\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/captifs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/captifs\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/02\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/02\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/captifs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Captifs"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2021\/02\/20210213_083103_1.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s7kvK4-captifs","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=3983"}],"version-history":[{"count":3,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3983\/revisions"}],"predecessor-version":[{"id":3987,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3983\/revisions\/3987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3984"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=3983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=3983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=3983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}