{"id":3902,"date":"2020-12-12T09:42:00","date_gmt":"2020-12-12T13:42:00","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=3902"},"modified":"2020-12-11T19:48:00","modified_gmt":"2020-12-11T23:48:00","slug":"how-proust-can-change-your-life","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/how-proust-can-change-your-life\/","title":{"rendered":"How Proust Can Change Your Life"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Je n&#8217;aurais jamais entendu parler de ce livre si je ne l&#8217;avais pas re\u00e7u en cadeau. \u00c7a aurait \u00e9t\u00e9 trop dommage.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">On le sait, Proust est un g\u00e9nie. En tout cas, beaucoup de gens le pensent, <a href=\"https:\/\/prochainelecture.com\/du-cote-de-chez-swann\/\">moi y compris<\/a>. Son sens de l&#8217;observation absolument extraordinaire peut nous faire r\u00e9aliser que certains d\u00e9tails qui passent souvent inaper\u00e7us sont en fait de la plus haute importance. Il refuse les clich\u00e9s, tente, comme un peintre le ferait, de d\u00e9crire le plus exactement possible ce qu&#8217;il voit et ce qu&#8217;il ressent, ce qui nous pousse \u00e0 ouvrir les yeux et \u00e0 r\u00e9ellement observer ce qu&#8217;il y a autour de nous et en nous. Si on le lit avec attention, il peut nous apprendre \u00e0 mieux nous conna\u00eetre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le probl\u00e8me, c&#8217;est que son oeuvre est interminable. Comme son fr\u00e8re, Robert, l&#8217;a dit :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>The sad thing is that people to be very ill or have broken a leg in order to have the opportunity to read <em>In Search of Lost Time<\/em>.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Non seulement l&#8217;oeuvre, mais les phrases \u00e0 l&#8217;int\u00e9rieur sont interminables. \u00c7a a son charme, mais disons qu&#8217;il faut qu&#8217;il nous reste du jus de cerveau \u00e0 la fin de la journ\u00e9e si on ne veut pas se perdre 8 fois par phrase. C&#8217;est une oeuvre immens\u00e9ment riche, mais pas \u00e9vidente d&#8217;approche. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alain de Botton a donc eu la brillante id\u00e9e de condenser les enseignements qu&#8217;on peut en retirer dans un petit volume de 200 pages. Il nous apprend notamment comment donner un sens \u00e0 notre souffrance, comment ouvrir les yeux, comment \u00eatre un bon ami, comment \u00eatre heureux en amour&#8230; et comment comprendre l&#8217;oeuvre de ce brillant auteur.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Avant m\u00eame d&#8217;ouvrir le livre, j&#8217;avais l&#8217;impression qu&#8217;il avait \u00e9t\u00e9 \u00e9crit pour moi. Mais honn\u00eatement, je me p\u00e9tais les bretelles. Il a en fait \u00e9t\u00e9 \u00e9crit pour tous ceux qui ont le moindre int\u00e9r\u00eat pour le d\u00e9veloppement personnel et pour Proust.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derri\u00e8re ce livre il doit y avoir un travail de recherche extraordinaire. Non seulement il fait une tr\u00e8s bonne analyse de son oeuvre, ce qui en soi est un exploit, mais il y a \u00e9galement des citations savoureuses de l&#8217;auteur tir\u00e9es de toutes sortes de documents autres que La Recherche, des t\u00e9moignages de ses amis, des faits sur sa famille, des anecdotes, etc. Le tout ficel\u00e9 avec finesse, humour, et concision (pour faire changement).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et ce n&#8217;est pas tout : les enseignements qu&#8217;il tire sont brillants. Ils m&#8217;ont fait r\u00e9fl\u00e9chir et m&#8217;ont m\u00eame \u00e9mu. Ils sont beaux. Ils font du bien. Ils sortent de l&#8217;ordinaire. \u00c0 la parfaite image de l&#8217;oeuvre de Proust.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme vous pouvez le voir, je suis d&#8217;un enthousiasme assez d\u00e9bordant. Et je suis s\u00fbre, amis fans de Proust et de d\u00e9veloppement personnel, que vous le serez \u00e9galement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je n&#8217;aurais jamais entendu parler de ce livre si je ne l&#8217;avais pas re\u00e7u en cadeau. \u00c7a aurait \u00e9t\u00e9 trop dommage. R\u00e9sum\u00e9 On le sait, Proust est un g\u00e9nie. En tout cas, beaucoup de gens le pensent, moi y compris. Son sens de l&#8217;observation absolument extraordinaire peut nous faire r\u00e9aliser que certains d\u00e9tails qui passent souvent inaper\u00e7us sont en fait de la plus haute importance. Il refuse les clich\u00e9s, tente, comme un peintre le ferait, de d\u00e9crire le plus exactement possible ce qu&#8217;il voit et ce qu&#8217;il ressent, ce qui nous pousse \u00e0 ouvrir les yeux et \u00e0 r\u00e9ellement observer ce qu&#8217;il y a autour de nous et en nous. Si on le lit avec attention, il peut nous apprendre \u00e0 mieux nous conna\u00eetre. Le probl\u00e8me, c&#8217;est que son oeuvre est interminable. Comme son fr\u00e8re, Robert, l&#8217;a dit : The sad thing is that people to be very ill or have broken a leg in order to have the opportunity to read In Search of Lost Time. Non seulement l&#8217;oeuvre, mais les phrases \u00e0 l&#8217;int\u00e9rieur sont interminables. \u00c7a a son charme, mais disons qu&#8217;il faut qu&#8217;il nous reste du jus de cerveau \u00e0 la fin de la journ\u00e9e si on ne veut pas se perdre 8 fois par phrase. C&#8217;est une oeuvre immens\u00e9ment riche, mais pas \u00e9vidente d&#8217;approche. Alain de Botton a donc eu la brillante id\u00e9e de condenser les enseignements qu&#8217;on peut en retirer dans un petit volume de 200 pages. Il nous apprend notamment comment donner un sens \u00e0 notre souffrance, comment ouvrir les yeux, comment \u00eatre un bon ami, comment \u00eatre heureux en amour&#8230; et comment comprendre l&#8217;oeuvre de ce brillant auteur. Impressions Avant m\u00eame d&#8217;ouvrir le livre, j&#8217;avais l&#8217;impression qu&#8217;il avait \u00e9t\u00e9 \u00e9crit pour moi. Mais honn\u00eatement, je me p\u00e9tais les bretelles. Il a en fait \u00e9t\u00e9 \u00e9crit pour tous ceux qui ont le moindre int\u00e9r\u00eat pour le d\u00e9veloppement personnel et pour Proust. Derri\u00e8re ce livre il doit y avoir un travail de recherche extraordinaire. Non seulement il fait une tr\u00e8s bonne analyse de son oeuvre, ce qui en soi est un exploit, mais il y a \u00e9galement des citations savoureuses de l&#8217;auteur tir\u00e9es de toutes sortes de documents autres que La Recherche, des t\u00e9moignages de ses amis, des faits sur sa famille, des anecdotes, etc. Le tout ficel\u00e9 avec finesse, humour, et concision (pour faire changement). Et ce n&#8217;est pas tout : les enseignements qu&#8217;il tire sont brillants. Ils m&#8217;ont fait r\u00e9fl\u00e9chir et m&#8217;ont m\u00eame \u00e9mu. Ils sont beaux. Ils font du bien. Ils sortent de l&#8217;ordinaire. \u00c0 la parfaite image de l&#8217;oeuvre de Proust. Comme vous pouvez le voir, je suis d&#8217;un enthousiasme assez d\u00e9bordant. Et je suis s\u00fbre, amis fans de Proust et de d\u00e9veloppement personnel, que vous le serez \u00e9galement.<\/p>\n","protected":false},"author":1,"featured_media":3904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[274,255,254,249],"tags":[],"class_list":["post-3902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biographies","category-coups-de-coeur","category-developpement-personnel","category-se-renseigner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How Proust Can Change Your Life - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/how-proust-can-change-your-life\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How Proust Can Change Your Life - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Je n&#8217;aurais jamais entendu parler de ce livre si je ne l&#8217;avais pas re\u00e7u en cadeau. \u00c7a aurait \u00e9t\u00e9 trop dommage. R\u00e9sum\u00e9 On le sait, Proust est un g\u00e9nie. En tout cas, beaucoup de gens le pensent, moi y compris. Son sens de l&#8217;observation absolument extraordinaire peut nous faire r\u00e9aliser que certains d\u00e9tails qui passent souvent inaper\u00e7us sont en fait de la plus haute importance. Il refuse les clich\u00e9s, tente, comme un peintre le ferait, de d\u00e9crire le plus exactement possible ce qu&#8217;il voit et ce qu&#8217;il ressent, ce qui nous pousse \u00e0 ouvrir les yeux et \u00e0 r\u00e9ellement observer ce qu&#8217;il y a autour de nous et en nous. Si on le lit avec attention, il peut nous apprendre \u00e0 mieux nous conna\u00eetre. Le probl\u00e8me, c&#8217;est que son oeuvre est interminable. Comme son fr\u00e8re, Robert, l&#8217;a dit : The sad thing is that people to be very ill or have broken a leg in order to have the opportunity to read In Search of Lost Time. Non seulement l&#8217;oeuvre, mais les phrases \u00e0 l&#8217;int\u00e9rieur sont interminables. \u00c7a a son charme, mais disons qu&#8217;il faut qu&#8217;il nous reste du jus de cerveau \u00e0 la fin de la journ\u00e9e si on ne veut pas se perdre 8 fois par phrase. C&#8217;est une oeuvre immens\u00e9ment riche, mais pas \u00e9vidente d&#8217;approche. Alain de Botton a donc eu la brillante id\u00e9e de condenser les enseignements qu&#8217;on peut en retirer dans un petit volume de 200 pages. Il nous apprend notamment comment donner un sens \u00e0 notre souffrance, comment ouvrir les yeux, comment \u00eatre un bon ami, comment \u00eatre heureux en amour&#8230; et comment comprendre l&#8217;oeuvre de ce brillant auteur. Impressions Avant m\u00eame d&#8217;ouvrir le livre, j&#8217;avais l&#8217;impression qu&#8217;il avait \u00e9t\u00e9 \u00e9crit pour moi. Mais honn\u00eatement, je me p\u00e9tais les bretelles. Il a en fait \u00e9t\u00e9 \u00e9crit pour tous ceux qui ont le moindre int\u00e9r\u00eat pour le d\u00e9veloppement personnel et pour Proust. Derri\u00e8re ce livre il doit y avoir un travail de recherche extraordinaire. Non seulement il fait une tr\u00e8s bonne analyse de son oeuvre, ce qui en soi est un exploit, mais il y a \u00e9galement des citations savoureuses de l&#8217;auteur tir\u00e9es de toutes sortes de documents autres que La Recherche, des t\u00e9moignages de ses amis, des faits sur sa famille, des anecdotes, etc. Le tout ficel\u00e9 avec finesse, humour, et concision (pour faire changement). Et ce n&#8217;est pas tout : les enseignements qu&#8217;il tire sont brillants. Ils m&#8217;ont fait r\u00e9fl\u00e9chir et m&#8217;ont m\u00eame \u00e9mu. Ils sont beaux. Ils font du bien. Ils sortent de l&#8217;ordinaire. \u00c0 la parfaite image de l&#8217;oeuvre de Proust. Comme vous pouvez le voir, je suis d&#8217;un enthousiasme assez d\u00e9bordant. Et je suis s\u00fbre, amis fans de Proust et de d\u00e9veloppement personnel, que vous le serez \u00e9galement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/how-proust-can-change-your-life\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-12T13:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"How Proust Can Change Your Life\",\"datePublished\":\"2020-12-12T13:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/\"},\"wordCount\":513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Biographies\",\"Coups de coeur\",\"D\u00e9veloppement personnel\",\"Se renseigner\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/\",\"name\":\"How Proust Can Change Your Life - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2020-12-12T13:42:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/how-proust-can-change-your-life\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Proust Can Change Your Life\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"How Proust Can Change Your Life - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/how-proust-can-change-your-life\/","og_locale":"fr_CA","og_type":"article","og_title":"How Proust Can Change Your Life - Prochaine lecture","og_description":"Je n&#8217;aurais jamais entendu parler de ce livre si je ne l&#8217;avais pas re\u00e7u en cadeau. \u00c7a aurait \u00e9t\u00e9 trop dommage. R\u00e9sum\u00e9 On le sait, Proust est un g\u00e9nie. En tout cas, beaucoup de gens le pensent, moi y compris. Son sens de l&#8217;observation absolument extraordinaire peut nous faire r\u00e9aliser que certains d\u00e9tails qui passent souvent inaper\u00e7us sont en fait de la plus haute importance. Il refuse les clich\u00e9s, tente, comme un peintre le ferait, de d\u00e9crire le plus exactement possible ce qu&#8217;il voit et ce qu&#8217;il ressent, ce qui nous pousse \u00e0 ouvrir les yeux et \u00e0 r\u00e9ellement observer ce qu&#8217;il y a autour de nous et en nous. Si on le lit avec attention, il peut nous apprendre \u00e0 mieux nous conna\u00eetre. Le probl\u00e8me, c&#8217;est que son oeuvre est interminable. Comme son fr\u00e8re, Robert, l&#8217;a dit : The sad thing is that people to be very ill or have broken a leg in order to have the opportunity to read In Search of Lost Time. Non seulement l&#8217;oeuvre, mais les phrases \u00e0 l&#8217;int\u00e9rieur sont interminables. \u00c7a a son charme, mais disons qu&#8217;il faut qu&#8217;il nous reste du jus de cerveau \u00e0 la fin de la journ\u00e9e si on ne veut pas se perdre 8 fois par phrase. C&#8217;est une oeuvre immens\u00e9ment riche, mais pas \u00e9vidente d&#8217;approche. Alain de Botton a donc eu la brillante id\u00e9e de condenser les enseignements qu&#8217;on peut en retirer dans un petit volume de 200 pages. Il nous apprend notamment comment donner un sens \u00e0 notre souffrance, comment ouvrir les yeux, comment \u00eatre un bon ami, comment \u00eatre heureux en amour&#8230; et comment comprendre l&#8217;oeuvre de ce brillant auteur. Impressions Avant m\u00eame d&#8217;ouvrir le livre, j&#8217;avais l&#8217;impression qu&#8217;il avait \u00e9t\u00e9 \u00e9crit pour moi. Mais honn\u00eatement, je me p\u00e9tais les bretelles. Il a en fait \u00e9t\u00e9 \u00e9crit pour tous ceux qui ont le moindre int\u00e9r\u00eat pour le d\u00e9veloppement personnel et pour Proust. Derri\u00e8re ce livre il doit y avoir un travail de recherche extraordinaire. Non seulement il fait une tr\u00e8s bonne analyse de son oeuvre, ce qui en soi est un exploit, mais il y a \u00e9galement des citations savoureuses de l&#8217;auteur tir\u00e9es de toutes sortes de documents autres que La Recherche, des t\u00e9moignages de ses amis, des faits sur sa famille, des anecdotes, etc. Le tout ficel\u00e9 avec finesse, humour, et concision (pour faire changement). Et ce n&#8217;est pas tout : les enseignements qu&#8217;il tire sont brillants. Ils m&#8217;ont fait r\u00e9fl\u00e9chir et m&#8217;ont m\u00eame \u00e9mu. Ils sont beaux. Ils font du bien. Ils sortent de l&#8217;ordinaire. \u00c0 la parfaite image de l&#8217;oeuvre de Proust. Comme vous pouvez le voir, je suis d&#8217;un enthousiasme assez d\u00e9bordant. Et je suis s\u00fbre, amis fans de Proust et de d\u00e9veloppement personnel, que vous le serez \u00e9galement.","og_url":"https:\/\/prochainelecture.com\/fr\/how-proust-can-change-your-life\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2020-12-12T13:42:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"How Proust Can Change Your Life","datePublished":"2020-12-12T13:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1","articleSection":["Biographies","Coups de coeur","D\u00e9veloppement personnel","Se renseigner"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/","url":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/","name":"How Proust Can Change Your Life - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1","datePublished":"2020-12-12T13:42:00+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/how-proust-can-change-your-life\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"How Proust Can Change Your Life"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201208_190830-1.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-10W","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=3902"}],"version-history":[{"count":3,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3902\/revisions"}],"predecessor-version":[{"id":3906,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3902\/revisions\/3906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3904"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=3902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=3902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=3902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}