{"id":3858,"date":"2020-11-23T08:31:00","date_gmt":"2020-11-23T12:31:00","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=3858"},"modified":"2020-11-23T11:17:42","modified_gmt":"2020-11-23T15:17:42","slug":"limmense-fatigue-des-pierres","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/limmense-fatigue-des-pierres\/","title":{"rendered":"L&#8217;immense fatigue des pierres"},"content":{"rendered":"\n<p><a href=\"https:\/\/prochainelecture.com\/deux-romans-quebecois-sur-la-deuxieme-guerre-mondiale\/\">Toujours sur le th\u00e8me des romans sur la Deuxi\u00e8me Guerre mondiale<\/a>, j&#8217;ai d\u00fb lire dans un cours ce texte de R\u00e9gine Robin. Fascinante femme : n\u00e9e en France d&#8217;une famille juive polonaise en 1939, anciennement professeure \u00e0 l&#8217;UQAM en sociologie, historienne, qui a \u00e9crit une histoire de la linguistique et qui \u00e9crit des romans. Elle a donc v\u00e9cu la Shoah dans les premi\u00e8res ann\u00e9es de sa vie. Le livre en parle, mais j&#8217;ai d\u00e9cid\u00e9 de ne pas l&#8217;inclure dans ma liste pr\u00e9c\u00e9dente, car il est tellement original que le classer serait ne pas lui rendre pleinement hommage.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p>Il est bien difficile de vous proposer un r\u00e9sum\u00e9 concluant. On peut toutefois dire que le livre est compos\u00e9 de textes qui s&#8217;apparentent \u00e0 des nouvelles, mais que des noms, des personnages et des lieux reviennent. Dans un de ces textes, clairement inspir\u00e9 des souvenirs de l&#8217;auteur, une petite fille juive doit se cacher dans un garage pour \u00e9viter les rafles. Dans un autre, la petite-fille d&#8217;une femme qui a v\u00e9cu la Pologne avant la Shoah est en conflit avec sa m\u00e8re et tente de renouer avec la m\u00e9moire de sa grand-m\u00e8re. Dans un autre, un professeur de litt\u00e9rature se cr\u00e9e sur Internet un alias qui s&#8217;av\u00e9rera un peu trop r\u00e9aliste. Dans un autre enfin, une \u00e9crivaine tente d&#8217;\u00e9crire sur les membres disparus de sa famille. <\/p>\n\n\n\n<p>Tous ces textes ont un point en commun : ils portent sur la m\u00e9moire. Tous ces textes abordent, par le biais de la fiction, les enjeux auxquels sont confront\u00e9s les survivants de la Shoah et les descendants de ces survivants, notamment les enjeux d&#8217;identit\u00e9, de m\u00e9moire et de langue.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>Ce livre m&#8217;a beaucoup impressionn\u00e9e. R\u00e9gine Robin a mis le doigt sur un aspect qui m&#8217;int\u00e9ressait beaucoup sans le savoir : la difficult\u00e9 de repr\u00e9senter correctement des souvenirs charg\u00e9s d&#8217;\u00e9motion. Comment, en effet, peut-on passer \u00e0 des lecteurs \u00e9trangers \u00e0 notre r\u00e9alit\u00e9 des \u00e9motions que nous \u00e9prouvons ou que nous avons \u00e9prouv\u00e9es nous m\u00eames? Comment construire un r\u00e9cit qui rend hommage \u00e0 ces gens du pass\u00e9 et \u00e0 ces souvenirs sans tomber dans la mi\u00e8vrerie? C&#8217;est tr\u00e8s difficile. Et dans le cas d&#8217;un \u00e9v\u00e9nement aussi vaste et traumatique que celui de la Shoah, si on n&#8217;est pas nous-m\u00eames survivants et qu&#8217;on peut difficilement rajouter quelque chose aux nombreux t\u00e9moignages existants, peut-\u00eatre est-ce tout simplement impossible. <\/p>\n\n\n\n<p>Alors l&#8217;auteure a d\u00e9cid\u00e9 de sortir de \u00e7a carr\u00e9ment. Plut\u00f4t qu&#8217;une autobiographie, elle a \u00e9crit un roman. Plut\u00f4t que de construire un r\u00e9cit, elle en a \u00e9crit plusieurs, de formes vari\u00e9es. Plut\u00f4t que d&#8217;essayer de nous tirer des larmes, elle a tent\u00e9 de rendre compte, de nous laisser comprendre par nous-m\u00eames. <\/p>\n\n\n\n<p>J&#8217;ai trouv\u00e9 ce livre brillant. Il est dense. Il m&#8217;a fait beaucoup r\u00e9fl\u00e9chir. Il m\u00e9riterait certainement une deuxi\u00e8me lecture.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toujours sur le th\u00e8me des romans sur la Deuxi\u00e8me Guerre mondiale, j&#8217;ai d\u00fb lire dans un cours ce texte de R\u00e9gine Robin. Fascinante femme : n\u00e9e en France d&#8217;une famille juive polonaise en 1939, anciennement professeure \u00e0 l&#8217;UQAM en sociologie, historienne, qui a \u00e9crit une histoire de la linguistique et qui \u00e9crit des romans. Elle a donc v\u00e9cu la Shoah dans les premi\u00e8res ann\u00e9es de sa vie. Le livre en parle, mais j&#8217;ai d\u00e9cid\u00e9 de ne pas l&#8217;inclure dans ma liste pr\u00e9c\u00e9dente, car il est tellement original que le classer serait ne pas lui rendre pleinement hommage. R\u00e9sum\u00e9 Il est bien difficile de vous proposer un r\u00e9sum\u00e9 concluant. On peut toutefois dire que le livre est compos\u00e9 de textes qui s&#8217;apparentent \u00e0 des nouvelles, mais que des noms, des personnages et des lieux reviennent. Dans un de ces textes, clairement inspir\u00e9 des souvenirs de l&#8217;auteur, une petite fille juive doit se cacher dans un garage pour \u00e9viter les rafles. Dans un autre, la petite-fille d&#8217;une femme qui a v\u00e9cu la Pologne avant la Shoah est en conflit avec sa m\u00e8re et tente de renouer avec la m\u00e9moire de sa grand-m\u00e8re. Dans un autre, un professeur de litt\u00e9rature se cr\u00e9e sur Internet un alias qui s&#8217;av\u00e9rera un peu trop r\u00e9aliste. Dans un autre enfin, une \u00e9crivaine tente d&#8217;\u00e9crire sur les membres disparus de sa famille. Tous ces textes ont un point en commun : ils portent sur la m\u00e9moire. Tous ces textes abordent, par le biais de la fiction, les enjeux auxquels sont confront\u00e9s les survivants de la Shoah et les descendants de ces survivants, notamment les enjeux d&#8217;identit\u00e9, de m\u00e9moire et de langue. Impressions Ce livre m&#8217;a beaucoup impressionn\u00e9e. R\u00e9gine Robin a mis le doigt sur un aspect qui m&#8217;int\u00e9ressait beaucoup sans le savoir : la difficult\u00e9 de repr\u00e9senter correctement des souvenirs charg\u00e9s d&#8217;\u00e9motion. Comment, en effet, peut-on passer \u00e0 des lecteurs \u00e9trangers \u00e0 notre r\u00e9alit\u00e9 des \u00e9motions que nous \u00e9prouvons ou que nous avons \u00e9prouv\u00e9es nous m\u00eames? Comment construire un r\u00e9cit qui rend hommage \u00e0 ces gens du pass\u00e9 et \u00e0 ces souvenirs sans tomber dans la mi\u00e8vrerie? C&#8217;est tr\u00e8s difficile. Et dans le cas d&#8217;un \u00e9v\u00e9nement aussi vaste et traumatique que celui de la Shoah, si on n&#8217;est pas nous-m\u00eames survivants et qu&#8217;on peut difficilement rajouter quelque chose aux nombreux t\u00e9moignages existants, peut-\u00eatre est-ce tout simplement impossible. Alors l&#8217;auteure a d\u00e9cid\u00e9 de sortir de \u00e7a carr\u00e9ment. Plut\u00f4t qu&#8217;une autobiographie, elle a \u00e9crit un roman. Plut\u00f4t que de construire un r\u00e9cit, elle en a \u00e9crit plusieurs, de formes vari\u00e9es. Plut\u00f4t que d&#8217;essayer de nous tirer des larmes, elle a tent\u00e9 de rendre compte, de nous laisser comprendre par nous-m\u00eames. J&#8217;ai trouv\u00e9 ce livre brillant. Il est dense. Il m&#8217;a fait beaucoup r\u00e9fl\u00e9chir. Il m\u00e9riterait certainement une deuxi\u00e8me lecture.<\/p>\n","protected":false},"author":1,"featured_media":3860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Il y a certaines choses qui se mettent bien mal en r\u00e9cit. La m\u00e9moire d'un \u00e9v\u00e9nement aussi vaste et traumatique que la Shoah en est une. Alors que faire pour rendre compte, pour rendre hommage? R\u00e9gine Robin propose une solution. Et elle est brillante. ","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[276,245,242,249],"tags":[],"class_list":["post-3858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-litterature-quebecoise","category-se-distraire","category-se-renseigner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;immense fatigue des pierres - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/limmense-fatigue-des-pierres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;immense fatigue des pierres - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Toujours sur le th\u00e8me des romans sur la Deuxi\u00e8me Guerre mondiale, j&#8217;ai d\u00fb lire dans un cours ce texte de R\u00e9gine Robin. Fascinante femme : n\u00e9e en France d&#8217;une famille juive polonaise en 1939, anciennement professeure \u00e0 l&#8217;UQAM en sociologie, historienne, qui a \u00e9crit une histoire de la linguistique et qui \u00e9crit des romans. Elle a donc v\u00e9cu la Shoah dans les premi\u00e8res ann\u00e9es de sa vie. Le livre en parle, mais j&#8217;ai d\u00e9cid\u00e9 de ne pas l&#8217;inclure dans ma liste pr\u00e9c\u00e9dente, car il est tellement original que le classer serait ne pas lui rendre pleinement hommage. R\u00e9sum\u00e9 Il est bien difficile de vous proposer un r\u00e9sum\u00e9 concluant. On peut toutefois dire que le livre est compos\u00e9 de textes qui s&#8217;apparentent \u00e0 des nouvelles, mais que des noms, des personnages et des lieux reviennent. Dans un de ces textes, clairement inspir\u00e9 des souvenirs de l&#8217;auteur, une petite fille juive doit se cacher dans un garage pour \u00e9viter les rafles. Dans un autre, la petite-fille d&#8217;une femme qui a v\u00e9cu la Pologne avant la Shoah est en conflit avec sa m\u00e8re et tente de renouer avec la m\u00e9moire de sa grand-m\u00e8re. Dans un autre, un professeur de litt\u00e9rature se cr\u00e9e sur Internet un alias qui s&#8217;av\u00e9rera un peu trop r\u00e9aliste. Dans un autre enfin, une \u00e9crivaine tente d&#8217;\u00e9crire sur les membres disparus de sa famille. Tous ces textes ont un point en commun : ils portent sur la m\u00e9moire. Tous ces textes abordent, par le biais de la fiction, les enjeux auxquels sont confront\u00e9s les survivants de la Shoah et les descendants de ces survivants, notamment les enjeux d&#8217;identit\u00e9, de m\u00e9moire et de langue. Impressions Ce livre m&#8217;a beaucoup impressionn\u00e9e. R\u00e9gine Robin a mis le doigt sur un aspect qui m&#8217;int\u00e9ressait beaucoup sans le savoir : la difficult\u00e9 de repr\u00e9senter correctement des souvenirs charg\u00e9s d&#8217;\u00e9motion. Comment, en effet, peut-on passer \u00e0 des lecteurs \u00e9trangers \u00e0 notre r\u00e9alit\u00e9 des \u00e9motions que nous \u00e9prouvons ou que nous avons \u00e9prouv\u00e9es nous m\u00eames? Comment construire un r\u00e9cit qui rend hommage \u00e0 ces gens du pass\u00e9 et \u00e0 ces souvenirs sans tomber dans la mi\u00e8vrerie? C&#8217;est tr\u00e8s difficile. Et dans le cas d&#8217;un \u00e9v\u00e9nement aussi vaste et traumatique que celui de la Shoah, si on n&#8217;est pas nous-m\u00eames survivants et qu&#8217;on peut difficilement rajouter quelque chose aux nombreux t\u00e9moignages existants, peut-\u00eatre est-ce tout simplement impossible. Alors l&#8217;auteure a d\u00e9cid\u00e9 de sortir de \u00e7a carr\u00e9ment. Plut\u00f4t qu&#8217;une autobiographie, elle a \u00e9crit un roman. Plut\u00f4t que de construire un r\u00e9cit, elle en a \u00e9crit plusieurs, de formes vari\u00e9es. Plut\u00f4t que d&#8217;essayer de nous tirer des larmes, elle a tent\u00e9 de rendre compte, de nous laisser comprendre par nous-m\u00eames. J&#8217;ai trouv\u00e9 ce livre brillant. Il est dense. Il m&#8217;a fait beaucoup r\u00e9fl\u00e9chir. Il m\u00e9riterait certainement une deuxi\u00e8me lecture.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/limmense-fatigue-des-pierres\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-23T12:31:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-23T15:17:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/11\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"L&#8217;immense fatigue des pierres\",\"datePublished\":\"2020-11-23T12:31:00+00:00\",\"dateModified\":\"2020-11-23T15:17:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/\"},\"wordCount\":527,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Histoire\",\"Litt\u00e9rature qu\u00e9b\u00e9coise\",\"Se distraire\",\"Se renseigner\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/\",\"name\":\"L'immense fatigue des pierres - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2020-11-23T12:31:00+00:00\",\"dateModified\":\"2020-11-23T15:17:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/limmense-fatigue-des-pierres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;immense fatigue des pierres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'immense fatigue des pierres - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/limmense-fatigue-des-pierres\/","og_locale":"fr_CA","og_type":"article","og_title":"L'immense fatigue des pierres - Prochaine lecture","og_description":"Toujours sur le th\u00e8me des romans sur la Deuxi\u00e8me Guerre mondiale, j&#8217;ai d\u00fb lire dans un cours ce texte de R\u00e9gine Robin. Fascinante femme : n\u00e9e en France d&#8217;une famille juive polonaise en 1939, anciennement professeure \u00e0 l&#8217;UQAM en sociologie, historienne, qui a \u00e9crit une histoire de la linguistique et qui \u00e9crit des romans. Elle a donc v\u00e9cu la Shoah dans les premi\u00e8res ann\u00e9es de sa vie. Le livre en parle, mais j&#8217;ai d\u00e9cid\u00e9 de ne pas l&#8217;inclure dans ma liste pr\u00e9c\u00e9dente, car il est tellement original que le classer serait ne pas lui rendre pleinement hommage. R\u00e9sum\u00e9 Il est bien difficile de vous proposer un r\u00e9sum\u00e9 concluant. On peut toutefois dire que le livre est compos\u00e9 de textes qui s&#8217;apparentent \u00e0 des nouvelles, mais que des noms, des personnages et des lieux reviennent. Dans un de ces textes, clairement inspir\u00e9 des souvenirs de l&#8217;auteur, une petite fille juive doit se cacher dans un garage pour \u00e9viter les rafles. Dans un autre, la petite-fille d&#8217;une femme qui a v\u00e9cu la Pologne avant la Shoah est en conflit avec sa m\u00e8re et tente de renouer avec la m\u00e9moire de sa grand-m\u00e8re. Dans un autre, un professeur de litt\u00e9rature se cr\u00e9e sur Internet un alias qui s&#8217;av\u00e9rera un peu trop r\u00e9aliste. Dans un autre enfin, une \u00e9crivaine tente d&#8217;\u00e9crire sur les membres disparus de sa famille. Tous ces textes ont un point en commun : ils portent sur la m\u00e9moire. Tous ces textes abordent, par le biais de la fiction, les enjeux auxquels sont confront\u00e9s les survivants de la Shoah et les descendants de ces survivants, notamment les enjeux d&#8217;identit\u00e9, de m\u00e9moire et de langue. Impressions Ce livre m&#8217;a beaucoup impressionn\u00e9e. R\u00e9gine Robin a mis le doigt sur un aspect qui m&#8217;int\u00e9ressait beaucoup sans le savoir : la difficult\u00e9 de repr\u00e9senter correctement des souvenirs charg\u00e9s d&#8217;\u00e9motion. Comment, en effet, peut-on passer \u00e0 des lecteurs \u00e9trangers \u00e0 notre r\u00e9alit\u00e9 des \u00e9motions que nous \u00e9prouvons ou que nous avons \u00e9prouv\u00e9es nous m\u00eames? Comment construire un r\u00e9cit qui rend hommage \u00e0 ces gens du pass\u00e9 et \u00e0 ces souvenirs sans tomber dans la mi\u00e8vrerie? C&#8217;est tr\u00e8s difficile. Et dans le cas d&#8217;un \u00e9v\u00e9nement aussi vaste et traumatique que celui de la Shoah, si on n&#8217;est pas nous-m\u00eames survivants et qu&#8217;on peut difficilement rajouter quelque chose aux nombreux t\u00e9moignages existants, peut-\u00eatre est-ce tout simplement impossible. Alors l&#8217;auteure a d\u00e9cid\u00e9 de sortir de \u00e7a carr\u00e9ment. Plut\u00f4t qu&#8217;une autobiographie, elle a \u00e9crit un roman. Plut\u00f4t que de construire un r\u00e9cit, elle en a \u00e9crit plusieurs, de formes vari\u00e9es. Plut\u00f4t que d&#8217;essayer de nous tirer des larmes, elle a tent\u00e9 de rendre compte, de nous laisser comprendre par nous-m\u00eames. J&#8217;ai trouv\u00e9 ce livre brillant. Il est dense. Il m&#8217;a fait beaucoup r\u00e9fl\u00e9chir. Il m\u00e9riterait certainement une deuxi\u00e8me lecture.","og_url":"https:\/\/prochainelecture.com\/fr\/limmense-fatigue-des-pierres\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2020-11-23T12:31:00+00:00","article_modified_time":"2020-11-23T15:17:42+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i2.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/11\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"L&#8217;immense fatigue des pierres","datePublished":"2020-11-23T12:31:00+00:00","dateModified":"2020-11-23T15:17:42+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/"},"wordCount":527,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/11\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1","articleSection":["Histoire","Litt\u00e9rature qu\u00e9b\u00e9coise","Se distraire","Se renseigner"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/","url":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/","name":"L'immense fatigue des pierres - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/11\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1","datePublished":"2020-11-23T12:31:00+00:00","dateModified":"2020-11-23T15:17:42+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/11\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/11\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/limmense-fatigue-des-pierres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;immense fatigue des pierres"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/11\/20201121_152959_HDR_cut.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-10e","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=3858"}],"version-history":[{"count":3,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3858\/revisions"}],"predecessor-version":[{"id":3862,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3858\/revisions\/3862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3860"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=3858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=3858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=3858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}