{"id":3807,"date":"2020-12-02T09:00:00","date_gmt":"2020-12-02T13:00:00","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=3807"},"modified":"2020-12-02T22:00:28","modified_gmt":"2020-12-03T02:00:28","slug":"mes-livres-preferes-de-lannee-a-offrir-a-noel","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/","title":{"rendered":"Mes livres pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl"},"content":{"rendered":"\n<p>Quoi de mieux qu&#8217;un livre pour No\u00ebl? Quand on choisit bien, \u00e7a garantit au chanceux qui le re\u00e7oit des heures de plaisir, \u00e0 un prix tr\u00e8s modeste. Voici mes coups de coeur de la derni\u00e8re ann\u00e9e avec lesquels, je crois bien, vous ne vous tromperez pas. Cliquez sur le titre pour lire ma critique compl\u00e8te, et sur l&#8217;image pour acheter le livre. (Note : cette liste n&#8217;est pas en ordre de pr\u00e9f\u00e9rence, je n&#8217;y arriverais pas, mais en ordre chronologique, de la lecture la plus r\u00e9cente \u00e0 la plus ancienne.)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. <a href=\"https:\/\/prochainelecture.com\/la-scouine\/\">La Scouine<\/a><\/h2>\n\n\n\n<p>Une tr\u00e8s agr\u00e9able surprise de mon cours de litt\u00e9rature. Il s&#8217;agit d&#8217;une r\u00e9\u00e9criture d&#8217;un roman d&#8217;Albert Laberge \u00e9crit en 1918. Si je n&#8217;ai pas lu la version originale, je peux vous assurer que celle-ci va vous accrocher. De l&#8217;humour noir, du joual, et des phrases qui riment comme s&#8217;il n&#8217;y avait rien de plus naturel. Un d\u00e9lice.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/la-scouine-gabriel-marcoux-chabot-9782924519707.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">2. <a href=\"https:\/\/prochainelecture.com\/comment-devenir-antiraciste\/\">Comment devenir antiraciste<\/a><\/h2>\n\n\n\n<p>2020 \u00e9tait l&#8217;ann\u00e9e des bouleversements. La mort de George Floyd et les manifestations qui ont suivi en \u00e9tait un, et \u00e7a a peut-\u00eatre fait r\u00e9aliser \u00e0 certaines personnes qu&#8217;elles ne sont pas aussi renseign\u00e9es qu&#8217;elles le devraient. Pour ces personnes, je conseille fortement ce livre. Il couvre les bases d&#8217;un ton pas du tout moralisateur, et il remplit sa fonction : renseigner magnifiquement.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/comment-devenir-antiraciste-ibram-x-kendi-9782761956901.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">3. <a href=\"https:\/\/prochainelecture.com\/aliss\/\">Aliss, version bande dessin\u00e9e<\/a> <\/h2>\n\n\n\n<p>Ce fameux livre de Patrick S\u00e9n\u00e9cal a maintenant sa version BD, et c&#8217;est tout \u00e0 fait r\u00e9ussi. Les illustrations sont \u00e0 la fois magnifiques et horrifiantes et l&#8217;histoire est tout aussi accrocheuse que dans nos souvenirs. Une fois commenc\u00e9, il est impossible de s&#8217;arr\u00eater. Les fans de l&#8217;auteur seront ravis.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/aliss-patrick-senecal-9782896153008.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">4. <a href=\"https:\/\/prochainelecture.com\/la-bouche-pleine\/\">La bouche pleine<\/a><\/h2>\n\n\n\n<p>Ce livre est con\u00e7u pour les jeunes femmes, et id\u00e9alement, celles qui rushent avec leurs relations amoureuses. C&#8217;est dr\u00f4le, c&#8217;est cru, c&#8217;est profond\u00e9ment attachant. Le genre de livre auquel on pense encore des mois apr\u00e8s. <\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/la-bouche-pleine-elisabeth-massicolli-9782764440858.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">5. <a href=\"https:\/\/prochainelecture.com\/loving-what-is\/\">Loving What Is<\/a><\/h2>\n\n\n\n<p>Ceci est un livre de croissance personnelle on ne peut plus terre-\u00e0-terre. Il nous donne une m\u00e9thode d&#8217;une redoutable simplicit\u00e9 pour d\u00e9cortiquer nos pens\u00e9es qui nous chicotent et nous faire nous demander o\u00f9 est la v\u00e9rit\u00e9 l\u00e0-dedans. Ce livre est vraiment efficace et \u00e0 la port\u00e9e de tous.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/loving-what-is-byron-katie-9781400045372.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">6. <a href=\"https:\/\/prochainelecture.com\/une-demi-heure-derotisme\/\">Quelques-unes de ces nouvelles qu\u00e9b\u00e9coises en format parfait<\/a><\/h2>\n\n\n\n<p><a href=\"https:\/\/www.quebec-amerique.com\/livres\/litterature\/qa\">Cette collection<\/a> m&#8217;a charm\u00e9e. De toutes petites nouvelles, en format de poche, qui se lisent en une demi-heure. Mais quelles demi-heures. M\u00eame ceux qui ne lisent pas beaucoup vont adorer.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/la-madrague-sarah-maude-beauchesne-9782764440872.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/les-amours-d-ete-stephane-dompierre-9782764440841.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">7. <a href=\"https:\/\/prochainelecture.com\/the-book-of-dust-volume-1-la-belle-sauvage\/\">The Book of Dust<\/a><\/h2>\n\n\n\n<p>Je ne suis pas la seule \u00e0 avoir absolument ador\u00e9 le premier tome de cette nouvelle trilogie. Ceux qui ont d\u00e9j\u00e0 lu <em>\u00c0 la crois\u00e9e des mondes <\/em>vont adorer se replonger dedans, et ceux qui ne la connaissent pas auront la chance de se plonger dans l&#8217;histoire en partant du tout d\u00e9but. <\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/the-book-of-dust-la-belle-philip-pullman-9780553510744.html\/?type=livre&amp;configuration=125&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">8. <a href=\"https:\/\/prochainelecture.com\/mindset-the-new-psychology-of-success\/\">Mindset: The New Psychology of Success<\/a><\/h2>\n\n\n\n<p>Je ne comprends sinc\u00e8rement pas comment j&#8217;ai pu faire une aussi grande partie de ma scolarit\u00e9 sans avoir lu ce livre avant. C&#8217;est la base : en gros, il explique que quand on voit l&#8217;intelligence comme une aptitude qui se d\u00e9veloppe, on r\u00e9ussit mieux et on devient plus intelligent. La voir comme une qualit\u00e9 intrins\u00e8que sur laquelle on a aucun contr\u00f4le est non seulement d\u00e9primant, mais faux. C&#8217;est exceptionnellement bien \u00e9crit et c&#8217;est incroyablement \u00e9clairant.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/mindset-carol-s-dweck-9780345472328.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">9. <a href=\"https:\/\/prochainelecture.com\/propriete-privee\/\">Propri\u00e9t\u00e9 priv\u00e9e<\/a><\/h2>\n\n\n\n<p>Je vois ce livre comme un substitut de cin\u00e9ma. Sans farce, si vous avez une panne d&#8217;\u00e9lectricit\u00e9 chez vous et qu&#8217;il ne vous reste que deux bougies, ouvrez ce livre, vous aurez une toute aussi bonne exp\u00e9rience. Il se lit en quelques heures \u00e0 peine, dans un seul souffle, il nous fait angoisser et rire. J&#8217;ai ador\u00e9.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/propriete-privee-julia-deck-9782707345783.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">10. <a href=\"https:\/\/prochainelecture.com\/roux-clair-naturel-de-fanie-demeule\/\">Roux clair naturel<\/a><\/h2>\n\n\n\n<p>\u00c9tant moi-m\u00eame une ex-rousse, j&#8217;\u00e9tais la lectrice parfaite pour ce petit roman. Vous vous attendez peut-\u00eatre \u00e0 quelque chose de l\u00e9ger et superficiel avec ce titre, mais d\u00e9trompez-vous. Il est plein de suspense et fait r\u00e9fl\u00e9chir longtemps apr\u00e8s. Mais dans la joie, car c&#8217;est un livre extr\u00eamement agr\u00e9able \u00e0 lire. <\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/roux-clair-naturel-fanie-demeule-9782897910303.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Quoi de mieux qu&#8217;un livre pour No\u00ebl? Quand on choisit bien, \u00e7a garantit au chanceux qui le re\u00e7oit des heures de plaisir, \u00e0 un prix tr\u00e8s modeste. Voici mes coups de coeur de la derni\u00e8re ann\u00e9e avec lesquels, je crois bien, vous ne vous tromperez pas. Cliquez sur le titre pour lire ma critique compl\u00e8te, et sur l&#8217;image pour acheter le livre. (Note : cette liste n&#8217;est pas en ordre de pr\u00e9f\u00e9rence, je n&#8217;y arriverais pas, mais en ordre chronologique, de la lecture la plus r\u00e9cente \u00e0 la plus ancienne.) 1. La Scouine Une tr\u00e8s agr\u00e9able surprise de mon cours de litt\u00e9rature. Il s&#8217;agit d&#8217;une r\u00e9\u00e9criture d&#8217;un roman d&#8217;Albert Laberge \u00e9crit en 1918. Si je n&#8217;ai pas lu la version originale, je peux vous assurer que celle-ci va vous accrocher. De l&#8217;humour noir, du joual, et des phrases qui riment comme s&#8217;il n&#8217;y avait rien de plus naturel. Un d\u00e9lice. 2. Comment devenir antiraciste 2020 \u00e9tait l&#8217;ann\u00e9e des bouleversements. La mort de George Floyd et les manifestations qui ont suivi en \u00e9tait un, et \u00e7a a peut-\u00eatre fait r\u00e9aliser \u00e0 certaines personnes qu&#8217;elles ne sont pas aussi renseign\u00e9es qu&#8217;elles le devraient. Pour ces personnes, je conseille fortement ce livre. Il couvre les bases d&#8217;un ton pas du tout moralisateur, et il remplit sa fonction : renseigner magnifiquement. 3. Aliss, version bande dessin\u00e9e Ce fameux livre de Patrick S\u00e9n\u00e9cal a maintenant sa version BD, et c&#8217;est tout \u00e0 fait r\u00e9ussi. Les illustrations sont \u00e0 la fois magnifiques et horrifiantes et l&#8217;histoire est tout aussi accrocheuse que dans nos souvenirs. Une fois commenc\u00e9, il est impossible de s&#8217;arr\u00eater. Les fans de l&#8217;auteur seront ravis. 4. La bouche pleine Ce livre est con\u00e7u pour les jeunes femmes, et id\u00e9alement, celles qui rushent avec leurs relations amoureuses. C&#8217;est dr\u00f4le, c&#8217;est cru, c&#8217;est profond\u00e9ment attachant. Le genre de livre auquel on pense encore des mois apr\u00e8s. 5. Loving What Is Ceci est un livre de croissance personnelle on ne peut plus terre-\u00e0-terre. Il nous donne une m\u00e9thode d&#8217;une redoutable simplicit\u00e9 pour d\u00e9cortiquer nos pens\u00e9es qui nous chicotent et nous faire nous demander o\u00f9 est la v\u00e9rit\u00e9 l\u00e0-dedans. Ce livre est vraiment efficace et \u00e0 la port\u00e9e de tous. 6. Quelques-unes de ces nouvelles qu\u00e9b\u00e9coises en format parfait Cette collection m&#8217;a charm\u00e9e. De toutes petites nouvelles, en format de poche, qui se lisent en une demi-heure. Mais quelles demi-heures. M\u00eame ceux qui ne lisent pas beaucoup vont adorer. 7. The Book of Dust Je ne suis pas la seule \u00e0 avoir absolument ador\u00e9 le premier tome de cette nouvelle trilogie. Ceux qui ont d\u00e9j\u00e0 lu \u00c0 la crois\u00e9e des mondes vont adorer se replonger dedans, et ceux qui ne la connaissent pas auront la chance de se plonger dans l&#8217;histoire en partant du tout d\u00e9but. 8. Mindset: The New Psychology of Success Je ne comprends sinc\u00e8rement pas comment j&#8217;ai pu faire une aussi grande partie de ma scolarit\u00e9 sans avoir lu ce livre avant. C&#8217;est la base : en gros, il explique que quand on voit l&#8217;intelligence comme une aptitude qui se d\u00e9veloppe, on r\u00e9ussit mieux et on devient plus intelligent. La voir comme une qualit\u00e9 intrins\u00e8que sur laquelle on a aucun contr\u00f4le est non seulement d\u00e9primant, mais faux. C&#8217;est exceptionnellement bien \u00e9crit et c&#8217;est incroyablement \u00e9clairant. 9. Propri\u00e9t\u00e9 priv\u00e9e Je vois ce livre comme un substitut de cin\u00e9ma. Sans farce, si vous avez une panne d&#8217;\u00e9lectricit\u00e9 chez vous et qu&#8217;il ne vous reste que deux bougies, ouvrez ce livre, vous aurez une toute aussi bonne exp\u00e9rience. Il se lit en quelques heures \u00e0 peine, dans un seul souffle, il nous fait angoisser et rire. J&#8217;ai ador\u00e9. 10. Roux clair naturel \u00c9tant moi-m\u00eame une ex-rousse, j&#8217;\u00e9tais la lectrice parfaite pour ce petit roman. Vous vous attendez peut-\u00eatre \u00e0 quelque chose de l\u00e9ger et superficiel avec ce titre, mais d\u00e9trompez-vous. Il est plein de suspense et fait r\u00e9fl\u00e9chir longtemps apr\u00e8s. Mais dans la joie, car c&#8217;est un livre extr\u00eamement agr\u00e9able \u00e0 lire.<\/p>\n","protected":false},"author":1,"featured_media":3809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Quoi de mieux qu'un livre pour No\u00ebl? Quand on choisit bien, \u00e7a garantit au chanceux qui le re\u00e7oit des heures de plaisir, \u00e0 un prix tr\u00e8s modeste. Voici mes coups de coeur de la derni\u00e8re ann\u00e9e avec lesquels, je crois bien, vous ne vous tromperez pas.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[64],"tags":[],"class_list":["post-3807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recommandations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mes livres pr\u00e9f\u00e9r\u00e9s de l&#039;ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mes livres pr\u00e9f\u00e9r\u00e9s de l&#039;ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Quoi de mieux qu&#8217;un livre pour No\u00ebl? Quand on choisit bien, \u00e7a garantit au chanceux qui le re\u00e7oit des heures de plaisir, \u00e0 un prix tr\u00e8s modeste. Voici mes coups de coeur de la derni\u00e8re ann\u00e9e avec lesquels, je crois bien, vous ne vous tromperez pas. Cliquez sur le titre pour lire ma critique compl\u00e8te, et sur l&#8217;image pour acheter le livre. (Note : cette liste n&#8217;est pas en ordre de pr\u00e9f\u00e9rence, je n&#8217;y arriverais pas, mais en ordre chronologique, de la lecture la plus r\u00e9cente \u00e0 la plus ancienne.) 1. La Scouine Une tr\u00e8s agr\u00e9able surprise de mon cours de litt\u00e9rature. Il s&#8217;agit d&#8217;une r\u00e9\u00e9criture d&#8217;un roman d&#8217;Albert Laberge \u00e9crit en 1918. Si je n&#8217;ai pas lu la version originale, je peux vous assurer que celle-ci va vous accrocher. De l&#8217;humour noir, du joual, et des phrases qui riment comme s&#8217;il n&#8217;y avait rien de plus naturel. Un d\u00e9lice. 2. Comment devenir antiraciste 2020 \u00e9tait l&#8217;ann\u00e9e des bouleversements. La mort de George Floyd et les manifestations qui ont suivi en \u00e9tait un, et \u00e7a a peut-\u00eatre fait r\u00e9aliser \u00e0 certaines personnes qu&#8217;elles ne sont pas aussi renseign\u00e9es qu&#8217;elles le devraient. Pour ces personnes, je conseille fortement ce livre. Il couvre les bases d&#8217;un ton pas du tout moralisateur, et il remplit sa fonction : renseigner magnifiquement. 3. Aliss, version bande dessin\u00e9e Ce fameux livre de Patrick S\u00e9n\u00e9cal a maintenant sa version BD, et c&#8217;est tout \u00e0 fait r\u00e9ussi. Les illustrations sont \u00e0 la fois magnifiques et horrifiantes et l&#8217;histoire est tout aussi accrocheuse que dans nos souvenirs. Une fois commenc\u00e9, il est impossible de s&#8217;arr\u00eater. Les fans de l&#8217;auteur seront ravis. 4. La bouche pleine Ce livre est con\u00e7u pour les jeunes femmes, et id\u00e9alement, celles qui rushent avec leurs relations amoureuses. C&#8217;est dr\u00f4le, c&#8217;est cru, c&#8217;est profond\u00e9ment attachant. Le genre de livre auquel on pense encore des mois apr\u00e8s. 5. Loving What Is Ceci est un livre de croissance personnelle on ne peut plus terre-\u00e0-terre. Il nous donne une m\u00e9thode d&#8217;une redoutable simplicit\u00e9 pour d\u00e9cortiquer nos pens\u00e9es qui nous chicotent et nous faire nous demander o\u00f9 est la v\u00e9rit\u00e9 l\u00e0-dedans. Ce livre est vraiment efficace et \u00e0 la port\u00e9e de tous. 6. Quelques-unes de ces nouvelles qu\u00e9b\u00e9coises en format parfait Cette collection m&#8217;a charm\u00e9e. De toutes petites nouvelles, en format de poche, qui se lisent en une demi-heure. Mais quelles demi-heures. M\u00eame ceux qui ne lisent pas beaucoup vont adorer. 7. The Book of Dust Je ne suis pas la seule \u00e0 avoir absolument ador\u00e9 le premier tome de cette nouvelle trilogie. Ceux qui ont d\u00e9j\u00e0 lu \u00c0 la crois\u00e9e des mondes vont adorer se replonger dedans, et ceux qui ne la connaissent pas auront la chance de se plonger dans l&#8217;histoire en partant du tout d\u00e9but. 8. Mindset: The New Psychology of Success Je ne comprends sinc\u00e8rement pas comment j&#8217;ai pu faire une aussi grande partie de ma scolarit\u00e9 sans avoir lu ce livre avant. C&#8217;est la base : en gros, il explique que quand on voit l&#8217;intelligence comme une aptitude qui se d\u00e9veloppe, on r\u00e9ussit mieux et on devient plus intelligent. La voir comme une qualit\u00e9 intrins\u00e8que sur laquelle on a aucun contr\u00f4le est non seulement d\u00e9primant, mais faux. C&#8217;est exceptionnellement bien \u00e9crit et c&#8217;est incroyablement \u00e9clairant. 9. Propri\u00e9t\u00e9 priv\u00e9e Je vois ce livre comme un substitut de cin\u00e9ma. Sans farce, si vous avez une panne d&#8217;\u00e9lectricit\u00e9 chez vous et qu&#8217;il ne vous reste que deux bougies, ouvrez ce livre, vous aurez une toute aussi bonne exp\u00e9rience. Il se lit en quelques heures \u00e0 peine, dans un seul souffle, il nous fait angoisser et rire. J&#8217;ai ador\u00e9. 10. Roux clair naturel \u00c9tant moi-m\u00eame une ex-rousse, j&#8217;\u00e9tais la lectrice parfaite pour ce petit roman. Vous vous attendez peut-\u00eatre \u00e0 quelque chose de l\u00e9ger et superficiel avec ce titre, mais d\u00e9trompez-vous. Il est plein de suspense et fait r\u00e9fl\u00e9chir longtemps apr\u00e8s. Mais dans la joie, car c&#8217;est un livre extr\u00eamement agr\u00e9able \u00e0 lire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-02T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-03T02:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Mes livres pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl\",\"datePublished\":\"2020-12-02T13:00:00+00:00\",\"dateModified\":\"2020-12-03T02:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/\"},\"wordCount\":739,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Recommandations\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/\",\"name\":\"Mes livres pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2020-12-02T13:00:00+00:00\",\"dateModified\":\"2020-12-03T02:00:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/mes-livres-preferes-de-lannee-a-offrir-a-noel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mes livres pr\u00e9f\u00e9r\u00e9s de l&rsquo;ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mes livres pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/","og_locale":"fr_CA","og_type":"article","og_title":"Mes livres pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl - Prochaine lecture","og_description":"Quoi de mieux qu&#8217;un livre pour No\u00ebl? Quand on choisit bien, \u00e7a garantit au chanceux qui le re\u00e7oit des heures de plaisir, \u00e0 un prix tr\u00e8s modeste. Voici mes coups de coeur de la derni\u00e8re ann\u00e9e avec lesquels, je crois bien, vous ne vous tromperez pas. Cliquez sur le titre pour lire ma critique compl\u00e8te, et sur l&#8217;image pour acheter le livre. (Note : cette liste n&#8217;est pas en ordre de pr\u00e9f\u00e9rence, je n&#8217;y arriverais pas, mais en ordre chronologique, de la lecture la plus r\u00e9cente \u00e0 la plus ancienne.) 1. La Scouine Une tr\u00e8s agr\u00e9able surprise de mon cours de litt\u00e9rature. Il s&#8217;agit d&#8217;une r\u00e9\u00e9criture d&#8217;un roman d&#8217;Albert Laberge \u00e9crit en 1918. Si je n&#8217;ai pas lu la version originale, je peux vous assurer que celle-ci va vous accrocher. De l&#8217;humour noir, du joual, et des phrases qui riment comme s&#8217;il n&#8217;y avait rien de plus naturel. Un d\u00e9lice. 2. Comment devenir antiraciste 2020 \u00e9tait l&#8217;ann\u00e9e des bouleversements. La mort de George Floyd et les manifestations qui ont suivi en \u00e9tait un, et \u00e7a a peut-\u00eatre fait r\u00e9aliser \u00e0 certaines personnes qu&#8217;elles ne sont pas aussi renseign\u00e9es qu&#8217;elles le devraient. Pour ces personnes, je conseille fortement ce livre. Il couvre les bases d&#8217;un ton pas du tout moralisateur, et il remplit sa fonction : renseigner magnifiquement. 3. Aliss, version bande dessin\u00e9e Ce fameux livre de Patrick S\u00e9n\u00e9cal a maintenant sa version BD, et c&#8217;est tout \u00e0 fait r\u00e9ussi. Les illustrations sont \u00e0 la fois magnifiques et horrifiantes et l&#8217;histoire est tout aussi accrocheuse que dans nos souvenirs. Une fois commenc\u00e9, il est impossible de s&#8217;arr\u00eater. Les fans de l&#8217;auteur seront ravis. 4. La bouche pleine Ce livre est con\u00e7u pour les jeunes femmes, et id\u00e9alement, celles qui rushent avec leurs relations amoureuses. C&#8217;est dr\u00f4le, c&#8217;est cru, c&#8217;est profond\u00e9ment attachant. Le genre de livre auquel on pense encore des mois apr\u00e8s. 5. Loving What Is Ceci est un livre de croissance personnelle on ne peut plus terre-\u00e0-terre. Il nous donne une m\u00e9thode d&#8217;une redoutable simplicit\u00e9 pour d\u00e9cortiquer nos pens\u00e9es qui nous chicotent et nous faire nous demander o\u00f9 est la v\u00e9rit\u00e9 l\u00e0-dedans. Ce livre est vraiment efficace et \u00e0 la port\u00e9e de tous. 6. Quelques-unes de ces nouvelles qu\u00e9b\u00e9coises en format parfait Cette collection m&#8217;a charm\u00e9e. De toutes petites nouvelles, en format de poche, qui se lisent en une demi-heure. Mais quelles demi-heures. M\u00eame ceux qui ne lisent pas beaucoup vont adorer. 7. The Book of Dust Je ne suis pas la seule \u00e0 avoir absolument ador\u00e9 le premier tome de cette nouvelle trilogie. Ceux qui ont d\u00e9j\u00e0 lu \u00c0 la crois\u00e9e des mondes vont adorer se replonger dedans, et ceux qui ne la connaissent pas auront la chance de se plonger dans l&#8217;histoire en partant du tout d\u00e9but. 8. Mindset: The New Psychology of Success Je ne comprends sinc\u00e8rement pas comment j&#8217;ai pu faire une aussi grande partie de ma scolarit\u00e9 sans avoir lu ce livre avant. C&#8217;est la base : en gros, il explique que quand on voit l&#8217;intelligence comme une aptitude qui se d\u00e9veloppe, on r\u00e9ussit mieux et on devient plus intelligent. La voir comme une qualit\u00e9 intrins\u00e8que sur laquelle on a aucun contr\u00f4le est non seulement d\u00e9primant, mais faux. C&#8217;est exceptionnellement bien \u00e9crit et c&#8217;est incroyablement \u00e9clairant. 9. Propri\u00e9t\u00e9 priv\u00e9e Je vois ce livre comme un substitut de cin\u00e9ma. Sans farce, si vous avez une panne d&#8217;\u00e9lectricit\u00e9 chez vous et qu&#8217;il ne vous reste que deux bougies, ouvrez ce livre, vous aurez une toute aussi bonne exp\u00e9rience. Il se lit en quelques heures \u00e0 peine, dans un seul souffle, il nous fait angoisser et rire. J&#8217;ai ador\u00e9. 10. Roux clair naturel \u00c9tant moi-m\u00eame une ex-rousse, j&#8217;\u00e9tais la lectrice parfaite pour ce petit roman. Vous vous attendez peut-\u00eatre \u00e0 quelque chose de l\u00e9ger et superficiel avec ce titre, mais d\u00e9trompez-vous. Il est plein de suspense et fait r\u00e9fl\u00e9chir longtemps apr\u00e8s. Mais dans la joie, car c&#8217;est un livre extr\u00eamement agr\u00e9able \u00e0 lire.","og_url":"https:\/\/prochainelecture.com\/fr\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2020-12-02T13:00:00+00:00","article_modified_time":"2020-12-03T02:00:28+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Mes livres pr\u00e9f\u00e9r\u00e9s de l&#8217;ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl","datePublished":"2020-12-02T13:00:00+00:00","dateModified":"2020-12-03T02:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/"},"wordCount":739,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1","articleSection":["Recommandations"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/","url":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/","name":"Mes livres pr\u00e9f\u00e9r\u00e9s de l'ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1","datePublished":"2020-12-02T13:00:00+00:00","dateModified":"2020-12-03T02:00:28+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/mes-livres-preferes-de-lannee-a-offrir-a-noel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Mes livres pr\u00e9f\u00e9r\u00e9s de l&rsquo;ann\u00e9e \u00e0 offrir \u00e0 No\u00ebl"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/books-3454381_1280_cut.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-Zp","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=3807"}],"version-history":[{"count":5,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3807\/revisions"}],"predecessor-version":[{"id":3886,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3807\/revisions\/3886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3809"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=3807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=3807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=3807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}