{"id":3800,"date":"2020-10-25T20:56:24","date_gmt":"2020-10-26T00:56:24","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=3800"},"modified":"2020-12-09T09:10:17","modified_gmt":"2020-12-09T13:10:17","slug":"la-bouche-pleine","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/la-bouche-pleine\/","title":{"rendered":"La bouche pleine"},"content":{"rendered":"\n<p>J&#8217;adore la litt\u00e9rature \u00e9trang\u00e8re, \u00e9videmment, mais je dois dire que quand je tombe sur de la bonne litt\u00e9rature qu\u00e9b\u00e9coise, je trippe. Je lis \u00e7a \u00e0 voix haute, et \u00e7a coule. C&#8217;est un peu la diff\u00e9rence entre lire un texte de th\u00e9\u00e2tre et parler dans la vraie vie. Je comprends les blagues pour vrai, et je les trouve dr\u00f4le. J&#8217;oublie presque que je ne suis pas en train de jaser avec ma meilleure chum. J&#8217;adore. Et \u00e7a a \u00e9t\u00e9 en plein mon exp\u00e9rience avec <em>La bouche pleine<\/em>, d&#8217;Elisabeth Massicolli.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9sum\u00e9<\/h2>\n\n\n\n<p>Camille, une jeune Montr\u00e9alaise de 26 ans, fait de la r\u00e9daction dans une compagnie, niaise avec sa meilleure amie Julianne, et se cherche d\u00e9sesp\u00e9r\u00e9ment un gars pas trop pire qui va l&#8217;aimer en swipant sur Tinder et en cruisant \u00e0 la Taverna. Elle a le coeur amoch\u00e9, mais pas assez pour arr\u00eater d&#8217;essayer. <\/p>\n\n\n\n<p>Dis comme \u00e7a, \u00e7a n&#8217;a pas l&#8217;air d&#8217;aller si mal. Mais son coeur est sur le point d&#8217;exploser. Elle se fait offrir une job qui ne lui ressemble pas par un monsieur qui a plus l&#8217;air de vouloir coucher avec, \u00e7a fait une couple de fois qu&#8217;elle oublie qu&#8217;il y a d&#8217;autres personnes qu&#8217;elle sur la terre qui m\u00e9ritent de l&#8217;attention, ses s\u00e9ances chez la psy ne l&#8217;aident pas beaucoup, et elle vient de rencontrer un gars qui a l&#8217;air fin. Oh oh. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>J&#8217;ai 25 ans, Camille 26. Je suis Montr\u00e9alaise, elle aussi. Et \u00e7a ne pas fait assez longtemps que j&#8217;ai arr\u00eat\u00e9 d&#8217;\u00eatre une c\u00e9libataire d\u00e9sesp\u00e9r\u00e9e pour oublier comment c&#8217;est. J&#8217;ai choisi ce livre parce que je pensais que \u00e7a pourrait me rejoindre : je n&#8217;avais pas id\u00e9e \u00e0 quel point. <\/p>\n\n\n\n<p>Elisabeth Massicolli est f\u00e9ministe, et \u00e7a para\u00eet. Dans son roman, je me sentais comprise en tant que femme. Il y a les messages que Camille re\u00e7oit sur Tinder :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>hey<\/p><p>u up???<\/p><p>wanna fuck<\/p><p>&#8230;<\/p><p>bitch<\/p><p>ur not even pretty<\/p><p>&#8211; Alessandro, 36 ans<\/p><\/blockquote>\n\n\n\n<p>Il y a son besoin de dire aux gars qu&#8217;elle a un chum, pour qu&#8217;on la laisse tranquille. Il y a les messieurs louches qui pr\u00e9tendent voir en elle un grand potentiel. Il y a les sentiments de marde le lendemain d&#8217;une soir\u00e9e o\u00f9 elle a juste trop bu pour rien. Et j&#8217;en passe plein. C&#8217;est cru. \u00c7a n&#8217;y va pas avec le dos de la cuill\u00e8re.<\/p>\n\n\n\n<p>Mais j&#8217;ai aussi beaucoup ri. Camille a un tr\u00e8s bon sens de l&#8217;humour. J&#8217;ai ador\u00e9 les dialogues. Et il y a un chat qui s&#8217;appelle Tourti\u00e8re. <\/p>\n\n\n\n<p>Un beau m\u00e9lange de l\u00e9g\u00e8ret\u00e9 et de profondeur. \u00c0 mettre entre les mains des jeunes femmes qui, \u00e0 certains moments, trouvent la vie dure.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/la-bouche-pleine-elisabeth-massicolli-9782764440858.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>J&#8217;adore la litt\u00e9rature \u00e9trang\u00e8re, \u00e9videmment, mais je dois dire que quand je tombe sur de la bonne litt\u00e9rature qu\u00e9b\u00e9coise, je trippe. Je lis \u00e7a \u00e0 voix haute, et \u00e7a coule. C&#8217;est un peu la diff\u00e9rence entre lire un texte de th\u00e9\u00e2tre et parler dans la vraie vie. Je comprends les blagues pour vrai, et je les trouve dr\u00f4le. J&#8217;oublie presque que je ne suis pas en train de jaser avec ma meilleure chum. J&#8217;adore. Et \u00e7a a \u00e9t\u00e9 en plein mon exp\u00e9rience avec La bouche pleine, d&#8217;Elisabeth Massicolli. R\u00e9sum\u00e9 Camille, une jeune Montr\u00e9alaise de 26 ans, fait de la r\u00e9daction dans une compagnie, niaise avec sa meilleure amie Julianne, et se cherche d\u00e9sesp\u00e9r\u00e9ment un gars pas trop pire qui va l&#8217;aimer en swipant sur Tinder et en cruisant \u00e0 la Taverna. Elle a le coeur amoch\u00e9, mais pas assez pour arr\u00eater d&#8217;essayer. Dis comme \u00e7a, \u00e7a n&#8217;a pas l&#8217;air d&#8217;aller si mal. Mais son coeur est sur le point d&#8217;exploser. Elle se fait offrir une job qui ne lui ressemble pas par un monsieur qui a plus l&#8217;air de vouloir coucher avec, \u00e7a fait une couple de fois qu&#8217;elle oublie qu&#8217;il y a d&#8217;autres personnes qu&#8217;elle sur la terre qui m\u00e9ritent de l&#8217;attention, ses s\u00e9ances chez la psy ne l&#8217;aident pas beaucoup, et elle vient de rencontrer un gars qui a l&#8217;air fin. Oh oh. Impressions J&#8217;ai 25 ans, Camille 26. Je suis Montr\u00e9alaise, elle aussi. Et \u00e7a ne pas fait assez longtemps que j&#8217;ai arr\u00eat\u00e9 d&#8217;\u00eatre une c\u00e9libataire d\u00e9sesp\u00e9r\u00e9e pour oublier comment c&#8217;est. J&#8217;ai choisi ce livre parce que je pensais que \u00e7a pourrait me rejoindre : je n&#8217;avais pas id\u00e9e \u00e0 quel point. Elisabeth Massicolli est f\u00e9ministe, et \u00e7a para\u00eet. Dans son roman, je me sentais comprise en tant que femme. Il y a les messages que Camille re\u00e7oit sur Tinder : hey u up??? wanna fuck &#8230; bitch ur not even pretty &#8211; Alessandro, 36 ans Il y a son besoin de dire aux gars qu&#8217;elle a un chum, pour qu&#8217;on la laisse tranquille. Il y a les messieurs louches qui pr\u00e9tendent voir en elle un grand potentiel. Il y a les sentiments de marde le lendemain d&#8217;une soir\u00e9e o\u00f9 elle a juste trop bu pour rien. Et j&#8217;en passe plein. C&#8217;est cru. \u00c7a n&#8217;y va pas avec le dos de la cuill\u00e8re. Mais j&#8217;ai aussi beaucoup ri. Camille a un tr\u00e8s bon sens de l&#8217;humour. J&#8217;ai ador\u00e9 les dialogues. Et il y a un chat qui s&#8217;appelle Tourti\u00e8re. Un beau m\u00e9lange de l\u00e9g\u00e8ret\u00e9 et de profondeur. \u00c0 mettre entre les mains des jeunes femmes qui, \u00e0 certains moments, trouvent la vie dure.<\/p>\n","protected":false},"author":1,"featured_media":3802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Je me suis sentie comprise par ce beau petit roman. Il est cru, parfois dur, mais il fait aussi beaucoup rire. \u00c0 mettre entre les mains des jeunes femmes qui, \u00e0 certains moments, trouvent la vie dure.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[255,245,242],"tags":[],"class_list":["post-3800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coups-de-coeur","category-litterature-quebecoise","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La bouche pleine - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/la-bouche-pleine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La bouche pleine - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"J&#8217;adore la litt\u00e9rature \u00e9trang\u00e8re, \u00e9videmment, mais je dois dire que quand je tombe sur de la bonne litt\u00e9rature qu\u00e9b\u00e9coise, je trippe. Je lis \u00e7a \u00e0 voix haute, et \u00e7a coule. C&#8217;est un peu la diff\u00e9rence entre lire un texte de th\u00e9\u00e2tre et parler dans la vraie vie. Je comprends les blagues pour vrai, et je les trouve dr\u00f4le. J&#8217;oublie presque que je ne suis pas en train de jaser avec ma meilleure chum. J&#8217;adore. Et \u00e7a a \u00e9t\u00e9 en plein mon exp\u00e9rience avec La bouche pleine, d&#8217;Elisabeth Massicolli. R\u00e9sum\u00e9 Camille, une jeune Montr\u00e9alaise de 26 ans, fait de la r\u00e9daction dans une compagnie, niaise avec sa meilleure amie Julianne, et se cherche d\u00e9sesp\u00e9r\u00e9ment un gars pas trop pire qui va l&#8217;aimer en swipant sur Tinder et en cruisant \u00e0 la Taverna. Elle a le coeur amoch\u00e9, mais pas assez pour arr\u00eater d&#8217;essayer. Dis comme \u00e7a, \u00e7a n&#8217;a pas l&#8217;air d&#8217;aller si mal. Mais son coeur est sur le point d&#8217;exploser. Elle se fait offrir une job qui ne lui ressemble pas par un monsieur qui a plus l&#8217;air de vouloir coucher avec, \u00e7a fait une couple de fois qu&#8217;elle oublie qu&#8217;il y a d&#8217;autres personnes qu&#8217;elle sur la terre qui m\u00e9ritent de l&#8217;attention, ses s\u00e9ances chez la psy ne l&#8217;aident pas beaucoup, et elle vient de rencontrer un gars qui a l&#8217;air fin. Oh oh. Impressions J&#8217;ai 25 ans, Camille 26. Je suis Montr\u00e9alaise, elle aussi. Et \u00e7a ne pas fait assez longtemps que j&#8217;ai arr\u00eat\u00e9 d&#8217;\u00eatre une c\u00e9libataire d\u00e9sesp\u00e9r\u00e9e pour oublier comment c&#8217;est. J&#8217;ai choisi ce livre parce que je pensais que \u00e7a pourrait me rejoindre : je n&#8217;avais pas id\u00e9e \u00e0 quel point. Elisabeth Massicolli est f\u00e9ministe, et \u00e7a para\u00eet. Dans son roman, je me sentais comprise en tant que femme. Il y a les messages que Camille re\u00e7oit sur Tinder : hey u up??? wanna fuck &#8230; bitch ur not even pretty &#8211; Alessandro, 36 ans Il y a son besoin de dire aux gars qu&#8217;elle a un chum, pour qu&#8217;on la laisse tranquille. Il y a les messieurs louches qui pr\u00e9tendent voir en elle un grand potentiel. Il y a les sentiments de marde le lendemain d&#8217;une soir\u00e9e o\u00f9 elle a juste trop bu pour rien. Et j&#8217;en passe plein. C&#8217;est cru. \u00c7a n&#8217;y va pas avec le dos de la cuill\u00e8re. Mais j&#8217;ai aussi beaucoup ri. Camille a un tr\u00e8s bon sens de l&#8217;humour. J&#8217;ai ador\u00e9 les dialogues. Et il y a un chat qui s&#8217;appelle Tourti\u00e8re. Un beau m\u00e9lange de l\u00e9g\u00e8ret\u00e9 et de profondeur. \u00c0 mettre entre les mains des jeunes femmes qui, \u00e0 certains moments, trouvent la vie dure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/la-bouche-pleine\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-26T00:56:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-09T13:10:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"La bouche pleine\",\"datePublished\":\"2020-10-26T00:56:24+00:00\",\"dateModified\":\"2020-12-09T13:10:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/\"},\"wordCount\":498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Coups de coeur\",\"Litt\u00e9rature qu\u00e9b\u00e9coise\",\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/\",\"name\":\"La bouche pleine - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2020-10-26T00:56:24+00:00\",\"dateModified\":\"2020-12-09T13:10:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-bouche-pleine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La bouche pleine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La bouche pleine - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/la-bouche-pleine\/","og_locale":"fr_CA","og_type":"article","og_title":"La bouche pleine - Prochaine lecture","og_description":"J&#8217;adore la litt\u00e9rature \u00e9trang\u00e8re, \u00e9videmment, mais je dois dire que quand je tombe sur de la bonne litt\u00e9rature qu\u00e9b\u00e9coise, je trippe. Je lis \u00e7a \u00e0 voix haute, et \u00e7a coule. C&#8217;est un peu la diff\u00e9rence entre lire un texte de th\u00e9\u00e2tre et parler dans la vraie vie. Je comprends les blagues pour vrai, et je les trouve dr\u00f4le. J&#8217;oublie presque que je ne suis pas en train de jaser avec ma meilleure chum. J&#8217;adore. Et \u00e7a a \u00e9t\u00e9 en plein mon exp\u00e9rience avec La bouche pleine, d&#8217;Elisabeth Massicolli. R\u00e9sum\u00e9 Camille, une jeune Montr\u00e9alaise de 26 ans, fait de la r\u00e9daction dans une compagnie, niaise avec sa meilleure amie Julianne, et se cherche d\u00e9sesp\u00e9r\u00e9ment un gars pas trop pire qui va l&#8217;aimer en swipant sur Tinder et en cruisant \u00e0 la Taverna. Elle a le coeur amoch\u00e9, mais pas assez pour arr\u00eater d&#8217;essayer. Dis comme \u00e7a, \u00e7a n&#8217;a pas l&#8217;air d&#8217;aller si mal. Mais son coeur est sur le point d&#8217;exploser. Elle se fait offrir une job qui ne lui ressemble pas par un monsieur qui a plus l&#8217;air de vouloir coucher avec, \u00e7a fait une couple de fois qu&#8217;elle oublie qu&#8217;il y a d&#8217;autres personnes qu&#8217;elle sur la terre qui m\u00e9ritent de l&#8217;attention, ses s\u00e9ances chez la psy ne l&#8217;aident pas beaucoup, et elle vient de rencontrer un gars qui a l&#8217;air fin. Oh oh. Impressions J&#8217;ai 25 ans, Camille 26. Je suis Montr\u00e9alaise, elle aussi. Et \u00e7a ne pas fait assez longtemps que j&#8217;ai arr\u00eat\u00e9 d&#8217;\u00eatre une c\u00e9libataire d\u00e9sesp\u00e9r\u00e9e pour oublier comment c&#8217;est. J&#8217;ai choisi ce livre parce que je pensais que \u00e7a pourrait me rejoindre : je n&#8217;avais pas id\u00e9e \u00e0 quel point. Elisabeth Massicolli est f\u00e9ministe, et \u00e7a para\u00eet. Dans son roman, je me sentais comprise en tant que femme. Il y a les messages que Camille re\u00e7oit sur Tinder : hey u up??? wanna fuck &#8230; bitch ur not even pretty &#8211; Alessandro, 36 ans Il y a son besoin de dire aux gars qu&#8217;elle a un chum, pour qu&#8217;on la laisse tranquille. Il y a les messieurs louches qui pr\u00e9tendent voir en elle un grand potentiel. Il y a les sentiments de marde le lendemain d&#8217;une soir\u00e9e o\u00f9 elle a juste trop bu pour rien. Et j&#8217;en passe plein. C&#8217;est cru. \u00c7a n&#8217;y va pas avec le dos de la cuill\u00e8re. Mais j&#8217;ai aussi beaucoup ri. Camille a un tr\u00e8s bon sens de l&#8217;humour. J&#8217;ai ador\u00e9 les dialogues. Et il y a un chat qui s&#8217;appelle Tourti\u00e8re. Un beau m\u00e9lange de l\u00e9g\u00e8ret\u00e9 et de profondeur. \u00c0 mettre entre les mains des jeunes femmes qui, \u00e0 certains moments, trouvent la vie dure.","og_url":"https:\/\/prochainelecture.com\/fr\/la-bouche-pleine\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2020-10-26T00:56:24+00:00","article_modified_time":"2020-12-09T13:10:17+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"La bouche pleine","datePublished":"2020-10-26T00:56:24+00:00","dateModified":"2020-12-09T13:10:17+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/"},"wordCount":498,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1","articleSection":["Coups de coeur","Litt\u00e9rature qu\u00e9b\u00e9coise","Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/la-bouche-pleine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/","url":"https:\/\/prochainelecture.com\/la-bouche-pleine\/","name":"La bouche pleine - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1","datePublished":"2020-10-26T00:56:24+00:00","dateModified":"2020-12-09T13:10:17+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/la-bouche-pleine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/la-bouche-pleine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"La bouche pleine"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/10\/20201025_203317-1.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-Zi","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=3800"}],"version-history":[{"count":4,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3800\/revisions"}],"predecessor-version":[{"id":3899,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/3800\/revisions\/3899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3802"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=3800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=3800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=3800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}