{"id":215,"date":"2013-04-03T02:08:38","date_gmt":"2013-04-03T02:08:38","guid":{"rendered":"http:\/\/naimahassert.com\/?p=215"},"modified":"2020-08-03T22:04:47","modified_gmt":"2020-08-03T22:04:47","slug":"petit-manuel-du-travailleur-autonome","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/petit-manuel-du-travailleur-autonome\/","title":{"rendered":"Petit manuel du travailleur autonome"},"content":{"rendered":"<div class=\"single-metainfo\"><a href=\"https:\/\/kiosquemedias.wordpress.com\/2013\/04\/03\/petit-manuel-du-travail-autonome\/\">Publi\u00e9 le\u00a03 avril 2013<\/a>\u00a0dans le <a href=\"https:\/\/kiosquemedias.wordpress.com\/\"><strong>Kiosque M\u00e9dias<\/strong><\/a><\/div>\n<p><b>Petit manuel du travailleur autonome<\/b><b><\/b><\/p>\n<p><strong>Conseils et t\u00e9moignages<\/strong><\/p>\n<p><strong>Par Martine Letarte et Judith Lussier<\/strong><\/p>\n<p><strong>Les \u00c9ditions La Presse<\/strong><\/p>\n<p><strong>199 p.<\/strong><\/p>\n<p><a href=\"http:\/\/www.renaud-bray.com\/Livre_Numerique_Produit.aspx?id=1407493&amp;def=Petit+manuel+du+travail+autonome+%3a+conseils+et+t%C3%A9moignages%2cLETARTE%2c+MARTINE%2cLUSSIER%2c+JUDITH%2c9782897051396\">17,99 $<\/a><\/p>\n<p>Pourquoi s\u2019imposer un patron, alors qu\u2019on est parfaitement capables de se g\u00e9rer soi-m\u00eame\u00a0? Pourquoi se d\u00e9placer tous les jours \u00e0 un bureau, alors qu\u2019il est possible de travailler du confort de notre salon\u00a0?\u00a0 Et surtout, qu\u2019est-ce qui nous retient de mener la vie qu\u2019on aime vraiment\u00a0?<\/p>\n<p>\u00ab\u00a0Les gens se sous-estiment. Avec ce livre, je voulais leur dire qu\u2019ils sont capables. Les gens pensent qu\u2019ils ont besoin d\u2019un patron dans leur dos pour leur dire quoi faire, alors que ce n\u2019est pas vrai\u00a0!\u00a0\u00bb<\/p>\n<p>Judith Lussier, journaliste pour plusieurs magazines ainsi que sur le web, a aussi une chronique dans le journal M\u00e9tro. \u00ab\u00a0Et je me permets de faire plein d\u2019autres choses.\u00a0\u00bb Comme d\u2019\u00e9crire un film de fiction avec sa conjointe et d\u2019entretenir d\u2019autres projets de livres.<\/p>\n<p>\u00ab\u00a0Ma vie est extraordinaire. Je pense que des salari\u00e9s peuvent \u00eatre tr\u00e8s confortables dans le salariat et trouver que j\u2019ai un discours un peu utopiste, mais on le dit dans le livre, nous, c\u2019est \u00e7a qui nous convient. \u00c0 vous de voir si c\u2019est pour vous ou pas.\u00a0\u00bb<\/p>\n<p>Et c\u2019est ce qu\u2019elle et Martine Letarte nous proposent. Le Petit manuel du travailleur autonome est un guide pour tous ceux qui r\u00eavent de travailler \u00e0 leur compte, mais qui n\u2019osent pas abandonner leur paye du jeudi, ou qui pensent manquer de discipline personnelle. Les deux journalistes nous partagent leurs exp\u00e9riences, leurs conseils, ainsi que ceux d\u2019autres travailleurs autonomes dans des secteurs aussi vari\u00e9s que le marketing, les arts, l\u2019architecture et la sant\u00e9. S\u2019y rajoutent avis d\u2019expert en comptabilit\u00e9, de sp\u00e9cialiste en gestion du temps, psychologue, kin\u00e9siologue, pour offrir \u00e0 tous ceux qui le souhaitent les outils n\u00e9cessaires pour se lancer dans le travail autonome.<\/p>\n<p>On verra ainsi que les mythes du pigiste qui meurt de faim, qui m\u00e8ne une vie instable en attendant de se trouver un vrai travail, ou qui est en vacances tous les jours sont, tout simplement\u2026 des mythes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publi\u00e9 le\u00a03 avril 2013\u00a0dans le Kiosque M\u00e9dias Petit manuel du travailleur autonome Conseils et t\u00e9moignages Par Martine Letarte et Judith Lussier Les \u00c9ditions La Presse 199 p. 17,99 $ Pourquoi s\u2019imposer un patron, alors qu\u2019on est parfaitement capables de se g\u00e9rer soi-m\u00eame\u00a0? Pourquoi se d\u00e9placer tous les jours \u00e0 un bureau, alors qu\u2019il est possible de travailler du confort de notre salon\u00a0?\u00a0 Et surtout, qu\u2019est-ce qui nous retient de mener la vie qu\u2019on aime vraiment\u00a0? \u00ab\u00a0Les gens se sous-estiment. Avec ce livre, je voulais leur dire qu\u2019ils sont capables. Les gens pensent qu\u2019ils ont besoin d\u2019un patron dans leur dos pour leur dire quoi faire, alors que ce n\u2019est pas vrai\u00a0!\u00a0\u00bb Judith Lussier, journaliste pour plusieurs magazines ainsi que sur le web, a aussi une chronique dans le journal M\u00e9tro. \u00ab\u00a0Et je me permets de faire plein d\u2019autres choses.\u00a0\u00bb Comme d\u2019\u00e9crire un film de fiction avec sa conjointe et d\u2019entretenir d\u2019autres projets de livres. \u00ab\u00a0Ma vie est extraordinaire. Je pense que des salari\u00e9s peuvent \u00eatre tr\u00e8s confortables dans le salariat et trouver que j\u2019ai un discours un peu utopiste, mais on le dit dans le livre, nous, c\u2019est \u00e7a qui nous convient. \u00c0 vous de voir si c\u2019est pour vous ou pas.\u00a0\u00bb Et c\u2019est ce qu\u2019elle et Martine Letarte nous proposent. Le Petit manuel du travailleur autonome est un guide pour tous ceux qui r\u00eavent de travailler \u00e0 leur compte, mais qui n\u2019osent pas abandonner leur paye du jeudi, ou qui pensent manquer de discipline personnelle. Les deux journalistes nous partagent leurs exp\u00e9riences, leurs conseils, ainsi que ceux d\u2019autres travailleurs autonomes dans des secteurs aussi vari\u00e9s que le marketing, les arts, l\u2019architecture et la sant\u00e9. S\u2019y rajoutent avis d\u2019expert en comptabilit\u00e9, de sp\u00e9cialiste en gestion du temps, psychologue, kin\u00e9siologue, pour offrir \u00e0 tous ceux qui le souhaitent les outils n\u00e9cessaires pour se lancer dans le travail autonome. On verra ainsi que les mythes du pigiste qui meurt de faim, qui m\u00e8ne une vie instable en attendant de se trouver un vrai travail, ou qui est en vacances tous les jours sont, tout simplement\u2026 des mythes.<\/p>\n","protected":false},"author":1,"featured_media":3413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[249],"tags":[],"class_list":["post-215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-se-renseigner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Petit manuel du travailleur autonome - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/petit-manuel-du-travailleur-autonome\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petit manuel du travailleur autonome - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Publi\u00e9 le\u00a03 avril 2013\u00a0dans le Kiosque M\u00e9dias Petit manuel du travailleur autonome Conseils et t\u00e9moignages Par Martine Letarte et Judith Lussier Les \u00c9ditions La Presse 199 p. 17,99 $ Pourquoi s\u2019imposer un patron, alors qu\u2019on est parfaitement capables de se g\u00e9rer soi-m\u00eame\u00a0? Pourquoi se d\u00e9placer tous les jours \u00e0 un bureau, alors qu\u2019il est possible de travailler du confort de notre salon\u00a0?\u00a0 Et surtout, qu\u2019est-ce qui nous retient de mener la vie qu\u2019on aime vraiment\u00a0? \u00ab\u00a0Les gens se sous-estiment. Avec ce livre, je voulais leur dire qu\u2019ils sont capables. Les gens pensent qu\u2019ils ont besoin d\u2019un patron dans leur dos pour leur dire quoi faire, alors que ce n\u2019est pas vrai\u00a0!\u00a0\u00bb Judith Lussier, journaliste pour plusieurs magazines ainsi que sur le web, a aussi une chronique dans le journal M\u00e9tro. \u00ab\u00a0Et je me permets de faire plein d\u2019autres choses.\u00a0\u00bb Comme d\u2019\u00e9crire un film de fiction avec sa conjointe et d\u2019entretenir d\u2019autres projets de livres. \u00ab\u00a0Ma vie est extraordinaire. Je pense que des salari\u00e9s peuvent \u00eatre tr\u00e8s confortables dans le salariat et trouver que j\u2019ai un discours un peu utopiste, mais on le dit dans le livre, nous, c\u2019est \u00e7a qui nous convient. \u00c0 vous de voir si c\u2019est pour vous ou pas.\u00a0\u00bb Et c\u2019est ce qu\u2019elle et Martine Letarte nous proposent. Le Petit manuel du travailleur autonome est un guide pour tous ceux qui r\u00eavent de travailler \u00e0 leur compte, mais qui n\u2019osent pas abandonner leur paye du jeudi, ou qui pensent manquer de discipline personnelle. Les deux journalistes nous partagent leurs exp\u00e9riences, leurs conseils, ainsi que ceux d\u2019autres travailleurs autonomes dans des secteurs aussi vari\u00e9s que le marketing, les arts, l\u2019architecture et la sant\u00e9. S\u2019y rajoutent avis d\u2019expert en comptabilit\u00e9, de sp\u00e9cialiste en gestion du temps, psychologue, kin\u00e9siologue, pour offrir \u00e0 tous ceux qui le souhaitent les outils n\u00e9cessaires pour se lancer dans le travail autonome. On verra ainsi que les mythes du pigiste qui meurt de faim, qui m\u00e8ne une vie instable en attendant de se trouver un vrai travail, ou qui est en vacances tous les jours sont, tout simplement\u2026 des mythes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/petit-manuel-du-travailleur-autonome\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-03T02:08:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-03T22:04:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/prochainelecture.com\/wp-content\/uploads\/2013\/04\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Petit manuel du travailleur autonome\",\"datePublished\":\"2013-04-03T02:08:38+00:00\",\"dateModified\":\"2020-08-03T22:04:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/\"},\"wordCount\":381,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1\",\"articleSection\":[\"Se renseigner\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/\",\"name\":\"Petit manuel du travailleur autonome - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1\",\"datePublished\":\"2013-04-03T02:08:38+00:00\",\"dateModified\":\"2020-08-03T22:04:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1\",\"width\":675,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/petit-manuel-du-travailleur-autonome\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petit manuel du travailleur autonome\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petit manuel du travailleur autonome - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/petit-manuel-du-travailleur-autonome\/","og_locale":"fr_CA","og_type":"article","og_title":"Petit manuel du travailleur autonome - Prochaine lecture","og_description":"Publi\u00e9 le\u00a03 avril 2013\u00a0dans le Kiosque M\u00e9dias Petit manuel du travailleur autonome Conseils et t\u00e9moignages Par Martine Letarte et Judith Lussier Les \u00c9ditions La Presse 199 p. 17,99 $ Pourquoi s\u2019imposer un patron, alors qu\u2019on est parfaitement capables de se g\u00e9rer soi-m\u00eame\u00a0? Pourquoi se d\u00e9placer tous les jours \u00e0 un bureau, alors qu\u2019il est possible de travailler du confort de notre salon\u00a0?\u00a0 Et surtout, qu\u2019est-ce qui nous retient de mener la vie qu\u2019on aime vraiment\u00a0? \u00ab\u00a0Les gens se sous-estiment. Avec ce livre, je voulais leur dire qu\u2019ils sont capables. Les gens pensent qu\u2019ils ont besoin d\u2019un patron dans leur dos pour leur dire quoi faire, alors que ce n\u2019est pas vrai\u00a0!\u00a0\u00bb Judith Lussier, journaliste pour plusieurs magazines ainsi que sur le web, a aussi une chronique dans le journal M\u00e9tro. \u00ab\u00a0Et je me permets de faire plein d\u2019autres choses.\u00a0\u00bb Comme d\u2019\u00e9crire un film de fiction avec sa conjointe et d\u2019entretenir d\u2019autres projets de livres. \u00ab\u00a0Ma vie est extraordinaire. Je pense que des salari\u00e9s peuvent \u00eatre tr\u00e8s confortables dans le salariat et trouver que j\u2019ai un discours un peu utopiste, mais on le dit dans le livre, nous, c\u2019est \u00e7a qui nous convient. \u00c0 vous de voir si c\u2019est pour vous ou pas.\u00a0\u00bb Et c\u2019est ce qu\u2019elle et Martine Letarte nous proposent. Le Petit manuel du travailleur autonome est un guide pour tous ceux qui r\u00eavent de travailler \u00e0 leur compte, mais qui n\u2019osent pas abandonner leur paye du jeudi, ou qui pensent manquer de discipline personnelle. Les deux journalistes nous partagent leurs exp\u00e9riences, leurs conseils, ainsi que ceux d\u2019autres travailleurs autonomes dans des secteurs aussi vari\u00e9s que le marketing, les arts, l\u2019architecture et la sant\u00e9. S\u2019y rajoutent avis d\u2019expert en comptabilit\u00e9, de sp\u00e9cialiste en gestion du temps, psychologue, kin\u00e9siologue, pour offrir \u00e0 tous ceux qui le souhaitent les outils n\u00e9cessaires pour se lancer dans le travail autonome. On verra ainsi que les mythes du pigiste qui meurt de faim, qui m\u00e8ne une vie instable en attendant de se trouver un vrai travail, ou qui est en vacances tous les jours sont, tout simplement\u2026 des mythes.","og_url":"https:\/\/prochainelecture.com\/fr\/petit-manuel-du-travailleur-autonome\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2013-04-03T02:08:38+00:00","article_modified_time":"2020-08-03T22:04:47+00:00","og_image":[{"width":675,"height":450,"url":"https:\/\/i2.wp.com\/prochainelecture.com\/wp-content\/uploads\/2013\/04\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Petit manuel du travailleur autonome","datePublished":"2013-04-03T02:08:38+00:00","dateModified":"2020-08-03T22:04:47+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/"},"wordCount":381,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2013\/04\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1","articleSection":["Se renseigner"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/","url":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/","name":"Petit manuel du travailleur autonome - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2013\/04\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1","datePublished":"2013-04-03T02:08:38+00:00","dateModified":"2020-08-03T22:04:47+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2013\/04\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2013\/04\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1","width":675,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/petit-manuel-du-travailleur-autonome\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Petit manuel du travailleur autonome"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2013\/04\/manuel-travailleur-1.jpg?fit=675%2C450&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-3t","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=215"}],"version-history":[{"count":2,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/215\/revisions"}],"predecessor-version":[{"id":3414,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/215\/revisions\/3414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3413"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}