{"id":1810,"date":"2020-05-19T23:40:24","date_gmt":"2020-05-19T23:40:24","guid":{"rendered":"http:\/\/www.naimahassert.com\/?p=1810"},"modified":"2020-08-03T19:00:52","modified_gmt":"2020-08-03T19:00:52","slug":"alphabetical-how-every-letter-tells-a-story","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/alphabetical-how-every-letter-tells-a-story\/","title":{"rendered":"Alphabetical: How Every Letter Tells a Story"},"content":{"rendered":"\n<p><strong>Qui aurait cru que ce livre qui parle des lettres de l&#8217;alphabet, une \u00e0 la fois, me divertirait et m&#8217;inspirerait autant?<\/strong><\/p>\n\n\n\n<p>Ce livre de 400 pages est divis\u00e9 en 26 parties, pour les 26 lettres de l&#8217;alphabet. D&#8217;abord, on apprend l&#8217;histoire de la lettre en question, comment elle est arriv\u00e9e \u00e0 avoir l&#8217;apparence qu&#8217;elle a actuellement, comment on prononce le nom de la lettre et pourquoi, et quel est le son qu&#8217;elle sert \u00e0 repr\u00e9senter. Cette section finit \u00e0 chaque fois par le &#8220;sound-play&#8221; possible avec chaque lettre, ce qui me faisait toujours sourire. Par exemple, pour F : <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Sound-play for &#8216;f&#8217; gives us &#8216;fluff&#8217;, and the word my father used for &#8216;don&#8217;t fuss&#8217; &#8211; &#8216;don&#8217;t faff&#8217;. &#8216;Fee-fi-fo-fum&#8230;&#8217; has lasted several centuries. There is also a noise of disbelief doing the rounds which sounds something like &#8216;fwof&#8217;. Unhelpfully enough, sometimes the &#8216;f&#8217; sound can also be written with a &#8216;ph&#8217;: when we say &#8216;phew&#8217; to people we&#8217;re tired or relieved. &#8216;Phwoar&#8217; &#8211; as the noise to mean, &#8216;You&#8217;re sexy&#8217;.<\/p><p>&#8216;For better or for worse&#8217; is a double phrase in which each half is linked by the initial &#8216;f&#8217; in &#8216;for&#8217;.<\/p><\/blockquote>\n\n\n\n<p>Mais le plus savoureux, c&#8217;est ce qui vient apr\u00e8s. L&#8217;auteur s&#8217;amuse \u00e0 parler du sujet de son choix, reli\u00e9 d&#8217;une fa\u00e7on ou d&#8217;une autre \u00e0 l&#8217;alphabet, et c&#8217;est toujours fascinant. Pour F, c&#8217;est : &#8220;F is for Font&#8221;. \u00c0 travers ces multiples sections, j&#8217;ai appris plein de choses sur la calligraphie et comment elle a \u00e9t\u00e9 enseign\u00e9e aux enfants au fil du temps, sur les polices de caract\u00e8res avant l&#8217;arriv\u00e9e des ordinateurs, sur l&#8217;origine du code postal et du mot &#8220;OK&#8221;, et j&#8217;ai appris pourquoi notre clavier d&#8217;ordinateur est organis\u00e9 comme il l&#8217;est.<\/p>\n\n\n\n<p>La partie sur les claviers d&#8217;ordinateur m&#8217;a inspir\u00e9 de fa\u00e7on tout \u00e0 fait inattendue. Michael Rosen m&#8217;a fait remarquer qu&#8217;alors que tous les enfants apprennent \u00e0 \u00e9crire sur du papier \u00e0 l&#8217;aide d&#8217;une m\u00e9thode pr\u00e9cise \u00e0 l&#8217;\u00e9cole, l&#8217;\u00e9criture \u00e0 l&#8217;ordinateur est totalement absente du curriculum scolaire. Alors que j&#8217;\u00e9cris 10 fois plus souvent sur un ordinateur, je n&#8217;ai jamais appris \u00e0 le faire correctement. Je me suis alors empress\u00e9e de chercher sur internet ce qui pourrait m&#8217;apprendre \u00e0 taper rapidement, et je suis tomb\u00e9e sur ce site g\u00e9nial : <a href=\"https:\/\/www.typingclub.com\/\">https:\/\/www.typingclub.com\/<\/a>. Mon amoureux et moi sommes devenus accrocs et on a pass\u00e9 bien des soir\u00e9es \u00e0 se pratiquer comme des gros nerds l&#8217;un \u00e0 c\u00f4t\u00e9 de l&#8217;autre. Il a termin\u00e9 les le\u00e7ons avant moi, et maintenant il s&#8217;entra\u00eene en tapant un roman au complet gr\u00e2ce \u00e0 cet autre site g\u00e9nial <a href=\"https:\/\/www.keybr.com\/\">https:\/\/www.keybr.com\/<\/a>, o\u00f9 dans les param\u00e8tres on peut rentrer notre propre texte sur lesquels s&#8217;entra\u00eener. <a href=\"http:\/\/www.gutenberg.org\/wiki\/FR_Page_d%27Accueil\">Le projet Gutenberg<\/a> nous fournit pour \u00e7a une source infinie de plaisir.<\/p>\n\n\n\n<p>Je conseille ce livre aux amoureux des mots et aux parents d&#8217;enfants curieux qui ne manqueront pas de s&#8217;\u00e9merveiller&#8230; et qui auront peut-\u00eatre la chance de vouloir apprendre comment bien taper \u00e0 l&#8217;ordinateur avant d&#8217;atteindre l&#8217;\u00e2ge adulte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui aurait cru que ce livre qui parle des lettres de l&#8217;alphabet, une \u00e0 la fois, me divertirait et m&#8217;inspirerait autant? Ce livre de 400 pages est divis\u00e9 en 26 parties, pour les 26 lettres de l&#8217;alphabet. D&#8217;abord, on apprend l&#8217;histoire de la lettre en question, comment elle est arriv\u00e9e \u00e0 avoir l&#8217;apparence qu&#8217;elle a actuellement, comment on prononce le nom de la lettre et pourquoi, et quel est le son qu&#8217;elle sert \u00e0 repr\u00e9senter. Cette section finit \u00e0 chaque fois par le &#8220;sound-play&#8221; possible avec chaque lettre, ce qui me faisait toujours sourire. Par exemple, pour F : Sound-play for &#8216;f&#8217; gives us &#8216;fluff&#8217;, and the word my father used for &#8216;don&#8217;t fuss&#8217; &#8211; &#8216;don&#8217;t faff&#8217;. &#8216;Fee-fi-fo-fum&#8230;&#8217; has lasted several centuries. There is also a noise of disbelief doing the rounds which sounds something like &#8216;fwof&#8217;. Unhelpfully enough, sometimes the &#8216;f&#8217; sound can also be written with a &#8216;ph&#8217;: when we say &#8216;phew&#8217; to people we&#8217;re tired or relieved. &#8216;Phwoar&#8217; &#8211; as the noise to mean, &#8216;You&#8217;re sexy&#8217;. &#8216;For better or for worse&#8217; is a double phrase in which each half is linked by the initial &#8216;f&#8217; in &#8216;for&#8217;. Mais le plus savoureux, c&#8217;est ce qui vient apr\u00e8s. L&#8217;auteur s&#8217;amuse \u00e0 parler du sujet de son choix, reli\u00e9 d&#8217;une fa\u00e7on ou d&#8217;une autre \u00e0 l&#8217;alphabet, et c&#8217;est toujours fascinant. Pour F, c&#8217;est : &#8220;F is for Font&#8221;. \u00c0 travers ces multiples sections, j&#8217;ai appris plein de choses sur la calligraphie et comment elle a \u00e9t\u00e9 enseign\u00e9e aux enfants au fil du temps, sur les polices de caract\u00e8res avant l&#8217;arriv\u00e9e des ordinateurs, sur l&#8217;origine du code postal et du mot &#8220;OK&#8221;, et j&#8217;ai appris pourquoi notre clavier d&#8217;ordinateur est organis\u00e9 comme il l&#8217;est. La partie sur les claviers d&#8217;ordinateur m&#8217;a inspir\u00e9 de fa\u00e7on tout \u00e0 fait inattendue. Michael Rosen m&#8217;a fait remarquer qu&#8217;alors que tous les enfants apprennent \u00e0 \u00e9crire sur du papier \u00e0 l&#8217;aide d&#8217;une m\u00e9thode pr\u00e9cise \u00e0 l&#8217;\u00e9cole, l&#8217;\u00e9criture \u00e0 l&#8217;ordinateur est totalement absente du curriculum scolaire. Alors que j&#8217;\u00e9cris 10 fois plus souvent sur un ordinateur, je n&#8217;ai jamais appris \u00e0 le faire correctement. Je me suis alors empress\u00e9e de chercher sur internet ce qui pourrait m&#8217;apprendre \u00e0 taper rapidement, et je suis tomb\u00e9e sur ce site g\u00e9nial : https:\/\/www.typingclub.com\/. Mon amoureux et moi sommes devenus accrocs et on a pass\u00e9 bien des soir\u00e9es \u00e0 se pratiquer comme des gros nerds l&#8217;un \u00e0 c\u00f4t\u00e9 de l&#8217;autre. Il a termin\u00e9 les le\u00e7ons avant moi, et maintenant il s&#8217;entra\u00eene en tapant un roman au complet gr\u00e2ce \u00e0 cet autre site g\u00e9nial https:\/\/www.keybr.com\/, o\u00f9 dans les param\u00e8tres on peut rentrer notre propre texte sur lesquels s&#8217;entra\u00eener. Le projet Gutenberg nous fournit pour \u00e7a une source infinie de plaisir. Je conseille ce livre aux amoureux des mots et aux parents d&#8217;enfants curieux qui ne manqueront pas de s&#8217;\u00e9merveiller&#8230; et qui auront peut-\u00eatre la chance de vouloir apprendre comment bien taper \u00e0 l&#8217;ordinateur avant d&#8217;atteindre l&#8217;\u00e2ge adulte.<\/p>\n","protected":false},"author":1,"featured_media":3374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[252,249],"tags":[],"class_list":["post-1810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-langues-et-linguistique","category-se-renseigner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alphabetical: How Every Letter Tells a Story - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/alphabetical-how-every-letter-tells-a-story\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alphabetical: How Every Letter Tells a Story - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Qui aurait cru que ce livre qui parle des lettres de l&#8217;alphabet, une \u00e0 la fois, me divertirait et m&#8217;inspirerait autant? Ce livre de 400 pages est divis\u00e9 en 26 parties, pour les 26 lettres de l&#8217;alphabet. D&#8217;abord, on apprend l&#8217;histoire de la lettre en question, comment elle est arriv\u00e9e \u00e0 avoir l&#8217;apparence qu&#8217;elle a actuellement, comment on prononce le nom de la lettre et pourquoi, et quel est le son qu&#8217;elle sert \u00e0 repr\u00e9senter. Cette section finit \u00e0 chaque fois par le &#8220;sound-play&#8221; possible avec chaque lettre, ce qui me faisait toujours sourire. Par exemple, pour F : Sound-play for &#8216;f&#8217; gives us &#8216;fluff&#8217;, and the word my father used for &#8216;don&#8217;t fuss&#8217; &#8211; &#8216;don&#8217;t faff&#8217;. &#8216;Fee-fi-fo-fum&#8230;&#8217; has lasted several centuries. There is also a noise of disbelief doing the rounds which sounds something like &#8216;fwof&#8217;. Unhelpfully enough, sometimes the &#8216;f&#8217; sound can also be written with a &#8216;ph&#8217;: when we say &#8216;phew&#8217; to people we&#8217;re tired or relieved. &#8216;Phwoar&#8217; &#8211; as the noise to mean, &#8216;You&#8217;re sexy&#8217;. &#8216;For better or for worse&#8217; is a double phrase in which each half is linked by the initial &#8216;f&#8217; in &#8216;for&#8217;. Mais le plus savoureux, c&#8217;est ce qui vient apr\u00e8s. L&#8217;auteur s&#8217;amuse \u00e0 parler du sujet de son choix, reli\u00e9 d&#8217;une fa\u00e7on ou d&#8217;une autre \u00e0 l&#8217;alphabet, et c&#8217;est toujours fascinant. Pour F, c&#8217;est : &#8220;F is for Font&#8221;. \u00c0 travers ces multiples sections, j&#8217;ai appris plein de choses sur la calligraphie et comment elle a \u00e9t\u00e9 enseign\u00e9e aux enfants au fil du temps, sur les polices de caract\u00e8res avant l&#8217;arriv\u00e9e des ordinateurs, sur l&#8217;origine du code postal et du mot &#8220;OK&#8221;, et j&#8217;ai appris pourquoi notre clavier d&#8217;ordinateur est organis\u00e9 comme il l&#8217;est. La partie sur les claviers d&#8217;ordinateur m&#8217;a inspir\u00e9 de fa\u00e7on tout \u00e0 fait inattendue. Michael Rosen m&#8217;a fait remarquer qu&#8217;alors que tous les enfants apprennent \u00e0 \u00e9crire sur du papier \u00e0 l&#8217;aide d&#8217;une m\u00e9thode pr\u00e9cise \u00e0 l&#8217;\u00e9cole, l&#8217;\u00e9criture \u00e0 l&#8217;ordinateur est totalement absente du curriculum scolaire. Alors que j&#8217;\u00e9cris 10 fois plus souvent sur un ordinateur, je n&#8217;ai jamais appris \u00e0 le faire correctement. Je me suis alors empress\u00e9e de chercher sur internet ce qui pourrait m&#8217;apprendre \u00e0 taper rapidement, et je suis tomb\u00e9e sur ce site g\u00e9nial : https:\/\/www.typingclub.com\/. Mon amoureux et moi sommes devenus accrocs et on a pass\u00e9 bien des soir\u00e9es \u00e0 se pratiquer comme des gros nerds l&#8217;un \u00e0 c\u00f4t\u00e9 de l&#8217;autre. Il a termin\u00e9 les le\u00e7ons avant moi, et maintenant il s&#8217;entra\u00eene en tapant un roman au complet gr\u00e2ce \u00e0 cet autre site g\u00e9nial https:\/\/www.keybr.com\/, o\u00f9 dans les param\u00e8tres on peut rentrer notre propre texte sur lesquels s&#8217;entra\u00eener. Le projet Gutenberg nous fournit pour \u00e7a une source infinie de plaisir. Je conseille ce livre aux amoureux des mots et aux parents d&#8217;enfants curieux qui ne manqueront pas de s&#8217;\u00e9merveiller&#8230; et qui auront peut-\u00eatre la chance de vouloir apprendre comment bien taper \u00e0 l&#8217;ordinateur avant d&#8217;atteindre l&#8217;\u00e2ge adulte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/alphabetical-how-every-letter-tells-a-story\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-19T23:40:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-03T19:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/05\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Alphabetical: How Every Letter Tells a Story\",\"datePublished\":\"2020-05-19T23:40:24+00:00\",\"dateModified\":\"2020-08-03T19:00:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/\"},\"wordCount\":542,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Langues et linguistique\",\"Se renseigner\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/\",\"name\":\"Alphabetical: How Every Letter Tells a Story - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2020-05-19T23:40:24+00:00\",\"dateModified\":\"2020-08-03T19:00:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/alphabetical-how-every-letter-tells-a-story\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alphabetical: How Every Letter Tells a Story\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alphabetical: How Every Letter Tells a Story - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/alphabetical-how-every-letter-tells-a-story\/","og_locale":"fr_CA","og_type":"article","og_title":"Alphabetical: How Every Letter Tells a Story - Prochaine lecture","og_description":"Qui aurait cru que ce livre qui parle des lettres de l&#8217;alphabet, une \u00e0 la fois, me divertirait et m&#8217;inspirerait autant? Ce livre de 400 pages est divis\u00e9 en 26 parties, pour les 26 lettres de l&#8217;alphabet. D&#8217;abord, on apprend l&#8217;histoire de la lettre en question, comment elle est arriv\u00e9e \u00e0 avoir l&#8217;apparence qu&#8217;elle a actuellement, comment on prononce le nom de la lettre et pourquoi, et quel est le son qu&#8217;elle sert \u00e0 repr\u00e9senter. Cette section finit \u00e0 chaque fois par le &#8220;sound-play&#8221; possible avec chaque lettre, ce qui me faisait toujours sourire. Par exemple, pour F : Sound-play for &#8216;f&#8217; gives us &#8216;fluff&#8217;, and the word my father used for &#8216;don&#8217;t fuss&#8217; &#8211; &#8216;don&#8217;t faff&#8217;. &#8216;Fee-fi-fo-fum&#8230;&#8217; has lasted several centuries. There is also a noise of disbelief doing the rounds which sounds something like &#8216;fwof&#8217;. Unhelpfully enough, sometimes the &#8216;f&#8217; sound can also be written with a &#8216;ph&#8217;: when we say &#8216;phew&#8217; to people we&#8217;re tired or relieved. &#8216;Phwoar&#8217; &#8211; as the noise to mean, &#8216;You&#8217;re sexy&#8217;. &#8216;For better or for worse&#8217; is a double phrase in which each half is linked by the initial &#8216;f&#8217; in &#8216;for&#8217;. Mais le plus savoureux, c&#8217;est ce qui vient apr\u00e8s. L&#8217;auteur s&#8217;amuse \u00e0 parler du sujet de son choix, reli\u00e9 d&#8217;une fa\u00e7on ou d&#8217;une autre \u00e0 l&#8217;alphabet, et c&#8217;est toujours fascinant. Pour F, c&#8217;est : &#8220;F is for Font&#8221;. \u00c0 travers ces multiples sections, j&#8217;ai appris plein de choses sur la calligraphie et comment elle a \u00e9t\u00e9 enseign\u00e9e aux enfants au fil du temps, sur les polices de caract\u00e8res avant l&#8217;arriv\u00e9e des ordinateurs, sur l&#8217;origine du code postal et du mot &#8220;OK&#8221;, et j&#8217;ai appris pourquoi notre clavier d&#8217;ordinateur est organis\u00e9 comme il l&#8217;est. La partie sur les claviers d&#8217;ordinateur m&#8217;a inspir\u00e9 de fa\u00e7on tout \u00e0 fait inattendue. Michael Rosen m&#8217;a fait remarquer qu&#8217;alors que tous les enfants apprennent \u00e0 \u00e9crire sur du papier \u00e0 l&#8217;aide d&#8217;une m\u00e9thode pr\u00e9cise \u00e0 l&#8217;\u00e9cole, l&#8217;\u00e9criture \u00e0 l&#8217;ordinateur est totalement absente du curriculum scolaire. Alors que j&#8217;\u00e9cris 10 fois plus souvent sur un ordinateur, je n&#8217;ai jamais appris \u00e0 le faire correctement. Je me suis alors empress\u00e9e de chercher sur internet ce qui pourrait m&#8217;apprendre \u00e0 taper rapidement, et je suis tomb\u00e9e sur ce site g\u00e9nial : https:\/\/www.typingclub.com\/. Mon amoureux et moi sommes devenus accrocs et on a pass\u00e9 bien des soir\u00e9es \u00e0 se pratiquer comme des gros nerds l&#8217;un \u00e0 c\u00f4t\u00e9 de l&#8217;autre. Il a termin\u00e9 les le\u00e7ons avant moi, et maintenant il s&#8217;entra\u00eene en tapant un roman au complet gr\u00e2ce \u00e0 cet autre site g\u00e9nial https:\/\/www.keybr.com\/, o\u00f9 dans les param\u00e8tres on peut rentrer notre propre texte sur lesquels s&#8217;entra\u00eener. Le projet Gutenberg nous fournit pour \u00e7a une source infinie de plaisir. Je conseille ce livre aux amoureux des mots et aux parents d&#8217;enfants curieux qui ne manqueront pas de s&#8217;\u00e9merveiller&#8230; et qui auront peut-\u00eatre la chance de vouloir apprendre comment bien taper \u00e0 l&#8217;ordinateur avant d&#8217;atteindre l&#8217;\u00e2ge adulte.","og_url":"https:\/\/prochainelecture.com\/fr\/alphabetical-how-every-letter-tells-a-story\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2020-05-19T23:40:24+00:00","article_modified_time":"2020-08-03T19:00:52+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/05\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Alphabetical: How Every Letter Tells a Story","datePublished":"2020-05-19T23:40:24+00:00","dateModified":"2020-08-03T19:00:52+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/"},"wordCount":542,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/05\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1","articleSection":["Langues et linguistique","Se renseigner"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/","url":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/","name":"Alphabetical: How Every Letter Tells a Story - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/05\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1","datePublished":"2020-05-19T23:40:24+00:00","dateModified":"2020-08-03T19:00:52+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/05\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/05\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/alphabetical-how-every-letter-tells-a-story\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Alphabetical: How Every Letter Tells a Story"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/05\/714iS3By-L-1.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-tc","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=1810"}],"version-history":[{"count":2,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1810\/revisions"}],"predecessor-version":[{"id":3375,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1810\/revisions\/3375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3374"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=1810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=1810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=1810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}