{"id":1476,"date":"2017-04-23T20:59:54","date_gmt":"2017-04-23T20:59:54","guid":{"rendered":"http:\/\/www.naimahassert.com\/?p=1476"},"modified":"2025-11-09T23:34:40","modified_gmt":"2025-11-10T03:34:40","slug":"men-marry-bitches-womans-guide-winning-mans-heart","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/men-marry-bitches-womans-guide-winning-mans-heart\/","title":{"rendered":"Why Men Marry Bitches &#8211; A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart"},"content":{"rendered":"<p><strong>\u00catre c\u00e9libataire, c&#8217;est plate. J&#8217;ai le go\u00fbt d&#8217;avoir du fun et de partager ma vie avec quelqu&#8217;un de bien. Mais non, \u00e0 la place, je m&#8217;entiche de gars avec qui il n&#8217;y a pas d&#8217;avenir et apr\u00e8s je d\u00e9prime. Moi, tann\u00e9e. J&#8217;imagine qu&#8217;on a fini par avoir piti\u00e9 : on m&#8217;a donn\u00e9 ce livre.<\/strong><\/p>\n<p>D\u00e9j\u00e0, un avertissement : quand l&#8217;auteure parle des &#8220;bitchs&#8221;, il faut le prendre avec humour. Selon son lexique, une bitch est une femme ind\u00e9pendante, qui n&#8217;a besoin de personne, qui dit ce qu&#8217;elle pense et qui ne va pas se laisser marcher sur les pieds. C&#8217;est \u00e0 la fois bon pour elle, et bon pour sa future relation, parce que les hommes n&#8217;aiment pas les moumounes. Faire la gentille, c&#8217;est peut-\u00eatre naturel pour beaucoup d&#8217;entre nous, mais c&#8217;est pas gagnant. Solution : arr\u00eater \u00e7a! Elle nous dit comment faire en 74 &#8220;principes relationnels&#8221;, divis\u00e9s en 7 cat\u00e9gories.<\/p>\n<h3>1- D\u00e9truire les mythes, ou jeter les magazines f\u00e9minins \u00e0 la poubelle<\/h3>\n<p>On parle de la femme parfaite, la bombe de sexe et la yes-girl. Les gars ne veulent pas d&#8217;une poup\u00e9e. Ils veulent une blonde avec qui&#8230; avoir du fun et partager leur vie.<\/p>\n<h3>2- Se laisser courir apr\u00e8s<\/h3>\n<p>Un principe pas nouveau du tout. Les gars adorent \u00e7a courir apr\u00e8s les filles. Sinon, c&#8217;est trop facile et ils perdent l&#8217;int\u00e9r\u00eat. Je sais, vous me croirez pas. Tant pis pour vous.<\/p>\n<h3>3- Allumer le feu\u00a0dans ses pantalons<\/h3>\n<p>\u00c7a, c&#8217;\u00e9tait du nouveau pour moi. Je vous r\u00e9serve le punch.<\/p>\n<h3>4- Conna\u00eetre les petits jeux des gars<\/h3>\n<p>C&#8217;est pas m\u00e9chant, mais ils veulent savoir \u00e0 qui ils font affaire. Ils vont essayer de trouver les points faibles de la fille et d&#8217;appuyer dessus. Si elle r\u00e9pond bien, elle va gagner son respect. Ne pas le prendre trop personnel.<\/p>\n<h3>5- Avoir une vie professionnelle<\/h3>\n<p>Un gars va vouloir passer sa vie avec une femme qui sait gagner au moins assez d&#8217;argent pour vivre. \u00c7a lui fera plaisir de l&#8217;inviter \u00e0 des dates, mais il ne veut pas qu&#8217;elle d\u00e9pende de lui. C&#8217;est un gros turn-off.<\/p>\n<h3>6- Se mettre dans sa t\u00eate<\/h3>\n<p>L&#8217;auteure dit avoir interview\u00e9 des centaines de gars qui lui ont r\u00e9v\u00e9l\u00e9 ce qui les allumaient ou pas chez les filles. Elle nous donne les grandes lignes. Aoutch.<\/p>\n<h3>7- L&#8217;amener \u00e0 s&#8217;engager<\/h3>\n<p>Le truc : s&#8217;arranger pour que ce soit lui qui veuille le faire. Et un gars en amour, c&#8217;est un gars qui veut passer sa vie avec\u00a0sa blonde.<\/p>\n<h3>Le plus int\u00e9ressant : la morale<\/h3>\n<p>Pas cucul du tout, ce livre m&#8217;a donn\u00e9 une \u00e9nergie incroyable, parce qu&#8217;il m&#8217;a rappel\u00e9 que je suis hot. (Malheureusement, c&#8217;est facile\u00a0\u00e0 oublier.) Beaucoup de gars vont \u00eatre int\u00e9ress\u00e9s, mais il faut que je regarde ce qu&#8217;ils peuvent m&#8217;apporter, \u00e0 moi. Comment je me sens avec eux et apr\u00e8s que je les ai vus? Est-ce que je me sens nulle, rabaiss\u00e9e, d\u00e9\u00e7ue, mal \u00e0 l&#8217;aise, triste, ins\u00e9cure? Je flushe. (Plut\u00f4t que de dire &#8220;Peut-\u00eatre que c&#8217;est ma faute? Peut-\u00eatre que c&#8217;est un gars incroyable et que je pourrais \u00eatre heureuse avec si j&#8217;agissais de la bonne mani\u00e8re?&#8221; Non. Il n&#8217;y a rien derri\u00e8re la colline.)\u00a0Ou bien dr\u00f4le, belle et en confiance?\u00a0Ceux qui nous font sentir comme \u00e7a sont \u00e0 conserver pr\u00e9cieusement. Et \u00e7a commence par prendre soin de soi.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/amzn.to\/2pan2IG\"><strong>Why Men Marry Bitches : A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart<\/strong><\/a><\/p>\n<p><strong>Sherry Argov\u00a0<\/strong><\/p>\n<p><strong>0,01 $ (!!)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00catre c\u00e9libataire, c&#8217;est plate. J&#8217;ai le go\u00fbt d&#8217;avoir du fun et de partager ma vie avec quelqu&#8217;un de bien. Mais non, \u00e0 la place, je m&#8217;entiche de gars avec qui il n&#8217;y a pas d&#8217;avenir et apr\u00e8s je d\u00e9prime. Moi, tann\u00e9e. J&#8217;imagine qu&#8217;on a fini par avoir piti\u00e9 : on m&#8217;a donn\u00e9 ce livre. D\u00e9j\u00e0, un avertissement : quand l&#8217;auteure parle des &#8220;bitchs&#8221;, il faut le prendre avec humour. Selon son lexique, une bitch est une femme ind\u00e9pendante, qui n&#8217;a besoin de personne, qui dit ce qu&#8217;elle pense et qui ne va pas se laisser marcher sur les pieds. C&#8217;est \u00e0 la fois bon pour elle, et bon pour sa future relation, parce que les hommes n&#8217;aiment pas les moumounes. Faire la gentille, c&#8217;est peut-\u00eatre naturel pour beaucoup d&#8217;entre nous, mais c&#8217;est pas gagnant. Solution : arr\u00eater \u00e7a! Elle nous dit comment faire en 74 &#8220;principes relationnels&#8221;, divis\u00e9s en 7 cat\u00e9gories. 1- D\u00e9truire les mythes, ou jeter les magazines f\u00e9minins \u00e0 la poubelle On parle de la femme parfaite, la bombe de sexe et la yes-girl. Les gars ne veulent pas d&#8217;une poup\u00e9e. Ils veulent une blonde avec qui&#8230; avoir du fun et partager leur vie. 2- Se laisser courir apr\u00e8s Un principe pas nouveau du tout. Les gars adorent \u00e7a courir apr\u00e8s les filles. Sinon, c&#8217;est trop facile et ils perdent l&#8217;int\u00e9r\u00eat. Je sais, vous me croirez pas. Tant pis pour vous. 3- Allumer le feu\u00a0dans ses pantalons \u00c7a, c&#8217;\u00e9tait du nouveau pour moi. Je vous r\u00e9serve le punch. 4- Conna\u00eetre les petits jeux des gars C&#8217;est pas m\u00e9chant, mais ils veulent savoir \u00e0 qui ils font affaire. Ils vont essayer de trouver les points faibles de la fille et d&#8217;appuyer dessus. Si elle r\u00e9pond bien, elle va gagner son respect. Ne pas le prendre trop personnel. 5- Avoir une vie professionnelle Un gars va vouloir passer sa vie avec une femme qui sait gagner au moins assez d&#8217;argent pour vivre. \u00c7a lui fera plaisir de l&#8217;inviter \u00e0 des dates, mais il ne veut pas qu&#8217;elle d\u00e9pende de lui. C&#8217;est un gros turn-off. 6- Se mettre dans sa t\u00eate L&#8217;auteure dit avoir interview\u00e9 des centaines de gars qui lui ont r\u00e9v\u00e9l\u00e9 ce qui les allumaient ou pas chez les filles. Elle nous donne les grandes lignes. Aoutch. 7- L&#8217;amener \u00e0 s&#8217;engager Le truc : s&#8217;arranger pour que ce soit lui qui veuille le faire. Et un gars en amour, c&#8217;est un gars qui veut passer sa vie avec\u00a0sa blonde. Le plus int\u00e9ressant : la morale Pas cucul du tout, ce livre m&#8217;a donn\u00e9 une \u00e9nergie incroyable, parce qu&#8217;il m&#8217;a rappel\u00e9 que je suis hot. (Malheureusement, c&#8217;est facile\u00a0\u00e0 oublier.) Beaucoup de gars vont \u00eatre int\u00e9ress\u00e9s, mais il faut que je regarde ce qu&#8217;ils peuvent m&#8217;apporter, \u00e0 moi. Comment je me sens avec eux et apr\u00e8s que je les ai vus? Est-ce que je me sens nulle, rabaiss\u00e9e, d\u00e9\u00e7ue, mal \u00e0 l&#8217;aise, triste, ins\u00e9cure? Je flushe. (Plut\u00f4t que de dire &#8220;Peut-\u00eatre que c&#8217;est ma faute? Peut-\u00eatre que c&#8217;est un gars incroyable et que je pourrais \u00eatre heureuse avec si j&#8217;agissais de la bonne mani\u00e8re?&#8221; Non. Il n&#8217;y a rien derri\u00e8re la colline.)\u00a0Ou bien dr\u00f4le, belle et en confiance?\u00a0Ceux qui nous font sentir comme \u00e7a sont \u00e0 conserver pr\u00e9cieusement. Et \u00e7a commence par prendre soin de soi. Why Men Marry Bitches : A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart Sherry Argov\u00a0 0,01 $ (!!)<\/p>\n","protected":false},"author":1,"featured_media":3425,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[254,249],"tags":[],"class_list":["post-1476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-developpement-personnel","category-se-renseigner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Why Men Marry Bitches - A Woman&#039;s Guide to Winning Her Man&#039;s Heart - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/men-marry-bitches-womans-guide-winning-mans-heart\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Why Men Marry Bitches - A Woman&#039;s Guide to Winning Her Man&#039;s Heart - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"\u00catre c\u00e9libataire, c&#8217;est plate. J&#8217;ai le go\u00fbt d&#8217;avoir du fun et de partager ma vie avec quelqu&#8217;un de bien. Mais non, \u00e0 la place, je m&#8217;entiche de gars avec qui il n&#8217;y a pas d&#8217;avenir et apr\u00e8s je d\u00e9prime. Moi, tann\u00e9e. J&#8217;imagine qu&#8217;on a fini par avoir piti\u00e9 : on m&#8217;a donn\u00e9 ce livre. D\u00e9j\u00e0, un avertissement : quand l&#8217;auteure parle des &#8220;bitchs&#8221;, il faut le prendre avec humour. Selon son lexique, une bitch est une femme ind\u00e9pendante, qui n&#8217;a besoin de personne, qui dit ce qu&#8217;elle pense et qui ne va pas se laisser marcher sur les pieds. C&#8217;est \u00e0 la fois bon pour elle, et bon pour sa future relation, parce que les hommes n&#8217;aiment pas les moumounes. Faire la gentille, c&#8217;est peut-\u00eatre naturel pour beaucoup d&#8217;entre nous, mais c&#8217;est pas gagnant. Solution : arr\u00eater \u00e7a! Elle nous dit comment faire en 74 &#8220;principes relationnels&#8221;, divis\u00e9s en 7 cat\u00e9gories. 1- D\u00e9truire les mythes, ou jeter les magazines f\u00e9minins \u00e0 la poubelle On parle de la femme parfaite, la bombe de sexe et la yes-girl. Les gars ne veulent pas d&#8217;une poup\u00e9e. Ils veulent une blonde avec qui&#8230; avoir du fun et partager leur vie. 2- Se laisser courir apr\u00e8s Un principe pas nouveau du tout. Les gars adorent \u00e7a courir apr\u00e8s les filles. Sinon, c&#8217;est trop facile et ils perdent l&#8217;int\u00e9r\u00eat. Je sais, vous me croirez pas. Tant pis pour vous. 3- Allumer le feu\u00a0dans ses pantalons \u00c7a, c&#8217;\u00e9tait du nouveau pour moi. Je vous r\u00e9serve le punch. 4- Conna\u00eetre les petits jeux des gars C&#8217;est pas m\u00e9chant, mais ils veulent savoir \u00e0 qui ils font affaire. Ils vont essayer de trouver les points faibles de la fille et d&#8217;appuyer dessus. Si elle r\u00e9pond bien, elle va gagner son respect. Ne pas le prendre trop personnel. 5- Avoir une vie professionnelle Un gars va vouloir passer sa vie avec une femme qui sait gagner au moins assez d&#8217;argent pour vivre. \u00c7a lui fera plaisir de l&#8217;inviter \u00e0 des dates, mais il ne veut pas qu&#8217;elle d\u00e9pende de lui. C&#8217;est un gros turn-off. 6- Se mettre dans sa t\u00eate L&#8217;auteure dit avoir interview\u00e9 des centaines de gars qui lui ont r\u00e9v\u00e9l\u00e9 ce qui les allumaient ou pas chez les filles. Elle nous donne les grandes lignes. Aoutch. 7- L&#8217;amener \u00e0 s&#8217;engager Le truc : s&#8217;arranger pour que ce soit lui qui veuille le faire. Et un gars en amour, c&#8217;est un gars qui veut passer sa vie avec\u00a0sa blonde. Le plus int\u00e9ressant : la morale Pas cucul du tout, ce livre m&#8217;a donn\u00e9 une \u00e9nergie incroyable, parce qu&#8217;il m&#8217;a rappel\u00e9 que je suis hot. (Malheureusement, c&#8217;est facile\u00a0\u00e0 oublier.) Beaucoup de gars vont \u00eatre int\u00e9ress\u00e9s, mais il faut que je regarde ce qu&#8217;ils peuvent m&#8217;apporter, \u00e0 moi. Comment je me sens avec eux et apr\u00e8s que je les ai vus? Est-ce que je me sens nulle, rabaiss\u00e9e, d\u00e9\u00e7ue, mal \u00e0 l&#8217;aise, triste, ins\u00e9cure? Je flushe. (Plut\u00f4t que de dire &#8220;Peut-\u00eatre que c&#8217;est ma faute? Peut-\u00eatre que c&#8217;est un gars incroyable et que je pourrais \u00eatre heureuse avec si j&#8217;agissais de la bonne mani\u00e8re?&#8221; Non. Il n&#8217;y a rien derri\u00e8re la colline.)\u00a0Ou bien dr\u00f4le, belle et en confiance?\u00a0Ceux qui nous font sentir comme \u00e7a sont \u00e0 conserver pr\u00e9cieusement. Et \u00e7a commence par prendre soin de soi. Why Men Marry Bitches : A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart Sherry Argov\u00a0 0,01 $ (!!)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/men-marry-bitches-womans-guide-winning-mans-heart\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-23T20:59:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T03:34:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2017\/04\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"519\" \/>\n\t<meta property=\"og:image:height\" content=\"346\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Why Men Marry Bitches &#8211; A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart\",\"datePublished\":\"2017-04-23T20:59:54+00:00\",\"dateModified\":\"2025-11-10T03:34:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/\"},\"wordCount\":648,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1\",\"articleSection\":[\"D\u00e9veloppement personnel\",\"Se renseigner\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/\",\"name\":\"Why Men Marry Bitches - A Woman's Guide to Winning Her Man's Heart - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1\",\"datePublished\":\"2017-04-23T20:59:54+00:00\",\"dateModified\":\"2025-11-10T03:34:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1\",\"width\":519,\"height\":346},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/men-marry-bitches-womans-guide-winning-mans-heart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Why Men Marry Bitches &#8211; A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Why Men Marry Bitches - A Woman's Guide to Winning Her Man's Heart - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/men-marry-bitches-womans-guide-winning-mans-heart\/","og_locale":"fr_CA","og_type":"article","og_title":"Why Men Marry Bitches - A Woman's Guide to Winning Her Man's Heart - Prochaine lecture","og_description":"\u00catre c\u00e9libataire, c&#8217;est plate. J&#8217;ai le go\u00fbt d&#8217;avoir du fun et de partager ma vie avec quelqu&#8217;un de bien. Mais non, \u00e0 la place, je m&#8217;entiche de gars avec qui il n&#8217;y a pas d&#8217;avenir et apr\u00e8s je d\u00e9prime. Moi, tann\u00e9e. J&#8217;imagine qu&#8217;on a fini par avoir piti\u00e9 : on m&#8217;a donn\u00e9 ce livre. D\u00e9j\u00e0, un avertissement : quand l&#8217;auteure parle des &#8220;bitchs&#8221;, il faut le prendre avec humour. Selon son lexique, une bitch est une femme ind\u00e9pendante, qui n&#8217;a besoin de personne, qui dit ce qu&#8217;elle pense et qui ne va pas se laisser marcher sur les pieds. C&#8217;est \u00e0 la fois bon pour elle, et bon pour sa future relation, parce que les hommes n&#8217;aiment pas les moumounes. Faire la gentille, c&#8217;est peut-\u00eatre naturel pour beaucoup d&#8217;entre nous, mais c&#8217;est pas gagnant. Solution : arr\u00eater \u00e7a! Elle nous dit comment faire en 74 &#8220;principes relationnels&#8221;, divis\u00e9s en 7 cat\u00e9gories. 1- D\u00e9truire les mythes, ou jeter les magazines f\u00e9minins \u00e0 la poubelle On parle de la femme parfaite, la bombe de sexe et la yes-girl. Les gars ne veulent pas d&#8217;une poup\u00e9e. Ils veulent une blonde avec qui&#8230; avoir du fun et partager leur vie. 2- Se laisser courir apr\u00e8s Un principe pas nouveau du tout. Les gars adorent \u00e7a courir apr\u00e8s les filles. Sinon, c&#8217;est trop facile et ils perdent l&#8217;int\u00e9r\u00eat. Je sais, vous me croirez pas. Tant pis pour vous. 3- Allumer le feu\u00a0dans ses pantalons \u00c7a, c&#8217;\u00e9tait du nouveau pour moi. Je vous r\u00e9serve le punch. 4- Conna\u00eetre les petits jeux des gars C&#8217;est pas m\u00e9chant, mais ils veulent savoir \u00e0 qui ils font affaire. Ils vont essayer de trouver les points faibles de la fille et d&#8217;appuyer dessus. Si elle r\u00e9pond bien, elle va gagner son respect. Ne pas le prendre trop personnel. 5- Avoir une vie professionnelle Un gars va vouloir passer sa vie avec une femme qui sait gagner au moins assez d&#8217;argent pour vivre. \u00c7a lui fera plaisir de l&#8217;inviter \u00e0 des dates, mais il ne veut pas qu&#8217;elle d\u00e9pende de lui. C&#8217;est un gros turn-off. 6- Se mettre dans sa t\u00eate L&#8217;auteure dit avoir interview\u00e9 des centaines de gars qui lui ont r\u00e9v\u00e9l\u00e9 ce qui les allumaient ou pas chez les filles. Elle nous donne les grandes lignes. Aoutch. 7- L&#8217;amener \u00e0 s&#8217;engager Le truc : s&#8217;arranger pour que ce soit lui qui veuille le faire. Et un gars en amour, c&#8217;est un gars qui veut passer sa vie avec\u00a0sa blonde. Le plus int\u00e9ressant : la morale Pas cucul du tout, ce livre m&#8217;a donn\u00e9 une \u00e9nergie incroyable, parce qu&#8217;il m&#8217;a rappel\u00e9 que je suis hot. (Malheureusement, c&#8217;est facile\u00a0\u00e0 oublier.) Beaucoup de gars vont \u00eatre int\u00e9ress\u00e9s, mais il faut que je regarde ce qu&#8217;ils peuvent m&#8217;apporter, \u00e0 moi. Comment je me sens avec eux et apr\u00e8s que je les ai vus? Est-ce que je me sens nulle, rabaiss\u00e9e, d\u00e9\u00e7ue, mal \u00e0 l&#8217;aise, triste, ins\u00e9cure? Je flushe. (Plut\u00f4t que de dire &#8220;Peut-\u00eatre que c&#8217;est ma faute? Peut-\u00eatre que c&#8217;est un gars incroyable et que je pourrais \u00eatre heureuse avec si j&#8217;agissais de la bonne mani\u00e8re?&#8221; Non. Il n&#8217;y a rien derri\u00e8re la colline.)\u00a0Ou bien dr\u00f4le, belle et en confiance?\u00a0Ceux qui nous font sentir comme \u00e7a sont \u00e0 conserver pr\u00e9cieusement. Et \u00e7a commence par prendre soin de soi. Why Men Marry Bitches : A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart Sherry Argov\u00a0 0,01 $ (!!)","og_url":"https:\/\/prochainelecture.com\/fr\/men-marry-bitches-womans-guide-winning-mans-heart\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2017-04-23T20:59:54+00:00","article_modified_time":"2025-11-10T03:34:40+00:00","og_image":[{"width":519,"height":346,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2017\/04\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Why Men Marry Bitches &#8211; A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart","datePublished":"2017-04-23T20:59:54+00:00","dateModified":"2025-11-10T03:34:40+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/"},"wordCount":648,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2017\/04\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1","articleSection":["D\u00e9veloppement personnel","Se renseigner"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/","url":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/","name":"Why Men Marry Bitches - A Woman's Guide to Winning Her Man's Heart - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2017\/04\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1","datePublished":"2017-04-23T20:59:54+00:00","dateModified":"2025-11-10T03:34:40+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2017\/04\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2017\/04\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1","width":519,"height":346},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/men-marry-bitches-womans-guide-winning-mans-heart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Why Men Marry Bitches &#8211; A Woman&#8217;s Guide to Winning Her Man&#8217;s Heart"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2017\/04\/51j0jmGUBoL._SY344_BO1204203200_-1.jpg?fit=519%2C346&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-nO","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=1476"}],"version-history":[{"count":4,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1476\/revisions"}],"predecessor-version":[{"id":5002,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1476\/revisions\/5002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3425"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=1476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=1476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=1476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}