{"id":1295,"date":"2016-05-02T19:43:29","date_gmt":"2016-05-02T19:43:29","guid":{"rendered":"http:\/\/www.naimahassert.com\/?p=1295"},"modified":"2020-08-04T21:46:23","modified_gmt":"2020-08-04T21:46:23","slug":"la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/","title":{"rendered":"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant)"},"content":{"rendered":"<p><strong>J&#8217;aime quand les gens d\u00e9m\u00e9nagent, surtout quand ils sont des lecteurs. Ma partenaire de radio, Isabelle, m&#8217;a donn\u00e9 quelques-uns de ses livres pour se d\u00e9charger un peu. Je pensais qu&#8217;elle les donnait au hasard de ses connaissances, mais apparemment, non&#8230; Il \u00e9tait en plein pour moi, et je l&#8217;ai d\u00e9gust\u00e9 comme un bonbon.<\/strong><strong><br \/>\n<\/strong><\/p>\n<p>Le petit Varguitas, 18 ans, travaille \u00e0 la radio Panamericana, une job qui consiste \u00e0 d\u00e9couper les nouvelles int\u00e9ressantes dans les journaux et \u00e0 les rem\u00e2cher pour qu&#8217;elles soient potables \u00e0 la radio. Accessoirement, il doit surveiller son coll\u00e8gue Pascual, obs\u00e9d\u00e9 par les nouvelles d&#8217;accidents, de catastrophes et de meurtres et qui a la f\u00e2cheuse tendance de consacrer tout un bulletin de nouvelles \u00e0 une bataille sanglante entre gangs de rues.<\/p>\n<p>Une nouvelle venue dans la famille lui tape \u00e0 l&#8217;oeil : la tante Julia, la soeur de la femme \u00e0 son oncle. Divorc\u00e9e, 32 ans, elle rit beaucoup, trouve Varguitas mignon comme un gamin et se cherche un nouveau mari.<\/p>\n<p>Le chapitre se termine. Commence alors une toute nouvelle histoire qui n&#8217;a absolument rien \u00e0 voir avec la premi\u00e8re. Du moins c&#8217;est ce qu&#8217;on croit. Elle aurait \u00e9t\u00e9 du go\u00fbt de Pascual : dramatique jusqu&#8217;\u00e0 la caricature. Un docteur dans la cinquantaine, beau bonhomme, s&#8217;appr\u00eate \u00e0 assister au mariage de sa ni\u00e8ce avec un petit rouquin, bien gentil, mais stupide. Il se sent un peu mal de penser ainsi, mais au gym o\u00f9 il s&#8217;entra\u00eene avec son neveu, celui-ci lui confirme ses impressions. Le rouquin est un con, un imb\u00e9cile heureux. Il forme d\u00e9cid\u00e9ment un dr\u00f4le de couple avec la ni\u00e8ce du docteur, la plus belle et la plus p\u00e9tillante femme de la ville. Le neveu, l&#8217;air furieux, l\u00e8ve ses poids avec ses biceps d&#8217;Apollon, pendant que l&#8217;entra\u00eeneur les traite de cadavres.\u00a0C&#8217;est une sc\u00e8ne hilarante.<\/p>\n<p>Le mariage, splendide, commence. Tout le monde danse, pendant que le fr\u00e8re de la mari\u00e9e, so\u00fbl comme une barrique, broie du noir sous un arbre. Tout \u00e0 coup, la mari\u00e9e s&#8217;effondre en pleine piste de danse. Le docteur l&#8217;am\u00e8ne dans sa chambre, et s&#8217;aper\u00e7oit qu&#8217;elle est enceinte&#8230; de quatre mois. Le rouquin n&#8217;est pas au courant. Mais de qui peut-elle bien \u00eatre enceinte? Le docteur, catastroph\u00e9, voit son neveu qui semble proche du suicide, et un affreux doute s&#8217;empare de lui&#8230;<\/p>\n<p>Fin du deuxi\u00e8me chapitre. Je retourne \u00e0 l&#8217;histoire principale, secou\u00e9e, amus\u00e9e, \u00e9merveill\u00e9e. L&#8217;histoire \u00e9tait dr\u00f4le, surprenante, et remarquablement bien \u00e9crite. Le genre d&#8217;histoire o\u00f9 on passe autant de temps \u00e0 admirer l&#8217;\u00e9criture qu&#8217;\u00e0 appr\u00e9cier l&#8217;histoire.<\/p>\n<p>On alterne ainsi entre l&#8217;histoire d&#8217;amour entre le petit journaliste et la tante Julia et des histoires rocambolesques, toutes plus dr\u00f4les, dramatiques et originales les unes que les autres. J&#8217;ai fini par comprendre le lien entre toutes ces histoires, mais apr\u00e8s bien des chapitres d\u00e9concertants.<\/p>\n<p>Mon enthousiasme pour ce roman est d\u00e9bordant.\u00a0J&#8217;ai d\u00fb tout raconter au moins cinq fois \u00e0 mes proches, et ils devaient me supplier pour ne pas que je leur r\u00e9v\u00e8le tous les punchs. \u00c7a m&#8217;a pris du temps \u00e0 le lire, car comme \u00e0 chaque fois que je tombe sur une perle, je veux me r\u00e9server du temps de qualit\u00e9 pour lire \u00e0 voix haute, dans le silence et avec toute ma concentration.<\/p>\n<p>Merci Isabelle!<\/p>\n<hr \/>\n<p><strong><a href=\"http:\/\/www.amazon.ca\/TANTE-JULIA-SCRIBOUILLARD-VARGAS-LLOSA\/dp\/2070376494\/?_encoding=UTF8&amp;camp=15121&amp;creative=330641&amp;keywords=tante%20julia%20et%20le%20scribouillard&amp;linkCode=ur2&amp;qid=1462217577&amp;sr=8-1&amp;tag=naimahassertc-20\" target=\"_blank\" rel=\"noopener noreferrer\">La tante Julia et le scribouillard<\/a><img decoding=\"async\" style=\"border: none !important; margin: 0px !important;\" src=\"http:\/\/ir-ca.amazon-adsystem.com\/e\/ir?t=naimahassertc-20&amp;l=ur2&amp;o=15\" alt=\"\" width=\"1\" height=\"1\" border=\"0\" \/><\/strong><\/p>\n<p><strong>Mario Vargas Llosa<\/strong><\/p>\n<p><strong>17,96 $<\/strong><\/p>\n<hr \/>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1298 aligncenter\" src=\"https:\/\/i0.wp.com\/www.naimahassert.com\/wp-content\/uploads\/2016\/05\/La-tante-Julia-et-le-scribouillard-1.png?resize=434%2C464\" alt=\"La tante Julia et le scribouillard\" width=\"434\" height=\"464\" srcset=\"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/La-tante-Julia-et-le-scribouillard-1.png?w=683&amp;ssl=1 683w, https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/La-tante-Julia-et-le-scribouillard-1.png?resize=280%2C300&amp;ssl=1 280w\" sizes=\"(max-width: 434px) 100vw, 434px\" \/><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&#8217;aime quand les gens d\u00e9m\u00e9nagent, surtout quand ils sont des lecteurs. Ma partenaire de radio, Isabelle, m&#8217;a donn\u00e9 quelques-uns de ses livres pour se d\u00e9charger un peu. Je pensais qu&#8217;elle les donnait au hasard de ses connaissances, mais apparemment, non&#8230; Il \u00e9tait en plein pour moi, et je l&#8217;ai d\u00e9gust\u00e9 comme un bonbon. Le petit Varguitas, 18 ans, travaille \u00e0 la radio Panamericana, une job qui consiste \u00e0 d\u00e9couper les nouvelles int\u00e9ressantes dans les journaux et \u00e0 les rem\u00e2cher pour qu&#8217;elles soient potables \u00e0 la radio. Accessoirement, il doit surveiller son coll\u00e8gue Pascual, obs\u00e9d\u00e9 par les nouvelles d&#8217;accidents, de catastrophes et de meurtres et qui a la f\u00e2cheuse tendance de consacrer tout un bulletin de nouvelles \u00e0 une bataille sanglante entre gangs de rues. Une nouvelle venue dans la famille lui tape \u00e0 l&#8217;oeil : la tante Julia, la soeur de la femme \u00e0 son oncle. Divorc\u00e9e, 32 ans, elle rit beaucoup, trouve Varguitas mignon comme un gamin et se cherche un nouveau mari. Le chapitre se termine. Commence alors une toute nouvelle histoire qui n&#8217;a absolument rien \u00e0 voir avec la premi\u00e8re. Du moins c&#8217;est ce qu&#8217;on croit. Elle aurait \u00e9t\u00e9 du go\u00fbt de Pascual : dramatique jusqu&#8217;\u00e0 la caricature. Un docteur dans la cinquantaine, beau bonhomme, s&#8217;appr\u00eate \u00e0 assister au mariage de sa ni\u00e8ce avec un petit rouquin, bien gentil, mais stupide. Il se sent un peu mal de penser ainsi, mais au gym o\u00f9 il s&#8217;entra\u00eene avec son neveu, celui-ci lui confirme ses impressions. Le rouquin est un con, un imb\u00e9cile heureux. Il forme d\u00e9cid\u00e9ment un dr\u00f4le de couple avec la ni\u00e8ce du docteur, la plus belle et la plus p\u00e9tillante femme de la ville. Le neveu, l&#8217;air furieux, l\u00e8ve ses poids avec ses biceps d&#8217;Apollon, pendant que l&#8217;entra\u00eeneur les traite de cadavres.\u00a0C&#8217;est une sc\u00e8ne hilarante. Le mariage, splendide, commence. Tout le monde danse, pendant que le fr\u00e8re de la mari\u00e9e, so\u00fbl comme une barrique, broie du noir sous un arbre. Tout \u00e0 coup, la mari\u00e9e s&#8217;effondre en pleine piste de danse. Le docteur l&#8217;am\u00e8ne dans sa chambre, et s&#8217;aper\u00e7oit qu&#8217;elle est enceinte&#8230; de quatre mois. Le rouquin n&#8217;est pas au courant. Mais de qui peut-elle bien \u00eatre enceinte? Le docteur, catastroph\u00e9, voit son neveu qui semble proche du suicide, et un affreux doute s&#8217;empare de lui&#8230; Fin du deuxi\u00e8me chapitre. Je retourne \u00e0 l&#8217;histoire principale, secou\u00e9e, amus\u00e9e, \u00e9merveill\u00e9e. L&#8217;histoire \u00e9tait dr\u00f4le, surprenante, et remarquablement bien \u00e9crite. Le genre d&#8217;histoire o\u00f9 on passe autant de temps \u00e0 admirer l&#8217;\u00e9criture qu&#8217;\u00e0 appr\u00e9cier l&#8217;histoire. On alterne ainsi entre l&#8217;histoire d&#8217;amour entre le petit journaliste et la tante Julia et des histoires rocambolesques, toutes plus dr\u00f4les, dramatiques et originales les unes que les autres. J&#8217;ai fini par comprendre le lien entre toutes ces histoires, mais apr\u00e8s bien des chapitres d\u00e9concertants. Mon enthousiasme pour ce roman est d\u00e9bordant.\u00a0J&#8217;ai d\u00fb tout raconter au moins cinq fois \u00e0 mes proches, et ils devaient me supplier pour ne pas que je leur r\u00e9v\u00e8le tous les punchs. \u00c7a m&#8217;a pris du temps \u00e0 le lire, car comme \u00e0 chaque fois que je tombe sur une perle, je veux me r\u00e9server du temps de qualit\u00e9 pour lire \u00e0 voix haute, dans le silence et avec toute ma concentration. Merci Isabelle! La tante Julia et le scribouillard Mario Vargas Llosa 17,96 $ \u00a0<\/p>\n","protected":false},"author":1,"featured_media":3516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[255,242],"tags":[],"class_list":["post-1295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coups-de-coeur","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant) - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant) - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"J&#8217;aime quand les gens d\u00e9m\u00e9nagent, surtout quand ils sont des lecteurs. Ma partenaire de radio, Isabelle, m&#8217;a donn\u00e9 quelques-uns de ses livres pour se d\u00e9charger un peu. Je pensais qu&#8217;elle les donnait au hasard de ses connaissances, mais apparemment, non&#8230; Il \u00e9tait en plein pour moi, et je l&#8217;ai d\u00e9gust\u00e9 comme un bonbon. Le petit Varguitas, 18 ans, travaille \u00e0 la radio Panamericana, une job qui consiste \u00e0 d\u00e9couper les nouvelles int\u00e9ressantes dans les journaux et \u00e0 les rem\u00e2cher pour qu&#8217;elles soient potables \u00e0 la radio. Accessoirement, il doit surveiller son coll\u00e8gue Pascual, obs\u00e9d\u00e9 par les nouvelles d&#8217;accidents, de catastrophes et de meurtres et qui a la f\u00e2cheuse tendance de consacrer tout un bulletin de nouvelles \u00e0 une bataille sanglante entre gangs de rues. Une nouvelle venue dans la famille lui tape \u00e0 l&#8217;oeil : la tante Julia, la soeur de la femme \u00e0 son oncle. Divorc\u00e9e, 32 ans, elle rit beaucoup, trouve Varguitas mignon comme un gamin et se cherche un nouveau mari. Le chapitre se termine. Commence alors une toute nouvelle histoire qui n&#8217;a absolument rien \u00e0 voir avec la premi\u00e8re. Du moins c&#8217;est ce qu&#8217;on croit. Elle aurait \u00e9t\u00e9 du go\u00fbt de Pascual : dramatique jusqu&#8217;\u00e0 la caricature. Un docteur dans la cinquantaine, beau bonhomme, s&#8217;appr\u00eate \u00e0 assister au mariage de sa ni\u00e8ce avec un petit rouquin, bien gentil, mais stupide. Il se sent un peu mal de penser ainsi, mais au gym o\u00f9 il s&#8217;entra\u00eene avec son neveu, celui-ci lui confirme ses impressions. Le rouquin est un con, un imb\u00e9cile heureux. Il forme d\u00e9cid\u00e9ment un dr\u00f4le de couple avec la ni\u00e8ce du docteur, la plus belle et la plus p\u00e9tillante femme de la ville. Le neveu, l&#8217;air furieux, l\u00e8ve ses poids avec ses biceps d&#8217;Apollon, pendant que l&#8217;entra\u00eeneur les traite de cadavres.\u00a0C&#8217;est une sc\u00e8ne hilarante. Le mariage, splendide, commence. Tout le monde danse, pendant que le fr\u00e8re de la mari\u00e9e, so\u00fbl comme une barrique, broie du noir sous un arbre. Tout \u00e0 coup, la mari\u00e9e s&#8217;effondre en pleine piste de danse. Le docteur l&#8217;am\u00e8ne dans sa chambre, et s&#8217;aper\u00e7oit qu&#8217;elle est enceinte&#8230; de quatre mois. Le rouquin n&#8217;est pas au courant. Mais de qui peut-elle bien \u00eatre enceinte? Le docteur, catastroph\u00e9, voit son neveu qui semble proche du suicide, et un affreux doute s&#8217;empare de lui&#8230; Fin du deuxi\u00e8me chapitre. Je retourne \u00e0 l&#8217;histoire principale, secou\u00e9e, amus\u00e9e, \u00e9merveill\u00e9e. L&#8217;histoire \u00e9tait dr\u00f4le, surprenante, et remarquablement bien \u00e9crite. Le genre d&#8217;histoire o\u00f9 on passe autant de temps \u00e0 admirer l&#8217;\u00e9criture qu&#8217;\u00e0 appr\u00e9cier l&#8217;histoire. On alterne ainsi entre l&#8217;histoire d&#8217;amour entre le petit journaliste et la tante Julia et des histoires rocambolesques, toutes plus dr\u00f4les, dramatiques et originales les unes que les autres. J&#8217;ai fini par comprendre le lien entre toutes ces histoires, mais apr\u00e8s bien des chapitres d\u00e9concertants. Mon enthousiasme pour ce roman est d\u00e9bordant.\u00a0J&#8217;ai d\u00fb tout raconter au moins cinq fois \u00e0 mes proches, et ils devaient me supplier pour ne pas que je leur r\u00e9v\u00e8le tous les punchs. \u00c7a m&#8217;a pris du temps \u00e0 le lire, car comme \u00e0 chaque fois que je tombe sur une perle, je veux me r\u00e9server du temps de qualit\u00e9 pour lire \u00e0 voix haute, dans le silence et avec toute ma concentration. Merci Isabelle! La tante Julia et le scribouillard Mario Vargas Llosa 17,96 $ \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-02T19:43:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-04T21:46:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/Tante_Julia_1.png?fit=1000%2C667&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant)\",\"datePublished\":\"2016-05-02T19:43:29+00:00\",\"dateModified\":\"2020-08-04T21:46:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Tante_Julia_1.png?fit=1000%2C667&ssl=1\",\"articleSection\":[\"Coups de coeur\",\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/\",\"name\":\"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant) - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Tante_Julia_1.png?fit=1000%2C667&ssl=1\",\"datePublished\":\"2016-05-02T19:43:29+00:00\",\"dateModified\":\"2020-08-04T21:46:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Tante_Julia_1.png?fit=1000%2C667&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/Tante_Julia_1.png?fit=1000%2C667&ssl=1\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant) - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/","og_locale":"fr_CA","og_type":"article","og_title":"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant) - Prochaine lecture","og_description":"J&#8217;aime quand les gens d\u00e9m\u00e9nagent, surtout quand ils sont des lecteurs. Ma partenaire de radio, Isabelle, m&#8217;a donn\u00e9 quelques-uns de ses livres pour se d\u00e9charger un peu. Je pensais qu&#8217;elle les donnait au hasard de ses connaissances, mais apparemment, non&#8230; Il \u00e9tait en plein pour moi, et je l&#8217;ai d\u00e9gust\u00e9 comme un bonbon. Le petit Varguitas, 18 ans, travaille \u00e0 la radio Panamericana, une job qui consiste \u00e0 d\u00e9couper les nouvelles int\u00e9ressantes dans les journaux et \u00e0 les rem\u00e2cher pour qu&#8217;elles soient potables \u00e0 la radio. Accessoirement, il doit surveiller son coll\u00e8gue Pascual, obs\u00e9d\u00e9 par les nouvelles d&#8217;accidents, de catastrophes et de meurtres et qui a la f\u00e2cheuse tendance de consacrer tout un bulletin de nouvelles \u00e0 une bataille sanglante entre gangs de rues. Une nouvelle venue dans la famille lui tape \u00e0 l&#8217;oeil : la tante Julia, la soeur de la femme \u00e0 son oncle. Divorc\u00e9e, 32 ans, elle rit beaucoup, trouve Varguitas mignon comme un gamin et se cherche un nouveau mari. Le chapitre se termine. Commence alors une toute nouvelle histoire qui n&#8217;a absolument rien \u00e0 voir avec la premi\u00e8re. Du moins c&#8217;est ce qu&#8217;on croit. Elle aurait \u00e9t\u00e9 du go\u00fbt de Pascual : dramatique jusqu&#8217;\u00e0 la caricature. Un docteur dans la cinquantaine, beau bonhomme, s&#8217;appr\u00eate \u00e0 assister au mariage de sa ni\u00e8ce avec un petit rouquin, bien gentil, mais stupide. Il se sent un peu mal de penser ainsi, mais au gym o\u00f9 il s&#8217;entra\u00eene avec son neveu, celui-ci lui confirme ses impressions. Le rouquin est un con, un imb\u00e9cile heureux. Il forme d\u00e9cid\u00e9ment un dr\u00f4le de couple avec la ni\u00e8ce du docteur, la plus belle et la plus p\u00e9tillante femme de la ville. Le neveu, l&#8217;air furieux, l\u00e8ve ses poids avec ses biceps d&#8217;Apollon, pendant que l&#8217;entra\u00eeneur les traite de cadavres.\u00a0C&#8217;est une sc\u00e8ne hilarante. Le mariage, splendide, commence. Tout le monde danse, pendant que le fr\u00e8re de la mari\u00e9e, so\u00fbl comme une barrique, broie du noir sous un arbre. Tout \u00e0 coup, la mari\u00e9e s&#8217;effondre en pleine piste de danse. Le docteur l&#8217;am\u00e8ne dans sa chambre, et s&#8217;aper\u00e7oit qu&#8217;elle est enceinte&#8230; de quatre mois. Le rouquin n&#8217;est pas au courant. Mais de qui peut-elle bien \u00eatre enceinte? Le docteur, catastroph\u00e9, voit son neveu qui semble proche du suicide, et un affreux doute s&#8217;empare de lui&#8230; Fin du deuxi\u00e8me chapitre. Je retourne \u00e0 l&#8217;histoire principale, secou\u00e9e, amus\u00e9e, \u00e9merveill\u00e9e. L&#8217;histoire \u00e9tait dr\u00f4le, surprenante, et remarquablement bien \u00e9crite. Le genre d&#8217;histoire o\u00f9 on passe autant de temps \u00e0 admirer l&#8217;\u00e9criture qu&#8217;\u00e0 appr\u00e9cier l&#8217;histoire. On alterne ainsi entre l&#8217;histoire d&#8217;amour entre le petit journaliste et la tante Julia et des histoires rocambolesques, toutes plus dr\u00f4les, dramatiques et originales les unes que les autres. J&#8217;ai fini par comprendre le lien entre toutes ces histoires, mais apr\u00e8s bien des chapitres d\u00e9concertants. Mon enthousiasme pour ce roman est d\u00e9bordant.\u00a0J&#8217;ai d\u00fb tout raconter au moins cinq fois \u00e0 mes proches, et ils devaient me supplier pour ne pas que je leur r\u00e9v\u00e8le tous les punchs. \u00c7a m&#8217;a pris du temps \u00e0 le lire, car comme \u00e0 chaque fois que je tombe sur une perle, je veux me r\u00e9server du temps de qualit\u00e9 pour lire \u00e0 voix haute, dans le silence et avec toute ma concentration. Merci Isabelle! La tante Julia et le scribouillard Mario Vargas Llosa 17,96 $ \u00a0","og_url":"https:\/\/prochainelecture.com\/fr\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2016-05-02T19:43:29+00:00","article_modified_time":"2020-08-04T21:46:23+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/Tante_Julia_1.png?fit=1000%2C667&ssl=1","type":"image\/png"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant)","datePublished":"2016-05-02T19:43:29+00:00","dateModified":"2020-08-04T21:46:23+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/Tante_Julia_1.png?fit=1000%2C667&ssl=1","articleSection":["Coups de coeur","Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/","url":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/","name":"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant) - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/Tante_Julia_1.png?fit=1000%2C667&ssl=1","datePublished":"2016-05-02T19:43:29+00:00","dateModified":"2020-08-04T21:46:23+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/Tante_Julia_1.png?fit=1000%2C667&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/Tante_Julia_1.png?fit=1000%2C667&ssl=1","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/la-tante-julia-et-le-scribouillard-et-mon-enthousiasme-debordant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"La tante Julia et le scribouillard (et mon enthousiasme d\u00e9bordant)"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/05\/Tante_Julia_1.png?fit=1000%2C667&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-kT","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=1295"}],"version-history":[{"count":5,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1295\/revisions"}],"predecessor-version":[{"id":3517,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1295\/revisions\/3517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3516"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=1295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=1295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=1295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}