{"id":1273,"date":"2016-04-11T22:10:50","date_gmt":"2016-04-11T22:10:50","guid":{"rendered":"http:\/\/www.naimahassert.com\/?p=1273"},"modified":"2020-08-03T22:54:13","modified_gmt":"2020-08-03T22:54:13","slug":"replay-de-la-science-fiction-dans-un-paysage-retro","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/fr\/replay-de-la-science-fiction-dans-un-paysage-retro\/","title":{"rendered":"Replay, de la science-fiction dans un paysage r\u00e9tro"},"content":{"rendered":"<p><strong>Mon copain voulait m&#8217;offrir un livre, et il en avait un en t\u00eate. Ce n&#8217;\u00e9tait pas\u00a0<em>Replay.<\/em><\/strong><strong>\u00a0On est entr\u00e9s dans une librairie Renaissance, et il a fouill\u00e9 les rayons pour trouver l&#8217;auteur qu&#8217;il cherchait. Pas trouv\u00e9. On allait partir quand ce roman de Ken Grimwood<em>\u00a0<\/em>l&#8217;a accroch\u00e9. Il a ri : &#8220;\u00c7a, c&#8217;est super int\u00e9ressant! Tu le veux?&#8221; Bien s\u00fbr. Et j&#8217;ai accroch\u00e9.<\/strong><\/p>\n<p>En commen\u00e7ant par la premi\u00e8re phrase :<\/p>\n<blockquote><p>Jeff Winston \u00e9tait en train de t\u00e9l\u00e9phoner \u00e0 sa femme quand il mourut.<\/p><\/blockquote>\n<p>Ce Jeff a quarante ans\u00a0quand il meurt subitement d&#8217;une crise\u00a0cardiaque, en 1988, dans son bureau \u00e0 New York. 25 ans plus t\u00f4t, il se r\u00e9veille\u00a0dans sa chambre d&#8217;universit\u00e9 \u00e0 Atlanta. Il a 18 ans.<\/p>\n<p>Il commence ainsi un des nombreux &#8220;replays&#8221; qui lui font revivre les m\u00eames ann\u00e9es de sa vie, jusqu&#8217;\u00e0 ce qu&#8217;il meurt, encore et encore, toujours \u00e0 la m\u00eame date. La premi\u00e8re fois, c&#8217;est grisant : il se fait une fortune colossale en pariant sur des courses de chevaux et en investissant sur de toutes petites compagnies prometteuses (comme Apple). Une autre fois, il vivra une vie de d\u00e9bauche et de drogues. Une autre, il s&#8217;isole dans une ferme et reprend contact avec la nature. Mais apr\u00e8s avoir perdu sa fille et \u00e9chou\u00e9 \u00e0 charmer de nouveau son ancienne femme, il d\u00e9sesp\u00e8re. \u00c0 quoi bon revenir en arri\u00e8re, si tout ce qu&#8217;il entreprend est \u00e0 recommencer, s&#8217;il perd chacune de ses relations?<\/p>\n<p>C&#8217;est alors qu&#8217;il rencontre Pam\u00e9la, une femme comme lui, qui a d\u00e9j\u00e0 v\u00e9cu sa vie une dizaine de fois. Ensemble, ils tenteront de changer le monde et de comprendre le myst\u00e8re qui les entoure, jusqu&#8217;\u00e0 ce qu&#8217;ils se rendent compte que toute chose, m\u00eame eux, a une fin&#8230;<\/p>\n<p>On ne lit pas ce livre pour l&#8217;\u00e9criture, mais pour le concept, puissant. J&#8217;avoue avoir eu les larmes aux yeux au moins deux fois&#8230; \u00c0 un moment, j&#8217;ai m\u00eame \u00e9t\u00e9 \u00e0 ce point \u00e9mue que je me suis sauv\u00e9e de chez moi\u00a0pour courir\u00a0jusque chez mon amoureux, frapp\u00e9e par la sensation qu&#8217;il ne fallait rien prendre pour acquis, que le temps passait sans jamais revenir et qu&#8217;il fallait profiter de ce qu&#8217;on avait.<\/p>\n<p>Oui, c&#8217;est un cas de morale avant tout. Mais avec une si belle excuse, on l&#8217;accepte.<\/p>\n<p>&#8212;<\/p>\n<p><a href=\"http:\/\/www.amazon.ca\/gp\/product\/2020115751\/ref=as_li_tf_tl?ie=UTF8&amp;camp=15121&amp;creative=330641&amp;creativeASIN=2020115751&amp;linkCode=as2&amp;tag=naimahassertc-20\">Replay [ancienne \u00e9dition]<\/a><img decoding=\"async\" style=\"border: none !important; margin: 0px !important;\" src=\"http:\/\/ir-ca.amazon-adsystem.com\/e\/ir?t=naimahassertc-20&amp;l=as2&amp;o=15&amp;a=2020115751\" alt=\"\" width=\"1\" height=\"1\" border=\"0\" \/><\/p>\n<p><strong>Ken Grimwood<\/strong><\/p>\n<p><strong>Seuil\u00a0<\/strong><\/p>\n<p><strong>2,77 $<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mon copain voulait m&#8217;offrir un livre, et il en avait un en t\u00eate. Ce n&#8217;\u00e9tait pas\u00a0Replay.\u00a0On est entr\u00e9s dans une librairie Renaissance, et il a fouill\u00e9 les rayons pour trouver l&#8217;auteur qu&#8217;il cherchait. Pas trouv\u00e9. On allait partir quand ce roman de Ken Grimwood\u00a0l&#8217;a accroch\u00e9. Il a ri : &#8220;\u00c7a, c&#8217;est super int\u00e9ressant! Tu le veux?&#8221; Bien s\u00fbr. Et j&#8217;ai accroch\u00e9. En commen\u00e7ant par la premi\u00e8re phrase : Jeff Winston \u00e9tait en train de t\u00e9l\u00e9phoner \u00e0 sa femme quand il mourut. Ce Jeff a quarante ans\u00a0quand il meurt subitement d&#8217;une crise\u00a0cardiaque, en 1988, dans son bureau \u00e0 New York. 25 ans plus t\u00f4t, il se r\u00e9veille\u00a0dans sa chambre d&#8217;universit\u00e9 \u00e0 Atlanta. Il a 18 ans. Il commence ainsi un des nombreux &#8220;replays&#8221; qui lui font revivre les m\u00eames ann\u00e9es de sa vie, jusqu&#8217;\u00e0 ce qu&#8217;il meurt, encore et encore, toujours \u00e0 la m\u00eame date. La premi\u00e8re fois, c&#8217;est grisant : il se fait une fortune colossale en pariant sur des courses de chevaux et en investissant sur de toutes petites compagnies prometteuses (comme Apple). Une autre fois, il vivra une vie de d\u00e9bauche et de drogues. Une autre, il s&#8217;isole dans une ferme et reprend contact avec la nature. Mais apr\u00e8s avoir perdu sa fille et \u00e9chou\u00e9 \u00e0 charmer de nouveau son ancienne femme, il d\u00e9sesp\u00e8re. \u00c0 quoi bon revenir en arri\u00e8re, si tout ce qu&#8217;il entreprend est \u00e0 recommencer, s&#8217;il perd chacune de ses relations? C&#8217;est alors qu&#8217;il rencontre Pam\u00e9la, une femme comme lui, qui a d\u00e9j\u00e0 v\u00e9cu sa vie une dizaine de fois. Ensemble, ils tenteront de changer le monde et de comprendre le myst\u00e8re qui les entoure, jusqu&#8217;\u00e0 ce qu&#8217;ils se rendent compte que toute chose, m\u00eame eux, a une fin&#8230; On ne lit pas ce livre pour l&#8217;\u00e9criture, mais pour le concept, puissant. J&#8217;avoue avoir eu les larmes aux yeux au moins deux fois&#8230; \u00c0 un moment, j&#8217;ai m\u00eame \u00e9t\u00e9 \u00e0 ce point \u00e9mue que je me suis sauv\u00e9e de chez moi\u00a0pour courir\u00a0jusque chez mon amoureux, frapp\u00e9e par la sensation qu&#8217;il ne fallait rien prendre pour acquis, que le temps passait sans jamais revenir et qu&#8217;il fallait profiter de ce qu&#8217;on avait. Oui, c&#8217;est un cas de morale avant tout. Mais avec une si belle excuse, on l&#8217;accepte. &#8212; Replay [ancienne \u00e9dition] Ken Grimwood Seuil\u00a0 2,77 $<\/p>\n","protected":false},"author":1,"featured_media":3445,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[247,242],"tags":[],"class_list":["post-1273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-science-fiction","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Replay, de la science-fiction dans un paysage r\u00e9tro - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/fr\/replay-de-la-science-fiction-dans-un-paysage-retro\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Replay, de la science-fiction dans un paysage r\u00e9tro - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Mon copain voulait m&#8217;offrir un livre, et il en avait un en t\u00eate. Ce n&#8217;\u00e9tait pas\u00a0Replay.\u00a0On est entr\u00e9s dans une librairie Renaissance, et il a fouill\u00e9 les rayons pour trouver l&#8217;auteur qu&#8217;il cherchait. Pas trouv\u00e9. On allait partir quand ce roman de Ken Grimwood\u00a0l&#8217;a accroch\u00e9. Il a ri : &#8220;\u00c7a, c&#8217;est super int\u00e9ressant! Tu le veux?&#8221; Bien s\u00fbr. Et j&#8217;ai accroch\u00e9. En commen\u00e7ant par la premi\u00e8re phrase : Jeff Winston \u00e9tait en train de t\u00e9l\u00e9phoner \u00e0 sa femme quand il mourut. Ce Jeff a quarante ans\u00a0quand il meurt subitement d&#8217;une crise\u00a0cardiaque, en 1988, dans son bureau \u00e0 New York. 25 ans plus t\u00f4t, il se r\u00e9veille\u00a0dans sa chambre d&#8217;universit\u00e9 \u00e0 Atlanta. Il a 18 ans. Il commence ainsi un des nombreux &#8220;replays&#8221; qui lui font revivre les m\u00eames ann\u00e9es de sa vie, jusqu&#8217;\u00e0 ce qu&#8217;il meurt, encore et encore, toujours \u00e0 la m\u00eame date. La premi\u00e8re fois, c&#8217;est grisant : il se fait une fortune colossale en pariant sur des courses de chevaux et en investissant sur de toutes petites compagnies prometteuses (comme Apple). Une autre fois, il vivra une vie de d\u00e9bauche et de drogues. Une autre, il s&#8217;isole dans une ferme et reprend contact avec la nature. Mais apr\u00e8s avoir perdu sa fille et \u00e9chou\u00e9 \u00e0 charmer de nouveau son ancienne femme, il d\u00e9sesp\u00e8re. \u00c0 quoi bon revenir en arri\u00e8re, si tout ce qu&#8217;il entreprend est \u00e0 recommencer, s&#8217;il perd chacune de ses relations? C&#8217;est alors qu&#8217;il rencontre Pam\u00e9la, une femme comme lui, qui a d\u00e9j\u00e0 v\u00e9cu sa vie une dizaine de fois. Ensemble, ils tenteront de changer le monde et de comprendre le myst\u00e8re qui les entoure, jusqu&#8217;\u00e0 ce qu&#8217;ils se rendent compte que toute chose, m\u00eame eux, a une fin&#8230; On ne lit pas ce livre pour l&#8217;\u00e9criture, mais pour le concept, puissant. J&#8217;avoue avoir eu les larmes aux yeux au moins deux fois&#8230; \u00c0 un moment, j&#8217;ai m\u00eame \u00e9t\u00e9 \u00e0 ce point \u00e9mue que je me suis sauv\u00e9e de chez moi\u00a0pour courir\u00a0jusque chez mon amoureux, frapp\u00e9e par la sensation qu&#8217;il ne fallait rien prendre pour acquis, que le temps passait sans jamais revenir et qu&#8217;il fallait profiter de ce qu&#8217;on avait. Oui, c&#8217;est un cas de morale avant tout. Mais avec une si belle excuse, on l&#8217;accepte. &#8212; Replay [ancienne \u00e9dition] Ken Grimwood Seuil\u00a0 2,77 $\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/fr\/replay-de-la-science-fiction-dans-un-paysage-retro\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-11T22:10:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-03T22:54:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/04\/seuil-010084_0.png?fit=525%2C350&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"525\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Replay, de la science-fiction dans un paysage r\u00e9tro\",\"datePublished\":\"2016-04-11T22:10:50+00:00\",\"dateModified\":\"2020-08-03T22:54:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/\"},\"wordCount\":433,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/seuil-010084_0.png?fit=525%2C350&ssl=1\",\"articleSection\":[\"Science-fiction\",\"Se distraire\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/\",\"name\":\"Replay, de la science-fiction dans un paysage r\u00e9tro - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/seuil-010084_0.png?fit=525%2C350&ssl=1\",\"datePublished\":\"2016-04-11T22:10:50+00:00\",\"dateModified\":\"2020-08-03T22:54:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/seuil-010084_0.png?fit=525%2C350&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/seuil-010084_0.png?fit=525%2C350&ssl=1\",\"width\":525,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/replay-de-la-science-fiction-dans-un-paysage-retro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Replay, de la science-fiction dans un paysage r\u00e9tro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/fr\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Replay, de la science-fiction dans un paysage r\u00e9tro - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/fr\/replay-de-la-science-fiction-dans-un-paysage-retro\/","og_locale":"fr_CA","og_type":"article","og_title":"Replay, de la science-fiction dans un paysage r\u00e9tro - Prochaine lecture","og_description":"Mon copain voulait m&#8217;offrir un livre, et il en avait un en t\u00eate. Ce n&#8217;\u00e9tait pas\u00a0Replay.\u00a0On est entr\u00e9s dans une librairie Renaissance, et il a fouill\u00e9 les rayons pour trouver l&#8217;auteur qu&#8217;il cherchait. Pas trouv\u00e9. On allait partir quand ce roman de Ken Grimwood\u00a0l&#8217;a accroch\u00e9. Il a ri : &#8220;\u00c7a, c&#8217;est super int\u00e9ressant! Tu le veux?&#8221; Bien s\u00fbr. Et j&#8217;ai accroch\u00e9. En commen\u00e7ant par la premi\u00e8re phrase : Jeff Winston \u00e9tait en train de t\u00e9l\u00e9phoner \u00e0 sa femme quand il mourut. Ce Jeff a quarante ans\u00a0quand il meurt subitement d&#8217;une crise\u00a0cardiaque, en 1988, dans son bureau \u00e0 New York. 25 ans plus t\u00f4t, il se r\u00e9veille\u00a0dans sa chambre d&#8217;universit\u00e9 \u00e0 Atlanta. Il a 18 ans. Il commence ainsi un des nombreux &#8220;replays&#8221; qui lui font revivre les m\u00eames ann\u00e9es de sa vie, jusqu&#8217;\u00e0 ce qu&#8217;il meurt, encore et encore, toujours \u00e0 la m\u00eame date. La premi\u00e8re fois, c&#8217;est grisant : il se fait une fortune colossale en pariant sur des courses de chevaux et en investissant sur de toutes petites compagnies prometteuses (comme Apple). Une autre fois, il vivra une vie de d\u00e9bauche et de drogues. Une autre, il s&#8217;isole dans une ferme et reprend contact avec la nature. Mais apr\u00e8s avoir perdu sa fille et \u00e9chou\u00e9 \u00e0 charmer de nouveau son ancienne femme, il d\u00e9sesp\u00e8re. \u00c0 quoi bon revenir en arri\u00e8re, si tout ce qu&#8217;il entreprend est \u00e0 recommencer, s&#8217;il perd chacune de ses relations? C&#8217;est alors qu&#8217;il rencontre Pam\u00e9la, une femme comme lui, qui a d\u00e9j\u00e0 v\u00e9cu sa vie une dizaine de fois. Ensemble, ils tenteront de changer le monde et de comprendre le myst\u00e8re qui les entoure, jusqu&#8217;\u00e0 ce qu&#8217;ils se rendent compte que toute chose, m\u00eame eux, a une fin&#8230; On ne lit pas ce livre pour l&#8217;\u00e9criture, mais pour le concept, puissant. J&#8217;avoue avoir eu les larmes aux yeux au moins deux fois&#8230; \u00c0 un moment, j&#8217;ai m\u00eame \u00e9t\u00e9 \u00e0 ce point \u00e9mue que je me suis sauv\u00e9e de chez moi\u00a0pour courir\u00a0jusque chez mon amoureux, frapp\u00e9e par la sensation qu&#8217;il ne fallait rien prendre pour acquis, que le temps passait sans jamais revenir et qu&#8217;il fallait profiter de ce qu&#8217;on avait. Oui, c&#8217;est un cas de morale avant tout. Mais avec une si belle excuse, on l&#8217;accepte. &#8212; Replay [ancienne \u00e9dition] Ken Grimwood Seuil\u00a0 2,77 $","og_url":"https:\/\/prochainelecture.com\/fr\/replay-de-la-science-fiction-dans-un-paysage-retro\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2016-04-11T22:10:50+00:00","article_modified_time":"2020-08-03T22:54:13+00:00","og_image":[{"width":525,"height":350,"url":"https:\/\/i2.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/04\/seuil-010084_0.png?fit=525%2C350&ssl=1","type":"image\/png"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"\u00c9crit par":"Na\u00efma Hassert","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Replay, de la science-fiction dans un paysage r\u00e9tro","datePublished":"2016-04-11T22:10:50+00:00","dateModified":"2020-08-03T22:54:13+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/"},"wordCount":433,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/04\/seuil-010084_0.png?fit=525%2C350&ssl=1","articleSection":["Science-fiction","Se distraire"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/","url":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/","name":"Replay, de la science-fiction dans un paysage r\u00e9tro - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/04\/seuil-010084_0.png?fit=525%2C350&ssl=1","datePublished":"2016-04-11T22:10:50+00:00","dateModified":"2020-08-03T22:54:13+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/04\/seuil-010084_0.png?fit=525%2C350&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/04\/seuil-010084_0.png?fit=525%2C350&ssl=1","width":525,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/replay-de-la-science-fiction-dans-un-paysage-retro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Replay, de la science-fiction dans un paysage r\u00e9tro"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Prochaine lecture","description":"Mes lectures, pour vous inspirer","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Prochaine lecture","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/fr\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/04\/seuil-010084_0.png?fit=525%2C350&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-kx","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/comments?post=1273"}],"version-history":[{"count":5,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1273\/revisions"}],"predecessor-version":[{"id":3446,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/posts\/1273\/revisions\/3446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media\/3445"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/media?parent=1273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/categories?post=1273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/fr\/wp-json\/wp\/v2\/tags?post=1273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}