{"id":4764,"date":"2023-05-21T17:04:50","date_gmt":"2023-05-21T21:04:50","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4764"},"modified":"2023-05-21T17:04:53","modified_gmt":"2023-05-21T21:04:53","slug":"lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/en\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/","title":{"rendered":"Lucy Sullivan is Getting Married, by Marian Keyes"},"content":{"rendered":"<p><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Marian_Keyes\">Marian Keyes<\/a> is considered one of the founders of the <em>chick lit genre.<\/em>. And you know that I have a rather big weakness for this kind (if not go to the <em><a href=\"https:\/\/prochainelecture.com\/en\/category\/se-distraire\/litterature-sentimentale\/\">Romance<\/a><\/em>section, my more or less successful politically correct translation of \"chick lit\"). Plus, one of her books, <em>Watermelon<\/em>, has been recommended in <a href=\"https:\/\/play.acast.com\/s\/sentimentalgarbage\/watermelonwithlucyvine\">Sentimental Garbage<\/a>, which has a great influence on my reading. I absolutely had to read it.<\/p>\n\n\n\n<p>The problem is that for a founder of the <em>chick lit genre, <\/em>Marian Keyes is not super well represented in the French-speaking world. I don't think that <em>Watermelon <\/em>is translated into French, and the English version is just not in stock on <a href=\"https:\/\/www.leslibraires.ca\/\">leslibraires.ca<\/a>. But by chance, the other day, I found <em>Lucy Sullivan is Getting Married <\/em>in a box of books. It was destiny: it was through it that I would be introduced to Marian Keyes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Summary<\/h2>\n\n\n\n<p>Lucy, the one in the title, is told by a fortune teller that she will soon be married. Of course she doesn't believe a word of it: she doesn't even have a boyfriend, it's a bit difficult to be further away from getting married than that. <\/p>\n\n\n\n<p>But our Lucy is a romantic at heart, and she can't help but hope. Especially when she meets this handsome boy who is <em>exactly <\/em>her kind: cute, artistic, funny... poor, selfish, unreliable... Who is breaking her heart...<\/p>\n\n\n\n<p>Maybe it's time for her to ask herself why she finds this kind of guys so attractive. Maybe that would allow her to recognize that love, real love, has been there from the very beginning.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>The book started out pretty well, Lucy was funny, I liked the English humor. The book has a bit of a <em>Friends<\/em>, with several very close roommates who love and fight with each other, and we agree that it is comforting. <\/p>\n\n\n\n<p>And then, all of a sudden, it became difficult. One bad joke after another, grossophobic jokes, suicide jokes... Please. It makes you uncomfortable. I'm not sure why I continued. <\/p>\n\n\n\n<p>Thankfully, it has recovered. The frequency of bad jokes has decreased, and it turns out that I actually really like the point of this book. It's a story about a young woman who realizes that she was idealizing a father figure who was actually unhealthy, and then changes her kind of men. And turns to the one who really loves her. And when that happens, oh how cute. My heart swelled up. <\/p>\n\n\n\n<p>It is therefore a book that I do not recommend to sensitive people. But if you can get over the bad taste, there is a very nice moral, which can do a lot of women good. <\/p>","protected":false},"excerpt":{"rendered":"<p>Marian Keyes est consid\u00e9r\u00e9e comme l&#8217;une des fondatrices du chick lit. Et vous savez que j&#8217;ai un assez gros faible pour ce genre-l\u00e0 (sinon allez voir ma section Litt\u00e9rature sentimentale, ma traduction politiquement correcte plus ou moins r\u00e9ussie de &#8220;chick lit&#8221;). En plus, un de ses livres, Watermelon, a \u00e9t\u00e9 recommand\u00e9 dans Sentimental Garbage, qui a une assez grande influence sur mes lectures. Il fallait absolument que je la lise. Le probl\u00e8me, c&#8217;est que pour une fondatrice de la chick lit, Marian Keyes n&#8217;est pas super bien repr\u00e9sent\u00e9e dans le monde francophone. Je ne pense pas que Watermelon est traduit en fran\u00e7ais, et la version anglaise n&#8217;est juste pas en stock sur leslibraires.ca. Mais par hasard, l&#8217;autre jour, j&#8217;ai trouv\u00e9 Lucy Sullivan is Getting Married dans une bo\u00eete de livres. C&#8217;\u00e9tait le destin : c&#8217;est par lui que j&#8217;allais m&#8217;initier \u00e0 Marian Keyes. R\u00e9sum\u00e9 Lucy, celle du titre, se fait dire par une voyante qu&#8217;elle se mariera bient\u00f4t. \u00c9videmment elle n&#8217;en croit pas un mot: elle n&#8217;a m\u00eame pas de chum, c&#8217;est un peu difficile d&#8217;\u00eatre plus loin de se marier que \u00e7a. Mais notre Lucy est une romantique dans l&#8217;\u00e2me, et elle ne peut s&#8217;emp\u00eacher d&#8217;esp\u00e9rer. Surtout quand elle rencontre ce beau gar\u00e7on qui est exactement son genre: mignon, artiste, dr\u00f4le&#8230; pauvre, \u00e9go\u00efste, pas fiable&#8230; Qui est en train de lui briser le coeur&#8230; Peut-\u00eatre qu&#8217;il est temps pour elle de se demander pourquoi elle trouve ce genre de gars si attirant. Peut-\u00eatre cela lui permettrait-elle de reconna\u00eetre que l&#8217;amour, le vrai, est l\u00e0 depuis le tout d\u00e9but. Impressions Le livre a plut\u00f4t bien commenc\u00e9, Lucy \u00e9tait dr\u00f4le, j&#8217;aimais bien l&#8217;humour anglais. Le livre a une ambiance un peu \u00e0 la Friends, avec plusieurs colocs tr\u00e8s proches qui s&#8217;aiment et se chicanent, et on s&#8217;entend que c&#8217;est r\u00e9confortant. Et puis, tout \u00e0 coup c&#8217;est devenu difficile. Les blagues de mauvais go\u00fbt se sont encha\u00een\u00e9es, des blagues grossophobes, sur le suicide&#8230; Piti\u00e9. \u00c7a rend mal \u00e0 l&#8217;aise. Je ne sais pas trop pourquoi j&#8217;ai continu\u00e9. Heureusement, \u00e7a s&#8217;est r\u00e9tabli. La fr\u00e9quence des mauvaises blagues a diminu\u00e9, et il s&#8217;av\u00e8re qu&#8217;en fait, j&#8217;aime beaucoup le propos de ce livre-l\u00e0. C&#8217;est une histoire d&#8217;une jeune femme qui r\u00e9alise qu&#8217;elle id\u00e9alisait une figure paternelle qui \u00e9tait en fait malsaine, puis qui change de genre de gars. Et se tourne vers celui qui l&#8217;aime pour vrai. Et quand \u00e7a arrive, oh que c&#8217;est cute. Mon coeur s&#8217;est tout gonfl\u00e9. C&#8217;est donc un livre que je ne conseille pas aux personnes sensibles. Mais si on arrive \u00e0 passer par-dessus le mauvais go\u00fbt, il y a une tr\u00e8s belle morale, qui peut faire du bien \u00e0 beaucoup de femmes.<\/p>","protected":false},"author":1,"featured_media":4766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":false,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[244,242],"tags":[],"class_list":["post-4764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litterature-sentimentale","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lucy Sullivan is Getting Married (&quot;Lucy Sullivan se marie&quot;), de Marian Keyes - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/en\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lucy Sullivan is Getting Married (&quot;Lucy Sullivan se marie&quot;), de Marian Keyes - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Marian Keyes est consid\u00e9r\u00e9e comme l&#8217;une des fondatrices du chick lit. Et vous savez que j&#8217;ai un assez gros faible pour ce genre-l\u00e0 (sinon allez voir ma section Litt\u00e9rature sentimentale, ma traduction politiquement correcte plus ou moins r\u00e9ussie de &#8220;chick lit&#8221;). En plus, un de ses livres, Watermelon, a \u00e9t\u00e9 recommand\u00e9 dans Sentimental Garbage, qui a une assez grande influence sur mes lectures. Il fallait absolument que je la lise. Le probl\u00e8me, c&#8217;est que pour une fondatrice de la chick lit, Marian Keyes n&#8217;est pas super bien repr\u00e9sent\u00e9e dans le monde francophone. Je ne pense pas que Watermelon est traduit en fran\u00e7ais, et la version anglaise n&#8217;est juste pas en stock sur leslibraires.ca. Mais par hasard, l&#8217;autre jour, j&#8217;ai trouv\u00e9 Lucy Sullivan is Getting Married dans une bo\u00eete de livres. C&#8217;\u00e9tait le destin : c&#8217;est par lui que j&#8217;allais m&#8217;initier \u00e0 Marian Keyes. R\u00e9sum\u00e9 Lucy, celle du titre, se fait dire par une voyante qu&#8217;elle se mariera bient\u00f4t. \u00c9videmment elle n&#8217;en croit pas un mot: elle n&#8217;a m\u00eame pas de chum, c&#8217;est un peu difficile d&#8217;\u00eatre plus loin de se marier que \u00e7a. Mais notre Lucy est une romantique dans l&#8217;\u00e2me, et elle ne peut s&#8217;emp\u00eacher d&#8217;esp\u00e9rer. Surtout quand elle rencontre ce beau gar\u00e7on qui est exactement son genre: mignon, artiste, dr\u00f4le&#8230; pauvre, \u00e9go\u00efste, pas fiable&#8230; Qui est en train de lui briser le coeur&#8230; Peut-\u00eatre qu&#8217;il est temps pour elle de se demander pourquoi elle trouve ce genre de gars si attirant. Peut-\u00eatre cela lui permettrait-elle de reconna\u00eetre que l&#8217;amour, le vrai, est l\u00e0 depuis le tout d\u00e9but. Impressions Le livre a plut\u00f4t bien commenc\u00e9, Lucy \u00e9tait dr\u00f4le, j&#8217;aimais bien l&#8217;humour anglais. Le livre a une ambiance un peu \u00e0 la Friends, avec plusieurs colocs tr\u00e8s proches qui s&#8217;aiment et se chicanent, et on s&#8217;entend que c&#8217;est r\u00e9confortant. Et puis, tout \u00e0 coup c&#8217;est devenu difficile. Les blagues de mauvais go\u00fbt se sont encha\u00een\u00e9es, des blagues grossophobes, sur le suicide&#8230; Piti\u00e9. \u00c7a rend mal \u00e0 l&#8217;aise. Je ne sais pas trop pourquoi j&#8217;ai continu\u00e9. Heureusement, \u00e7a s&#8217;est r\u00e9tabli. La fr\u00e9quence des mauvaises blagues a diminu\u00e9, et il s&#8217;av\u00e8re qu&#8217;en fait, j&#8217;aime beaucoup le propos de ce livre-l\u00e0. C&#8217;est une histoire d&#8217;une jeune femme qui r\u00e9alise qu&#8217;elle id\u00e9alisait une figure paternelle qui \u00e9tait en fait malsaine, puis qui change de genre de gars. Et se tourne vers celui qui l&#8217;aime pour vrai. Et quand \u00e7a arrive, oh que c&#8217;est cute. Mon coeur s&#8217;est tout gonfl\u00e9. C&#8217;est donc un livre que je ne conseille pas aux personnes sensibles. Mais si on arrive \u00e0 passer par-dessus le mauvais go\u00fbt, il y a une tr\u00e8s belle morale, qui peut faire du bien \u00e0 beaucoup de femmes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/en\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-21T21:04:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-21T21:04:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2023\/05\/20230420_171608_HDR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Lucy Sullivan is Getting Married (&#8220;Lucy Sullivan se marie&#8221;), de Marian Keyes\",\"datePublished\":\"2023-05-21T21:04:50+00:00\",\"dateModified\":\"2023-05-21T21:04:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/\"},\"wordCount\":524,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Litt\u00e9rature sentimentale\",\"Se distraire\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/\",\"name\":\"Lucy Sullivan is Getting Married (\\\"Lucy Sullivan se marie\\\"), de Marian Keyes - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2023-05-21T21:04:50+00:00\",\"dateModified\":\"2023-05-21T21:04:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lucy Sullivan is Getting Married (&#8220;Lucy Sullivan se marie&#8221;), de Marian Keyes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/en\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lucy Sullivan is Getting Married (\"Lucy Sullivan se marie\"), de Marian Keyes - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/en\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/","og_locale":"en_US","og_type":"article","og_title":"Lucy Sullivan is Getting Married (\"Lucy Sullivan se marie\"), de Marian Keyes - Prochaine lecture","og_description":"Marian Keyes est consid\u00e9r\u00e9e comme l&#8217;une des fondatrices du chick lit. Et vous savez que j&#8217;ai un assez gros faible pour ce genre-l\u00e0 (sinon allez voir ma section Litt\u00e9rature sentimentale, ma traduction politiquement correcte plus ou moins r\u00e9ussie de &#8220;chick lit&#8221;). En plus, un de ses livres, Watermelon, a \u00e9t\u00e9 recommand\u00e9 dans Sentimental Garbage, qui a une assez grande influence sur mes lectures. Il fallait absolument que je la lise. Le probl\u00e8me, c&#8217;est que pour une fondatrice de la chick lit, Marian Keyes n&#8217;est pas super bien repr\u00e9sent\u00e9e dans le monde francophone. Je ne pense pas que Watermelon est traduit en fran\u00e7ais, et la version anglaise n&#8217;est juste pas en stock sur leslibraires.ca. Mais par hasard, l&#8217;autre jour, j&#8217;ai trouv\u00e9 Lucy Sullivan is Getting Married dans une bo\u00eete de livres. C&#8217;\u00e9tait le destin : c&#8217;est par lui que j&#8217;allais m&#8217;initier \u00e0 Marian Keyes. R\u00e9sum\u00e9 Lucy, celle du titre, se fait dire par une voyante qu&#8217;elle se mariera bient\u00f4t. \u00c9videmment elle n&#8217;en croit pas un mot: elle n&#8217;a m\u00eame pas de chum, c&#8217;est un peu difficile d&#8217;\u00eatre plus loin de se marier que \u00e7a. Mais notre Lucy est une romantique dans l&#8217;\u00e2me, et elle ne peut s&#8217;emp\u00eacher d&#8217;esp\u00e9rer. Surtout quand elle rencontre ce beau gar\u00e7on qui est exactement son genre: mignon, artiste, dr\u00f4le&#8230; pauvre, \u00e9go\u00efste, pas fiable&#8230; Qui est en train de lui briser le coeur&#8230; Peut-\u00eatre qu&#8217;il est temps pour elle de se demander pourquoi elle trouve ce genre de gars si attirant. Peut-\u00eatre cela lui permettrait-elle de reconna\u00eetre que l&#8217;amour, le vrai, est l\u00e0 depuis le tout d\u00e9but. Impressions Le livre a plut\u00f4t bien commenc\u00e9, Lucy \u00e9tait dr\u00f4le, j&#8217;aimais bien l&#8217;humour anglais. Le livre a une ambiance un peu \u00e0 la Friends, avec plusieurs colocs tr\u00e8s proches qui s&#8217;aiment et se chicanent, et on s&#8217;entend que c&#8217;est r\u00e9confortant. Et puis, tout \u00e0 coup c&#8217;est devenu difficile. Les blagues de mauvais go\u00fbt se sont encha\u00een\u00e9es, des blagues grossophobes, sur le suicide&#8230; Piti\u00e9. \u00c7a rend mal \u00e0 l&#8217;aise. Je ne sais pas trop pourquoi j&#8217;ai continu\u00e9. Heureusement, \u00e7a s&#8217;est r\u00e9tabli. La fr\u00e9quence des mauvaises blagues a diminu\u00e9, et il s&#8217;av\u00e8re qu&#8217;en fait, j&#8217;aime beaucoup le propos de ce livre-l\u00e0. C&#8217;est une histoire d&#8217;une jeune femme qui r\u00e9alise qu&#8217;elle id\u00e9alisait une figure paternelle qui \u00e9tait en fait malsaine, puis qui change de genre de gars. Et se tourne vers celui qui l&#8217;aime pour vrai. Et quand \u00e7a arrive, oh que c&#8217;est cute. Mon coeur s&#8217;est tout gonfl\u00e9. C&#8217;est donc un livre que je ne conseille pas aux personnes sensibles. Mais si on arrive \u00e0 passer par-dessus le mauvais go\u00fbt, il y a une tr\u00e8s belle morale, qui peut faire du bien \u00e0 beaucoup de femmes.","og_url":"https:\/\/prochainelecture.com\/en\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2023-05-21T21:04:50+00:00","article_modified_time":"2023-05-21T21:04:53+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2023\/05\/20230420_171608_HDR.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"Written by":"Na\u00efma Hassert","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Lucy Sullivan is Getting Married (&#8220;Lucy Sullivan se marie&#8221;), de Marian Keyes","datePublished":"2023-05-21T21:04:50+00:00","dateModified":"2023-05-21T21:04:53+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/"},"wordCount":524,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/05\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1","articleSection":["Litt\u00e9rature sentimentale","Se distraire"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/","url":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/","name":"Lucy Sullivan is Getting Married (\"Lucy Sullivan se marie\"), de Marian Keyes - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/05\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1","datePublished":"2023-05-21T21:04:50+00:00","dateModified":"2023-05-21T21:04:53+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/05\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/05\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/lucy-sullivan-is-getting-married-lucy-sullivan-se-marie-de-marian-keyes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Lucy Sullivan is Getting Married (&#8220;Lucy Sullivan se marie&#8221;), de Marian Keyes"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Next Read","description":"My readings, to inspire you","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Next Read","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/en\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/05\/20230420_171608_HDR.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-1eQ","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/comments?post=4764"}],"version-history":[{"count":5,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4764\/revisions"}],"predecessor-version":[{"id":4772,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4764\/revisions\/4772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media\/4766"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media?parent=4764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/categories?post=4764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/tags?post=4764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}