{"id":4709,"date":"2023-03-21T10:28:41","date_gmt":"2023-03-21T14:28:41","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4709"},"modified":"2023-03-21T10:28:44","modified_gmt":"2023-03-21T14:28:44","slug":"jean-philippe-baril-guerard","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/en\/jean-philippe-baril-guerard\/","title":{"rendered":"Jean-Philippe Baril Gu\u00e9rard: the one who could have been in my CEGEP class"},"content":{"rendered":"<p>It's not often that I read a book and think, \"Wow, I want to read every book by that person.\" I think the last time that happened was when I was about 8 years old and I decided to read <em>all <\/em>Lucy Maud Montgomery's books, because I so much liked <em>Anne of Green Gables. <\/em><\/p>\n\n\n\n<p>Well, it seems that Jean-Philippe Baril Gu\u00e9rard is my Lucy Maud Montgomery, adult version. It's cynical, quite dark, there's sex, drugs, and a lot a curses. But it's also incredibly creative, surprisingly deep and close to me. It takes place not only in my city (Montreal), but in my area, in my language, and with people my age. I had the strong impression that I could have met the author in one of my CEGEP classes. Enough to develop an instant obsession. <\/p>\n\n\n\n<p>I read these four novels in a row. Since my goal is to have you read them, I'll just give you an introductory taste.<\/p>\n\n\n\n<p>Note that no one paid me to make this shameless publicity.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Haute d\u00e9molition (\"High demolition\")<\/h2>\n\n\n\n<p>A woman, at a party, starts telling a guy who is starting to fall for her what would happen if they slept together that night. In great detail, so much so that it takes a whole book. Spoiler: it's not pretty.<\/p>\n\n\n\n<p>With its narration in the you and the simple future tense, the text is a bit confusing. For me, it's a totally new concept. I wasn't sure I liked it, I wasn't sure I liked the narrator (a bit pretentious to imagine how a guy will develop a consuming passion for you, isn't it?), but I devoured it. The guy works in the comedy industry and you get a behind-the-scenes look at the business, including tips on how to craft a good joke, and how to react when a friend gets outed as part of the #MeToo movement. I still often find myself thinking about that book.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/haute-demolition-jean-philippe-baril-guerard-9782924670972.html\/?type=livre&#038;configuration=2&#038;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">Manuel de la vie sauvage (\"Wildlife manual\")<\/h2>\n\n\n\n<p>I just found out that <em>Manuel de la vie sauvage (\"Wildlife manual\")<\/em> has been adapted <a href=\"https:\/\/www.seriesplus.com\/emissions\/manuel-de-la-vie-sauvage\/\">for television<\/a> and <a href=\"https:\/\/duceppe.com\/manuel-de-la-vie-sauvage\/\">to the theater<\/a>. I can even listen to the whole series for free on S\u00e9ries Plus it seems. The excitement is building.<\/p>\n\n\n\n<p>This one is a satire of the business world. Kevin Bedard (worst name on earth according to him) explains how to become a millionaire in Quebec, and it basically involves being an asshole. I was a little less impressed with the concept than I was with <em>Haute d\u00e9molition (\"High demolition\")<\/em>, not as original in my opinion, and I think that in the end, it is the one I like the least. But the whole Baril Gu\u00e9rard vibe is there, and like his other books, I got through it in record time.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/manuel-de-la-vie-sauvage-jean-philippe-baril-guerard-9782924670422.html\/?type=livre&#038;configuration=2&#038;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">Royal<\/h2>\n\n\n\n<p>This one is by far the most satisfying of the bunch. I've never been interested in trying to \" carve out \" a place for myself in contingent fields like medicine or law, and it's really nice to be proven right in this way. Here we have a critique of law school at the University of Montreal, where students are told at the outset that they are part of society's elite (if they manage to survive the program, of course), and where getting average grades one term can throw you into a cold sweat. All of Jean-Philippe Baril Gu\u00e9rard's books criticize some aspect of society, but this one is the most scathing in my opinion. It will be a pleasure for me to offer it to the cynics around me.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/royal-jean-philippe-baril-guerard-9782924670033.html\/?type=livre&#038;configuration=2&#038;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">Sports et divertissements (\"Sports and entertainment\")<\/h2>\n\n\n\n<p>I was introduced to this author with this one. Here we have a 22-year-old actress who made her name with a teen show she starred in years ago, and who is way too rich for her maturity level. She's beautiful, people love her, and she thinks she can do anything. The worst part is that she seems to be right. She uses people as tools, takes drugs, says exactly what she thinks, and never gets punished. I read this book in a hurry, driven by a kind of unhealthy curiosity, and it rubbed my dark humor the right way. This one stuck in my head too, because it's really more brilliant than it looks. <\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/sports-et-divertissements-jean-philippe-baril-guerard-9782923553696.html\/?type=livre&#038;configuration=2&#038;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>","protected":false},"excerpt":{"rendered":"<p>\u00c7a ne m&#8217;arrive pas souvent de lire un livre et de me dire &#8220;Wow, j&#8217;ai envie de lire tous les livres de cette personne-l\u00e0.&#8221; Je pense que la derni\u00e8re fois que c&#8217;est arriv\u00e9, c&#8217;\u00e9tait quand j&#8217;avais \u00e0 peu pr\u00e8s 8 ans et que j&#8217;ai d\u00e9cid\u00e9 de lire tous les livres de Lucy Maud Montgomery, parce que j&#8217;avais tellement aim\u00e9 Anne&#8230; la maison aux pignons verts. Eh bien on dirait que Jean-Philippe Baril Gu\u00e9rard est mon Lucy Maud Montgomery, version adulte. C&#8217;est cynique, assez dark, il y a du sexe, de la drogue, et ben des sacres. Mais c&#8217;est aussi incroyablement cr\u00e9atif, \u00e9tonnamment profond et proche de moi. \u00c7a se passe non seulement dans ma ville (Montr\u00e9al), mais dans mon coin, dans ma langue, et avec des gens de mon \u00e2ge. J&#8217;avais la forte impression que j&#8217;aurais pu croiser l&#8217;auteur dans une de mes classes au c\u00e9gep. De quoi d\u00e9velopper instantan\u00e9ment une obsession. J&#8217;ai lu ces quatres romans d&#8217;un coup. Vu que mon objectif est de vous les faire lire, je vais simplement vous donner une mise en bouche. Notez que personne ne m&#8217;a pay\u00e9e pour faire cette publicit\u00e9 si impudente. Haute d\u00e9molition Une femme, dans un party, commence \u00e0 raconter \u00e0 un gars qui commence \u00e0 tripper dessus ce qui arriverait s&#8217;ils couchaient ensemble ce soir-l\u00e0. Avec beaucoup de d\u00e9tails, tellement que \u00e7a prend un livre au complet. Spoiler : c&#8217;est pas joyeux. Avec sa narration au tu et au futur simple, le texte est un peu d\u00e9routant. Pour moi, c&#8217;est un concept totalement nouveau. Je n&#8217;\u00e9tais pas s\u00fbre d&#8217;aimer \u00e7a, je n&#8217;\u00e9tais pas s\u00fbre d&#8217;aimer la narratrice (un peu pr\u00e9tentieux d&#8217;imaginer comment un gars va d\u00e9velopper une passion d\u00e9vorante pour toi, non?), mais j&#8217;ai d\u00e9vor\u00e9. Le gars travaille dans l&#8217;humour et on a acc\u00e8s aux coulisses de ce milieu, incluant des trucs pour construire une bonne blague, et pour comment r\u00e9agir quand un ami se fait d\u00e9noncer dans le cadre du mouvement #MeToo. Je me surprends encore souvent \u00e0 penser \u00e0 ce livre-l\u00e0. Manuel de la vie sauvage Je viens de d\u00e9couvrir que Manuel de la vie sauvage a \u00e9t\u00e9 adapt\u00e9 \u00e0 la t\u00e9l\u00e9 et au th\u00e9\u00e2tre. Je peux m\u00eame \u00e9couter la s\u00e9rie au complet gratuitement sur S\u00e9ries Plus on dirait. L&#8217;excitation monte. Celui-l\u00e0 est une satire du monde des affaires. Kevin B\u00e9dard (pire nom de la terre selon ses propres dires) explique comment devenir millionaire au Qu\u00e9bec, et \u00e7a implique, en gros, de devenir un trou de cul. J&#8217;ai \u00e9t\u00e9 un peu moins impressionn\u00e9e par le concept que je l&#8217;ai \u00e9t\u00e9 avec Haute d\u00e9molition, moins original \u00e0 mon avis, et je crois qu&#8217;au final, c&#8217;est celui que j&#8217;aime le moins. Mais tout le Baril Gu\u00e9rard est l\u00e0, et comme pour ses autres livres, j&#8217;ai pass\u00e9 au travers en un temps record. Royal Celui-l\u00e0 est de loin le plus satisfaisant de la gang. Je n&#8217;ai jamais \u00e9t\u00e9 int\u00e9ress\u00e9e \u00e0 essayer de me &#8220;tailler une place&#8221; dans des domaines contingent\u00e9s comme la m\u00e9decine ou le droit, et c&#8217;est vraiment agr\u00e9able de se faire donner raison de cette fa\u00e7on. Ici, on a une critique des \u00e9tudes en droit \u00e0 l&#8217;Universit\u00e9 de Montr\u00e9al, o\u00f9 les \u00e9tudiants se font dire en partant qu&#8217;ils font partie de l&#8217;\u00e9lite de la soci\u00e9t\u00e9 (s&#8217;ils r\u00e9ussissent \u00e0 survivre au programme, bien s\u00fbr), et o\u00f9 avoir des notes moyennes une session peut te jeter dans des sueurs froides. Tous les livres de Jean-Philippe Baril Gu\u00e9rard critiquent un aspect de la soci\u00e9t\u00e9, mais celui-l\u00e0 est selon moi le plus cinglant. Ce sera un plaisir pour moi de l&#8217;offrir aux cyniques de mon entourage. Sports et divertissements C&#8217;est avec celui-l\u00e0 que je me suis initi\u00e9e \u00e0 cet auteur. Ici, on a une actrice de 22 ans qui s&#8217;est fait conna\u00eetre avec une s\u00e9rie pour ados dans laquelle elle a jou\u00e9 il y a d\u00e9j\u00e0 plusieurs ann\u00e9es, et qui est beaucoup trop riche pour son niveau de maturit\u00e9. Elle est belle, les gens l&#8217;aiment, et elle se croit tout permis. Le pire, c&#8217;est qu&#8217;on dirait qu&#8217;elle a raison. Elle utilise les gens comme des outils, prend de la drogue, dit exactement ce qu&#8217;elle pense, et ne se fait jamais punir. J&#8217;ai lu ce livre \u00e0 toute vitesse, mue par une sorte de curiosit\u00e9 malsaine, et il a caress\u00e9 mon humour noir dans le sens du poil. Celui-l\u00e0 aussi m&#8217;est rest\u00e9 en t\u00eate, parce qu&#8217;il est vraiment plus brillant qu&#8217;il n&#8217;en a l&#8217;air.<\/p>","protected":false},"author":1,"featured_media":4710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[283,245,242],"tags":[],"class_list":["post-4709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auteurs","category-litterature-quebecoise","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/en\/jean-philippe-baril-guerard\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"\u00c7a ne m&#8217;arrive pas souvent de lire un livre et de me dire &#8220;Wow, j&#8217;ai envie de lire tous les livres de cette personne-l\u00e0.&#8221; Je pense que la derni\u00e8re fois que c&#8217;est arriv\u00e9, c&#8217;\u00e9tait quand j&#8217;avais \u00e0 peu pr\u00e8s 8 ans et que j&#8217;ai d\u00e9cid\u00e9 de lire tous les livres de Lucy Maud Montgomery, parce que j&#8217;avais tellement aim\u00e9 Anne&#8230; la maison aux pignons verts. Eh bien on dirait que Jean-Philippe Baril Gu\u00e9rard est mon Lucy Maud Montgomery, version adulte. C&#8217;est cynique, assez dark, il y a du sexe, de la drogue, et ben des sacres. Mais c&#8217;est aussi incroyablement cr\u00e9atif, \u00e9tonnamment profond et proche de moi. \u00c7a se passe non seulement dans ma ville (Montr\u00e9al), mais dans mon coin, dans ma langue, et avec des gens de mon \u00e2ge. J&#8217;avais la forte impression que j&#8217;aurais pu croiser l&#8217;auteur dans une de mes classes au c\u00e9gep. De quoi d\u00e9velopper instantan\u00e9ment une obsession. J&#8217;ai lu ces quatres romans d&#8217;un coup. Vu que mon objectif est de vous les faire lire, je vais simplement vous donner une mise en bouche. Notez que personne ne m&#8217;a pay\u00e9e pour faire cette publicit\u00e9 si impudente. Haute d\u00e9molition Une femme, dans un party, commence \u00e0 raconter \u00e0 un gars qui commence \u00e0 tripper dessus ce qui arriverait s&#8217;ils couchaient ensemble ce soir-l\u00e0. Avec beaucoup de d\u00e9tails, tellement que \u00e7a prend un livre au complet. Spoiler : c&#8217;est pas joyeux. Avec sa narration au tu et au futur simple, le texte est un peu d\u00e9routant. Pour moi, c&#8217;est un concept totalement nouveau. Je n&#8217;\u00e9tais pas s\u00fbre d&#8217;aimer \u00e7a, je n&#8217;\u00e9tais pas s\u00fbre d&#8217;aimer la narratrice (un peu pr\u00e9tentieux d&#8217;imaginer comment un gars va d\u00e9velopper une passion d\u00e9vorante pour toi, non?), mais j&#8217;ai d\u00e9vor\u00e9. Le gars travaille dans l&#8217;humour et on a acc\u00e8s aux coulisses de ce milieu, incluant des trucs pour construire une bonne blague, et pour comment r\u00e9agir quand un ami se fait d\u00e9noncer dans le cadre du mouvement #MeToo. Je me surprends encore souvent \u00e0 penser \u00e0 ce livre-l\u00e0. Manuel de la vie sauvage Je viens de d\u00e9couvrir que Manuel de la vie sauvage a \u00e9t\u00e9 adapt\u00e9 \u00e0 la t\u00e9l\u00e9 et au th\u00e9\u00e2tre. Je peux m\u00eame \u00e9couter la s\u00e9rie au complet gratuitement sur S\u00e9ries Plus on dirait. L&#8217;excitation monte. Celui-l\u00e0 est une satire du monde des affaires. Kevin B\u00e9dard (pire nom de la terre selon ses propres dires) explique comment devenir millionaire au Qu\u00e9bec, et \u00e7a implique, en gros, de devenir un trou de cul. J&#8217;ai \u00e9t\u00e9 un peu moins impressionn\u00e9e par le concept que je l&#8217;ai \u00e9t\u00e9 avec Haute d\u00e9molition, moins original \u00e0 mon avis, et je crois qu&#8217;au final, c&#8217;est celui que j&#8217;aime le moins. Mais tout le Baril Gu\u00e9rard est l\u00e0, et comme pour ses autres livres, j&#8217;ai pass\u00e9 au travers en un temps record. Royal Celui-l\u00e0 est de loin le plus satisfaisant de la gang. Je n&#8217;ai jamais \u00e9t\u00e9 int\u00e9ress\u00e9e \u00e0 essayer de me &#8220;tailler une place&#8221; dans des domaines contingent\u00e9s comme la m\u00e9decine ou le droit, et c&#8217;est vraiment agr\u00e9able de se faire donner raison de cette fa\u00e7on. Ici, on a une critique des \u00e9tudes en droit \u00e0 l&#8217;Universit\u00e9 de Montr\u00e9al, o\u00f9 les \u00e9tudiants se font dire en partant qu&#8217;ils font partie de l&#8217;\u00e9lite de la soci\u00e9t\u00e9 (s&#8217;ils r\u00e9ussissent \u00e0 survivre au programme, bien s\u00fbr), et o\u00f9 avoir des notes moyennes une session peut te jeter dans des sueurs froides. Tous les livres de Jean-Philippe Baril Gu\u00e9rard critiquent un aspect de la soci\u00e9t\u00e9, mais celui-l\u00e0 est selon moi le plus cinglant. Ce sera un plaisir pour moi de l&#8217;offrir aux cyniques de mon entourage. Sports et divertissements C&#8217;est avec celui-l\u00e0 que je me suis initi\u00e9e \u00e0 cet auteur. Ici, on a une actrice de 22 ans qui s&#8217;est fait conna\u00eetre avec une s\u00e9rie pour ados dans laquelle elle a jou\u00e9 il y a d\u00e9j\u00e0 plusieurs ann\u00e9es, et qui est beaucoup trop riche pour son niveau de maturit\u00e9. Elle est belle, les gens l&#8217;aiment, et elle se croit tout permis. Le pire, c&#8217;est qu&#8217;on dirait qu&#8217;elle a raison. Elle utilise les gens comme des outils, prend de la drogue, dit exactement ce qu&#8217;elle pense, et ne se fait jamais punir. J&#8217;ai lu ce livre \u00e0 toute vitesse, mue par une sorte de curiosit\u00e9 malsaine, et il a caress\u00e9 mon humour noir dans le sens du poil. Celui-l\u00e0 aussi m&#8217;est rest\u00e9 en t\u00eate, parce qu&#8217;il est vraiment plus brillant qu&#8217;il n&#8217;en a l&#8217;air.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/en\/jean-philippe-baril-guerard\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-21T14:28:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T14:28:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2023\/03\/20230319_154036.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep\",\"datePublished\":\"2023-03-21T14:28:41+00:00\",\"dateModified\":\"2023-03-21T14:28:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/\"},\"wordCount\":833,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/20230319_154036.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Auteurs coups de coeur\",\"Litt\u00e9rature qu\u00e9b\u00e9coise\",\"Se distraire\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/\",\"name\":\"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/20230319_154036.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2023-03-21T14:28:41+00:00\",\"dateModified\":\"2023-03-21T14:28:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/20230319_154036.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/20230319_154036.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/jean-philippe-baril-guerard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/en\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/en\/jean-philippe-baril-guerard\/","og_locale":"en_US","og_type":"article","og_title":"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep - Prochaine lecture","og_description":"\u00c7a ne m&#8217;arrive pas souvent de lire un livre et de me dire &#8220;Wow, j&#8217;ai envie de lire tous les livres de cette personne-l\u00e0.&#8221; Je pense que la derni\u00e8re fois que c&#8217;est arriv\u00e9, c&#8217;\u00e9tait quand j&#8217;avais \u00e0 peu pr\u00e8s 8 ans et que j&#8217;ai d\u00e9cid\u00e9 de lire tous les livres de Lucy Maud Montgomery, parce que j&#8217;avais tellement aim\u00e9 Anne&#8230; la maison aux pignons verts. Eh bien on dirait que Jean-Philippe Baril Gu\u00e9rard est mon Lucy Maud Montgomery, version adulte. C&#8217;est cynique, assez dark, il y a du sexe, de la drogue, et ben des sacres. Mais c&#8217;est aussi incroyablement cr\u00e9atif, \u00e9tonnamment profond et proche de moi. \u00c7a se passe non seulement dans ma ville (Montr\u00e9al), mais dans mon coin, dans ma langue, et avec des gens de mon \u00e2ge. J&#8217;avais la forte impression que j&#8217;aurais pu croiser l&#8217;auteur dans une de mes classes au c\u00e9gep. De quoi d\u00e9velopper instantan\u00e9ment une obsession. J&#8217;ai lu ces quatres romans d&#8217;un coup. Vu que mon objectif est de vous les faire lire, je vais simplement vous donner une mise en bouche. Notez que personne ne m&#8217;a pay\u00e9e pour faire cette publicit\u00e9 si impudente. Haute d\u00e9molition Une femme, dans un party, commence \u00e0 raconter \u00e0 un gars qui commence \u00e0 tripper dessus ce qui arriverait s&#8217;ils couchaient ensemble ce soir-l\u00e0. Avec beaucoup de d\u00e9tails, tellement que \u00e7a prend un livre au complet. Spoiler : c&#8217;est pas joyeux. Avec sa narration au tu et au futur simple, le texte est un peu d\u00e9routant. Pour moi, c&#8217;est un concept totalement nouveau. Je n&#8217;\u00e9tais pas s\u00fbre d&#8217;aimer \u00e7a, je n&#8217;\u00e9tais pas s\u00fbre d&#8217;aimer la narratrice (un peu pr\u00e9tentieux d&#8217;imaginer comment un gars va d\u00e9velopper une passion d\u00e9vorante pour toi, non?), mais j&#8217;ai d\u00e9vor\u00e9. Le gars travaille dans l&#8217;humour et on a acc\u00e8s aux coulisses de ce milieu, incluant des trucs pour construire une bonne blague, et pour comment r\u00e9agir quand un ami se fait d\u00e9noncer dans le cadre du mouvement #MeToo. Je me surprends encore souvent \u00e0 penser \u00e0 ce livre-l\u00e0. Manuel de la vie sauvage Je viens de d\u00e9couvrir que Manuel de la vie sauvage a \u00e9t\u00e9 adapt\u00e9 \u00e0 la t\u00e9l\u00e9 et au th\u00e9\u00e2tre. Je peux m\u00eame \u00e9couter la s\u00e9rie au complet gratuitement sur S\u00e9ries Plus on dirait. L&#8217;excitation monte. Celui-l\u00e0 est une satire du monde des affaires. Kevin B\u00e9dard (pire nom de la terre selon ses propres dires) explique comment devenir millionaire au Qu\u00e9bec, et \u00e7a implique, en gros, de devenir un trou de cul. J&#8217;ai \u00e9t\u00e9 un peu moins impressionn\u00e9e par le concept que je l&#8217;ai \u00e9t\u00e9 avec Haute d\u00e9molition, moins original \u00e0 mon avis, et je crois qu&#8217;au final, c&#8217;est celui que j&#8217;aime le moins. Mais tout le Baril Gu\u00e9rard est l\u00e0, et comme pour ses autres livres, j&#8217;ai pass\u00e9 au travers en un temps record. Royal Celui-l\u00e0 est de loin le plus satisfaisant de la gang. Je n&#8217;ai jamais \u00e9t\u00e9 int\u00e9ress\u00e9e \u00e0 essayer de me &#8220;tailler une place&#8221; dans des domaines contingent\u00e9s comme la m\u00e9decine ou le droit, et c&#8217;est vraiment agr\u00e9able de se faire donner raison de cette fa\u00e7on. Ici, on a une critique des \u00e9tudes en droit \u00e0 l&#8217;Universit\u00e9 de Montr\u00e9al, o\u00f9 les \u00e9tudiants se font dire en partant qu&#8217;ils font partie de l&#8217;\u00e9lite de la soci\u00e9t\u00e9 (s&#8217;ils r\u00e9ussissent \u00e0 survivre au programme, bien s\u00fbr), et o\u00f9 avoir des notes moyennes une session peut te jeter dans des sueurs froides. Tous les livres de Jean-Philippe Baril Gu\u00e9rard critiquent un aspect de la soci\u00e9t\u00e9, mais celui-l\u00e0 est selon moi le plus cinglant. Ce sera un plaisir pour moi de l&#8217;offrir aux cyniques de mon entourage. Sports et divertissements C&#8217;est avec celui-l\u00e0 que je me suis initi\u00e9e \u00e0 cet auteur. Ici, on a une actrice de 22 ans qui s&#8217;est fait conna\u00eetre avec une s\u00e9rie pour ados dans laquelle elle a jou\u00e9 il y a d\u00e9j\u00e0 plusieurs ann\u00e9es, et qui est beaucoup trop riche pour son niveau de maturit\u00e9. Elle est belle, les gens l&#8217;aiment, et elle se croit tout permis. Le pire, c&#8217;est qu&#8217;on dirait qu&#8217;elle a raison. Elle utilise les gens comme des outils, prend de la drogue, dit exactement ce qu&#8217;elle pense, et ne se fait jamais punir. J&#8217;ai lu ce livre \u00e0 toute vitesse, mue par une sorte de curiosit\u00e9 malsaine, et il a caress\u00e9 mon humour noir dans le sens du poil. Celui-l\u00e0 aussi m&#8217;est rest\u00e9 en t\u00eate, parce qu&#8217;il est vraiment plus brillant qu&#8217;il n&#8217;en a l&#8217;air.","og_url":"https:\/\/prochainelecture.com\/en\/jean-philippe-baril-guerard\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2023-03-21T14:28:41+00:00","article_modified_time":"2023-03-21T14:28:44+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2023\/03\/20230319_154036.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"Written by":"Na\u00efma Hassert","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep","datePublished":"2023-03-21T14:28:41+00:00","dateModified":"2023-03-21T14:28:44+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/"},"wordCount":833,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/03\/20230319_154036.jpg?fit=1200%2C800&ssl=1","articleSection":["Auteurs coups de coeur","Litt\u00e9rature qu\u00e9b\u00e9coise","Se distraire"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/","url":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/","name":"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/03\/20230319_154036.jpg?fit=1200%2C800&ssl=1","datePublished":"2023-03-21T14:28:41+00:00","dateModified":"2023-03-21T14:28:44+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/03\/20230319_154036.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/03\/20230319_154036.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/jean-philippe-baril-guerard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Jean-Philippe Baril Gu\u00e9rard: celui qui aurait pu \u00eatre dans ma classe au c\u00e9gep"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Next Read","description":"My readings, to inspire you","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Next Read","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/en\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2023\/03\/20230319_154036.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-1dX","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/comments?post=4709"}],"version-history":[{"count":4,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4709\/revisions"}],"predecessor-version":[{"id":4716,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4709\/revisions\/4716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media\/4710"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media?parent=4709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/categories?post=4709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/tags?post=4709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}