{"id":4281,"date":"2022-01-16T15:04:13","date_gmt":"2022-01-16T19:04:13","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=4281"},"modified":"2022-01-16T15:04:17","modified_gmt":"2022-01-16T19:04:17","slug":"career-girls","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/en\/career-girls\/","title":{"rendered":"Career Girls"},"content":{"rendered":"<p>Wow, this book. I finished it a few weeks ago already, and I still think about it every day. <\/p>\n\n\n\n<p>Again, I took the suggestion from the podcast <em>Sentimental Garbage. <\/em>To all the book lovers in the world, I highly recommend this podcast. It's a blast. The host is brilliant, funny, and very passionate, and so are her guests. I agree with just about everything they say, including their comments on <em>Career Girls<\/em>. So much so that I don't know if I can add much to what they have already said.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Career Girls with Helen O&amp;apos;Hara\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" src=\"https:\/\/open.spotify.com\/embed\/episode\/1sIKHDyJwgSmp6ez8McwVE?utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Summary<\/h2>\n\n\n\n<p>Rowena and Topaz are two incredibly bright, incredibly attractive women. Rowena, from the Scottish elite, has long blonde hair, blue eyes, a slim body, exudes class, and loves rock music. Topaz, half American, half Italian, has long curly red hair, a curvy body, and a passion for journalism. <\/p>\n\n\n\n<p>The two women meet at Oxford University, where they recognize each other's beauty and talent, and become inseparable. Until Rowena betrays her friend by sleeping with her boyfriend. Their friendship turns into a fierce and voracious hatred. They will rise to the top of their respective industries and, from the height of their fame and wealth, will do anything to destroy the other.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>This book is not perfect. There are several very questionable aspects: the feminism, in particular, is very dubious. The girls, although powerful, use their bodies to advance their careers and are, not only but very importantly, objects of desire. They sleep all the time with older men, in positions of authority, and sometimes married. The sex scenes (very numerous) are often very unrealistic and a bit unhealthy. Their richness is a bit sickening. And so on. There are a lot of people who will hate this book for this reason, and I understand.<\/p>\n\n\n\n<p>But what a read! First, you have to admit that the story is rock solid. It's rare that a book summary hooks me, but this one managed to get me excited. And it's well written: the chapters follow each other frantically, and you could very well get through the book in a single day (it would be a long day, but very satisfying). <\/p>\n\n\n\n<p>It's fun to see what machines those women are in their work. They have great ideas, they are ambitious and talented, and they destroy every poor sucker in their path. Their work environment is very well described and seems quite realistic. To witness their success is in itself a joy.<\/p>\n\n\n\n<p>And then there's the glam. Topaz and Rowena weren't doing too bad already, but they are getting incredibly rich. They are bathed in luxury, and this luxury is described in all its details. Clothes, in particular, are always described in great detail. We will never see a simple \"she wore a beautiful blue dress that highlighted the color of her eyes\", no: we will have not only the precise cut of the dress, but its brand (always real brands, I actually had quite a lot of fun going to see what they looked like), the exact shade of blue, the length of the dress, which parts of the body it highlights, the jewelry, the shoes, the makeup, etc. You can not give a damn about those details, but I really liked it. <\/p>\n\n\n\n<p>Sexuality is a very important aspect of the book, I must say. All the main characters are exceptionally beautiful, but especially Topaz and Rowena. They exude sex appeal like you wouldn't believe. Their curves always spill out of their clothes, their hair is always flaming, and they are always two minutes away from an orgasm, it's fascinating. There is at least one sex scene per chapter, always very graphic and very pornographic. We're not into realism, and I didn't find them particularly arousing, but they definitely strike the imagination. <\/p>\n\n\n\n<p>The host of <em>Sentimental Garbage<\/em> said that <em>Career Girls <\/em>was one of the most captivating books she ever read, and I agree with her. It's pretty compelling. It is exciting and really takes us out of our daily lives. I forced myself to read it slowly so as not to exhaust my pleasure too quickly. If you can get past its obvious flaws, I think you'll have a great time.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wow, ce livre. Je l&#8217;ai fini il y a quelques semaines d\u00e9j\u00e0, et j&#8217;y pense encore tous les jours. Encore une fois, j&#8217;ai pris la suggestion du podcast Sentimental Garbage. \u00c0 tous les amoureux de lecture de ce monde, je vous conseille tr\u00e8s vivement ce podcast. C&#8217;est du bonbon. L&#8217;animatrice est brillante, dr\u00f4le et tr\u00e8s passionn\u00e9e, et ses invit\u00e9es le sont tout autant. Je suis d&#8217;accord avec \u00e0 peu pr\u00e8s tout ce qu&#8217;elles disent, y compris leurs propos sur Career Girls. Tellement que je ne sais pas si je vais pouvoir ajouter grand-chose \u00e0 ce qu&#8217;elles en ont d\u00e9j\u00e0 dit. R\u00e9sum\u00e9 Rowena et Topaz sont deux femmes incroyablement brillantes, et incroyablement s\u00e9duisantes. Rowena, issue de l&#8217;\u00e9lite \u00e9cossaise, a de longs cheveux blonds, des yeux bleus, un corps fin, respire la classe, et adore le rock. Topaz, moiti\u00e9 am\u00e9ricaine, moiti\u00e9 italienne, a de longs cheveux roux boucl\u00e9s, un corps d&#8217;enfer tout en courbes, et est passionn\u00e9e par le journalisme. Les deux femmes se rencontrent \u00e0 l&#8217;universit\u00e9 d&#8217;Oxford, o\u00f9 elles se reconnaissent dans leur beaut\u00e9 et leur talent, et deviennent ins\u00e9parables. Jusqu&#8217;\u00e0 ce que Rowena trahisse son amie en couchant avec son chum. Leur amiti\u00e9 se change alors en haine f\u00e9roce et vorace. Elles s&#8217;\u00e9l\u00e8veront au sommet de leur industrie respective et, du haut de leur gloire et de leur richesse vertigineuses, feront tout pour d\u00e9truire l&#8217;autre. Impressions Ce livre n&#8217;est pas parfait. Il y a plusieurs aspects tr\u00e8s discutables : le f\u00e9minisme, notamment, est tr\u00e8s douteux. Les filles, certes puissantes, utilisent leur corps pour avancer dans leur carri\u00e8re et sont, pas seulement mais de fa\u00e7on tr\u00e8s importante, des objets de d\u00e9sir. Elles couchent tout le temps avec des hommes plus vieux, en position d&#8217;autorit\u00e9, et parfois mari\u00e9s. Les sc\u00e8nes de sexe (tr\u00e8s nombreuses) sont souvent tr\u00e8s peu r\u00e9alistes et moyennement saines. Leur richesse est un peu \u00e9coeurante. Et j&#8217;en passe. Il y a beaucoup de gens qui vont d\u00e9tester ce livre pour cette raison, et je comprends tr\u00e8s bien. Mais quelle lecture! D&#8217;abord, avouez que l&#8217;histoire est b\u00e9ton. C&#8217;est rare qu&#8217;un r\u00e9sum\u00e9 d&#8217;un livre m&#8217;accroche, mais celui-ci a r\u00e9ussi \u00e0 m&#8217;exciter. Et c&#8217;est bien \u00e9crit : les chapitres s&#8217;encha\u00eenent fr\u00e9n\u00e9tiquement, et on pourrait tr\u00e8s bien passer au travers du livre en une seule journ\u00e9e (ce serait une journ\u00e9e longue, mais tr\u00e8s satisfaisante). C&#8217;est jouissif de voir \u00e0 quel point les femmes sont des b\u00eates dans leur travail. Elles ont d&#8217;excellentes id\u00e9es, elles sont ambitieuses et talentueuses, et d\u00e9truisent tous les pauvres ploucs sur leur passage. Leur environnement de travail est tr\u00e8s bien d\u00e9crit et semble assez r\u00e9aliste. Assister \u00e0 leur succ\u00e8s est en soi un bonheur. Et puis, il y a le glam. Topaz et Rowena ne s&#8217;en tiraient d\u00e9j\u00e0 pas trop mal, mais elles deviennent incroyablement riches. Elles baignent dans le luxe, et ce luxe est d\u00e9crit dans tous ses d\u00e9tails. Les v\u00eatements, notamment, sont toujours d\u00e9crits avec minutie. Jamais on ne verra un simple &#8220;elle portait une belle robe bleue qui relevait la couleur de ses yeux&#8221;, non : on aura non seulement la coupe pr\u00e9cise de la robe, mais sa marque (toujours des vraies marques, j&#8217;ai d&#8217;ailleurs eu pas mal de plaisir \u00e0 aller voir \u00e0 quoi elles ressemblaient), la teinte exacte de bleu, la longueur de la robe, quelles parties du corps elle met en avantage, les bijoux, les souliers, le maquillage, alouette. On peut se foutre de ces d\u00e9tails-l\u00e0, mais moi j&#8217;ai beaucoup aim\u00e9. La sexualit\u00e9 est un aspect tr\u00e8s important du livre, il faut le dire. Tous les personnages principaux sont d&#8217;une beaut\u00e9 exceptionnelle, mais surtout Topaz et Rowena. Elles exultent de sex-appeal comme vous n&#8217;avez m\u00eame pas id\u00e9e. Leurs courbes d\u00e9bordent toujours de leurs v\u00eatements, leurs cheveux sont toujours flamboyants, et elles sont toujours \u00e0 deux minutes d&#8217;un orgasme, c&#8217;est fascinant. Il y a au moins une sc\u00e8ne de sexe par chapitre, toujours tr\u00e8s graphique et tr\u00e8s pornographique. On n&#8217;est pas dans le r\u00e9alisme, et je ne les ai pas trouv\u00e9es particuli\u00e8rement excitantes, mais elles frappent l&#8217;imaginaire, c&#8217;est certain. L&#8217;animatrice de Sentimental Garbage a dit que Career Girls \u00e9tait un des livres les plus captivants qu&#8217;elle ait jamais lu, et je suis d&#8217;accord avec elle. Il est assez irr\u00e9sistible. Il est excitant et nous sort vraiment de notre quotidien. Je me suis forc\u00e9e \u00e0 le lire lentement pour ne pas \u00e9puiser mon plaisir trop vite. Si vous \u00eates capables de passer outre ses d\u00e9fauts \u00e9vidents, je crois que vous allez passer un tr\u00e8s bon moment.<\/p>","protected":false},"author":1,"featured_media":4284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[242],"tags":[],"class_list":["post-4281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Career Girls - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/en\/career-girls\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Career Girls - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Wow, ce livre. Je l&#8217;ai fini il y a quelques semaines d\u00e9j\u00e0, et j&#8217;y pense encore tous les jours. Encore une fois, j&#8217;ai pris la suggestion du podcast Sentimental Garbage. \u00c0 tous les amoureux de lecture de ce monde, je vous conseille tr\u00e8s vivement ce podcast. C&#8217;est du bonbon. L&#8217;animatrice est brillante, dr\u00f4le et tr\u00e8s passionn\u00e9e, et ses invit\u00e9es le sont tout autant. Je suis d&#8217;accord avec \u00e0 peu pr\u00e8s tout ce qu&#8217;elles disent, y compris leurs propos sur Career Girls. Tellement que je ne sais pas si je vais pouvoir ajouter grand-chose \u00e0 ce qu&#8217;elles en ont d\u00e9j\u00e0 dit. R\u00e9sum\u00e9 Rowena et Topaz sont deux femmes incroyablement brillantes, et incroyablement s\u00e9duisantes. Rowena, issue de l&#8217;\u00e9lite \u00e9cossaise, a de longs cheveux blonds, des yeux bleus, un corps fin, respire la classe, et adore le rock. Topaz, moiti\u00e9 am\u00e9ricaine, moiti\u00e9 italienne, a de longs cheveux roux boucl\u00e9s, un corps d&#8217;enfer tout en courbes, et est passionn\u00e9e par le journalisme. Les deux femmes se rencontrent \u00e0 l&#8217;universit\u00e9 d&#8217;Oxford, o\u00f9 elles se reconnaissent dans leur beaut\u00e9 et leur talent, et deviennent ins\u00e9parables. Jusqu&#8217;\u00e0 ce que Rowena trahisse son amie en couchant avec son chum. Leur amiti\u00e9 se change alors en haine f\u00e9roce et vorace. Elles s&#8217;\u00e9l\u00e8veront au sommet de leur industrie respective et, du haut de leur gloire et de leur richesse vertigineuses, feront tout pour d\u00e9truire l&#8217;autre. Impressions Ce livre n&#8217;est pas parfait. Il y a plusieurs aspects tr\u00e8s discutables : le f\u00e9minisme, notamment, est tr\u00e8s douteux. Les filles, certes puissantes, utilisent leur corps pour avancer dans leur carri\u00e8re et sont, pas seulement mais de fa\u00e7on tr\u00e8s importante, des objets de d\u00e9sir. Elles couchent tout le temps avec des hommes plus vieux, en position d&#8217;autorit\u00e9, et parfois mari\u00e9s. Les sc\u00e8nes de sexe (tr\u00e8s nombreuses) sont souvent tr\u00e8s peu r\u00e9alistes et moyennement saines. Leur richesse est un peu \u00e9coeurante. Et j&#8217;en passe. Il y a beaucoup de gens qui vont d\u00e9tester ce livre pour cette raison, et je comprends tr\u00e8s bien. Mais quelle lecture! D&#8217;abord, avouez que l&#8217;histoire est b\u00e9ton. C&#8217;est rare qu&#8217;un r\u00e9sum\u00e9 d&#8217;un livre m&#8217;accroche, mais celui-ci a r\u00e9ussi \u00e0 m&#8217;exciter. Et c&#8217;est bien \u00e9crit : les chapitres s&#8217;encha\u00eenent fr\u00e9n\u00e9tiquement, et on pourrait tr\u00e8s bien passer au travers du livre en une seule journ\u00e9e (ce serait une journ\u00e9e longue, mais tr\u00e8s satisfaisante). C&#8217;est jouissif de voir \u00e0 quel point les femmes sont des b\u00eates dans leur travail. Elles ont d&#8217;excellentes id\u00e9es, elles sont ambitieuses et talentueuses, et d\u00e9truisent tous les pauvres ploucs sur leur passage. Leur environnement de travail est tr\u00e8s bien d\u00e9crit et semble assez r\u00e9aliste. Assister \u00e0 leur succ\u00e8s est en soi un bonheur. Et puis, il y a le glam. Topaz et Rowena ne s&#8217;en tiraient d\u00e9j\u00e0 pas trop mal, mais elles deviennent incroyablement riches. Elles baignent dans le luxe, et ce luxe est d\u00e9crit dans tous ses d\u00e9tails. Les v\u00eatements, notamment, sont toujours d\u00e9crits avec minutie. Jamais on ne verra un simple &#8220;elle portait une belle robe bleue qui relevait la couleur de ses yeux&#8221;, non : on aura non seulement la coupe pr\u00e9cise de la robe, mais sa marque (toujours des vraies marques, j&#8217;ai d&#8217;ailleurs eu pas mal de plaisir \u00e0 aller voir \u00e0 quoi elles ressemblaient), la teinte exacte de bleu, la longueur de la robe, quelles parties du corps elle met en avantage, les bijoux, les souliers, le maquillage, alouette. On peut se foutre de ces d\u00e9tails-l\u00e0, mais moi j&#8217;ai beaucoup aim\u00e9. La sexualit\u00e9 est un aspect tr\u00e8s important du livre, il faut le dire. Tous les personnages principaux sont d&#8217;une beaut\u00e9 exceptionnelle, mais surtout Topaz et Rowena. Elles exultent de sex-appeal comme vous n&#8217;avez m\u00eame pas id\u00e9e. Leurs courbes d\u00e9bordent toujours de leurs v\u00eatements, leurs cheveux sont toujours flamboyants, et elles sont toujours \u00e0 deux minutes d&#8217;un orgasme, c&#8217;est fascinant. Il y a au moins une sc\u00e8ne de sexe par chapitre, toujours tr\u00e8s graphique et tr\u00e8s pornographique. On n&#8217;est pas dans le r\u00e9alisme, et je ne les ai pas trouv\u00e9es particuli\u00e8rement excitantes, mais elles frappent l&#8217;imaginaire, c&#8217;est certain. L&#8217;animatrice de Sentimental Garbage a dit que Career Girls \u00e9tait un des livres les plus captivants qu&#8217;elle ait jamais lu, et je suis d&#8217;accord avec elle. Il est assez irr\u00e9sistible. Il est excitant et nous sort vraiment de notre quotidien. Je me suis forc\u00e9e \u00e0 le lire lentement pour ne pas \u00e9puiser mon plaisir trop vite. Si vous \u00eates capables de passer outre ses d\u00e9fauts \u00e9vidents, je crois que vous allez passer un tr\u00e8s bon moment.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/en\/career-girls\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-16T19:04:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-16T19:04:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220116_111555_HDR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Career Girls\",\"datePublished\":\"2022-01-16T19:04:13+00:00\",\"dateModified\":\"2022-01-16T19:04:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/\"},\"wordCount\":849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Se distraire\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/\",\"name\":\"Career Girls - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2022-01-16T19:04:13+00:00\",\"dateModified\":\"2022-01-16T19:04:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/career-girls\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Career Girls\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/en\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Career Girls - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/en\/career-girls\/","og_locale":"en_US","og_type":"article","og_title":"Career Girls - Prochaine lecture","og_description":"Wow, ce livre. Je l&#8217;ai fini il y a quelques semaines d\u00e9j\u00e0, et j&#8217;y pense encore tous les jours. Encore une fois, j&#8217;ai pris la suggestion du podcast Sentimental Garbage. \u00c0 tous les amoureux de lecture de ce monde, je vous conseille tr\u00e8s vivement ce podcast. C&#8217;est du bonbon. L&#8217;animatrice est brillante, dr\u00f4le et tr\u00e8s passionn\u00e9e, et ses invit\u00e9es le sont tout autant. Je suis d&#8217;accord avec \u00e0 peu pr\u00e8s tout ce qu&#8217;elles disent, y compris leurs propos sur Career Girls. Tellement que je ne sais pas si je vais pouvoir ajouter grand-chose \u00e0 ce qu&#8217;elles en ont d\u00e9j\u00e0 dit. R\u00e9sum\u00e9 Rowena et Topaz sont deux femmes incroyablement brillantes, et incroyablement s\u00e9duisantes. Rowena, issue de l&#8217;\u00e9lite \u00e9cossaise, a de longs cheveux blonds, des yeux bleus, un corps fin, respire la classe, et adore le rock. Topaz, moiti\u00e9 am\u00e9ricaine, moiti\u00e9 italienne, a de longs cheveux roux boucl\u00e9s, un corps d&#8217;enfer tout en courbes, et est passionn\u00e9e par le journalisme. Les deux femmes se rencontrent \u00e0 l&#8217;universit\u00e9 d&#8217;Oxford, o\u00f9 elles se reconnaissent dans leur beaut\u00e9 et leur talent, et deviennent ins\u00e9parables. Jusqu&#8217;\u00e0 ce que Rowena trahisse son amie en couchant avec son chum. Leur amiti\u00e9 se change alors en haine f\u00e9roce et vorace. Elles s&#8217;\u00e9l\u00e8veront au sommet de leur industrie respective et, du haut de leur gloire et de leur richesse vertigineuses, feront tout pour d\u00e9truire l&#8217;autre. Impressions Ce livre n&#8217;est pas parfait. Il y a plusieurs aspects tr\u00e8s discutables : le f\u00e9minisme, notamment, est tr\u00e8s douteux. Les filles, certes puissantes, utilisent leur corps pour avancer dans leur carri\u00e8re et sont, pas seulement mais de fa\u00e7on tr\u00e8s importante, des objets de d\u00e9sir. Elles couchent tout le temps avec des hommes plus vieux, en position d&#8217;autorit\u00e9, et parfois mari\u00e9s. Les sc\u00e8nes de sexe (tr\u00e8s nombreuses) sont souvent tr\u00e8s peu r\u00e9alistes et moyennement saines. Leur richesse est un peu \u00e9coeurante. Et j&#8217;en passe. Il y a beaucoup de gens qui vont d\u00e9tester ce livre pour cette raison, et je comprends tr\u00e8s bien. Mais quelle lecture! D&#8217;abord, avouez que l&#8217;histoire est b\u00e9ton. C&#8217;est rare qu&#8217;un r\u00e9sum\u00e9 d&#8217;un livre m&#8217;accroche, mais celui-ci a r\u00e9ussi \u00e0 m&#8217;exciter. Et c&#8217;est bien \u00e9crit : les chapitres s&#8217;encha\u00eenent fr\u00e9n\u00e9tiquement, et on pourrait tr\u00e8s bien passer au travers du livre en une seule journ\u00e9e (ce serait une journ\u00e9e longue, mais tr\u00e8s satisfaisante). C&#8217;est jouissif de voir \u00e0 quel point les femmes sont des b\u00eates dans leur travail. Elles ont d&#8217;excellentes id\u00e9es, elles sont ambitieuses et talentueuses, et d\u00e9truisent tous les pauvres ploucs sur leur passage. Leur environnement de travail est tr\u00e8s bien d\u00e9crit et semble assez r\u00e9aliste. Assister \u00e0 leur succ\u00e8s est en soi un bonheur. Et puis, il y a le glam. Topaz et Rowena ne s&#8217;en tiraient d\u00e9j\u00e0 pas trop mal, mais elles deviennent incroyablement riches. Elles baignent dans le luxe, et ce luxe est d\u00e9crit dans tous ses d\u00e9tails. Les v\u00eatements, notamment, sont toujours d\u00e9crits avec minutie. Jamais on ne verra un simple &#8220;elle portait une belle robe bleue qui relevait la couleur de ses yeux&#8221;, non : on aura non seulement la coupe pr\u00e9cise de la robe, mais sa marque (toujours des vraies marques, j&#8217;ai d&#8217;ailleurs eu pas mal de plaisir \u00e0 aller voir \u00e0 quoi elles ressemblaient), la teinte exacte de bleu, la longueur de la robe, quelles parties du corps elle met en avantage, les bijoux, les souliers, le maquillage, alouette. On peut se foutre de ces d\u00e9tails-l\u00e0, mais moi j&#8217;ai beaucoup aim\u00e9. La sexualit\u00e9 est un aspect tr\u00e8s important du livre, il faut le dire. Tous les personnages principaux sont d&#8217;une beaut\u00e9 exceptionnelle, mais surtout Topaz et Rowena. Elles exultent de sex-appeal comme vous n&#8217;avez m\u00eame pas id\u00e9e. Leurs courbes d\u00e9bordent toujours de leurs v\u00eatements, leurs cheveux sont toujours flamboyants, et elles sont toujours \u00e0 deux minutes d&#8217;un orgasme, c&#8217;est fascinant. Il y a au moins une sc\u00e8ne de sexe par chapitre, toujours tr\u00e8s graphique et tr\u00e8s pornographique. On n&#8217;est pas dans le r\u00e9alisme, et je ne les ai pas trouv\u00e9es particuli\u00e8rement excitantes, mais elles frappent l&#8217;imaginaire, c&#8217;est certain. L&#8217;animatrice de Sentimental Garbage a dit que Career Girls \u00e9tait un des livres les plus captivants qu&#8217;elle ait jamais lu, et je suis d&#8217;accord avec elle. Il est assez irr\u00e9sistible. Il est excitant et nous sort vraiment de notre quotidien. Je me suis forc\u00e9e \u00e0 le lire lentement pour ne pas \u00e9puiser mon plaisir trop vite. Si vous \u00eates capables de passer outre ses d\u00e9fauts \u00e9vidents, je crois que vous allez passer un tr\u00e8s bon moment.","og_url":"https:\/\/prochainelecture.com\/en\/career-girls\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2022-01-16T19:04:13+00:00","article_modified_time":"2022-01-16T19:04:17+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220116_111555_HDR.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"Written by":"Na\u00efma Hassert","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/career-girls\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/career-girls\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Career Girls","datePublished":"2022-01-16T19:04:13+00:00","dateModified":"2022-01-16T19:04:17+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/career-girls\/"},"wordCount":849,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/career-girls\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1","articleSection":["Se distraire"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/career-girls\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/career-girls\/","url":"https:\/\/prochainelecture.com\/career-girls\/","name":"Career Girls - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/career-girls\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/career-girls\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1","datePublished":"2022-01-16T19:04:13+00:00","dateModified":"2022-01-16T19:04:17+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/career-girls\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/career-girls\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/career-girls\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/career-girls\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Career Girls"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Next Read","description":"My readings, to inspire you","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Next Read","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/en\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2022\/01\/20220116_111555_HDR.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-173","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/comments?post=4281"}],"version-history":[{"count":2,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4281\/revisions"}],"predecessor-version":[{"id":4283,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/4281\/revisions\/4283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media\/4284"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media?parent=4281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/categories?post=4281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/tags?post=4281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}