{"id":3912,"date":"2020-12-19T11:36:59","date_gmt":"2020-12-19T15:36:59","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=3912"},"modified":"2020-12-19T11:37:03","modified_gmt":"2020-12-19T15:37:03","slug":"la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/en\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/","title":{"rendered":"La retraite \u00e0 40 ans (\"Retirement at 40\")"},"content":{"rendered":"<p>You have to admit that it sounds like a dream. At 40, our professional life is over. We have every day off and we're still in great shape. You may have children, and you can watch them grow up as much as you want. In fact, you can literally do whatever you want for the rest of your life.<\/p>\n\n\n\n<p>This book promises to teach us how to make this dream more attainable than it seems. Because you don't have to earn a huge salary or stumble upon a gold mine to achieve financial freedom faster than anyone else.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">The game plan<\/h2>\n\n\n\n<p>In fact, it couldn't be easier. First of all, you have to set a goal <em>based on our expenses <\/em>and not on our income. The best thing is to make a modest budget, so that financial freedom will be easier to reach. Then, we do a simple multiplication: if we look at the historical average, we can reasonably expect to get a 4% return on our investments. So, the amount necessary for our financial independence is equivalent to our annual expenses multiplied by 25. If we live on $25,000 a year, we will be free when we have raised $625,000. If we make $50,000 a year and save the rest of our income, we are potentially 16.6 years away from retirement.<\/p>\n\n\n\n<p>That's it. Simple as that. <\/p>\n\n\n\n<p>To reach this amount, we must become a pro at frugality and invest all our savings in the stock market or in real estate. The book explains how to do all this. The more the amount invested increases, the more profitable it is, and it creates a snowball effect. This is what allowed the author, who originally planned to retire at 45, to finally retire 6 years earlier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>This reading made me dream. I never thought it was that simple, and I saw my horizons open. Also, I like the idea of under-consuming and making the capitalist system work for me and not the other way around.<\/p>\n\n\n\n<p>So I seriously asked myself: is this the path I want to take? I am 25 years old, I am not ready to finish my studies, and I am excited about my future career. I don't feel like in 10 or 15 years I'll have done it all (or saved enough). So do I want to put a lot of my energy into finding <em>deals<\/em> and avoid anything that is not essential? I think not.<\/p>\n\n\n\n<p>But I can still do some pretty basic things, like educate myself a bit, rethink my priorities, budget my money, put my savings in, live simply. It would certainly allow me to stop working sooner if I wanted to. And most importantly, it would allow me to feel free.<\/p>\n\n\n\n<p>I highly recommend this book, even if, like me, retiring early is not your biggest dream. The sense of freedom it gives us is worth it. It reminds us that we are in control of our future and encourages us to think outside the box. Working is optional, and everyone deserves to know that.<\/p>","protected":false},"excerpt":{"rendered":"<p>Avouez que \u00e7a fait r\u00eaver. \u00c0 40 ans, notre vie professionnelle est termin\u00e9e. On a cong\u00e9 tous les jours et on est encore en pleine forme. On a peut-\u00eatre des enfants, et on peut les voir grandir autant qu&#8217;on veut. En fait, on peut faire litt\u00e9ralement ce qu&#8217;on veut pour le restant de nos jours. Ce livre nous promet de nous apprendre comment r\u00e9aliser ce r\u00eave plus atteignable qu&#8217;il n&#8217;y para\u00eet. Car on n&#8217;a pas besoin de gagner un salaire faramineux ni de tomber sur une mine d&#8217;or pour atteindre la libert\u00e9 financi\u00e8re plus vite que tout le monde. Le plan de match En fait, c&#8217;est difficile de faire plus simple. Tout d&#8217;abord, il faut se fixer un objectif bas\u00e9 sur nos d\u00e9penses et pas sur nos revenus. Le mieux est de se faire un budget modeste, comme \u00e7a la libert\u00e9 financi\u00e8re sera plus facile d&#8217;acc\u00e8s. Apr\u00e8s, on fait une simple multiplication : si on regarde la moyenne historique, on peut esp\u00e9rer raisonnablement obtenir un rendement de 4 % sur nos investissements. Alors, le montant n\u00e9cessaire \u00e0 notre ind\u00e9pendance financi\u00e8re \u00e9quivaut \u00e0 nos d\u00e9penses annuelles multipli\u00e9 par 25. Si on vit avec 25 000 $ par ann\u00e9e, on sera libre quand on aura amass\u00e9 625 000 $. Si on fait 50 000$ par ann\u00e9e et qu&#8217;on \u00e9pargne le reste de nos revenus, on est potentiellement \u00e0 16,6 ann\u00e9es de la retraite. Voil\u00e0. Simple de m\u00eame. Pour atteindre ce montant, il faut devenir un pro de la frugalit\u00e9 et investir toutes nos \u00e9conomies en bourse ou dans l&#8217;immobilier. Le livre nous explique comment faire tout \u00e7a. Plus le montant investi augmente, plus il est rentable, et \u00e7a cr\u00e9e un effet boule de neige. C&#8217;est ce qui a permis \u00e0 l&#8217;auteur, qui pr\u00e9voyait au d\u00e9part prendre sa retraite \u00e0 45 ans, de finalement la prendre 6 ans plus t\u00f4t. Impressions Cette lecture m&#8217;a fait r\u00eaver. Je n&#8217;aurais jamais cru que c&#8217;\u00e9tait aussi simple, et j&#8217;ai vu mes horizons s&#8217;ouvrir. Et puis, j&#8217;aime l&#8217;id\u00e9e de sous-consommer et de faire le syst\u00e8me capitaliste travailler pour moi et pas l&#8217;inverse. Je me suis donc s\u00e9rieusement pos\u00e9 la question : est-ce que c&#8217;est la voie que j&#8217;ai envie d&#8217;adopter? J&#8217;ai 25 ans, je ne suis pas pr\u00eate de terminer mes \u00e9tudes, et ma future carri\u00e8re m&#8217;enthousiasme. Je n&#8217;ai pas l&#8217;impression qu&#8217;en 10 ou 15 ans, j&#8217;aurai fait le tour (ni que j&#8217;aurai pu \u00e9conomiser suffisamment). Alors est-ce que j&#8217;ai envie de mettre une grande partie de mon \u00e9nergie \u00e0 trouver des deals et \u00e0 \u00e9viter tout ce qui n&#8217;est pas essentiel? Je crois que non. Mais je peux tout de m\u00eame faire des choses assez de base, comme m&#8217;\u00e9duquer un minimum, repenser mes priorit\u00e9s, me faire un budget, placer mes \u00e9conomies, vivre simplement. \u00c7a pourrait certainement me permettre d&#8217;arr\u00eater de travailler plus t\u00f4t si j&#8217;en envie. Et surtout, \u00e7a me permettrait de me sentir libre. Je vous conseille fortement ce livre, m\u00eame si, comme moi, prendre votre retraite tr\u00e8s t\u00f4t n&#8217;est pas votre plus grand r\u00eave. Le sentiment de libert\u00e9 qu&#8217;il nous procure vaut cher. Il nous rappelle qu&#8217;on est ma\u00eetre de notre avenir et nous encourage \u00e0 sortir des sentiers battus. Travailler est optionnel, et tout le monde m\u00e9rite de le savoir.<\/p>","protected":false},"author":1,"featured_media":3915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[254,249],"tags":[],"class_list":["post-3912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-developpement-personnel","category-se-renseigner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/en\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Avouez que \u00e7a fait r\u00eaver. \u00c0 40 ans, notre vie professionnelle est termin\u00e9e. On a cong\u00e9 tous les jours et on est encore en pleine forme. On a peut-\u00eatre des enfants, et on peut les voir grandir autant qu&#8217;on veut. En fait, on peut faire litt\u00e9ralement ce qu&#8217;on veut pour le restant de nos jours. Ce livre nous promet de nous apprendre comment r\u00e9aliser ce r\u00eave plus atteignable qu&#8217;il n&#8217;y para\u00eet. Car on n&#8217;a pas besoin de gagner un salaire faramineux ni de tomber sur une mine d&#8217;or pour atteindre la libert\u00e9 financi\u00e8re plus vite que tout le monde. Le plan de match En fait, c&#8217;est difficile de faire plus simple. Tout d&#8217;abord, il faut se fixer un objectif bas\u00e9 sur nos d\u00e9penses et pas sur nos revenus. Le mieux est de se faire un budget modeste, comme \u00e7a la libert\u00e9 financi\u00e8re sera plus facile d&#8217;acc\u00e8s. Apr\u00e8s, on fait une simple multiplication : si on regarde la moyenne historique, on peut esp\u00e9rer raisonnablement obtenir un rendement de 4 % sur nos investissements. Alors, le montant n\u00e9cessaire \u00e0 notre ind\u00e9pendance financi\u00e8re \u00e9quivaut \u00e0 nos d\u00e9penses annuelles multipli\u00e9 par 25. Si on vit avec 25 000 $ par ann\u00e9e, on sera libre quand on aura amass\u00e9 625 000 $. Si on fait 50 000$ par ann\u00e9e et qu&#8217;on \u00e9pargne le reste de nos revenus, on est potentiellement \u00e0 16,6 ann\u00e9es de la retraite. Voil\u00e0. Simple de m\u00eame. Pour atteindre ce montant, il faut devenir un pro de la frugalit\u00e9 et investir toutes nos \u00e9conomies en bourse ou dans l&#8217;immobilier. Le livre nous explique comment faire tout \u00e7a. Plus le montant investi augmente, plus il est rentable, et \u00e7a cr\u00e9e un effet boule de neige. C&#8217;est ce qui a permis \u00e0 l&#8217;auteur, qui pr\u00e9voyait au d\u00e9part prendre sa retraite \u00e0 45 ans, de finalement la prendre 6 ans plus t\u00f4t. Impressions Cette lecture m&#8217;a fait r\u00eaver. Je n&#8217;aurais jamais cru que c&#8217;\u00e9tait aussi simple, et j&#8217;ai vu mes horizons s&#8217;ouvrir. Et puis, j&#8217;aime l&#8217;id\u00e9e de sous-consommer et de faire le syst\u00e8me capitaliste travailler pour moi et pas l&#8217;inverse. Je me suis donc s\u00e9rieusement pos\u00e9 la question : est-ce que c&#8217;est la voie que j&#8217;ai envie d&#8217;adopter? J&#8217;ai 25 ans, je ne suis pas pr\u00eate de terminer mes \u00e9tudes, et ma future carri\u00e8re m&#8217;enthousiasme. Je n&#8217;ai pas l&#8217;impression qu&#8217;en 10 ou 15 ans, j&#8217;aurai fait le tour (ni que j&#8217;aurai pu \u00e9conomiser suffisamment). Alors est-ce que j&#8217;ai envie de mettre une grande partie de mon \u00e9nergie \u00e0 trouver des deals et \u00e0 \u00e9viter tout ce qui n&#8217;est pas essentiel? Je crois que non. Mais je peux tout de m\u00eame faire des choses assez de base, comme m&#8217;\u00e9duquer un minimum, repenser mes priorit\u00e9s, me faire un budget, placer mes \u00e9conomies, vivre simplement. \u00c7a pourrait certainement me permettre d&#8217;arr\u00eater de travailler plus t\u00f4t si j&#8217;en envie. Et surtout, \u00e7a me permettrait de me sentir libre. Je vous conseille fortement ce livre, m\u00eame si, comme moi, prendre votre retraite tr\u00e8s t\u00f4t n&#8217;est pas votre plus grand r\u00eave. Le sentiment de libert\u00e9 qu&#8217;il nous procure vaut cher. Il nous rappelle qu&#8217;on est ma\u00eetre de notre avenir et nous encourage \u00e0 sortir des sentiers battus. Travailler est optionnel, et tout le monde m\u00e9rite de le savoir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/en\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-19T15:36:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-19T15:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re\",\"datePublished\":\"2020-12-19T15:36:59+00:00\",\"dateModified\":\"2020-12-19T15:37:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/\"},\"wordCount\":603,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"D\u00e9veloppement personnel\",\"Se renseigner\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/\",\"name\":\"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2020-12-19T15:36:59+00:00\",\"dateModified\":\"2020-12-19T15:37:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/en\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/en\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/","og_locale":"en_US","og_type":"article","og_title":"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re - Prochaine lecture","og_description":"Avouez que \u00e7a fait r\u00eaver. \u00c0 40 ans, notre vie professionnelle est termin\u00e9e. On a cong\u00e9 tous les jours et on est encore en pleine forme. On a peut-\u00eatre des enfants, et on peut les voir grandir autant qu&#8217;on veut. En fait, on peut faire litt\u00e9ralement ce qu&#8217;on veut pour le restant de nos jours. Ce livre nous promet de nous apprendre comment r\u00e9aliser ce r\u00eave plus atteignable qu&#8217;il n&#8217;y para\u00eet. Car on n&#8217;a pas besoin de gagner un salaire faramineux ni de tomber sur une mine d&#8217;or pour atteindre la libert\u00e9 financi\u00e8re plus vite que tout le monde. Le plan de match En fait, c&#8217;est difficile de faire plus simple. Tout d&#8217;abord, il faut se fixer un objectif bas\u00e9 sur nos d\u00e9penses et pas sur nos revenus. Le mieux est de se faire un budget modeste, comme \u00e7a la libert\u00e9 financi\u00e8re sera plus facile d&#8217;acc\u00e8s. Apr\u00e8s, on fait une simple multiplication : si on regarde la moyenne historique, on peut esp\u00e9rer raisonnablement obtenir un rendement de 4 % sur nos investissements. Alors, le montant n\u00e9cessaire \u00e0 notre ind\u00e9pendance financi\u00e8re \u00e9quivaut \u00e0 nos d\u00e9penses annuelles multipli\u00e9 par 25. Si on vit avec 25 000 $ par ann\u00e9e, on sera libre quand on aura amass\u00e9 625 000 $. Si on fait 50 000$ par ann\u00e9e et qu&#8217;on \u00e9pargne le reste de nos revenus, on est potentiellement \u00e0 16,6 ann\u00e9es de la retraite. Voil\u00e0. Simple de m\u00eame. Pour atteindre ce montant, il faut devenir un pro de la frugalit\u00e9 et investir toutes nos \u00e9conomies en bourse ou dans l&#8217;immobilier. Le livre nous explique comment faire tout \u00e7a. Plus le montant investi augmente, plus il est rentable, et \u00e7a cr\u00e9e un effet boule de neige. C&#8217;est ce qui a permis \u00e0 l&#8217;auteur, qui pr\u00e9voyait au d\u00e9part prendre sa retraite \u00e0 45 ans, de finalement la prendre 6 ans plus t\u00f4t. Impressions Cette lecture m&#8217;a fait r\u00eaver. Je n&#8217;aurais jamais cru que c&#8217;\u00e9tait aussi simple, et j&#8217;ai vu mes horizons s&#8217;ouvrir. Et puis, j&#8217;aime l&#8217;id\u00e9e de sous-consommer et de faire le syst\u00e8me capitaliste travailler pour moi et pas l&#8217;inverse. Je me suis donc s\u00e9rieusement pos\u00e9 la question : est-ce que c&#8217;est la voie que j&#8217;ai envie d&#8217;adopter? J&#8217;ai 25 ans, je ne suis pas pr\u00eate de terminer mes \u00e9tudes, et ma future carri\u00e8re m&#8217;enthousiasme. Je n&#8217;ai pas l&#8217;impression qu&#8217;en 10 ou 15 ans, j&#8217;aurai fait le tour (ni que j&#8217;aurai pu \u00e9conomiser suffisamment). Alors est-ce que j&#8217;ai envie de mettre une grande partie de mon \u00e9nergie \u00e0 trouver des deals et \u00e0 \u00e9viter tout ce qui n&#8217;est pas essentiel? Je crois que non. Mais je peux tout de m\u00eame faire des choses assez de base, comme m&#8217;\u00e9duquer un minimum, repenser mes priorit\u00e9s, me faire un budget, placer mes \u00e9conomies, vivre simplement. \u00c7a pourrait certainement me permettre d&#8217;arr\u00eater de travailler plus t\u00f4t si j&#8217;en envie. Et surtout, \u00e7a me permettrait de me sentir libre. Je vous conseille fortement ce livre, m\u00eame si, comme moi, prendre votre retraite tr\u00e8s t\u00f4t n&#8217;est pas votre plus grand r\u00eave. Le sentiment de libert\u00e9 qu&#8217;il nous procure vaut cher. Il nous rappelle qu&#8217;on est ma\u00eetre de notre avenir et nous encourage \u00e0 sortir des sentiers battus. Travailler est optionnel, et tout le monde m\u00e9rite de le savoir.","og_url":"https:\/\/prochainelecture.com\/en\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2020-12-19T15:36:59+00:00","article_modified_time":"2020-12-19T15:37:03+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"Written by":"Na\u00efma Hassert","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re","datePublished":"2020-12-19T15:36:59+00:00","dateModified":"2020-12-19T15:37:03+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/"},"wordCount":603,"commentCount":2,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1","articleSection":["D\u00e9veloppement personnel","Se renseigner"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/","url":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/","name":"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1","datePublished":"2020-12-19T15:36:59+00:00","dateModified":"2020-12-19T15:37:03+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/la-retraite-a-40-ans-comment-dejouer-le-systeme-pour-atteindre-la-liberte-financiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"La retraite \u00e0 40 ans : comment d\u00e9jouer le syst\u00e8me pour atteindre la libert\u00e9 financi\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Next Read","description":"My readings, to inspire you","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Next Read","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/en\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201219_100019-1.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-116","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/3912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/comments?post=3912"}],"version-history":[{"count":3,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/3912\/revisions"}],"predecessor-version":[{"id":3916,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/3912\/revisions\/3916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media\/3915"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media?parent=3912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/categories?post=3912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/tags?post=3912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}