{"id":3881,"date":"2020-12-03T12:22:00","date_gmt":"2020-12-03T16:22:00","guid":{"rendered":"https:\/\/prochainelecture.com\/?p=3881"},"modified":"2020-12-03T12:45:53","modified_gmt":"2020-12-03T16:45:53","slug":"metamorphoses","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/en\/metamorphoses\/","title":{"rendered":"M\u00e9tamorphoses"},"content":{"rendered":"<p>Cet \u00e9t\u00e9, l&#8217;automne m&#8217;est tomb\u00e9 dessus. Je suis imm\u00e9diatement entr\u00e9e en mode cocooning : amenez-moi les gros bas, les couvertes douces et les boissons chaudes! Dans ce temps-l\u00e0, toute lecture est agr\u00e9able, mais un petit livre d&#8217;aventure angoissant, \u00e7a passe particuli\u00e8rement bien. D&#8217;o\u00f9 ce deuxi\u00e8me opus de Charles-\u00c9tienne Ferland. Il est paru deux ans apr\u00e8s <em>D\u00e9vor\u00e9s<\/em>, que je n&#8217;ai pas lu, mais je confirme qu&#8217;il peut tr\u00e8s bien \u00eatre lu individuellement.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Summary<\/h2>\n\n\n\n<p>\u00c7a fait un an que la nouvelle esp\u00e8ce de gu\u00eapes a envahi le monde. Les m\u00e2les, d&#8217;une dizaine de centim\u00e8tres de longueur, et les femelles, entre 60 et 90 centim\u00e8tres, sont munis d&#8217;\u00e9normes dards venimeux qui peuvent faire \u00e9clater le verre et empaler les humains. Ce qu&#8217;elles ont fait, apr\u00e8s avoir ravag\u00e9 la v\u00e9g\u00e9tation.<\/p>\n\n\n\n<p>Mais les gu\u00eapes ne sont pas le seul danger dans ce monde apocalyptique. Des rumeurs circulent comme quoi des b\u00eates humaines assoiff\u00e9es de sang et dot\u00e9es d&#8217;une force redoutable assassinent tous ceux qui se trouvent sur leur passage. Certains groupes de survivants se sont form\u00e9s pour essayer de r\u00e9sister \u00e0 cette effroyable adversit\u00e9. Et de comprendre d&#8217;o\u00f9 viennent ces b\u00eates humaines.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impressions<\/h2>\n\n\n\n<p>La pr\u00e9misse m&#8217;a beaucoup plu. Imaginer ma ville envahie d&#8217;insectes tueurs g\u00e9ants est \u00e0 la fois cocasse et vraiment effrayant. J&#8217;h\u00e9sitais entre le rire et le frisson. De plus, tous les chapitres commencent par des citations, souvent de (bonnes) chansons. \u00c7a m&#8217;a donn\u00e9 de les faire jouer pendant ma lecture, ce qui a encore am\u00e9lior\u00e9 mon exp\u00e9rience de cocooning. <\/p>\n\n\n\n<p>Le style est simple et le rythme, rapide. Parfois, trop. On a envie de lire vite parce que c&#8217;est prenant, mais si on ne porte pas suffisamment d&#8217;attention, on perd le fil. Attends, qui parle en ce moment? J&#8217;aurais aussi appr\u00e9ci\u00e9 en apprendre plus sur le monde, voir plus de paysages, avoir plus de d\u00e9tails, mais il n&#8217;y avait pas le temps pour \u00e7a. C&#8217;\u00e9tait parfois un peu frustrant.<\/p>\n\n\n\n<p>Mais sinon, j&#8217;ai appr\u00e9ci\u00e9 ma lecture. Le monde est vivant, et j&#8217;ai envie d&#8217;en savoir plus. Je le recommande particuli\u00e8rement aux adolescents.<\/p>\n\n\n\n<p>Le premier tome, <em>D\u00e9vor\u00e9s<\/em>, sera adapt\u00e9 en bande dessin\u00e9e, et je trouve que c&#8217;est une merveilleuse id\u00e9e. <a href=\"https:\/\/www.ledroit.com\/arts\/arts\/charles-etienne-ferland-vampire-guepes-et-fin-du-monde-318b2b96b82ecca290814cd9c1542dff\">Vous pouvez en voir une planche ici<\/a>.<\/p>\n\n\n\n<p>Merci aux <a href=\"https:\/\/interligne.ca\/\">\u00c9ditions l&#8217;Interligne<\/a> pour le service de presse!<\/p>\n\n\n\n<iframe src=\"https:\/\/www.leslibraires.ca\/livre-affiliation\/metamorphoses-charles-etienne-ferland-9782896997145.html\/?type=livre&amp;configuration=126&amp;u=174197\" width=\"180\" height=\"405\" frameborder=\"0\" scrolling=\"no\" style=\"overflow:hidden;\"><\/iframe>","protected":false},"excerpt":{"rendered":"<p>Cet \u00e9t\u00e9, l&#8217;automne m&#8217;est tomb\u00e9 dessus. Je suis imm\u00e9diatement entr\u00e9e en mode cocooning : amenez-moi les gros bas, les couvertes douces et les boissons chaudes! Dans ce temps-l\u00e0, toute lecture est agr\u00e9able, mais un petit livre d&#8217;aventure angoissant, \u00e7a passe particuli\u00e8rement bien. D&#8217;o\u00f9 ce deuxi\u00e8me opus de Charles-\u00c9tienne Ferland. Il est paru deux ans apr\u00e8s D\u00e9vor\u00e9s, que je n&#8217;ai pas lu, mais je confirme qu&#8217;il peut tr\u00e8s bien \u00eatre lu individuellement. R\u00e9sum\u00e9 \u00c7a fait un an que la nouvelle esp\u00e8ce de gu\u00eapes a envahi le monde. Les m\u00e2les, d&#8217;une dizaine de centim\u00e8tres de longueur, et les femelles, entre 60 et 90 centim\u00e8tres, sont munis d&#8217;\u00e9normes dards venimeux qui peuvent faire \u00e9clater le verre et empaler les humains. Ce qu&#8217;elles ont fait, apr\u00e8s avoir ravag\u00e9 la v\u00e9g\u00e9tation. Mais les gu\u00eapes ne sont pas le seul danger dans ce monde apocalyptique. Des rumeurs circulent comme quoi des b\u00eates humaines assoiff\u00e9es de sang et dot\u00e9es d&#8217;une force redoutable assassinent tous ceux qui se trouvent sur leur passage. Certains groupes de survivants se sont form\u00e9s pour essayer de r\u00e9sister \u00e0 cette effroyable adversit\u00e9. Et de comprendre d&#8217;o\u00f9 viennent ces b\u00eates humaines. Impressions La pr\u00e9misse m&#8217;a beaucoup plu. Imaginer ma ville envahie d&#8217;insectes tueurs g\u00e9ants est \u00e0 la fois cocasse et vraiment effrayant. J&#8217;h\u00e9sitais entre le rire et le frisson. De plus, tous les chapitres commencent par des citations, souvent de (bonnes) chansons. \u00c7a m&#8217;a donn\u00e9 de les faire jouer pendant ma lecture, ce qui a encore am\u00e9lior\u00e9 mon exp\u00e9rience de cocooning. Le style est simple et le rythme, rapide. Parfois, trop. On a envie de lire vite parce que c&#8217;est prenant, mais si on ne porte pas suffisamment d&#8217;attention, on perd le fil. Attends, qui parle en ce moment? J&#8217;aurais aussi appr\u00e9ci\u00e9 en apprendre plus sur le monde, voir plus de paysages, avoir plus de d\u00e9tails, mais il n&#8217;y avait pas le temps pour \u00e7a. C&#8217;\u00e9tait parfois un peu frustrant. Mais sinon, j&#8217;ai appr\u00e9ci\u00e9 ma lecture. Le monde est vivant, et j&#8217;ai envie d&#8217;en savoir plus. Je le recommande particuli\u00e8rement aux adolescents. Le premier tome, D\u00e9vor\u00e9s, sera adapt\u00e9 en bande dessin\u00e9e, et je trouve que c&#8217;est une merveilleuse id\u00e9e. Vous pouvez en voir une planche ici. Merci aux \u00c9ditions l&#8217;Interligne pour le service de presse!<\/p>","protected":false},"author":1,"featured_media":3884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"La pr\u00e9misse m'a beaucoup plu. Imaginer ma ville envahie d'insectes tueurs g\u00e9ants est \u00e0 la fois incongru et vraiment effrayant. On h\u00e9site entre le rire et le frisson. Une lecture agr\u00e9able, \u00e0 lire id\u00e9alement bien au chaud sous les couvertures.","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[245,242,278],"tags":[],"class_list":["post-3881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litterature-quebecoise","category-se-distraire","category-suspense"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9tamorphoses - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/en\/metamorphoses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9tamorphoses - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Cet \u00e9t\u00e9, l&#8217;automne m&#8217;est tomb\u00e9 dessus. Je suis imm\u00e9diatement entr\u00e9e en mode cocooning : amenez-moi les gros bas, les couvertes douces et les boissons chaudes! Dans ce temps-l\u00e0, toute lecture est agr\u00e9able, mais un petit livre d&#8217;aventure angoissant, \u00e7a passe particuli\u00e8rement bien. D&#8217;o\u00f9 ce deuxi\u00e8me opus de Charles-\u00c9tienne Ferland. Il est paru deux ans apr\u00e8s D\u00e9vor\u00e9s, que je n&#8217;ai pas lu, mais je confirme qu&#8217;il peut tr\u00e8s bien \u00eatre lu individuellement. R\u00e9sum\u00e9 \u00c7a fait un an que la nouvelle esp\u00e8ce de gu\u00eapes a envahi le monde. Les m\u00e2les, d&#8217;une dizaine de centim\u00e8tres de longueur, et les femelles, entre 60 et 90 centim\u00e8tres, sont munis d&#8217;\u00e9normes dards venimeux qui peuvent faire \u00e9clater le verre et empaler les humains. Ce qu&#8217;elles ont fait, apr\u00e8s avoir ravag\u00e9 la v\u00e9g\u00e9tation. Mais les gu\u00eapes ne sont pas le seul danger dans ce monde apocalyptique. Des rumeurs circulent comme quoi des b\u00eates humaines assoiff\u00e9es de sang et dot\u00e9es d&#8217;une force redoutable assassinent tous ceux qui se trouvent sur leur passage. Certains groupes de survivants se sont form\u00e9s pour essayer de r\u00e9sister \u00e0 cette effroyable adversit\u00e9. Et de comprendre d&#8217;o\u00f9 viennent ces b\u00eates humaines. Impressions La pr\u00e9misse m&#8217;a beaucoup plu. Imaginer ma ville envahie d&#8217;insectes tueurs g\u00e9ants est \u00e0 la fois cocasse et vraiment effrayant. J&#8217;h\u00e9sitais entre le rire et le frisson. De plus, tous les chapitres commencent par des citations, souvent de (bonnes) chansons. \u00c7a m&#8217;a donn\u00e9 de les faire jouer pendant ma lecture, ce qui a encore am\u00e9lior\u00e9 mon exp\u00e9rience de cocooning. Le style est simple et le rythme, rapide. Parfois, trop. On a envie de lire vite parce que c&#8217;est prenant, mais si on ne porte pas suffisamment d&#8217;attention, on perd le fil. Attends, qui parle en ce moment? J&#8217;aurais aussi appr\u00e9ci\u00e9 en apprendre plus sur le monde, voir plus de paysages, avoir plus de d\u00e9tails, mais il n&#8217;y avait pas le temps pour \u00e7a. C&#8217;\u00e9tait parfois un peu frustrant. Mais sinon, j&#8217;ai appr\u00e9ci\u00e9 ma lecture. Le monde est vivant, et j&#8217;ai envie d&#8217;en savoir plus. Je le recommande particuli\u00e8rement aux adolescents. Le premier tome, D\u00e9vor\u00e9s, sera adapt\u00e9 en bande dessin\u00e9e, et je trouve que c&#8217;est une merveilleuse id\u00e9e. Vous pouvez en voir une planche ici. Merci aux \u00c9ditions l&#8217;Interligne pour le service de presse!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/en\/metamorphoses\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-03T16:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-03T16:45:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"M\u00e9tamorphoses\",\"datePublished\":\"2020-12-03T16:22:00+00:00\",\"dateModified\":\"2020-12-03T16:45:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Litt\u00e9rature qu\u00e9b\u00e9coise\",\"Se distraire\",\"Suspense\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/\",\"name\":\"M\u00e9tamorphoses - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1\",\"datePublished\":\"2020-12-03T16:22:00+00:00\",\"dateModified\":\"2020-12-03T16:45:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/metamorphoses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9tamorphoses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/en\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9tamorphoses - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/en\/metamorphoses\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e9tamorphoses - Prochaine lecture","og_description":"Cet \u00e9t\u00e9, l&#8217;automne m&#8217;est tomb\u00e9 dessus. Je suis imm\u00e9diatement entr\u00e9e en mode cocooning : amenez-moi les gros bas, les couvertes douces et les boissons chaudes! Dans ce temps-l\u00e0, toute lecture est agr\u00e9able, mais un petit livre d&#8217;aventure angoissant, \u00e7a passe particuli\u00e8rement bien. D&#8217;o\u00f9 ce deuxi\u00e8me opus de Charles-\u00c9tienne Ferland. Il est paru deux ans apr\u00e8s D\u00e9vor\u00e9s, que je n&#8217;ai pas lu, mais je confirme qu&#8217;il peut tr\u00e8s bien \u00eatre lu individuellement. R\u00e9sum\u00e9 \u00c7a fait un an que la nouvelle esp\u00e8ce de gu\u00eapes a envahi le monde. Les m\u00e2les, d&#8217;une dizaine de centim\u00e8tres de longueur, et les femelles, entre 60 et 90 centim\u00e8tres, sont munis d&#8217;\u00e9normes dards venimeux qui peuvent faire \u00e9clater le verre et empaler les humains. Ce qu&#8217;elles ont fait, apr\u00e8s avoir ravag\u00e9 la v\u00e9g\u00e9tation. Mais les gu\u00eapes ne sont pas le seul danger dans ce monde apocalyptique. Des rumeurs circulent comme quoi des b\u00eates humaines assoiff\u00e9es de sang et dot\u00e9es d&#8217;une force redoutable assassinent tous ceux qui se trouvent sur leur passage. Certains groupes de survivants se sont form\u00e9s pour essayer de r\u00e9sister \u00e0 cette effroyable adversit\u00e9. Et de comprendre d&#8217;o\u00f9 viennent ces b\u00eates humaines. Impressions La pr\u00e9misse m&#8217;a beaucoup plu. Imaginer ma ville envahie d&#8217;insectes tueurs g\u00e9ants est \u00e0 la fois cocasse et vraiment effrayant. J&#8217;h\u00e9sitais entre le rire et le frisson. De plus, tous les chapitres commencent par des citations, souvent de (bonnes) chansons. \u00c7a m&#8217;a donn\u00e9 de les faire jouer pendant ma lecture, ce qui a encore am\u00e9lior\u00e9 mon exp\u00e9rience de cocooning. Le style est simple et le rythme, rapide. Parfois, trop. On a envie de lire vite parce que c&#8217;est prenant, mais si on ne porte pas suffisamment d&#8217;attention, on perd le fil. Attends, qui parle en ce moment? J&#8217;aurais aussi appr\u00e9ci\u00e9 en apprendre plus sur le monde, voir plus de paysages, avoir plus de d\u00e9tails, mais il n&#8217;y avait pas le temps pour \u00e7a. C&#8217;\u00e9tait parfois un peu frustrant. Mais sinon, j&#8217;ai appr\u00e9ci\u00e9 ma lecture. Le monde est vivant, et j&#8217;ai envie d&#8217;en savoir plus. Je le recommande particuli\u00e8rement aux adolescents. Le premier tome, D\u00e9vor\u00e9s, sera adapt\u00e9 en bande dessin\u00e9e, et je trouve que c&#8217;est une merveilleuse id\u00e9e. Vous pouvez en voir une planche ici. Merci aux \u00c9ditions l&#8217;Interligne pour le service de presse!","og_url":"https:\/\/prochainelecture.com\/en\/metamorphoses\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2020-12-03T16:22:00+00:00","article_modified_time":"2020-12-03T16:45:53+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"Written by":"Na\u00efma Hassert","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/metamorphoses\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/metamorphoses\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"M\u00e9tamorphoses","datePublished":"2020-12-03T16:22:00+00:00","dateModified":"2020-12-03T16:45:53+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/metamorphoses\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/metamorphoses\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1","articleSection":["Litt\u00e9rature qu\u00e9b\u00e9coise","Se distraire","Suspense"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/metamorphoses\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/metamorphoses\/","url":"https:\/\/prochainelecture.com\/metamorphoses\/","name":"M\u00e9tamorphoses - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/metamorphoses\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/metamorphoses\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1","datePublished":"2020-12-03T16:22:00+00:00","dateModified":"2020-12-03T16:45:53+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/metamorphoses\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/metamorphoses\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/metamorphoses\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/metamorphoses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9tamorphoses"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Next Read","description":"My readings, to inspire you","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Next Read","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/en\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/12\/20201202_162313_1.jpg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-10B","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/3881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/comments?post=3881"}],"version-history":[{"count":5,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/3881\/revisions"}],"predecessor-version":[{"id":3890,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/3881\/revisions\/3890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media\/3884"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media?parent=3881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/categories?post=3881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/tags?post=3881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}