{"id":1703,"date":"2019-08-16T16:50:53","date_gmt":"2019-08-16T16:50:53","guid":{"rendered":"http:\/\/www.naimahassert.com\/?p=1703"},"modified":"2020-08-10T12:44:18","modified_gmt":"2020-08-10T12:44:18","slug":"putain","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/en\/putain\/","title":{"rendered":"Whore"},"content":{"rendered":"\n<p><strong>Je me suis dit pendant des ann\u00e9es que je devais lire Nelly Arcan, mais j&#8217;h\u00e9sitais. Je me suis dit que je n&#8217;aimais pas les longues phrases sans point, qui ressemblent \u00e0 un flot de pens\u00e9es, \u00e7a me prenait des \u00abvraies phrases\u00bb, des phrases \u00abrecherch\u00e9es.\u00bb Oh que je ne savais pas de quoi je parlais.<\/strong><\/p>\n\n\n\n<p>Mis \u00e7a simple, c&#8217;est l&#8217;histoire d&#8217;une prostitu\u00e9e qui parle de sa condition. Elle raconte pourquoi et comment elle a commenc\u00e9 \u00e0 20 ans, ce qu&#8217;elle sent quand elle attend ses clients dans sa chambre d&#8217;h\u00f4tel sans \u00e2me, son rapport aux femmes, ses rivales, et aux hommes, ces b\u00eates auxquelles elle ne peut s&#8217;emp\u00eacher de vouloir plaire, et ses s\u00e9ances de th\u00e9rapie avec son psychanalyste. C&#8217;est \u00e9crit comme un journal intime d&#8217;adulte, sans date et sans \u00abCher journal\u00bb. Chaque phrase dure au moins une page, et quand la phrase s&#8217;arr\u00eate, un nouveau paragraphe commence. Une petite biographie avant le texte pr\u00e9vient que l&#8217;auteure s&#8217;est suicid\u00e9e quelques ann\u00e9es apr\u00e8s la parution de ce livre, \u00e7a donne le ton.<\/p>\n\n\n\n<p>Les phrases sont construites pour qu&#8217;on lise sans s&#8217;arr\u00eater, tr\u00e8s vite. J&#8217;ai tendance \u00e0 lire \u00e0 voix haute, mais avec celui-l\u00e0 je n&#8217;ai pas pu. De un parce que j&#8217;avais l&#8217;impression de manquer d&#8217;air avec seulement des virgules \u00e0 ma disposition, de deux parce j&#8217;avais l&#8217;impression qu&#8217;en lisant tout haut les propos si durs, \u00e9crits au \u00abje\u00bb, je m&#8217;identifiais \u00e0 la narratrice, ce que je n&#8217;avais pas du tout envie de faire, et la trahissait du m\u00eame coup. <\/p>\n\n\n\n<p>Et puis, il y a le c\u00f4te sombre, tr\u00e8s sombre. J&#8217;ai de la mis\u00e8re \u00e0 raconter \u00e0 voix haute des atrocit\u00e9s, que ce soit un meurtre sordide dans le journal ou une sc\u00e8ne de torture dans un roman, dans la t\u00eate c&#8217;est d\u00e9j\u00e0 \u00e0 la limite du supportable. \u00c7a ne va pas tout \u00e0 fait jusque l\u00e0 dans les romans de Nelly Arcan, mais c&#8217;est violent, c&#8217;est brutalement anatomique, et c&#8217;est teint\u00e9 de mort \u00e0 chaque phrase.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab [&#8230;] je l&#8217;ai d\u00e9j\u00e0 dit je crois, j&#8217;ai ma m\u00e8re sur le dos et sur les bras, pendue \u00e0 mon cou et roul\u00e9e en boule \u00e0 mes pieds, je l&#8217;ai de toutes les fa\u00e7ons et partout en m\u00eame temps, voil\u00e0 pourquoi il faudrait qu&#8217;on me coupe la t\u00eate, qu&#8217;on m&#8217;arrache la peau, il faudrait d\u00e9truire tout ce qu&#8217;elle a marqu\u00e9 de sa morsure de chienne lorsque j&#8217;\u00e9tais encore au berceau, il faudrait me d\u00e9pecer jusqu&#8217;\u00e0 ce qu&#8217;il n&#8217;y ait plus que les os, et au moment de ne plus offrir de surface o\u00f9 elle puisse d\u00e9poser sa charge, je deviendrai quelqu&#8217;un qui ne sera pas elle, je serai morte sans doute mais j&#8217;aurai accompli un exploit, celui d&#8217;\u00eatre la fille de personne [&#8230;] \u00bb<\/p><cite>Putain, p. 139, \u00e9dition Points<\/cite><\/blockquote>\n\n\n\n<p>Ce que j&#8217;ai trouv\u00e9 particuli\u00e8rement fascinant dans ce roman, c&#8217;est la dichotomie entre la froide lucidit\u00e9 de la narratrice et son incapacit\u00e9 \u00e0 se sortir de l\u00e0. Elle est visiblement brillante, ses r\u00e9flexions sont pr\u00e9cises \u00e0 faire peur, et pourtant elle se laisse enfoncer dans un gouffre de souffrance. C&#8217;est aussi fou comment on peut r\u00e9ussir \u00e0 enlever tout le c\u00f4t\u00e9 myst\u00e9rieux et excitant du sexe tout en en parlant sans arr\u00eat, j&#8217;en suis m\u00eame venue \u00e0 me demander ce qu&#8217;on avait tous \u00e0 s&#8217;exciter pour une chose aussi b\u00eate.<\/p>\n\n\n\n<p>J&#8217;ai suivi un cours de litt\u00e9rature qu\u00e9b\u00e9coise il y a un an et demi, on avait parl\u00e9 un peu de Nelly Arcan, et la prof avait bien insist\u00e9 sur la s\u00e9paration entre l&#8217;auteur et le personnage. Oui Nelly Arcan a \u00e9t\u00e9 escorte, mais c&#8217;est pousser le bouchon que d&#8217;assumer qu&#8217;elle a v\u00e9cu tout ce qu&#8217;elle raconte. C&#8217;est difficile de faire la part des choses avec un style d&#8217;\u00e9criture comme le sien, mais la narratrice reste un personnage.<\/p>\n\n\n\n<p>On peut mieux le comprendre en regardant son entrevue \u00e0 Tout le monde en parle, accord\u00e9e en 2007 (deux ans avant sa mort). L&#8217;auteure insiste sur le fait qu&#8217;elle exag\u00e8re beaucoup dans son \u00e9criture et qu&#8217;elle a plein d&#8217;amis contrairement \u00e0 son personnage, notamment. Malheureusement, tous les gens dans la salle, y compris les animateurs et les invit\u00e9s, ont l&#8217;air de s&#8217;en foutre pas mal, et c&#8217;est vraiment difficile \u00e0 voir. Il y a des gens qui ont baiss\u00e9 dans mon estime. Nelly Arcan <a href=\"https:\/\/nellyarcan.com\/pages\/la-honte.php\">l&#8217;a v\u00e9cu comme une humiliation<\/a>, et je la comprends. <\/p>\n\n\n\n<p>Je viens de finir le livre, et je le ressens comme un coup de poing. Je suis t\u00e9tanis\u00e9e, mon regard sur le monde a chang\u00e9, j&#8217;ai rarement lu quelque chose d&#8217;aussi cruellement humain. Ce n&#8217;est pas une lecture facile, mais c&#8217;est un incontournable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je me suis dit pendant des ann\u00e9es que je devais lire Nelly Arcan, mais j&#8217;h\u00e9sitais. Je me suis dit que je n&#8217;aimais pas les longues phrases sans point, qui ressemblent \u00e0 un flot de pens\u00e9es, \u00e7a me prenait des \u00abvraies phrases\u00bb, des phrases \u00abrecherch\u00e9es.\u00bb Oh que je ne savais pas de quoi je parlais. Mis \u00e7a simple, c&#8217;est l&#8217;histoire d&#8217;une prostitu\u00e9e qui parle de sa condition. Elle raconte pourquoi et comment elle a commenc\u00e9 \u00e0 20 ans, ce qu&#8217;elle sent quand elle attend ses clients dans sa chambre d&#8217;h\u00f4tel sans \u00e2me, son rapport aux femmes, ses rivales, et aux hommes, ces b\u00eates auxquelles elle ne peut s&#8217;emp\u00eacher de vouloir plaire, et ses s\u00e9ances de th\u00e9rapie avec son psychanalyste. C&#8217;est \u00e9crit comme un journal intime d&#8217;adulte, sans date et sans \u00abCher journal\u00bb. Chaque phrase dure au moins une page, et quand la phrase s&#8217;arr\u00eate, un nouveau paragraphe commence. Une petite biographie avant le texte pr\u00e9vient que l&#8217;auteure s&#8217;est suicid\u00e9e quelques ann\u00e9es apr\u00e8s la parution de ce livre, \u00e7a donne le ton. Les phrases sont construites pour qu&#8217;on lise sans s&#8217;arr\u00eater, tr\u00e8s vite. J&#8217;ai tendance \u00e0 lire \u00e0 voix haute, mais avec celui-l\u00e0 je n&#8217;ai pas pu. De un parce que j&#8217;avais l&#8217;impression de manquer d&#8217;air avec seulement des virgules \u00e0 ma disposition, de deux parce j&#8217;avais l&#8217;impression qu&#8217;en lisant tout haut les propos si durs, \u00e9crits au \u00abje\u00bb, je m&#8217;identifiais \u00e0 la narratrice, ce que je n&#8217;avais pas du tout envie de faire, et la trahissait du m\u00eame coup. Et puis, il y a le c\u00f4te sombre, tr\u00e8s sombre. J&#8217;ai de la mis\u00e8re \u00e0 raconter \u00e0 voix haute des atrocit\u00e9s, que ce soit un meurtre sordide dans le journal ou une sc\u00e8ne de torture dans un roman, dans la t\u00eate c&#8217;est d\u00e9j\u00e0 \u00e0 la limite du supportable. \u00c7a ne va pas tout \u00e0 fait jusque l\u00e0 dans les romans de Nelly Arcan, mais c&#8217;est violent, c&#8217;est brutalement anatomique, et c&#8217;est teint\u00e9 de mort \u00e0 chaque phrase. \u00ab [&#8230;] je l&#8217;ai d\u00e9j\u00e0 dit je crois, j&#8217;ai ma m\u00e8re sur le dos et sur les bras, pendue \u00e0 mon cou et roul\u00e9e en boule \u00e0 mes pieds, je l&#8217;ai de toutes les fa\u00e7ons et partout en m\u00eame temps, voil\u00e0 pourquoi il faudrait qu&#8217;on me coupe la t\u00eate, qu&#8217;on m&#8217;arrache la peau, il faudrait d\u00e9truire tout ce qu&#8217;elle a marqu\u00e9 de sa morsure de chienne lorsque j&#8217;\u00e9tais encore au berceau, il faudrait me d\u00e9pecer jusqu&#8217;\u00e0 ce qu&#8217;il n&#8217;y ait plus que les os, et au moment de ne plus offrir de surface o\u00f9 elle puisse d\u00e9poser sa charge, je deviendrai quelqu&#8217;un qui ne sera pas elle, je serai morte sans doute mais j&#8217;aurai accompli un exploit, celui d&#8217;\u00eatre la fille de personne [&#8230;] \u00bb Putain, p. 139, \u00e9dition Points Ce que j&#8217;ai trouv\u00e9 particuli\u00e8rement fascinant dans ce roman, c&#8217;est la dichotomie entre la froide lucidit\u00e9 de la narratrice et son incapacit\u00e9 \u00e0 se sortir de l\u00e0. Elle est visiblement brillante, ses r\u00e9flexions sont pr\u00e9cises \u00e0 faire peur, et pourtant elle se laisse enfoncer dans un gouffre de souffrance. C&#8217;est aussi fou comment on peut r\u00e9ussir \u00e0 enlever tout le c\u00f4t\u00e9 myst\u00e9rieux et excitant du sexe tout en en parlant sans arr\u00eat, j&#8217;en suis m\u00eame venue \u00e0 me demander ce qu&#8217;on avait tous \u00e0 s&#8217;exciter pour une chose aussi b\u00eate. J&#8217;ai suivi un cours de litt\u00e9rature qu\u00e9b\u00e9coise il y a un an et demi, on avait parl\u00e9 un peu de Nelly Arcan, et la prof avait bien insist\u00e9 sur la s\u00e9paration entre l&#8217;auteur et le personnage. Oui Nelly Arcan a \u00e9t\u00e9 escorte, mais c&#8217;est pousser le bouchon que d&#8217;assumer qu&#8217;elle a v\u00e9cu tout ce qu&#8217;elle raconte. C&#8217;est difficile de faire la part des choses avec un style d&#8217;\u00e9criture comme le sien, mais la narratrice reste un personnage. On peut mieux le comprendre en regardant son entrevue \u00e0 Tout le monde en parle, accord\u00e9e en 2007 (deux ans avant sa mort). L&#8217;auteure insiste sur le fait qu&#8217;elle exag\u00e8re beaucoup dans son \u00e9criture et qu&#8217;elle a plein d&#8217;amis contrairement \u00e0 son personnage, notamment. Malheureusement, tous les gens dans la salle, y compris les animateurs et les invit\u00e9s, ont l&#8217;air de s&#8217;en foutre pas mal, et c&#8217;est vraiment difficile \u00e0 voir. Il y a des gens qui ont baiss\u00e9 dans mon estime. Nelly Arcan l&#8217;a v\u00e9cu comme une humiliation, et je la comprends. Je viens de finir le livre, et je le ressens comme un coup de poing. Je suis t\u00e9tanis\u00e9e, mon regard sur le monde a chang\u00e9, j&#8217;ai rarement lu quelque chose d&#8217;aussi cruellement humain. Ce n&#8217;est pas une lecture facile, mais c&#8217;est un incontournable.<\/p>\n","protected":false},"author":1,"featured_media":3511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[245,242],"tags":[],"class_list":["post-1703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litterature-quebecoise","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Putain - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/en\/putain\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Putain - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Je me suis dit pendant des ann\u00e9es que je devais lire Nelly Arcan, mais j&#8217;h\u00e9sitais. Je me suis dit que je n&#8217;aimais pas les longues phrases sans point, qui ressemblent \u00e0 un flot de pens\u00e9es, \u00e7a me prenait des \u00abvraies phrases\u00bb, des phrases \u00abrecherch\u00e9es.\u00bb Oh que je ne savais pas de quoi je parlais. Mis \u00e7a simple, c&#8217;est l&#8217;histoire d&#8217;une prostitu\u00e9e qui parle de sa condition. Elle raconte pourquoi et comment elle a commenc\u00e9 \u00e0 20 ans, ce qu&#8217;elle sent quand elle attend ses clients dans sa chambre d&#8217;h\u00f4tel sans \u00e2me, son rapport aux femmes, ses rivales, et aux hommes, ces b\u00eates auxquelles elle ne peut s&#8217;emp\u00eacher de vouloir plaire, et ses s\u00e9ances de th\u00e9rapie avec son psychanalyste. C&#8217;est \u00e9crit comme un journal intime d&#8217;adulte, sans date et sans \u00abCher journal\u00bb. Chaque phrase dure au moins une page, et quand la phrase s&#8217;arr\u00eate, un nouveau paragraphe commence. Une petite biographie avant le texte pr\u00e9vient que l&#8217;auteure s&#8217;est suicid\u00e9e quelques ann\u00e9es apr\u00e8s la parution de ce livre, \u00e7a donne le ton. Les phrases sont construites pour qu&#8217;on lise sans s&#8217;arr\u00eater, tr\u00e8s vite. J&#8217;ai tendance \u00e0 lire \u00e0 voix haute, mais avec celui-l\u00e0 je n&#8217;ai pas pu. De un parce que j&#8217;avais l&#8217;impression de manquer d&#8217;air avec seulement des virgules \u00e0 ma disposition, de deux parce j&#8217;avais l&#8217;impression qu&#8217;en lisant tout haut les propos si durs, \u00e9crits au \u00abje\u00bb, je m&#8217;identifiais \u00e0 la narratrice, ce que je n&#8217;avais pas du tout envie de faire, et la trahissait du m\u00eame coup. Et puis, il y a le c\u00f4te sombre, tr\u00e8s sombre. J&#8217;ai de la mis\u00e8re \u00e0 raconter \u00e0 voix haute des atrocit\u00e9s, que ce soit un meurtre sordide dans le journal ou une sc\u00e8ne de torture dans un roman, dans la t\u00eate c&#8217;est d\u00e9j\u00e0 \u00e0 la limite du supportable. \u00c7a ne va pas tout \u00e0 fait jusque l\u00e0 dans les romans de Nelly Arcan, mais c&#8217;est violent, c&#8217;est brutalement anatomique, et c&#8217;est teint\u00e9 de mort \u00e0 chaque phrase. \u00ab [&#8230;] je l&#8217;ai d\u00e9j\u00e0 dit je crois, j&#8217;ai ma m\u00e8re sur le dos et sur les bras, pendue \u00e0 mon cou et roul\u00e9e en boule \u00e0 mes pieds, je l&#8217;ai de toutes les fa\u00e7ons et partout en m\u00eame temps, voil\u00e0 pourquoi il faudrait qu&#8217;on me coupe la t\u00eate, qu&#8217;on m&#8217;arrache la peau, il faudrait d\u00e9truire tout ce qu&#8217;elle a marqu\u00e9 de sa morsure de chienne lorsque j&#8217;\u00e9tais encore au berceau, il faudrait me d\u00e9pecer jusqu&#8217;\u00e0 ce qu&#8217;il n&#8217;y ait plus que les os, et au moment de ne plus offrir de surface o\u00f9 elle puisse d\u00e9poser sa charge, je deviendrai quelqu&#8217;un qui ne sera pas elle, je serai morte sans doute mais j&#8217;aurai accompli un exploit, celui d&#8217;\u00eatre la fille de personne [&#8230;] \u00bb Putain, p. 139, \u00e9dition Points Ce que j&#8217;ai trouv\u00e9 particuli\u00e8rement fascinant dans ce roman, c&#8217;est la dichotomie entre la froide lucidit\u00e9 de la narratrice et son incapacit\u00e9 \u00e0 se sortir de l\u00e0. Elle est visiblement brillante, ses r\u00e9flexions sont pr\u00e9cises \u00e0 faire peur, et pourtant elle se laisse enfoncer dans un gouffre de souffrance. C&#8217;est aussi fou comment on peut r\u00e9ussir \u00e0 enlever tout le c\u00f4t\u00e9 myst\u00e9rieux et excitant du sexe tout en en parlant sans arr\u00eat, j&#8217;en suis m\u00eame venue \u00e0 me demander ce qu&#8217;on avait tous \u00e0 s&#8217;exciter pour une chose aussi b\u00eate. J&#8217;ai suivi un cours de litt\u00e9rature qu\u00e9b\u00e9coise il y a un an et demi, on avait parl\u00e9 un peu de Nelly Arcan, et la prof avait bien insist\u00e9 sur la s\u00e9paration entre l&#8217;auteur et le personnage. Oui Nelly Arcan a \u00e9t\u00e9 escorte, mais c&#8217;est pousser le bouchon que d&#8217;assumer qu&#8217;elle a v\u00e9cu tout ce qu&#8217;elle raconte. C&#8217;est difficile de faire la part des choses avec un style d&#8217;\u00e9criture comme le sien, mais la narratrice reste un personnage. On peut mieux le comprendre en regardant son entrevue \u00e0 Tout le monde en parle, accord\u00e9e en 2007 (deux ans avant sa mort). L&#8217;auteure insiste sur le fait qu&#8217;elle exag\u00e8re beaucoup dans son \u00e9criture et qu&#8217;elle a plein d&#8217;amis contrairement \u00e0 son personnage, notamment. Malheureusement, tous les gens dans la salle, y compris les animateurs et les invit\u00e9s, ont l&#8217;air de s&#8217;en foutre pas mal, et c&#8217;est vraiment difficile \u00e0 voir. Il y a des gens qui ont baiss\u00e9 dans mon estime. Nelly Arcan l&#8217;a v\u00e9cu comme une humiliation, et je la comprends. Je viens de finir le livre, et je le ressens comme un coup de poing. Je suis t\u00e9tanis\u00e9e, mon regard sur le monde a chang\u00e9, j&#8217;ai rarement lu quelque chose d&#8217;aussi cruellement humain. Ce n&#8217;est pas une lecture facile, mais c&#8217;est un incontournable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/en\/putain\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-16T16:50:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-10T12:44:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2019\/08\/51GPEA5093L_1.png?fit=715%2C475&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"715\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Putain\",\"datePublished\":\"2019-08-16T16:50:53+00:00\",\"dateModified\":\"2020-08-10T12:44:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/\"},\"wordCount\":854,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/51GPEA5093L_1.png?fit=715%2C475&ssl=1\",\"articleSection\":[\"Litt\u00e9rature qu\u00e9b\u00e9coise\",\"Se distraire\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/\",\"name\":\"Putain - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/51GPEA5093L_1.png?fit=715%2C475&ssl=1\",\"datePublished\":\"2019-08-16T16:50:53+00:00\",\"dateModified\":\"2020-08-10T12:44:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/51GPEA5093L_1.png?fit=715%2C475&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/51GPEA5093L_1.png?fit=715%2C475&ssl=1\",\"width\":715,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/putain\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Putain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/en\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Putain - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/en\/putain\/","og_locale":"en_US","og_type":"article","og_title":"Putain - Prochaine lecture","og_description":"Je me suis dit pendant des ann\u00e9es que je devais lire Nelly Arcan, mais j&#8217;h\u00e9sitais. Je me suis dit que je n&#8217;aimais pas les longues phrases sans point, qui ressemblent \u00e0 un flot de pens\u00e9es, \u00e7a me prenait des \u00abvraies phrases\u00bb, des phrases \u00abrecherch\u00e9es.\u00bb Oh que je ne savais pas de quoi je parlais. Mis \u00e7a simple, c&#8217;est l&#8217;histoire d&#8217;une prostitu\u00e9e qui parle de sa condition. Elle raconte pourquoi et comment elle a commenc\u00e9 \u00e0 20 ans, ce qu&#8217;elle sent quand elle attend ses clients dans sa chambre d&#8217;h\u00f4tel sans \u00e2me, son rapport aux femmes, ses rivales, et aux hommes, ces b\u00eates auxquelles elle ne peut s&#8217;emp\u00eacher de vouloir plaire, et ses s\u00e9ances de th\u00e9rapie avec son psychanalyste. C&#8217;est \u00e9crit comme un journal intime d&#8217;adulte, sans date et sans \u00abCher journal\u00bb. Chaque phrase dure au moins une page, et quand la phrase s&#8217;arr\u00eate, un nouveau paragraphe commence. Une petite biographie avant le texte pr\u00e9vient que l&#8217;auteure s&#8217;est suicid\u00e9e quelques ann\u00e9es apr\u00e8s la parution de ce livre, \u00e7a donne le ton. Les phrases sont construites pour qu&#8217;on lise sans s&#8217;arr\u00eater, tr\u00e8s vite. J&#8217;ai tendance \u00e0 lire \u00e0 voix haute, mais avec celui-l\u00e0 je n&#8217;ai pas pu. De un parce que j&#8217;avais l&#8217;impression de manquer d&#8217;air avec seulement des virgules \u00e0 ma disposition, de deux parce j&#8217;avais l&#8217;impression qu&#8217;en lisant tout haut les propos si durs, \u00e9crits au \u00abje\u00bb, je m&#8217;identifiais \u00e0 la narratrice, ce que je n&#8217;avais pas du tout envie de faire, et la trahissait du m\u00eame coup. Et puis, il y a le c\u00f4te sombre, tr\u00e8s sombre. J&#8217;ai de la mis\u00e8re \u00e0 raconter \u00e0 voix haute des atrocit\u00e9s, que ce soit un meurtre sordide dans le journal ou une sc\u00e8ne de torture dans un roman, dans la t\u00eate c&#8217;est d\u00e9j\u00e0 \u00e0 la limite du supportable. \u00c7a ne va pas tout \u00e0 fait jusque l\u00e0 dans les romans de Nelly Arcan, mais c&#8217;est violent, c&#8217;est brutalement anatomique, et c&#8217;est teint\u00e9 de mort \u00e0 chaque phrase. \u00ab [&#8230;] je l&#8217;ai d\u00e9j\u00e0 dit je crois, j&#8217;ai ma m\u00e8re sur le dos et sur les bras, pendue \u00e0 mon cou et roul\u00e9e en boule \u00e0 mes pieds, je l&#8217;ai de toutes les fa\u00e7ons et partout en m\u00eame temps, voil\u00e0 pourquoi il faudrait qu&#8217;on me coupe la t\u00eate, qu&#8217;on m&#8217;arrache la peau, il faudrait d\u00e9truire tout ce qu&#8217;elle a marqu\u00e9 de sa morsure de chienne lorsque j&#8217;\u00e9tais encore au berceau, il faudrait me d\u00e9pecer jusqu&#8217;\u00e0 ce qu&#8217;il n&#8217;y ait plus que les os, et au moment de ne plus offrir de surface o\u00f9 elle puisse d\u00e9poser sa charge, je deviendrai quelqu&#8217;un qui ne sera pas elle, je serai morte sans doute mais j&#8217;aurai accompli un exploit, celui d&#8217;\u00eatre la fille de personne [&#8230;] \u00bb Putain, p. 139, \u00e9dition Points Ce que j&#8217;ai trouv\u00e9 particuli\u00e8rement fascinant dans ce roman, c&#8217;est la dichotomie entre la froide lucidit\u00e9 de la narratrice et son incapacit\u00e9 \u00e0 se sortir de l\u00e0. Elle est visiblement brillante, ses r\u00e9flexions sont pr\u00e9cises \u00e0 faire peur, et pourtant elle se laisse enfoncer dans un gouffre de souffrance. C&#8217;est aussi fou comment on peut r\u00e9ussir \u00e0 enlever tout le c\u00f4t\u00e9 myst\u00e9rieux et excitant du sexe tout en en parlant sans arr\u00eat, j&#8217;en suis m\u00eame venue \u00e0 me demander ce qu&#8217;on avait tous \u00e0 s&#8217;exciter pour une chose aussi b\u00eate. J&#8217;ai suivi un cours de litt\u00e9rature qu\u00e9b\u00e9coise il y a un an et demi, on avait parl\u00e9 un peu de Nelly Arcan, et la prof avait bien insist\u00e9 sur la s\u00e9paration entre l&#8217;auteur et le personnage. Oui Nelly Arcan a \u00e9t\u00e9 escorte, mais c&#8217;est pousser le bouchon que d&#8217;assumer qu&#8217;elle a v\u00e9cu tout ce qu&#8217;elle raconte. C&#8217;est difficile de faire la part des choses avec un style d&#8217;\u00e9criture comme le sien, mais la narratrice reste un personnage. On peut mieux le comprendre en regardant son entrevue \u00e0 Tout le monde en parle, accord\u00e9e en 2007 (deux ans avant sa mort). L&#8217;auteure insiste sur le fait qu&#8217;elle exag\u00e8re beaucoup dans son \u00e9criture et qu&#8217;elle a plein d&#8217;amis contrairement \u00e0 son personnage, notamment. Malheureusement, tous les gens dans la salle, y compris les animateurs et les invit\u00e9s, ont l&#8217;air de s&#8217;en foutre pas mal, et c&#8217;est vraiment difficile \u00e0 voir. Il y a des gens qui ont baiss\u00e9 dans mon estime. Nelly Arcan l&#8217;a v\u00e9cu comme une humiliation, et je la comprends. Je viens de finir le livre, et je le ressens comme un coup de poing. Je suis t\u00e9tanis\u00e9e, mon regard sur le monde a chang\u00e9, j&#8217;ai rarement lu quelque chose d&#8217;aussi cruellement humain. Ce n&#8217;est pas une lecture facile, mais c&#8217;est un incontournable.","og_url":"https:\/\/prochainelecture.com\/en\/putain\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2019-08-16T16:50:53+00:00","article_modified_time":"2020-08-10T12:44:18+00:00","og_image":[{"width":715,"height":475,"url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2019\/08\/51GPEA5093L_1.png?fit=715%2C475&ssl=1","type":"image\/png"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"Written by":"Na\u00efma Hassert","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/putain\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/putain\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Putain","datePublished":"2019-08-16T16:50:53+00:00","dateModified":"2020-08-10T12:44:18+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/putain\/"},"wordCount":854,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/putain\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2019\/08\/51GPEA5093L_1.png?fit=715%2C475&ssl=1","articleSection":["Litt\u00e9rature qu\u00e9b\u00e9coise","Se distraire"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/putain\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/putain\/","url":"https:\/\/prochainelecture.com\/putain\/","name":"Putain - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/putain\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/putain\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2019\/08\/51GPEA5093L_1.png?fit=715%2C475&ssl=1","datePublished":"2019-08-16T16:50:53+00:00","dateModified":"2020-08-10T12:44:18+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/putain\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/putain\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/putain\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2019\/08\/51GPEA5093L_1.png?fit=715%2C475&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2019\/08\/51GPEA5093L_1.png?fit=715%2C475&ssl=1","width":715,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/putain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Putain"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Next Read","description":"My readings, to inspire you","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Next Read","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/en\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2019\/08\/51GPEA5093L_1.png?fit=715%2C475&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s7kvK4-putain","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/comments?post=1703"}],"version-history":[{"count":5,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1703\/revisions"}],"predecessor-version":[{"id":3608,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1703\/revisions\/3608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media\/3511"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media?parent=1703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/categories?post=1703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/tags?post=1703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}