{"id":1411,"date":"2016-11-06T23:16:40","date_gmt":"2016-11-07T03:16:40","guid":{"rendered":"http:\/\/www.naimahassert.com\/?p=1411"},"modified":"2022-12-09T09:34:01","modified_gmt":"2022-12-09T13:34:01","slug":"1411-2","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/en\/1411-2\/","title":{"rendered":"Back in time with Harry Potter and the Cursed Child"},"content":{"rendered":"<p><strong>Je ne serai pas objective. Impossible. Quand j&#8217;\u00e9tais petite, je voulais marier Harry Potter. J&#8217;ai lu les 4 premiers livres au moins 8 fois chacun. Mon passe-temps, c&#8217;\u00e9tait de lire Harry Potter. Je d\u00e9fie quelqu&#8217;un d&#8217;avoir eu une relation aussi fusionnelle avec Harry Potter!<\/strong><\/p>\n<p>Harry Potter and the Cursed Child est suppos\u00e9ment le 8\u00e8me tome de la s\u00e9rie Harry Potter. Sauf que ce n&#8217;est pas \u00e9crit pas J.K. Rowling, et que ce n&#8217;est pas un roman, mais une pi\u00e8ce de th\u00e9\u00e2tre. J&#8217;avais un peu peur de le lire, tellement j&#8217;avais peur d&#8217;\u00eatre d\u00e9\u00e7ue. Mais un ami me l&#8217;a donn\u00e9 en cadeau, la belle \u00e9dition toute neuve en couverture rigide&#8230; J&#8217;\u00e9tais foutue.<\/p>\n<p>J&#8217;avais 6 ans quand j&#8217;ai commenc\u00e9 \u00e0 lire ces livres pour la premi\u00e8re fois. Maintenant que je suis adulte, j&#8217;avoue que le charme n&#8217;est pas exactement le m\u00eame. Le sc\u00e9nario est un peu simpliste. La psychologie des personnages n&#8217;est pas tr\u00e8s d\u00e9velopp\u00e9e. Ce n&#8217;est pas r\u00e9aliste (m\u00eame si on consid\u00e8re qu&#8217;on vit chez des magiciens). Les dialogues sont pr\u00e9cipit\u00e9s.<\/p>\n<p>Alors qu&#8217;est-ce qui fait que je n&#8217;ai pas pu arr\u00eater de tourner les pages tard la nuit? Parce que les &#8220;nouveaux&#8221; auteurs sont dou\u00e9s.\u00a0Le monde de Harry Potter \u00e9tait impeccable. J&#8217;\u00e9tais toute excit\u00e9e d'&#8221;entendre&#8221; de nouveau parler Rogue, Hermione, Ron, Harry,\u00a0Dumbledore (parce que je lis \u00e0 voix haute). L&#8217;histoire est bel et bien une suite aux tomes pr\u00e9c\u00e9dents, l&#8217;histoire progresse, c&#8217;est intrigant, et \u00e7a marche tr\u00e8s bien. Ils r\u00e9ussissent m\u00eame \u00e0 inclure des descriptions plut\u00f4t d\u00e9velopp\u00e9es dans le sc\u00e9nario, qui n&#8217;est pas con\u00e7u pour \u00e7a.<\/p>\n<p>Je serais tr\u00e8s curieuse de voir la pi\u00e8ce de th\u00e9\u00e2tre, parce que je n&#8217;ai aucune id\u00e9e comment ils ont pu reproduire Voldemort, les d\u00e9cors qui tournent, les personnages qui se m\u00e9tamorphosent, et autres tours de magie qui n\u00e9cessitent de la lumi\u00e8re et des objets qui bougent tout seuls.<\/p>\n<p>J&#8217;ai d\u00e9finitivement rev\u00e9cu mon enfance, et si vous \u00eates des fans comme moi (m\u00eame si\u00a0<em>vous ne pouvez pas\u00a0<\/em>\u00eatre aussi fans que moi), vous allez appr\u00e9cier ce retour dans le temps.<\/p>\n<hr \/>\n<p><a href=\"http:\/\/amzn.to\/2edRpK3\"><strong>Harry Potter and the Cursed Child Parts One and Two (Special Rehearsal Edition Script)<\/strong><\/a><\/p>\n<p><strong>Par J. K. Rowling, Jack Thorne et John Tiffany<\/strong><\/p>\n<p><strong>22,69 $<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Je ne serai pas objective. Impossible. Quand j&#8217;\u00e9tais petite, je voulais marier Harry Potter. J&#8217;ai lu les 4 premiers livres au moins 8 fois chacun. Mon passe-temps, c&#8217;\u00e9tait de lire Harry Potter. Je d\u00e9fie quelqu&#8217;un d&#8217;avoir eu une relation aussi fusionnelle avec Harry Potter! Harry Potter and the Cursed Child est suppos\u00e9ment le 8\u00e8me tome de la s\u00e9rie Harry Potter. Sauf que ce n&#8217;est pas \u00e9crit pas J.K. Rowling, et que ce n&#8217;est pas un roman, mais une pi\u00e8ce de th\u00e9\u00e2tre. J&#8217;avais un peu peur de le lire, tellement j&#8217;avais peur d&#8217;\u00eatre d\u00e9\u00e7ue. Mais un ami me l&#8217;a donn\u00e9 en cadeau, la belle \u00e9dition toute neuve en couverture rigide&#8230; J&#8217;\u00e9tais foutue. J&#8217;avais 6 ans quand j&#8217;ai commenc\u00e9 \u00e0 lire ces livres pour la premi\u00e8re fois. Maintenant que je suis adulte, j&#8217;avoue que le charme n&#8217;est pas exactement le m\u00eame. Le sc\u00e9nario est un peu simpliste. La psychologie des personnages n&#8217;est pas tr\u00e8s d\u00e9velopp\u00e9e. Ce n&#8217;est pas r\u00e9aliste (m\u00eame si on consid\u00e8re qu&#8217;on vit chez des magiciens). Les dialogues sont pr\u00e9cipit\u00e9s. Alors qu&#8217;est-ce qui fait que je n&#8217;ai pas pu arr\u00eater de tourner les pages tard la nuit? Parce que les &#8220;nouveaux&#8221; auteurs sont dou\u00e9s.\u00a0Le monde de Harry Potter \u00e9tait impeccable. J&#8217;\u00e9tais toute excit\u00e9e d&#8217;&#8221;entendre&#8221; de nouveau parler Rogue, Hermione, Ron, Harry,\u00a0Dumbledore (parce que je lis \u00e0 voix haute). L&#8217;histoire est bel et bien une suite aux tomes pr\u00e9c\u00e9dents, l&#8217;histoire progresse, c&#8217;est intrigant, et \u00e7a marche tr\u00e8s bien. Ils r\u00e9ussissent m\u00eame \u00e0 inclure des descriptions plut\u00f4t d\u00e9velopp\u00e9es dans le sc\u00e9nario, qui n&#8217;est pas con\u00e7u pour \u00e7a. Je serais tr\u00e8s curieuse de voir la pi\u00e8ce de th\u00e9\u00e2tre, parce que je n&#8217;ai aucune id\u00e9e comment ils ont pu reproduire Voldemort, les d\u00e9cors qui tournent, les personnages qui se m\u00e9tamorphosent, et autres tours de magie qui n\u00e9cessitent de la lumi\u00e8re et des objets qui bougent tout seuls. J&#8217;ai d\u00e9finitivement rev\u00e9cu mon enfance, et si vous \u00eates des fans comme moi (m\u00eame si\u00a0vous ne pouvez pas\u00a0\u00eatre aussi fans que moi), vous allez appr\u00e9cier ce retour dans le temps. Harry Potter and the Cursed Child Parts One and Two (Special Rehearsal Edition Script) Par J. K. Rowling, Jack Thorne et John Tiffany 22,69 $<\/p>","protected":false},"author":1,"featured_media":3439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[246,242],"tags":[],"class_list":["post-1411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fantastique","category-se-distraire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retour dans le temps avec Harry Potter and the Cursed Child - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/en\/1411-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retour dans le temps avec Harry Potter and the Cursed Child - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Je ne serai pas objective. Impossible. Quand j&#8217;\u00e9tais petite, je voulais marier Harry Potter. J&#8217;ai lu les 4 premiers livres au moins 8 fois chacun. Mon passe-temps, c&#8217;\u00e9tait de lire Harry Potter. Je d\u00e9fie quelqu&#8217;un d&#8217;avoir eu une relation aussi fusionnelle avec Harry Potter! Harry Potter and the Cursed Child est suppos\u00e9ment le 8\u00e8me tome de la s\u00e9rie Harry Potter. Sauf que ce n&#8217;est pas \u00e9crit pas J.K. Rowling, et que ce n&#8217;est pas un roman, mais une pi\u00e8ce de th\u00e9\u00e2tre. J&#8217;avais un peu peur de le lire, tellement j&#8217;avais peur d&#8217;\u00eatre d\u00e9\u00e7ue. Mais un ami me l&#8217;a donn\u00e9 en cadeau, la belle \u00e9dition toute neuve en couverture rigide&#8230; J&#8217;\u00e9tais foutue. J&#8217;avais 6 ans quand j&#8217;ai commenc\u00e9 \u00e0 lire ces livres pour la premi\u00e8re fois. Maintenant que je suis adulte, j&#8217;avoue que le charme n&#8217;est pas exactement le m\u00eame. Le sc\u00e9nario est un peu simpliste. La psychologie des personnages n&#8217;est pas tr\u00e8s d\u00e9velopp\u00e9e. Ce n&#8217;est pas r\u00e9aliste (m\u00eame si on consid\u00e8re qu&#8217;on vit chez des magiciens). Les dialogues sont pr\u00e9cipit\u00e9s. Alors qu&#8217;est-ce qui fait que je n&#8217;ai pas pu arr\u00eater de tourner les pages tard la nuit? Parce que les &#8220;nouveaux&#8221; auteurs sont dou\u00e9s.\u00a0Le monde de Harry Potter \u00e9tait impeccable. J&#8217;\u00e9tais toute excit\u00e9e d&#039;&#8221;entendre&#8221; de nouveau parler Rogue, Hermione, Ron, Harry,\u00a0Dumbledore (parce que je lis \u00e0 voix haute). L&#8217;histoire est bel et bien une suite aux tomes pr\u00e9c\u00e9dents, l&#8217;histoire progresse, c&#8217;est intrigant, et \u00e7a marche tr\u00e8s bien. Ils r\u00e9ussissent m\u00eame \u00e0 inclure des descriptions plut\u00f4t d\u00e9velopp\u00e9es dans le sc\u00e9nario, qui n&#8217;est pas con\u00e7u pour \u00e7a. Je serais tr\u00e8s curieuse de voir la pi\u00e8ce de th\u00e9\u00e2tre, parce que je n&#8217;ai aucune id\u00e9e comment ils ont pu reproduire Voldemort, les d\u00e9cors qui tournent, les personnages qui se m\u00e9tamorphosent, et autres tours de magie qui n\u00e9cessitent de la lumi\u00e8re et des objets qui bougent tout seuls. J&#8217;ai d\u00e9finitivement rev\u00e9cu mon enfance, et si vous \u00eates des fans comme moi (m\u00eame si\u00a0vous ne pouvez pas\u00a0\u00eatre aussi fans que moi), vous allez appr\u00e9cier ce retour dans le temps. Harry Potter and the Cursed Child Parts One and Two (Special Rehearsal Edition Script) Par J. K. Rowling, Jack Thorne et John Tiffany 22,69 $\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/en\/1411-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-07T03:16:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-09T13:34:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prochainelecture.com\/wp-content\/uploads\/2016\/11\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"2114\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"Retour dans le temps avec Harry Potter and the Cursed Child\",\"datePublished\":\"2016-11-07T03:16:40+00:00\",\"dateModified\":\"2022-12-09T13:34:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/\"},\"wordCount\":437,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1\",\"articleSection\":[\"Fantastique\",\"Se distraire\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/\",\"name\":\"Retour dans le temps avec Harry Potter and the Cursed Child - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1\",\"datePublished\":\"2016-11-07T03:16:40+00:00\",\"dateModified\":\"2022-12-09T13:34:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/1411-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retour dans le temps avec Harry Potter and the Cursed Child\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/en\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retour dans le temps avec Harry Potter and the Cursed Child - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/en\/1411-2\/","og_locale":"en_US","og_type":"article","og_title":"Retour dans le temps avec Harry Potter and the Cursed Child - Prochaine lecture","og_description":"Je ne serai pas objective. Impossible. Quand j&#8217;\u00e9tais petite, je voulais marier Harry Potter. J&#8217;ai lu les 4 premiers livres au moins 8 fois chacun. Mon passe-temps, c&#8217;\u00e9tait de lire Harry Potter. Je d\u00e9fie quelqu&#8217;un d&#8217;avoir eu une relation aussi fusionnelle avec Harry Potter! Harry Potter and the Cursed Child est suppos\u00e9ment le 8\u00e8me tome de la s\u00e9rie Harry Potter. Sauf que ce n&#8217;est pas \u00e9crit pas J.K. Rowling, et que ce n&#8217;est pas un roman, mais une pi\u00e8ce de th\u00e9\u00e2tre. J&#8217;avais un peu peur de le lire, tellement j&#8217;avais peur d&#8217;\u00eatre d\u00e9\u00e7ue. Mais un ami me l&#8217;a donn\u00e9 en cadeau, la belle \u00e9dition toute neuve en couverture rigide&#8230; J&#8217;\u00e9tais foutue. J&#8217;avais 6 ans quand j&#8217;ai commenc\u00e9 \u00e0 lire ces livres pour la premi\u00e8re fois. Maintenant que je suis adulte, j&#8217;avoue que le charme n&#8217;est pas exactement le m\u00eame. Le sc\u00e9nario est un peu simpliste. La psychologie des personnages n&#8217;est pas tr\u00e8s d\u00e9velopp\u00e9e. Ce n&#8217;est pas r\u00e9aliste (m\u00eame si on consid\u00e8re qu&#8217;on vit chez des magiciens). Les dialogues sont pr\u00e9cipit\u00e9s. Alors qu&#8217;est-ce qui fait que je n&#8217;ai pas pu arr\u00eater de tourner les pages tard la nuit? Parce que les &#8220;nouveaux&#8221; auteurs sont dou\u00e9s.\u00a0Le monde de Harry Potter \u00e9tait impeccable. J&#8217;\u00e9tais toute excit\u00e9e d'&#8221;entendre&#8221; de nouveau parler Rogue, Hermione, Ron, Harry,\u00a0Dumbledore (parce que je lis \u00e0 voix haute). L&#8217;histoire est bel et bien une suite aux tomes pr\u00e9c\u00e9dents, l&#8217;histoire progresse, c&#8217;est intrigant, et \u00e7a marche tr\u00e8s bien. Ils r\u00e9ussissent m\u00eame \u00e0 inclure des descriptions plut\u00f4t d\u00e9velopp\u00e9es dans le sc\u00e9nario, qui n&#8217;est pas con\u00e7u pour \u00e7a. Je serais tr\u00e8s curieuse de voir la pi\u00e8ce de th\u00e9\u00e2tre, parce que je n&#8217;ai aucune id\u00e9e comment ils ont pu reproduire Voldemort, les d\u00e9cors qui tournent, les personnages qui se m\u00e9tamorphosent, et autres tours de magie qui n\u00e9cessitent de la lumi\u00e8re et des objets qui bougent tout seuls. J&#8217;ai d\u00e9finitivement rev\u00e9cu mon enfance, et si vous \u00eates des fans comme moi (m\u00eame si\u00a0vous ne pouvez pas\u00a0\u00eatre aussi fans que moi), vous allez appr\u00e9cier ce retour dans le temps. Harry Potter and the Cursed Child Parts One and Two (Special Rehearsal Edition Script) Par J. K. Rowling, Jack Thorne et John Tiffany 22,69 $","og_url":"https:\/\/prochainelecture.com\/en\/1411-2\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2016-11-07T03:16:40+00:00","article_modified_time":"2022-12-09T13:34:01+00:00","og_image":[{"width":1400,"height":2114,"url":"https:\/\/prochainelecture.com\/wp-content\/uploads\/2016\/11\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.jpg","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_creator":"@ProchaineL","twitter_misc":{"Written by":"Na\u00efma Hassert","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/1411-2\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/1411-2\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"Retour dans le temps avec Harry Potter and the Cursed Child","datePublished":"2016-11-07T03:16:40+00:00","dateModified":"2022-12-09T13:34:01+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/1411-2\/"},"wordCount":437,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/1411-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/11\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1","articleSection":["Fantastique","Se distraire"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/1411-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/1411-2\/","url":"https:\/\/prochainelecture.com\/1411-2\/","name":"Retour dans le temps avec Harry Potter and the Cursed Child - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/1411-2\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/1411-2\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/11\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1","datePublished":"2016-11-07T03:16:40+00:00","dateModified":"2022-12-09T13:34:01+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/1411-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/1411-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/1411-2\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/11\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/11\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/1411-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"Retour dans le temps avec Harry Potter and the Cursed Child"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Next Read","description":"My readings, to inspire you","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Next Read","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/en\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/11\/Harry_Potter_and_the_Cursed_Child_Special_Rehearsal_Edition_Book_Cover.png?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-mL","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/comments?post=1411"}],"version-history":[{"count":3,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1411\/revisions"}],"predecessor-version":[{"id":3440,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1411\/revisions\/3440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media\/3439"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media?parent=1411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/categories?post=1411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/tags?post=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}