{"id":1358,"date":"2016-06-26T14:51:06","date_gmt":"2016-06-26T14:51:06","guid":{"rendered":"http:\/\/www.naimahassert.com\/?p=1358"},"modified":"2020-08-19T10:15:49","modified_gmt":"2020-08-19T14:15:49","slug":"la-jeune-millionnaire-en-affaires","status":"publish","type":"post","link":"https:\/\/prochainelecture.com\/en\/la-jeune-millionnaire-en-affaires\/","title":{"rendered":"La jeune millionnaire en affaires (\"The young millionaire in business\")"},"content":{"rendered":"<p><strong>With a title and cover like that, I had my doubts. This book that seemed to be trying to explain to girls how to become millionaires sounded funny and a bit silly, but not believable. And yet...<\/strong><\/p>\n<p>\u00c9liane Gamache begins by talking to us as if we were friends. Paragraphs are often one sentence long, with lots of exclamation points, often with capitalized words: she wants to get her readers' attention. Well, it worked enough for me to continue.<\/p>\n<p>She begins by explaining why there are quite a few more advantages than disadvantages to being a millionaire. She talks about it as an exhilarating adventure that requires taking risks and having \"guts\". She reminds us that a life in an office doing a job that you are not passionate about is killing you, and that in the end, you are always taking a risk, even with a \"stable\" job: companies can lay off people overnight, they can go bankrupt, even the government can cut its employees. But at least, when you start your own business, you are free, and you have much more control.<\/p>\n<p>It's hard not to agree with her, it makes you dream. Who doesn't want to have more money than they can spend?<\/p>\n<p>Then, she gives us some advice. I won't list them, I'll leave this short, light and inspiring reading to you, but I retained one that I applied the very next day: always negotiate. She gives the example of buying a car: she says to take the time to call several dealerships, then go to one and say that his competitor offers the same thing for $2000 less, then call that competitor in front of the dealership. Just watch how fast the dealer will give us that price. Then she asks us: how many hours do you need to work to make $2000? Especially since, in order to get $2000, you have to make $4000 with taxes. So with 45 minutes of calls, how much did we make per hour? She also says that most of the time, to get a better price, you just have to ask. People don't dare to do it for fear of looking poor or out of embarrassment, but it's worth it, and it doesn't cost anything!<\/p>\n<p>Basically, that's it. Short and effective. Not very advanced, but that's certainly not the point: it's not a guide to becoming a millionaire. It's just a little book to make us want to be one. And I must admit that it's working for me.<\/p>\n<hr \/>\n<p><strong><a href=\"http:\/\/www.amazon.ca\/jeune-millionnaire-en-affaires\/dp\/2892258898\/?_encoding=UTF8&amp;camp=15121&amp;creative=330641&amp;keywords=la%20jeune%20millionnaire%20en%20affaires&amp;linkCode=ur2&amp;qid=1466951642&amp;sr=8-1&amp;tag=naimahassertc-20\" target=\"_blank\" rel=\"noopener noreferrer\">La jeune millionnaire en affaires (\"The young millionaire in business\")<\/a><img decoding=\"async\" style=\"border: none !important; margin: 0px !important;\" src=\"http:\/\/ir-ca.amazon-adsystem.com\/e\/ir?t=naimahassertc-20&amp;l=ur2&amp;o=15\" alt=\"\" width=\"1\" height=\"1\" border=\"0\" \/><\/strong><\/p>\n<p><strong>\u00c9liane Gamache Latourelle et Marc Fisher<\/strong><\/p>\n<p><strong>17,96 $<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Avec un titre et un couverture pareils, j&#8217;avais des doutes. Ce livre qui semblait vouloir expliquer aux filles comment devenir millionnaires avait l&#8217;air dr\u00f4le et un peu niaiseux, mais pas cr\u00e9dible. Et pourtant&#8230; \u00c9liane Gamache amorce en nous parlant comme \u00e0 une amie. Les paragraphes\u00a0n&#8217;ont souvent qu&#8217;une phrase, il y a beaucoup de points d&#8217;exclamation, souvent des mots en majuscules : elle veut attirer l&#8217;attention de ses lectrices. Veut, veut pas, \u00e7a a assez march\u00e9 pour que je continue. Elle commence par nous expliquer pourquoi il y a pas mal plus d&#8217;avantages que d&#8217;inconv\u00e9nients \u00e0 \u00eatre millionnaire. Elle nous en parle comme d&#8217;une aventure exaltante, qui n\u00e9cessite de prendre des risques et d&#8217;avoir du &#8220;guts&#8221;. Elle nous rappelle \u00e0 quel point une vie dans un bureau \u00e0 faire un travail qui ne nous passionne pas c&#8217;est tuant, et que dans le fond, on prend toujours un risque, m\u00eame avec un travail &#8220;stable&#8221; : les entreprises peuvent faire des mises \u00e0 pied du jour au lendemain, elles peuvent faire faillite, m\u00eame le gouvernement peut couper dans ses fonctionnaires. Mais au moins, quand on part sa business, on est libres, et on a beaucoup plus de contr\u00f4le. Difficile de ne pas \u00eatre d&#8217;accord avec elle, \u00e7a fait r\u00eaver. Qui ne veut pas avoir plus d&#8217;argent qu&#8217;il ne peut en d\u00e9penser? Puis, elle nous donne des conseils. Je ne les \u00e9num\u00e9rerai pas, je vous laisse cette lecture courte, l\u00e9g\u00e8re et somme toute inspirante, mais j&#8217;en ai retenu une que j&#8217;ai appliqu\u00e9e d\u00e8s le lendemain : toujours n\u00e9gocier. Elle donne l&#8217;exemple de l&#8217;achat d&#8217;une voiture : elle dit de prendre le temps d&#8217;appeler plusieurs concessionnaires, puis de se pr\u00e9senter \u00e0 l&#8217;un en affirmant que son concurrent nous offre la m\u00eame chose pour 2000 $ de moins, puis d&#8217;appeler ce concurrent devant le concessionnaire. Il suffit de regarde la vitesse avec laquelle le concessionnaire va nous accorder ce prix-l\u00e0. Puis elle nous demande : combien d&#8217;heures avez-vous besoin de travailler pour faire 2000 $? Surtout qu&#8217;en fait, pour avoir 2000 $, il faut en faire 4000 $ avec les imp\u00f4ts. Donc, avec 45 minutes d&#8217;appels, on s&#8217;est fait combien de l&#8217;heure? Elle dit aussi que la plupart du temps, pour avoir un meilleur prix, il suffit de le demander. Les gens n&#8217;osent pas le faire par peur d&#8217;avoir l&#8217;air pauvre ou par g\u00eane, mais \u00e7a vaut la peine, et \u00e7a ne co\u00fbte rien! En gros, voil\u00e0. Court et efficace. Pas tr\u00e8s pouss\u00e9, mais le but n&#8217;est certainement pas \u00e7a : ce n&#8217;est pas un guide pour devenir millionnaire. Simplement un petit bouquin pour nous donner le go\u00fbt d&#8217;en \u00eatre une. Et j&#8217;avoue que l\u00e0, \u00e7a me travaille. La jeune millionnaire en affaires \u00c9liane Gamache Latourelle et Marc Fisher 17,96 $<\/p>","protected":false},"author":1,"featured_media":3646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"La jeune millionnaire en affaires... c'est moi!","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[254,249],"tags":[],"class_list":["post-1358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-developpement-personnel","category-se-renseigner"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La jeune millionnaire en affaires - Prochaine lecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prochainelecture.com\/en\/la-jeune-millionnaire-en-affaires\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La jeune millionnaire en affaires - Prochaine lecture\" \/>\n<meta property=\"og:description\" content=\"Avec un titre et un couverture pareils, j&#8217;avais des doutes. Ce livre qui semblait vouloir expliquer aux filles comment devenir millionnaires avait l&#8217;air dr\u00f4le et un peu niaiseux, mais pas cr\u00e9dible. Et pourtant&#8230; \u00c9liane Gamache amorce en nous parlant comme \u00e0 une amie. Les paragraphes\u00a0n&#8217;ont souvent qu&#8217;une phrase, il y a beaucoup de points d&#8217;exclamation, souvent des mots en majuscules : elle veut attirer l&#8217;attention de ses lectrices. Veut, veut pas, \u00e7a a assez march\u00e9 pour que je continue. Elle commence par nous expliquer pourquoi il y a pas mal plus d&#8217;avantages que d&#8217;inconv\u00e9nients \u00e0 \u00eatre millionnaire. Elle nous en parle comme d&#8217;une aventure exaltante, qui n\u00e9cessite de prendre des risques et d&#8217;avoir du &#8220;guts&#8221;. Elle nous rappelle \u00e0 quel point une vie dans un bureau \u00e0 faire un travail qui ne nous passionne pas c&#8217;est tuant, et que dans le fond, on prend toujours un risque, m\u00eame avec un travail &#8220;stable&#8221; : les entreprises peuvent faire des mises \u00e0 pied du jour au lendemain, elles peuvent faire faillite, m\u00eame le gouvernement peut couper dans ses fonctionnaires. Mais au moins, quand on part sa business, on est libres, et on a beaucoup plus de contr\u00f4le. Difficile de ne pas \u00eatre d&#8217;accord avec elle, \u00e7a fait r\u00eaver. Qui ne veut pas avoir plus d&#8217;argent qu&#8217;il ne peut en d\u00e9penser? Puis, elle nous donne des conseils. Je ne les \u00e9num\u00e9rerai pas, je vous laisse cette lecture courte, l\u00e9g\u00e8re et somme toute inspirante, mais j&#8217;en ai retenu une que j&#8217;ai appliqu\u00e9e d\u00e8s le lendemain : toujours n\u00e9gocier. Elle donne l&#8217;exemple de l&#8217;achat d&#8217;une voiture : elle dit de prendre le temps d&#8217;appeler plusieurs concessionnaires, puis de se pr\u00e9senter \u00e0 l&#8217;un en affirmant que son concurrent nous offre la m\u00eame chose pour 2000 $ de moins, puis d&#8217;appeler ce concurrent devant le concessionnaire. Il suffit de regarde la vitesse avec laquelle le concessionnaire va nous accorder ce prix-l\u00e0. Puis elle nous demande : combien d&#8217;heures avez-vous besoin de travailler pour faire 2000 $? Surtout qu&#8217;en fait, pour avoir 2000 $, il faut en faire 4000 $ avec les imp\u00f4ts. Donc, avec 45 minutes d&#8217;appels, on s&#8217;est fait combien de l&#8217;heure? Elle dit aussi que la plupart du temps, pour avoir un meilleur prix, il suffit de le demander. Les gens n&#8217;osent pas le faire par peur d&#8217;avoir l&#8217;air pauvre ou par g\u00eane, mais \u00e7a vaut la peine, et \u00e7a ne co\u00fbte rien! En gros, voil\u00e0. Court et efficace. Pas tr\u00e8s pouss\u00e9, mais le but n&#8217;est certainement pas \u00e7a : ce n&#8217;est pas un guide pour devenir millionnaire. Simplement un petit bouquin pour nous donner le go\u00fbt d&#8217;en \u00eatre une. Et j&#8217;avoue que l\u00e0, \u00e7a me travaille. La jeune millionnaire en affaires \u00c9liane Gamache Latourelle et Marc Fisher 17,96 $\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prochainelecture.com\/en\/la-jeune-millionnaire-en-affaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Prochaine lecture\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/prochainelecture\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/prochainelecture\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-26T14:51:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-19T14:15:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/06\/1766496-gf.jpg?fit=362%2C549&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"362\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Na\u00efma Hassert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/www.naimahassert.com\/wp-content\/uploads\/2016\/06\/1766496-gf.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@ProchaineL\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Na\u00efma Hassert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/\"},\"author\":{\"name\":\"Na\u00efma Hassert\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\"},\"headline\":\"La jeune millionnaire en affaires\",\"datePublished\":\"2016-06-26T14:51:06+00:00\",\"dateModified\":\"2020-08-19T14:15:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/\"},\"wordCount\":494,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/1766496-gf_1.png?fit=800%2C549&ssl=1\",\"articleSection\":[\"D\u00e9veloppement personnel\",\"Se renseigner\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/\",\"name\":\"La jeune millionnaire en affaires - Prochaine lecture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/1766496-gf_1.png?fit=800%2C549&ssl=1\",\"datePublished\":\"2016-06-26T14:51:06+00:00\",\"dateModified\":\"2020-08-19T14:15:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/1766496-gf_1.png?fit=800%2C549&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/1766496-gf_1.png?fit=800%2C549&ssl=1\",\"width\":800,\"height\":549},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/la-jeune-millionnaire-en-affaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prochainelecture.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La jeune millionnaire en affaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#website\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"name\":\"Prochaine lecture\",\"description\":\"Mes lectures, pour vous inspirer\",\"publisher\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prochainelecture.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#organization\",\"name\":\"Prochaine lecture\",\"url\":\"https:\\\/\\\/prochainelecture.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/prochainelecture.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1\",\"width\":781,\"height\":100,\"caption\":\"Prochaine lecture\"},\"image\":{\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\\\/\",\"https:\\\/\\\/www.instagram.com\\\/prochaine.lecture\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/prochainelecture.com\\\/#\\\/schema\\\/person\\\/28171c04af8e8a8f65d2d8ccdb8f2dc2\",\"name\":\"Na\u00efma Hassert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g\",\"caption\":\"Na\u00efma Hassert\"},\"sameAs\":[\"https:\\\/\\\/prochainelecture.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/prochainelecture\",\"https:\\\/\\\/x.com\\\/ProchaineL\"],\"url\":\"https:\\\/\\\/prochainelecture.com\\\/en\\\/author\\\/naima-hassertgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La jeune millionnaire en affaires - Prochaine lecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prochainelecture.com\/en\/la-jeune-millionnaire-en-affaires\/","og_locale":"en_US","og_type":"article","og_title":"La jeune millionnaire en affaires - Prochaine lecture","og_description":"Avec un titre et un couverture pareils, j&#8217;avais des doutes. Ce livre qui semblait vouloir expliquer aux filles comment devenir millionnaires avait l&#8217;air dr\u00f4le et un peu niaiseux, mais pas cr\u00e9dible. Et pourtant&#8230; \u00c9liane Gamache amorce en nous parlant comme \u00e0 une amie. Les paragraphes\u00a0n&#8217;ont souvent qu&#8217;une phrase, il y a beaucoup de points d&#8217;exclamation, souvent des mots en majuscules : elle veut attirer l&#8217;attention de ses lectrices. Veut, veut pas, \u00e7a a assez march\u00e9 pour que je continue. Elle commence par nous expliquer pourquoi il y a pas mal plus d&#8217;avantages que d&#8217;inconv\u00e9nients \u00e0 \u00eatre millionnaire. Elle nous en parle comme d&#8217;une aventure exaltante, qui n\u00e9cessite de prendre des risques et d&#8217;avoir du &#8220;guts&#8221;. Elle nous rappelle \u00e0 quel point une vie dans un bureau \u00e0 faire un travail qui ne nous passionne pas c&#8217;est tuant, et que dans le fond, on prend toujours un risque, m\u00eame avec un travail &#8220;stable&#8221; : les entreprises peuvent faire des mises \u00e0 pied du jour au lendemain, elles peuvent faire faillite, m\u00eame le gouvernement peut couper dans ses fonctionnaires. Mais au moins, quand on part sa business, on est libres, et on a beaucoup plus de contr\u00f4le. Difficile de ne pas \u00eatre d&#8217;accord avec elle, \u00e7a fait r\u00eaver. Qui ne veut pas avoir plus d&#8217;argent qu&#8217;il ne peut en d\u00e9penser? Puis, elle nous donne des conseils. Je ne les \u00e9num\u00e9rerai pas, je vous laisse cette lecture courte, l\u00e9g\u00e8re et somme toute inspirante, mais j&#8217;en ai retenu une que j&#8217;ai appliqu\u00e9e d\u00e8s le lendemain : toujours n\u00e9gocier. Elle donne l&#8217;exemple de l&#8217;achat d&#8217;une voiture : elle dit de prendre le temps d&#8217;appeler plusieurs concessionnaires, puis de se pr\u00e9senter \u00e0 l&#8217;un en affirmant que son concurrent nous offre la m\u00eame chose pour 2000 $ de moins, puis d&#8217;appeler ce concurrent devant le concessionnaire. Il suffit de regarde la vitesse avec laquelle le concessionnaire va nous accorder ce prix-l\u00e0. Puis elle nous demande : combien d&#8217;heures avez-vous besoin de travailler pour faire 2000 $? Surtout qu&#8217;en fait, pour avoir 2000 $, il faut en faire 4000 $ avec les imp\u00f4ts. Donc, avec 45 minutes d&#8217;appels, on s&#8217;est fait combien de l&#8217;heure? Elle dit aussi que la plupart du temps, pour avoir un meilleur prix, il suffit de le demander. Les gens n&#8217;osent pas le faire par peur d&#8217;avoir l&#8217;air pauvre ou par g\u00eane, mais \u00e7a vaut la peine, et \u00e7a ne co\u00fbte rien! En gros, voil\u00e0. Court et efficace. Pas tr\u00e8s pouss\u00e9, mais le but n&#8217;est certainement pas \u00e7a : ce n&#8217;est pas un guide pour devenir millionnaire. Simplement un petit bouquin pour nous donner le go\u00fbt d&#8217;en \u00eatre une. Et j&#8217;avoue que l\u00e0, \u00e7a me travaille. La jeune millionnaire en affaires \u00c9liane Gamache Latourelle et Marc Fisher 17,96 $","og_url":"https:\/\/prochainelecture.com\/en\/la-jeune-millionnaire-en-affaires\/","og_site_name":"Prochaine lecture","article_publisher":"https:\/\/www.facebook.com\/prochainelecture\/","article_author":"https:\/\/www.facebook.com\/prochainelecture","article_published_time":"2016-06-26T14:51:06+00:00","article_modified_time":"2020-08-19T14:15:49+00:00","og_image":[{"width":362,"height":549,"url":"https:\/\/i1.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/06\/1766496-gf.jpg?fit=362%2C549&ssl=1","type":"image\/jpeg"}],"author":"Na\u00efma Hassert","twitter_card":"summary_large_image","twitter_image":"http:\/\/www.naimahassert.com\/wp-content\/uploads\/2016\/06\/1766496-gf.jpg","twitter_creator":"@ProchaineL","twitter_misc":{"Written by":"Na\u00efma Hassert","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/#article","isPartOf":{"@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/"},"author":{"name":"Na\u00efma Hassert","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2"},"headline":"La jeune millionnaire en affaires","datePublished":"2016-06-26T14:51:06+00:00","dateModified":"2020-08-19T14:15:49+00:00","mainEntityOfPage":{"@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/"},"wordCount":494,"commentCount":0,"publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"image":{"@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/06\/1766496-gf_1.png?fit=800%2C549&ssl=1","articleSection":["D\u00e9veloppement personnel","Se renseigner"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/","url":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/","name":"La jeune millionnaire en affaires - Prochaine lecture","isPartOf":{"@id":"https:\/\/prochainelecture.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/#primaryimage"},"image":{"@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/06\/1766496-gf_1.png?fit=800%2C549&ssl=1","datePublished":"2016-06-26T14:51:06+00:00","dateModified":"2020-08-19T14:15:49+00:00","breadcrumb":{"@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/#primaryimage","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/06\/1766496-gf_1.png?fit=800%2C549&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/06\/1766496-gf_1.png?fit=800%2C549&ssl=1","width":800,"height":549},{"@type":"BreadcrumbList","@id":"https:\/\/prochainelecture.com\/la-jeune-millionnaire-en-affaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prochainelecture.com\/"},{"@type":"ListItem","position":2,"name":"La jeune millionnaire en affaires"}]},{"@type":"WebSite","@id":"https:\/\/prochainelecture.com\/#website","url":"https:\/\/prochainelecture.com\/","name":"Next Read","description":"My readings, to inspire you","publisher":{"@id":"https:\/\/prochainelecture.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prochainelecture.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prochainelecture.com\/#organization","name":"Next Read","url":"https:\/\/prochainelecture.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2020\/08\/117888325_336825540689736_603986003001583239_n.png?fit=781%2C100&ssl=1","width":781,"height":100,"caption":"Prochaine lecture"},"image":{"@id":"https:\/\/prochainelecture.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/prochainelecture\/","https:\/\/www.instagram.com\/prochaine.lecture\/"]},{"@type":"Person","@id":"https:\/\/prochainelecture.com\/#\/schema\/person\/28171c04af8e8a8f65d2d8ccdb8f2dc2","name":"Na\u00efma Hassert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0bcd64abdf76523c95ab87757f6706adb7301180b90d4958cb75ec7293b295c?s=96&d=mm&r=g","caption":"Na\u00efma Hassert"},"sameAs":["https:\/\/prochainelecture.com\/","https:\/\/www.facebook.com\/prochainelecture","https:\/\/x.com\/ProchaineL"],"url":"https:\/\/prochainelecture.com\/en\/author\/naima-hassertgmail-com\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/prochainelecture.com\/wp-content\/uploads\/2016\/06\/1766496-gf_1.png?fit=800%2C549&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7kvK4-lU","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/comments?post=1358"}],"version-history":[{"count":4,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1358\/revisions"}],"predecessor-version":[{"id":3647,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/posts\/1358\/revisions\/3647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media\/3646"}],"wp:attachment":[{"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/media?parent=1358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/categories?post=1358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prochainelecture.com\/en\/wp-json\/wp\/v2\/tags?post=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}